{"id":1470382,"date":"2026-01-22T09:03:52","date_gmt":"2026-01-22T17:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/"},"modified":"2026-01-22T09:03:52","modified_gmt":"2026-01-22T17:03:52","slug":"estudiantes-minnesota-nino-conejo-ice-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/","title":{"rendered":"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente"},"content":{"rendered":"<p>Cuatro estudiantes del distrito escolar de Columbia Heights, ciudad al norte de Minneapolis, incluyendo un ni\u00f1o de cinco a\u00f1os, han sido detenidos por el ICE en las \u00faltimas dos semanas, seg\u00fan Zena Stenvik, superintendente del distrito escolar.<\/p>\n<p>\u201cLos agentes del ICE han estado rondando nuestros vecindarios, rodeando nuestras escuelas, siguiendo nuestros autobuses, entrando en nuestros estacionamientos y llev\u00e1ndose a nuestros ni\u00f1os\u201d, declar\u00f3 Stenvik.<\/p>\n<p>Entre los detenidos se encuentra Liam Conejo Ramos, de cinco a\u00f1os, quien fue retenido el martes junto con su padre de la entrada de su casa tras regresar a casa del preescolar, a\u00f1adi\u00f3.<\/p>\n<p>Su familia tiene un caso de asilo activo y no tiene orden de deportaci\u00f3n, seg\u00fan Stenvik.<\/p>\n<p>En un comunicado a CNN, el Departamento de Seguridad Nacional indic\u00f3 que el ICE estaba realizando un operativo para arrestar al padre del ni\u00f1o cuando este \u201chuy\u00f3 a pie, abandonando a su hijo\u201d.<\/p>\n<p>\u201cPara la seguridad del ni\u00f1o, uno de nuestros oficiales de ICE permaneci\u00f3 con \u00e9l mientras los dem\u00e1s oficiales deten\u00edan\u201d al padre, declar\u00f3 la subsecretaria del Departamento de Seguridad Nacional, Tricia McLaughlin, en un comunicado enviado por correo electr\u00f3nico a CNN.<\/p>\n<p>\u201cSe les pregunta a los padres si desean ser deportados con sus hijos, o ICE los colocar\u00e1 con una persona de confianza que ellos designen. Esto es consistente con la aplicaci\u00f3n de la ley migratoria de administraciones anteriores\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Otros estudiantes detenidos, seg\u00fan Stenvik, incluyen:<\/p>\n<p>\u2014 un estudiante de preparatoria de 17 a\u00f1os que fue detenido ayer camino a la escuela y sacado de su auto;<\/p>\n<p>\u2014 una estudiante de 17 a\u00f1os que fue retenida la semana pasada junto con su madre<\/p>\n<p>\u2014 una estudiante de cuarto grado de 10 a\u00f1os que fue detenida hace dos semanas mientras caminaba a la escuela con su madre.<\/p>\n<p>\u201cLa sensaci\u00f3n de seguridad en nuestra comunidad y en nuestras escuelas est\u00e1 conmocionada, y nuestros corazones est\u00e1n destrozados\u201d, declar\u00f3 Stenvik.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuatro estudiantes del distrito escolar de Columbia Heights, ciudad al norte de Minneapolis, incluyendo un ni\u00f1o de cinco a\u00f1os, han sido detenidos por el ICE en las \u00faltimas dos semanas, seg\u00fan Zena Stenvik, superintendente del distrito escolar. \u201cLos agentes del ICE han estado rondando nuestros vecindarios, rodeando nuestras escuelas, siguiendo nuestros autobuses, entrando en nuestros [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470382","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuatro estudiantes del distrito escolar de Columbia Heights, ciudad al norte de Minneapolis, incluyendo un ni\u00f1o de cinco a\u00f1os, han sido detenidos por el ICE en las \u00faltimas dos semanas, seg\u00fan Zena Stenvik, superintendente del distrito escolar. \u201cLos agentes del ICE han estado rondando nuestros vecindarios, rodeando nuestras escuelas, siguiendo nuestros autobuses, entrando en nuestros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-22T17:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente\",\"datePublished\":\"2026-01-22T17:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/\",\"name\":\"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-22T17:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente - Noticias","og_description":"Cuatro estudiantes del distrito escolar de Columbia Heights, ciudad al norte de Minneapolis, incluyendo un ni\u00f1o de cinco a\u00f1os, han sido detenidos por el ICE en las \u00faltimas dos semanas, seg\u00fan Zena Stenvik, superintendente del distrito escolar. \u201cLos agentes del ICE han estado rondando nuestros vecindarios, rodeando nuestras escuelas, siguiendo nuestros autobuses, entrando en nuestros [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-22T17:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/"},"author":{"name":"","@id":""},"headline":"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente","datePublished":"2026-01-22T17:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/","name":"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-22T17:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cuatro estudiantes de Minnesota, incluido un ni\u00f1o de 5 a\u00f1os, fueron detenidos por ICE, dice la superintendente","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/22\/estudiantes-minnesota-nino-conejo-ice-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-22T17:03:52Z","datePublished":"2026-01-22T17:03:52Z","dateModified":"2026-01-22T17:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cuatro estudiantes de Minnesota, incluido un ni\\u00f1o de 5 a\\u00f1os, fueron detenidos por ICE, dice la superintendente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/22\\\/estudiantes-minnesota-nino-conejo-ice-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/22\\\/estudiantes-minnesota-nino-conejo-ice-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-22T17:03:52Z\",\"datePublished\":\"2026-01-22T17:03:52Z\",\"dateModified\":\"2026-01-22T17:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470387,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/liam-conejo-ramos-nino-5-anios-preescolar-detenido-ice-trax\/","url_meta":{"origin":1470382,"position":0},"title":"Liam Conejo Ramos: el ni\u00f1o de 5 a\u00f1os que fue detenido por ICE junto con su padre ecuatoriano","author":"","date":"enero 22, 2026","format":false,"excerpt":"Un ni\u00f1o de 5 a\u00f1os que fue llevado por agentes federales desde la entrada de su casa en el \u00e1rea metropolitana de Minneapolis el martes tras regresar del preescolar est\u00e1 detenido junto con su padre en una instalaci\u00f3n de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460972,"url":"https:\/\/noticiasya.com\/laredo\/2025\/04\/08\/liberan-madre-hijos-detenidos-ice-mes-nueva-york-trax\/","url_meta":{"origin":1470382,"position":1},"title":"Liberan a una madre y sus tres hijos despu\u00e9s de que ICE los detuviera el mes pasado en una granja lechera de Nueva York","author":"","date":"abril 8, 2025","format":false,"excerpt":"Una madre y sus tres hijos regresaron a su hogar en Nueva York tras su detenci\u00f3n por parte de funcionarios de inmigraci\u00f3n el mes pasado en una granja lechera, anunci\u00f3 el lunes la gobernadora de Nueva York, Kathy Hochul.Un estudiante de tercer grado, dos adolescentes y su madre \u2014cuyos nombres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466884,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/26\/ice-arresta-superintendente-distrito-escolar-iowa-trax\/","url_meta":{"origin":1470382,"position":2},"title":"El ICE arresta al superintendente del distrito escolar m\u00e1s grande de Iowa","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"El superintendente de las Escuelas P\u00fablicas de Des Moines \u2014el distrito escolar m\u00e1s grande de Iowa\u2014 fue detenido la ma\u00f1ana de este viernes por agentes de inmigraci\u00f3n, seg\u00fan el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), que indic\u00f3 que el educador estaba en el pa\u00eds ilegalmente y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470941,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/06\/ninos-detenidos-minnesota-ice-texas-trax\/","url_meta":{"origin":1470382,"position":3},"title":"Al menos seis ni\u00f1os fueron detenidos en Minnesota y trasladados a Texas. Una ni\u00f1a estuvo retenida durante casi un mes","author":"","date":"febrero 6, 2026","format":false,"excerpt":"M\u00e1s de una hora antes de que amanezca, en una calle completamente oscura y cubierta de montones de nieve de Minnesota, Elizabeth Zuna Caisaguano, de 10 a\u00f1os, y su madre, se dirigieron a la parada del autob\u00fas escolar, como lo hacen todos los d\u00edas de la semana a las 6:10\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470427,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/23\/que-paso-liam-conejo-ramos-5-anios-ice-trax\/","url_meta":{"origin":1470382,"position":4},"title":"\u00bfQu\u00e9 pas\u00f3 con el ni\u00f1o de 5 a\u00f1os Liam Conejo? Un pastor dice que ICE lo us\u00f3 de carnada y autoridades defienden la detenci\u00f3n","author":"","date":"enero 23, 2026","format":false,"excerpt":"Envuelto en su peque\u00f1o abrigo de cuadros y un gorro azul tejido de conejito, Liam Conejo Ramos, de 5 a\u00f1os, parece aterrorizado mientras desconocidos lo alejan de su hogar en Minnesota.Un agente federal enmascarado camina detr\u00e1s del ni\u00f1o, sosteniendo la manija de su mochila de Spiderman mientras Liam sube a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470708,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/31\/liam-conejo-ramos-liberan-ice-trax\/","url_meta":{"origin":1470382,"position":5},"title":"Un juez ordena la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre, seg\u00fan una fuente","author":"","date":"enero 31, 2026","format":false,"excerpt":"Un juez federal ha ordenado la liberaci\u00f3n de Liam Conejo Ramos, de 5 a\u00f1os, y su padre del Centro Residencial Familiar del Sur de Texas en Dilley, Texas, seg\u00fan una fuente con conocimiento del fallo del juez federal emitido el s\u00e1bado.CNN no logr\u00f3 hasta el momento obtener una copia del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470382"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470382\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}