{"id":1470400,"date":"2026-01-22T17:03:38","date_gmt":"2026-01-23T01:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/"},"modified":"2026-01-22T17:03:38","modified_gmt":"2026-01-23T01:03:38","slug":"estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","title":{"rendered":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud"},"content":{"rendered":"<p>El Departamento de Salud y Servicios Humanos de EE.UU. (HHS por sus siglas en ingl\u00e9s), confirm\u00f3 el jueves que Estados Unidos complet\u00f3 su retiro definitivo de la Organizaci\u00f3n Mundial de la Salud (OMS). Con este anuncio, se materializa uno de los objetivos m\u00e1s ambiciosos y controvertidos del Gobierno del presidente Donald Trump.<\/p>\n<p>Trump <a href=\"https:\/\/www.cnn.com\/2025\/01\/21\/world\/world-health-organization-trump-withdraw-explainer-intl\">intent\u00f3 salir de la OMS<\/a> durante su primer mandato, luego notific\u00f3<a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/01\/withdrawing-the-united-states-from-the-worldhealth-organization\/\"> a trav\u00e9s de un decreto<\/a> durante su primer d\u00eda de su segundo mandato que EE.UU. <a href=\"https:\/\/cnnespanol.cnn.com\/2020\/05\/19\/salud\/video\/organizacion-mundial-salud-cnn-recibo-analisis-presidente-eeuu-donald-trump-ayuda-economica-pandemia-coronavirus-tedros-adhanom-ghebreyesus-requena-panorama-cnnee\">abandonar\u00eda la organizaci\u00f3n<\/a>. Por ley, EE.UU. <a href=\"https:\/\/avalon.law.yale.edu\/20th_century\/decad052.asp#1\">debe dar a la OMS un aviso de un a\u00f1o<\/a> y pagar todas las cuotas pendientes antes de su partida.<\/p>\n<p>EE.UU. todav\u00eda le debe a la OMS aproximadamente<a href=\"https:\/\/avalon.law.yale.edu\/20th_century\/decad052.asp#1\"> US$ 260 millones<\/a>, pero expertos legales dijeron que es poco probable que EE.UU. pague y que la OMS tiene pocos recursos.<\/p>\n<p>CNN ha contactado a la OMS para obtener comentarios.<\/p>\n<p>\u201cLegalmente, est\u00e1 muy claro que Estados Unidos no puede retirarse oficialmente de la OMS a menos que pague sus obligaciones financieras pendientes\u201d, dijo el Dr. Lawrence Gostin, experto en derecho de la salud global y salud p\u00fablica en la Universidad de Georgetown. \u201cPero la OMS no tiene poder para obligar a EE.UU. a pagar lo que debe\u201d.<\/p>\n<p>La OMS podr\u00eda aprobar una resoluci\u00f3n diciendo que EE.UU. no puede retirarse hasta que pague, pero Gostin dijo que probablemente no arriesgar\u00e1 crear m\u00e1s tensi\u00f3n cuando Trump de todos modos probablemente se retire.<\/p>\n<p>El jueves, el HHS dijo que todo el financiamiento del gobierno estadounidense a la OMS hab\u00eda sido terminado y que todo el personal y contratistas asignados o integrados en la organizaci\u00f3n han sido retirados. Tambi\u00e9n se inform\u00f3 que EE.UU. hab\u00eda cesado la participaci\u00f3n oficial en comit\u00e9s patrocinados por la OMS, \u00f3rganos de liderazgo, estructuras de gobernanza y grupos t\u00e9cnicos de trabajo.<\/p>\n<p>Sin embargo, el HHS dej\u00f3 la puerta abierta a cierta colaboraci\u00f3n continua. Cuando se le pregunt\u00f3 si EE.UU. participar\u00eda en una pr\u00f3xima reuni\u00f3n liderada por la OMS para decidir la composici\u00f3n de las vacunas contra la gripe del pr\u00f3ximo a\u00f1o, la administraci\u00f3n dijo que las conversaciones sobre ese tema a\u00fan contin\u00faan.<\/p>\n<p>Durante una llamada con periodistas el jueves, un alto funcionario del Gobierno dijo que Estados Unidos \u201cno ha estado recibiendo mucho rendimiento por nuestro valor, por nuestro dinero, ni por el personal que hemos proporcionado\u201d.<\/p>\n<p>\u201cUna promesa hecha y una promesa cumplida\u201d, dijo un alto funcionario de la administraci\u00f3n. El funcionario dijo que la OMS \u201cha actuado en contra del inter\u00e9s de EE.UU. de proteger al p\u00fablico estadounidense\u201d.<\/p>\n<p>Aunque EE.UU. era el mayor financiador de la organizaci\u00f3n, el funcionario se\u00f1al\u00f3 que nunca ha habido un director general estadounidense de la OMS.<\/p>\n<p>El HHS dijo que la OMS nunca asumi\u00f3 lo que el Gobierno de EE.UU. considera fracasos durante la pandemia de covid-19. El HHS dijo que la OMS hab\u00eda tardado en declarar una emergencia de salud p\u00fablica global, lo que le cost\u00f3 al mundo semanas cr\u00edticas mientras el virus se propagaba.<\/p>\n<p>\u201cDurante ese periodo, el liderazgo de la OMS repiti\u00f3 y elogi\u00f3 la respuesta de China a pesar de la evidencia de subregistro temprano, supresi\u00f3n de informaci\u00f3n y retrasos en confirmar la transmisi\u00f3n de persona a persona\u201d, dijo la agencia en un comunicado de prensa.<\/p>\n<p>El HHS tambi\u00e9n se\u00f1al\u00f3 la renuencia de la OMS a reconocer el contagio a\u00e9reo del virus y dijo que minimiz\u00f3 la idea de que personas sin s\u00edntomas pudieran propagar la infecci\u00f3n.<\/p>\n<p>\u201cEsta acci\u00f3n significa que las pol\u00edticas de salud de nuestro pa\u00eds ya no pueden estar limitadas por bur\u00f3cratas extranjeros sin rendici\u00f3n de cuentas\u201d, dijo el funcionario del HHS.<\/p>\n<p>A pesar de la ruptura, la administraci\u00f3n afirm\u00f3 que EE.UU. seguir\u00e1 siendo un l\u00edder mundial en salud.<\/p>\n<p>A\u00fan no se han publicado los detalles de la nueva estrategia, pero los funcionarios dijeron que EE.UU. continuar\u00eda colaborando con otros pa\u00edses en la vigilancia de enfermedades infecciosas y el intercambio de datos, a trav\u00e9s de acuerdos con pa\u00edses individuales y trabajando con organizaciones no gubernamentales y grupos religiosos.<\/p>\n<p>Se espera que ese esfuerzo sea liderado por el Centro de Salud Global de los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU.<\/p>\n<p>\u201cHemos evaluado todas las brechas y las posibles brechas. Hemos hecho an\u00e1lisis. Tenemos planes en marcha. Continuaremos trabajando con los pa\u00edses y los ministerios de salud, como lo hemos hecho durante d\u00e9cadas, y seguiremos desarrollando esas relaciones y utiliz\u00e1ndolas de una forma mutuamente beneficiosa\u201d, dijo otro alto funcionario de la administraci\u00f3n.<\/p>\n<p>El Gobierno prometi\u00f3 \u201cuna serie de nuevos anuncios\u201d en los pr\u00f3ximos meses.<\/p>\n<p>Algunos expertos dijeron que intentar gestionar la salud global a trav\u00e9s de acuerdos con pa\u00edses individuales crear\u00eda un sistema fragmentado que no reemplazar\u00e1 lo que puede hacer la Organizaci\u00f3n Mundial de la Salud.<\/p>\n<p>\u201cNo permite el mismo nivel de colaboraci\u00f3n y vigilancia que trabajar con la OMS\u201d, dijo un exfuncionario de los CDC, que pidi\u00f3 no ser identificado. \u201cNo hay suficiente financiaci\u00f3n para reemplazarlo todo\u201d.<\/p>\n<p>El exfuncionario se\u00f1al\u00f3 que los CDC tienen personal en unos 60 pa\u00edses, pero no en todos los pa\u00edses, \u201cpor eso una estructura general como la OMS es importante\u201d.<\/p>\n<p>Los cr\u00edticos dijeron que la medida podr\u00eda cegar a Estados Unidos y al mundo ante posibles amenazas biol\u00f3gicas.<\/p>\n<p>\u201cLa retirada de EE.UU. de la Organizaci\u00f3n Mundial de la Salud es un abandono miope y equivocado de nuestros compromisos de salud global. La cooperaci\u00f3n y comunicaci\u00f3n globales son cr\u00edticas para mantener protegidos a nuestros propios ciudadanos porque los g\u00e9rmenes no respetan las fronteras\u201d, dijo el Dr. Ronald Nahass, presidente de la Sociedad de Enfermedades Infecciosas de Estados Unidos, en un comunicado.<\/p>\n<p>\u201cRetirarse de la Organizaci\u00f3n Mundial de la Salud es cient\u00edficamente irresponsable. No reconoce la historia natural fundamental de las enfermedades infecciosas. La cooperaci\u00f3n global no es un lujo; es una necesidad biol\u00f3gica\u201d, agreg\u00f3 Nahass.<\/p>\n<p>Otros estuvieron de acuerdo con esa valoraci\u00f3n.<\/p>\n<p>\u201cHoy es un d\u00eda en el que la salud p\u00fablica mundial sufri\u00f3 un golpe triste y trascendental. Viviremos m\u00e1s brotes mortales en todo el mundo. Ocurrir\u00e1n porque los expertos de la comunidad de salud p\u00fablica de EE.UU. no estar\u00e1n presentes para liderar la respuesta global. Estos brotes se propagar\u00e1n a Estados Unidos y nos har\u00e1n mucho da\u00f1o\u201d, dijo el Dr. Michael Osterholm, quien dirige el Centro de Investigaci\u00f3n y Pol\u00edtica de Enfermedades Infecciosas de la Universidad de Minnesota.<\/p>\n<p>\u201cEsta es la decisi\u00f3n presidencial m\u00e1s lamentable de mi vida\u201d, dijo Gostin, de Georgetown. \u201cNo ser miembro de la OMS es profundamente perjudicial para nuestros propios intereses y nuestra seguridad nacional\u201d.<\/p>\n<p>\u201cNo tendremos acceso r\u00e1pido y completo a los datos epidemiol\u00f3gicos, muestras de virus y datos de secuenciaci\u00f3n gen\u00f3mica para crear vacunas y tratamientos. Y no podremos trabajar internacionalmente para frenar amenazas graves a la salud antes de que lleguen a nuestras costas. Cuando llegue la pr\u00f3xima pandemia (y llegar\u00e1), Estados Unidos no estar\u00e1 preparado y nuestra respuesta ser\u00e1 lenta y d\u00e9bil. Eso perjudica a todos los estadounidenses\u201d, agreg\u00f3 Gostin.<\/p>\n<p>En una conferencia de prensa la primavera pasada, el director general de la OMS, Dr. Tedros Adhanom Ghebreyesus, calific\u00f3 la salida de EE.UU. como una propuesta de \u201cperder-perder\u201d.<\/p>\n<p>\u201cEstados Unidos pierde, y el resto del mundo, sabemos con certeza, pierde\u201d, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Salud y Servicios Humanos de EE.UU. (HHS por sus siglas en ingl\u00e9s), confirm\u00f3 el jueves que Estados Unidos complet\u00f3 su retiro definitivo de la Organizaci\u00f3n Mundial de la Salud (OMS). Con este anuncio, se materializa uno de los objetivos m\u00e1s ambiciosos y controvertidos del Gobierno del presidente Donald Trump. Trump intent\u00f3 salir [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470400","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Salud y Servicios Humanos de EE.UU. (HHS por sus siglas en ingl\u00e9s), confirm\u00f3 el jueves que Estados Unidos complet\u00f3 su retiro definitivo de la Organizaci\u00f3n Mundial de la Salud (OMS). Con este anuncio, se materializa uno de los objetivos m\u00e1s ambiciosos y controvertidos del Gobierno del presidente Donald Trump. Trump intent\u00f3 salir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T01:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud\",\"datePublished\":\"2026-01-23T01:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/\"},\"wordCount\":1329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/\",\"name\":\"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-23T01:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud - Noticias","og_description":"El Departamento de Salud y Servicios Humanos de EE.UU. (HHS por sus siglas en ingl\u00e9s), confirm\u00f3 el jueves que Estados Unidos complet\u00f3 su retiro definitivo de la Organizaci\u00f3n Mundial de la Salud (OMS). Con este anuncio, se materializa uno de los objetivos m\u00e1s ambiciosos y controvertidos del Gobierno del presidente Donald Trump. Trump intent\u00f3 salir [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-23T01:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/"},"author":{"name":"","@id":""},"headline":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud","datePublished":"2026-01-23T01:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/"},"wordCount":1329,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","name":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-23T01:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-23T01:03:38Z","datePublished":"2026-01-23T01:03:38Z","dateModified":"2026-01-23T01:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estados Unidos oficializa su salida de la Organizaci\\u00f3n Mundial de la Salud\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/22\\\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/22\\\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-23T01:03:38Z\",\"datePublished\":\"2026-01-23T01:03:38Z\",\"dateModified\":\"2026-01-23T01:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457689,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","url_meta":{"origin":1470400,"position":0},"title":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;","author":"","date":"enero 21, 2025","format":false,"excerpt":"La Organizaci\u00f3n Mundial de la Salud (OMS) espera que el presidente de Estados Unidos, Donald Trump, reconsidere su decisi\u00f3n de retirar a su pa\u00eds del organismo, seg\u00fan dijo este martes en un comunicado.\u201cLa Organizaci\u00f3n Mundial de la Salud lamenta el anuncio de que Estados Unidos de Am\u00e9rica tiene la intenci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458273,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/05\/milei-retira-oms-orix\/","url_meta":{"origin":1470400,"position":1},"title":"Javier Milei retira a Argentina de la OMS","author":"","date":"febrero 5, 2025","format":false,"excerpt":"El Gobierno de Argentina anunci\u00f3 este mi\u00e9rcoles que el pa\u00eds se retirar\u00e1 de la Organizaci\u00f3n Mundial de Salud (OMS), seg\u00fan confirm\u00f3 el portavoz de la Presidencia, Manuel Adorni, durante una conferencia de prensa.Adorni remarc\u00f3 que fue un pedido del presidente de Argentina, Javier Milei, al canciller argentino, Gerardo Werthein.Dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458413,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/07\/milei-argentina-oms-que-significa-orix\/","url_meta":{"origin":1470400,"position":2},"title":"\u00c1NALISIS | Tras los pasos de Trump, Milei busca sacar a Argentina de la OMS: \u00bfqu\u00e9 significa para el pa\u00eds?","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Dos semanas despu\u00e9s de que el presidente Donald Trump anunci\u00f3 que buscar\u00e1 retirar a Estados Unidos de la Organizaci\u00f3n Mundial de la Salud (OMS), su hom\u00f3logo argentino Javier Milei replic\u00f3 para su pa\u00eds esta decisi\u00f3n, con argumentos similares.\u201cLa mala gesti\u00f3n de la organizaci\u00f3n ante la pandemia de covid-19 y otras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464751,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/22\/trump-retira-pais-unesco-trax\/","url_meta":{"origin":1470400,"position":3},"title":"EE.UU. se retirar\u00e1 nuevamente de la agencia cient\u00edfica y cultural de la ONU, Unesco, dice la Casa Blanca","author":"","date":"julio 22, 2025","format":false,"excerpt":"El presidente Donald Trump retirar\u00e1 a Estados Unidos de la Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura (Unesco, por sus siglas en ingl\u00e9s), dijo a CNN una funcionaria de la Casa Blanca.La decisi\u00f3n se produce mientras el presidente contin\u00faa retirando al pa\u00eds de organismos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451905,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/16\/oms-casos-de-viruela-simica-europa-trax\/","url_meta":{"origin":1470400,"position":4},"title":"La OMS advierte de que es probable que haya m\u00e1s casos de viruela s\u00edmica en Europa en los pr\u00f3ximos d\u00edas y semanas","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN)-- La Organizaci\u00f3n Mundial de la Salud (OMS) ha advertido de que es probable que en los pr\u00f3ximos d\u00edas y semanas se produzcan m\u00e1s casos de viruela s\u00edmica en Europa.La advertencia se produjo despu\u00e9s de que Suecia confirmara este jueves su primer caso de la cepa Clade I del virus,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473286,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/17\/carlos-alvarado-ministro-salud-orix\/","url_meta":{"origin":1470400,"position":5},"title":"Siguen los cambios en Venezuela: Delcy Rodr\u00edguez nombr\u00f3 a Carlos Alvarado como ministro de Salud, un cargo que ya ocup\u00f3","author":"","date":"abril 17, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, nombr\u00f3 este viernes a Carlos Alvarado como nuevo ministro de Salud, un cargo que el m\u00e9dico ya hab\u00eda ocupado entre 2018 y 2022, durante el Gobierno del derrocado presidente Nicol\u00e1s Maduro.Rodr\u00edguez anunci\u00f3 el nombramiento en su canal de Telegram y sus redes sociales,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470400"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470400\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}