{"id":1470401,"date":"2026-01-22T17:03:39","date_gmt":"2026-01-23T01:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/"},"modified":"2026-01-22T17:03:39","modified_gmt":"2026-01-23T01:03:39","slug":"camara-representantes-resolucion-acciones-militares-venezuela-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/","title":{"rendered":"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela"},"content":{"rendered":"<p>La C\u00e1mara de Representantes rechaz\u00f3 este jueves una resoluci\u00f3n bipartidista que buscaba restringir a la Casa Blanca el poder de tomar cualquier acci\u00f3n militar adicional en Venezuela sin la aprobaci\u00f3n del Congreso.<\/p>\n<p>La resoluci\u00f3n, presentada por los representantes dem\u00f3cratas Jim McGovern y Joaquin Castro y el representante republicano Thomas Massie, no fue aprobada, con un empate de 215-215. Massie y el representante republicano Don Bacon se unieron a los dem\u00f3cratas para votar a favor de la resoluci\u00f3n.<\/p>\n<p>La iniciativa sigui\u00f3 al \u201cataque a gran escala\u201d del Gobierno de Trump contra Venezuela y la captura de Nicol\u00e1s Maduro. Desde entonces, el presidente Donald Trump ha dicho que Estados Unidos jugar\u00e1 un papel central en el Gobierno de Venezuela y no ha descartado la participaci\u00f3n militar en la naci\u00f3n, un punto de controversia en el Capitolio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de Representantes rechaz\u00f3 este jueves una resoluci\u00f3n bipartidista que buscaba restringir a la Casa Blanca el poder de tomar cualquier acci\u00f3n militar adicional en Venezuela sin la aprobaci\u00f3n del Congreso. La resoluci\u00f3n, presentada por los representantes dem\u00f3cratas Jim McGovern y Joaquin Castro y el representante republicano Thomas Massie, no fue aprobada, con un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470401","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"La C\u00e1mara de Representantes rechaz\u00f3 este jueves una resoluci\u00f3n bipartidista que buscaba restringir a la Casa Blanca el poder de tomar cualquier acci\u00f3n militar adicional en Venezuela sin la aprobaci\u00f3n del Congreso. La resoluci\u00f3n, presentada por los representantes dem\u00f3cratas Jim McGovern y Joaquin Castro y el representante republicano Thomas Massie, no fue aprobada, con un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T01:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela\",\"datePublished\":\"2026-01-23T01:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/\"},\"wordCount\":181,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/\",\"name\":\"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-23T01:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela - Noticias","og_description":"La C\u00e1mara de Representantes rechaz\u00f3 este jueves una resoluci\u00f3n bipartidista que buscaba restringir a la Casa Blanca el poder de tomar cualquier acci\u00f3n militar adicional en Venezuela sin la aprobaci\u00f3n del Congreso. La resoluci\u00f3n, presentada por los representantes dem\u00f3cratas Jim McGovern y Joaquin Castro y el representante republicano Thomas Massie, no fue aprobada, con un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-23T01:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela","datePublished":"2026-01-23T01:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/"},"wordCount":181,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/","name":"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-23T01:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00e1mara de Representantes rechaza una resoluci\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/22\/camara-representantes-resolucion-acciones-militares-venezuela-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-23T01:03:39Z","datePublished":"2026-01-23T01:03:39Z","dateModified":"2026-01-23T01:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00e1mara de Representantes rechaza una resoluci\\u00f3n que buscaba limitar las acciones militares de la Casa Blanca en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/22\\\/camara-representantes-resolucion-acciones-militares-venezuela-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/22\\\/camara-representantes-resolucion-acciones-militares-venezuela-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-23T01:03:39Z\",\"datePublished\":\"2026-01-23T01:03:39Z\",\"dateModified\":\"2026-01-23T01:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464745,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/22\/johnson-votacion-camara-archivos-epstein-trax\/","url_meta":{"origin":1470401,"position":0},"title":"Johnson cierra la puerta a una votaci\u00f3n en la C\u00e1mara antes de septiembre sobre la publicaci\u00f3n de los archivos de Epstein","author":"","date":"julio 22, 2025","format":false,"excerpt":"El presidente de la C\u00e1mara de Representantes, Mike Johnson, dijo el lunes que no planea permitir votaciones relacionadas con el caso de Jeffrey Epstein en la \u00faltima semana de la C\u00e1mara en Washington antes del receso, a pesar de la intensa presi\u00f3n de algunos de los miembros de su Partido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466102,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/02\/camara-archivos-epstein-congreso-washington-trax\/","url_meta":{"origin":1470401,"position":1},"title":"Comisi\u00f3n de la C\u00e1mara de Representantes publica parte de los archivos de Epstein","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"La Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes public\u00f3 este martes decenas de miles de archivos relacionados con Jeffrey Epstein que recibi\u00f3 del Departamento de Justicia, mientras la controversia sobre el caso se intensificaba con el regreso de los legisladores a Washington.Aunque se hicieron p\u00fablicos m\u00e1s de 30.000 p\u00e1ginas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468485,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/18\/camara-representantes-paso-trump-archivos-epstein-trax\/","url_meta":{"origin":1470401,"position":2},"title":"El Congreso da luz verde a un proyecto de ley que obliga al Departamento de Justicia  a publicar los archivos de Epstein","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"La C\u00e1mara de Representantes dio este martes el paso significativo de ordenar al Departamento de Justicia que publique todos los archivos de investigaci\u00f3n sobre el fallecido delincuente sexual convicto Jeffrey Epstein, tras meses de intensas luchas internas dentro del Partido Republicano.La medida \u2014que, de manera notable, obtuvo el respaldo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467628,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/22\/republicanos-involucrar-trump-negociaciones-cierre-gobierno-rechazo-lideres-trax\/","url_meta":{"origin":1470401,"position":3},"title":"Algunos republicanos dicen que Trump debe involucrarse en negociaciones del cierre del Gobierno. Sus l\u00edderes rechazan la idea","author":"","date":"octubre 22, 2025","format":false,"excerpt":"Los l\u00edderes republicanos se han mantenido firmes en una posici\u00f3n sencilla en su enfrentamiento con los dem\u00f3cratas sobre el financiamiento del Gobierno: no habr\u00e1 negociaciones hasta que termine el cierre gubernamental.Pero a medida que el impasse se prolonga, algunos republicanos de base est\u00e1n empezando a preguntarse si es hora de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456826,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/21\/mike-johnson-camara-representante-trump-desafios-trax\/","url_meta":{"origin":1470401,"position":4},"title":"La ca\u00f3tica lucha por evitar el cierre pone de relieve los retos que Johnson tiene por delante","author":"","date":"diciembre 21, 2024","format":false,"excerpt":"Tras una semana ca\u00f3tica en la que el presidente de la C\u00e1mara de Representantes, Mike Johnson, se enfrent\u00f3, en distintos momentos, al presidente electo Donald Trump, a los conservadores de l\u00ednea dura y a los dem\u00f3cratas minoritarios, volvi\u00f3 a hacer una broma similar.Cualquier otra persona que pudiera conseguir los 218\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468271,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/12\/gobierno-reunion-publicacion-epstein-trax\/","url_meta":{"origin":1470401,"position":5},"title":"El Gobierno de Trump se reunir\u00e1 para tratar la publicaci\u00f3n de todos los archivos del Departamento de Justicia sobre Epstein","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"Altos funcionarios del Gobierno de Trump ten\u00edan previsto reunirse el mi\u00e9rcoles para tratar una iniciativa en la C\u00e1mara de Representantes de EE.UU. que buscaba forzar una votaci\u00f3n sobre la publicaci\u00f3n de los archivos del Departamento de Justicia relacionados con Jeffrey Epstein, seg\u00fan varias fuentes familiarizadas con la reuni\u00f3n.Una de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470401"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470401\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}