{"id":1470421,"date":"2026-01-23T09:03:50","date_gmt":"2026-01-23T17:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/"},"modified":"2026-01-23T09:03:50","modified_gmt":"2026-01-23T17:03:50","slug":"economica-trump-caro-ia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/23\/economica-trump-caro-ia-trax\/","title":{"rendered":"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses)"},"content":{"rendered":"<p>Hay una corriente que se est\u00e1 consolidando dentro de la administraci\u00f3n Trump y en algunos sectores de Wall Street que imagina dos realidades, en cierto modo incompatibles, que se desarrollan simult\u00e1neamente: un r\u00e1pido crecimiento econ\u00f3mico y una baja inflaci\u00f3n.<\/p>\n<p>Es una idea tentadora: normalmente, el crecimiento r\u00e1pido genera una mayor demanda, lo que tiende a impulsar los precios al alza. Pero esta versi\u00f3n en particular depende de que muchas cosas salgan bien a la vez. E incluso entonces, el resultado podr\u00eda ser desastroso para la fuerza laboral estadounidense.<\/p>\n<p>En esencia: la teor\u00eda del \u201cejecutar a toda m\u00e1quina\u201d postula que las herramientas de inteligencia artificial est\u00e1n a punto de hacer en la d\u00e9cada de 2020 lo que internet hizo en la d\u00e9cada de 1990: es decir, impulsar la productividad en todos los sectores, permitiendo que las empresas crezcan r\u00e1pidamente y que las acciones suban, todo ello mientras los precios al consumidor se mantienen relativamente estables. La magia de ese momento fue posible, en parte, gracias a la r\u00e1pida adopci\u00f3n de las computadoras en red. (S\u00ed, hubo muchos otros factores macroecon\u00f3micos en juego: el fin de la Guerra Fr\u00eda, un esfuerzo masivo de desregulaci\u00f3n, un comercio cada vez m\u00e1s globalizado, pero tengan paciencia).<\/p>\n<p>El jueves, el asesor econ\u00f3mico de Trump, Kevin Hassett, reiter\u00f3 su convicci\u00f3n de que el pr\u00f3ximo presidente de la Reserva Federal deber\u00eda, en esencia, aplicar el modelo de Alan Greenspan y mantener bajas las tasas de inter\u00e9s.<\/p>\n<p>El crecimiento econ\u00f3mico de EE.UU. es s\u00f3lido, declar\u00f3 Hassett a la CNBC, pero la inflaci\u00f3n \u201cno est\u00e1 despegando\u201d.<\/p>\n<p>\u201cAs\u00ed que es obvio, porque la productividad est\u00e1 presente en la fuerza laboral ahora mismo, gracias a la IA y a los centros de datos\u2026 as\u00ed que, para m\u00ed, ahora mismo, se parece much\u00edsimo a los a\u00f1os 90\u201d.<\/p>\n<p>Esta comparaci\u00f3n es muy de moda \u00faltimamente, por razones obvias: <a href=\"https:\/\/www.cnn.com\/2025\/10\/18\/business\/ai-bubble-analyst-nightcap\">la IA parece una burbuja<\/a>, como lo fueron las empresas de internet, los vaqueros anchos est\u00e1n de moda y Gwyneth Paltrow parece estar en todas partes.<\/p>\n<p>Pero hay diferencias importantes entre entonces y ahora, y no se trata solo de que todos acordamos dejar de fumar en los restaurantes y empezamos a usar pijamas para ir al aeropuerto. La econom\u00eda en general se encuentra en una situaci\u00f3n extra\u00f1a, una que parece mucho m\u00e1s pr\u00f3spera en teor\u00eda que en la realidad.<\/p>\n<p>S\u00ed, el crecimiento econ\u00f3mico general es s\u00f3lido: los datos del Departamento de Comercio del jueves mostraron que la expansi\u00f3n del PIB del tercer trimestre alcanz\u00f3 una tasa anualizada del 4,4%, aproximadamente en l\u00ednea con la de mediados de los 90.<\/p>\n<p>Pero que parezca similar en t\u00e9rminos generales no significa que todo sea igual en el interior.<\/p>\n<p>El auge econ\u00f3mico de la d\u00e9cada de 1990 se vio impulsado por el gasto de todos los grupos de ingresos en EE.UU. (<a href=\"https:\/\/www.axios.com\/2026\/01\/22\/jobs-stock-market-rich-americans\">Aqu\u00ed hay un gr\u00e1fico \u00fatil de Emily Peck de Axios<\/a>).<\/p>\n<p>Pero hoy, como se\u00f1ala Peck, el 20% de los que m\u00e1s ganan representa un asombroso 59% del gasto de consumo. S\u00ed, esta es la <a href=\"https:\/\/www.cnn.com\/2026\/01\/14\/business\/k-shaped-economy-delta-nightcap\">econom\u00eda en forma de K<\/a>, donde a los ricos les va cada vez mejor, mientras que a los pobres les va cada vez peor. Los ricos se han vuelto tan ricos que, de hecho, su simple gasto puede hacer parecer que toda la econom\u00eda va viento en popa, incluso cuando la mayor\u00eda de la gente descubre que, de repente, los costes de productos b\u00e1sicos como la vivienda y la alimentaci\u00f3n se vuelven cada vez m\u00e1s dif\u00edciles de afrontar, y las tiendas de todo a un d\u00f3lar advierten que cada vez m\u00e1s gente se queda sin nada.<\/p>\n<p>Como hemos comentado en este bolet\u00edn, la econom\u00eda estadounidense de mediados de la d\u00e9cada de 2020 se ve impulsada por dos grandes fuerzas: los ricos gastando dinero y las empresas invirtiendo cientos de miles de millones en IA. Ambas est\u00e1n relacionadas: los ricos tienen m\u00e1s recursos, en parte, debido a su exposici\u00f3n al mercado de valores, donde el auge del gasto en IA lleva casi tres a\u00f1os.<\/p>\n<p>Entonces, \u00bfcu\u00e1l es el problema de \u201cimpulsarla a toda marcha\u201d? \u00a1Quiz\u00e1s nada! Si la IA logra que las empresas sean hipereficientes y reduce los costos de producci\u00f3n, como lo hizo internet hace 30 a\u00f1os, entonces realmente podr\u00eda tener sentido que el pr\u00f3ximo presidente de la Reserva Federal reduzca los tipos de inter\u00e9s y mantenga el flujo de capital, como han argumentado Hassett y el presidente Donald Trump.<\/p>\n<p>\u00a1Pero ojo! De entrada, existen al menos dos grandes riesgos:<\/p>\n<p><strong>1. <\/strong>Todo esto depende no solo de que la IA funcione, sino tambi\u00e9n de que la gente realmente la adopte y la utilice. Actualmente, eso no es nada seguro.<\/p>\n<p>Justo esta semana, Satya Nadella, director ejecutivo de Microsoft, advirti\u00f3 en la cumbre de Davos que la revoluci\u00f3n de la IA depende de que m\u00e1s personas realmente quieran usarla. \u201cPara que esto no sea una burbuja por definici\u00f3n, es necesario que los beneficios se distribuyan de forma mucho m\u00e1s equitativa\u201d, afirm\u00f3. Es optimista, por supuesto, porque el futuro de su empresa depende de ello, pero sus comentarios apuntan a un problema que muchos cr\u00edticos han se\u00f1alado durante a\u00f1os: que los consumidores no est\u00e1n tan entusiasmados con la tecnolog\u00eda como algunos inform\u00e1ticos y los primeros inversores.<\/p>\n<p><strong>2. <\/strong>En un mundo en forma de K, la econom\u00eda puede parecer excelente en teor\u00eda, incluso mientras la mayor\u00eda de la gente sufre. Esto ya est\u00e1 sucediendo. Trump no se equivoca cuando dice que la econom\u00eda va bien: el desempleo es bajo, el gasto se mantiene fuerte y la bolsa sigue batiendo r\u00e9cords. Pero, al igual que el expresidente Joe Biden antes que \u00e9l, Trump ha descubierto que no puede imponer la \u201casequibilidad\u201d repiti\u00e9ndola un mont\u00f3n (o descart\u00e1ndola como un enga\u00f1o). Como se\u00f1al\u00f3 mi colega <a href=\"https:\/\/www.cnn.com\/2026\/01\/20\/business\/affordability-economy-trump\">David Goldman esta semana<\/a>, la opini\u00f3n de los estadounidenses sobre la econom\u00eda estadounidense solo empezar\u00e1 a mejorar una vez que sus bolsillos se engorden.<\/p>\n<p>Y recuerden: si la IA cumple lo que prometen sus defensores, se producir\u00e1n despidos masivos a medida que las empresas reemplacen a los humanos por software. Si los tipos de inter\u00e9s ya son bajos cuando el mercado laboral se desplome, la Reserva Federal no tendr\u00e1 mucho poder para intentar enderezar el rumbo.<\/p>\n<p>En resumen: \u201cPuedes sentarte y decir que quieres \u2018impulsar el mercado\u2019, y as\u00ed puedes tener un PIB excelente y todo eso\u201d, dijo Mike O\u2019Rourke, estratega jefe de mercado de JonesTrading. \u201cPero perder\u00e1s las elecciones si la gente com\u00fan no se siente atra\u00edda por ese impulso\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay una corriente que se est\u00e1 consolidando dentro de la administraci\u00f3n Trump y en algunos sectores de Wall Street que imagina dos realidades, en cierto modo incompatibles, que se desarrollan simult\u00e1neamente: un r\u00e1pido crecimiento econ\u00f3mico y una baja inflaci\u00f3n. Es una idea tentadora: normalmente, el crecimiento r\u00e1pido genera una mayor demanda, lo que tiende a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470421","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses) - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses) - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hay una corriente que se est\u00e1 consolidando dentro de la administraci\u00f3n Trump y en algunos sectores de Wall Street que imagina dos realidades, en cierto modo incompatibles, que se desarrollan simult\u00e1neamente: un r\u00e1pido crecimiento econ\u00f3mico y una baja inflaci\u00f3n. Es una idea tentadora: normalmente, el crecimiento r\u00e1pido genera una mayor demanda, lo que tiende a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T17:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses)\",\"datePublished\":\"2026-01-23T17:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/\"},\"wordCount\":1188,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/\",\"name\":\"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses) - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-23T17:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses) - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses) - Noticias","og_description":"Hay una corriente que se est\u00e1 consolidando dentro de la administraci\u00f3n Trump y en algunos sectores de Wall Street que imagina dos realidades, en cierto modo incompatibles, que se desarrollan simult\u00e1neamente: un r\u00e1pido crecimiento econ\u00f3mico y una baja inflaci\u00f3n. Es una idea tentadora: normalmente, el crecimiento r\u00e1pido genera una mayor demanda, lo que tiende a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-23T17:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/"},"author":{"name":"","@id":""},"headline":"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses)","datePublished":"2026-01-23T17:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/"},"wordCount":1188,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/","name":"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses) - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-23T17:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/23\/economica-trump-caro-ia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses)"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/23\/economica-trump-caro-ia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La estrategia econ\u00f3mica de Trump podr\u00eda funcionar (pero les costar\u00e1 mucho a los estadounidenses)","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/23\/economica-trump-caro-ia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/23\/economica-trump-caro-ia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-23T17:03:50Z","datePublished":"2026-01-23T17:03:50Z","dateModified":"2026-01-23T17:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La estrategia econ\\u00f3mica de Trump podr\\u00eda funcionar (pero les costar\\u00e1 mucho a los estadounidenses)\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/23\\\/economica-trump-caro-ia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/23\\\/economica-trump-caro-ia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-23T17:03:50Z\",\"datePublished\":\"2026-01-23T17:03:50Z\",\"dateModified\":\"2026-01-23T17:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469639,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/29\/economia-trump-suena-mucho-como-biden-trax\/","url_meta":{"origin":1470421,"position":0},"title":"Trump de repente suena mucho como Biden en la econom\u00eda","author":"","date":"diciembre 29, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, nunca pierde la oportunidad de criticar a su predecesor sobre la econom\u00eda, alegando que el expresidente Joe Biden caus\u00f3 una crisis de inflaci\u00f3n. Pero algunas de las propuestas econ\u00f3micas de Trump est\u00e1n empezando a sonar muy parecidas a las de Biden.Al comienzo de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442775,"url":"https:\/\/noticiasya.com\/laredo\/2023\/12\/28\/analisis-la-economia-de-china-tuvo-un-ano-miserable-2024-podria-ser-aun-peor\/","url_meta":{"origin":1470421,"position":1},"title":"An\u00e1lisis: la econom\u00eda de China tuvo un a\u00f1o miserable. 2024 podr\u00eda ser a\u00fan peor","author":"","date":"diciembre 28, 2023","format":false,"excerpt":"(CNN) --\u00a0Se esperaba que la econom\u00eda china se recuperara r\u00e1pidamente en 2023 y retomara su papel de motor indiscutible del crecimiento mundial. En cambio, se estanc\u00f3 hasta el punto de que el Fondo Monetario Internacional (FMI), entre otros, lo llama un \u201clastre\u201d para la producci\u00f3n mundial. A pesar de sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467056,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/02\/planeta-errante-crecimiento-rapido-telescopio-trax\/","url_meta":{"origin":1470421,"position":2},"title":"Planeta errante tiene una tasa de crecimiento r\u00e9cord de 6.600 millones de toneladas por segundo","author":"","date":"octubre 2, 2025","format":false,"excerpt":"Astr\u00f3nomos han observado un planeta que, en algunos aspectos, se comporta m\u00e1s como una estrella, incluido un crecimiento repentino y como nunca se hab\u00eda visto en un planeta que errante.El planeta errante, que no orbita ninguna estrella, se llama Cha 1107-7626 y est\u00e1 fuera de nuestro sistema solar, a 620\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471106,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/11\/india-china-superpotencia-energia-limpia-trax\/","url_meta":{"origin":1470421,"position":3},"title":"China es la superpotencia de la energ\u00eda limpia, pero hay otro pa\u00eds que le pisa los talones (y avanza a\u00fan m\u00e1s r\u00e1pido)","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Prem Chand es uno de los muchos conductores de rickshaw \u2014como se conoce a los jinrikisha o las carretillas impulsadas por personas a pie\u2014 que pasan sus d\u00edas recorriendo las fren\u00e9ticas calles de Delhi. Y, al igual que un n\u00famero cada vez mayor de los miles de rickshaws de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468623,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/23\/tendencia-inusual-economia-preocupa-fed-trax\/","url_meta":{"origin":1470421,"position":4},"title":"Una tendencia inusual en la econom\u00eda preocupa a la Fed","author":"","date":"noviembre 23, 2025","format":false,"excerpt":"Algo en la econom\u00eda de EE.UU. no est\u00e1 cuadrando, y eso inquieta a quienes tienen la tarea de contener la inflaci\u00f3n y mantener estable el mercado laboral.Las empresas estadounidenses han reducido dr\u00e1sticamente sus contrataciones este a\u00f1o, reacias a invertir sin conocer los efectos completos de las amplias pol\u00edticas econ\u00f3micas del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466373,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/11\/economia-fase-estanflacion-prematura-trax\/","url_meta":{"origin":1470421,"position":5},"title":"La econom\u00eda de EE.UU. ha entrado en una fase de estanflaci\u00f3n prematura","author":"","date":"septiembre 11, 2025","format":false,"excerpt":"Dos informes clave publicados este jueves muestran que la econom\u00eda de Estados Unidos podr\u00eda estar en una fase de estanflaci\u00f3n prematura, un peligroso golpe doble de bajo crecimiento econ\u00f3mico y aumento de precios.Se trata de una combinaci\u00f3n particularmente problem\u00e1tica porque el bajo crecimiento econ\u00f3mico deber\u00eda, en tiempos normales, hacer que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470421"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470421\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}