{"id":1473606,"date":"2026-04-28T11:03:41","date_gmt":"2026-04-28T18:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/"},"modified":"2026-04-28T11:03:41","modified_gmt":"2026-04-28T18:03:41","slug":"juez-eeuu-acepta-licencias-pago-defensa-maduro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","title":{"rendered":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa"},"content":{"rendered":"<p>El juez Alvin K. Hellerstein, quien est\u00e1 a cargo del caso contra Nicol\u00e1s Maduro, acept\u00f3 la decisi\u00f3n del Gobierno de Estados Unidos de permitir que el Gobierno de Venezuela pague la defensa legal del derrocado presidente de Venezuela y de su esposa, la diputada Cilia Flores, quienes desde enero est\u00e1n bajo proceso penal en Nueva York.<\/p>\n<p>Mediante una orden emitida el lunes, Hellerstein informa que acepta las licencias modificadas de la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s) para que Venezuela pueda cubrir los gastos de Maduro y Flores.<\/p>\n<p>La disposici\u00f3n de la OFAC <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/25\/eeuu\/venezuela-maduro-defensa-legal-trax\">fue notificada al juez el viernes<\/a>, en una carta en la que los fiscales le explicaron que esto permitir\u00eda poner fin al que se hab\u00eda convertido en un reclamo constante de los acusados.<\/p>\n<p>Durante las \u00faltimas semanas, Maduro, Flores y sus abogados hab\u00edan se\u00f1alado que el impedimento de que Venezuela pagara los gastos de representaci\u00f3n legal <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/25\/venezuela\/abogado-maduro-ofac-eeuu-obstaculiza-defensa-orix\">obstaculizaba una defensa adecuada<\/a> porque, argumentaban, la pareja no cuenta con recursos propios para encargarse de ello.<\/p>\n<p>Por esta raz\u00f3n, hab\u00edan solicitado a las autoridades de Estados Unidos que se autorizara a Venezuela hacer estos pagos, lo que finalmente ocurri\u00f3.<\/p>\n<p>Maduro y Flores fueron capturados el 3 de enero en el operativo militar que Estados Unidos realiz\u00f3 en Caracas y otras ciudades de Venezuela. Ese mismo d\u00eda fueron trasladados a Nueva York, donde son acusados de delitos relacionados con narcoterrorismo, narcotr\u00e1fico y armas, cargos que ambos rechazan.<\/p>\n<p>En <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/26\/eeuu\/live-news\/ultima-hora-audiencia-nicolas-maduro-venezuela-noticias-reacciones-trax\">su m\u00e1s reciente audiencia, el 26 de marzo<\/a>, uno de los fiscales de Estados Unidos acus\u00f3 a la pareja de \u201csaquear\u201d a Venezuela, lo que ellos negaron. Adem\u00e1s, el juez dijo que pronto emitir\u00eda una orden sobre los pagos para la defensa de los acusados y rechaz\u00f3 desestimar el caso por ese tema.<\/p>\n<p>Afuera de la corte, se llevaron a cabo algunas manifestaciones a favor y en contra de Maduro, quien asumi\u00f3 la presidencia en 2013 tras la muerte del entonces presidente Hugo Ch\u00e1vez. Mientras algunos manifestantes exig\u00edan la libertad de Maduro, otros ped\u00edan que fuera castigado por el da\u00f1o que, dicen, hizo a su pa\u00eds.<\/p>\n<p>Tras la captura de Maduro, la vicepresidenta Delcy Rodr\u00edguez asumi\u00f3 como presidenta encargada. Desde entonces, si bien ha criticado el operativo contra Maduro, tambi\u00e9n se ha declarado dispuesta a tener una nueva relaci\u00f3n de cooperaci\u00f3n y respeto con Estados Unidos. A principios de marzo, ambos gobiernos anunciaron <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/05\/venezuela\/eeuu-reanudar-relaciones-diplomaticas-consulares-trax\">el restablecimiento de sus relaciones diplom\u00e1ticas y consulares<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El juez Alvin K. Hellerstein, quien est\u00e1 a cargo del caso contra Nicol\u00e1s Maduro, acept\u00f3 la decisi\u00f3n del Gobierno de Estados Unidos de permitir que el Gobierno de Venezuela pague la defensa legal del derrocado presidente de Venezuela y de su esposa, la diputada Cilia Flores, quienes desde enero est\u00e1n bajo proceso penal en Nueva [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473606","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa - Noticias\" \/>\n<meta property=\"og:description\" content=\"El juez Alvin K. Hellerstein, quien est\u00e1 a cargo del caso contra Nicol\u00e1s Maduro, acept\u00f3 la decisi\u00f3n del Gobierno de Estados Unidos de permitir que el Gobierno de Venezuela pague la defensa legal del derrocado presidente de Venezuela y de su esposa, la diputada Cilia Flores, quienes desde enero est\u00e1n bajo proceso penal en Nueva [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-28T18:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa\",\"datePublished\":\"2026-04-28T18:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/\"},\"wordCount\":468,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/\",\"name\":\"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-28T18:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa - Noticias","og_description":"El juez Alvin K. Hellerstein, quien est\u00e1 a cargo del caso contra Nicol\u00e1s Maduro, acept\u00f3 la decisi\u00f3n del Gobierno de Estados Unidos de permitir que el Gobierno de Venezuela pague la defensa legal del derrocado presidente de Venezuela y de su esposa, la diputada Cilia Flores, quienes desde enero est\u00e1n bajo proceso penal en Nueva [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-28T18:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/"},"author":{"name":"","@id":""},"headline":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa","datePublished":"2026-04-28T18:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/"},"wordCount":468,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","name":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-28T18:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa","url":"http:\/\/noticiasya.com\/laredo\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-28T18:03:41Z","datePublished":"2026-04-28T18:03:41Z","dateModified":"2026-04-28T18:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/04\\\/28\\\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/04\\\/28\\\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-28T18:03:41Z\",\"datePublished\":\"2026-04-28T18:03:41Z\",\"dateModified\":\"2026-04-28T18:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471661,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/25\/abogado-maduro-ofac-eeuu-obstaculiza-defensa-orix\/","url_meta":{"origin":1473606,"position":0},"title":"EE.UU. impide que el Gobierno de Venezuela pague por la defensa legal de Maduro, dice su abogado","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Barry J. Pollack, abogado del derrocado presidente de Venezuela, Nicol\u00e1s Maduro, acus\u00f3 a la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s) de obstaculizar la defensa de su cliente, al no conceder una licencia que permitir\u00eda al gobierno venezolano pagar por estos servicios legales.En una carta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472196,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/14\/fiscales-extraordinaria-solicitud-maduro-honorarios-legales-trax\/","url_meta":{"origin":1473606,"position":1},"title":"Fiscales califican de &#171;extraordinaria&#187; la solicitud de Maduro de que Venezuela pague su defensa legal","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Fiscales federales de Estados Unidos afirmaron que un juez deber\u00eda denegar la solicitud del presidente derrocado de Venezuela, Nicol\u00e1s Maduro, de desestimar los cargos de narcoterrorismo, alegando que el Gobierno estadounidense ha obstaculizado su derecho a la defensa.El mes pasado, los abogados de Maduro y su esposa, Cilia Flores, quienes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473497,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/25\/venezuela-maduro-defensa-legal-trax\/","url_meta":{"origin":1473606,"position":2},"title":"EE.UU. acepta que el Gobierno de Venezuela pague por la defensa de Maduro, lo que pone fin a la disputa legal","author":"","date":"abril 25, 2026","format":false,"excerpt":"Estados Unidos acept\u00f3 permitir que el Gobierno de Venezuela financie la defensa del presidente derrocado Nicol\u00e1s Maduro, lo que pone fin a un enfrentamiento legal.En una carta presentada a \u00faltima hora del viernes por la noche, los fiscales federales informaron al juez que supervisa el caso que el Departamento del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472621,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/27\/juez-hellerstein-maduro-flores-orix\/","url_meta":{"origin":1473606,"position":3},"title":"\u00bfQu\u00e9 le espera a Maduro y Flores en su proceso legal de ahora en m\u00e1s? El juez Hellerstein dio varias pistas","author":"","date":"marzo 27, 2026","format":false,"excerpt":"\u201c\u00bfCu\u00e1l es la alternativa entonces?\u201dLa recurrente pregunta del juez Alvin Hellerstein desde su estrado, entre frecuentes sorbos de agua, tanto al fiscal adjunto Kyle Adam Wirshba como al abogado de Nicol\u00e1s Maduro, Barry Pollack, indica cu\u00e1nto valora la justicia de Estados Unidos la posibilidad de que un acusado, as\u00ed sea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472397,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/20\/nicolas-maduro-cilia-flores-intensifican-ofensiva-legal-ee-uu-orix\/","url_meta":{"origin":1473606,"position":4},"title":"Abogados de Nicol\u00e1s Maduro y Cilia Flores insisten en que se desestime el caso en su contra en Nueva York","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Los abogados de Nicol\u00e1s Maduro y su esposa, Cilia Flores, presentaron el jueves una nueva moci\u00f3n ante la corte federal de Nueva York en la que insisten en que se desestimen los cargos de narcoterrorismo y cuestionan directamente los argumentos del Gobierno de Estados Unidos en el caso, a menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471866,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/04\/cilia-flores-nicolas-maduro-venezuela-desestimar-cargos-eeuu-orix\/","url_meta":{"origin":1473606,"position":5},"title":"Cilia Flores, esposa de Nicol\u00e1s Maduro, pide unirse a solicitud para desestimar cargos de narcoterrorismo en EE.UU.","author":"","date":"marzo 4, 2026","format":false,"excerpt":"La esposa del derrocado presidente de Venezuela, Cilia Flores de Maduro, pidi\u00f3 a un juez federal en Nueva York que le permita sumarse a la ofensiva legal de Nicol\u00e1s Maduro para desestimar la acusaci\u00f3n penal que ambos enfrentan en Estados Unidos.En documentos presentados ante la corte este martes, los abogados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1473606"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473606\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1473606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1473606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1473606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}