{"id":1473627,"date":"2026-04-29T05:03:46","date_gmt":"2026-04-29T12:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/"},"modified":"2026-04-29T05:03:46","modified_gmt":"2026-04-29T12:03:46","slug":"zorro-django-pelicula-comic-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/","title":{"rendered":"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic"},"content":{"rendered":"<p>Uno de los cruces o \u201ccrossovers\u201d m\u00e1s famosos de los comics ser\u00e1 llevado al cine: seg\u00fan un reporte de <a href=\"https:\/\/variety.com\/2026\/film\/news\/django-zorro-movie-revived-sony-quentin-tarantino-1236731586\/\">Variety<\/a>, Brian Helgeland escribir\u00e1 el guion de una pel\u00edcula basada en la popular historieta del Zorro y Django.<\/p>\n<p>El Zorro es el popular h\u00e9roe enmascarado creado por el escritor Johnston McCulley en 1919, que, desde su aparici\u00f3n como personaje literario, dio el salto al cine y a la TV en decenas de t\u00edtulos, siendo el m\u00e1s reciente la <a href=\"https:\/\/cnnespanol.cnn.com\/video\/zorro-series-estreno-trailer-miguel-bernardeau-showbiz\">serie de Prime Video<\/a> de 2024 protagonizada por el espa\u00f1ol Miguel Bernardeau.<\/p>\n<p>Y Django es un personaje de pel\u00edculas de vaqueros que apareci\u00f3 por primera vez en el western italiano \u201cDjango\u201d en 1966, pero que es recordado por la pel\u00edcula \u201cDjango Unchained\u201d, de 2012, dirigida por Quentin Tarantino y protagonizada por Jamie Foxx en el papel principal.<\/p>\n<p>La nueva pel\u00edcula estar\u00e1 basada en el c\u00f3mic \u201cDjango Zorro\u201d de 2014, cocreado por Quentin Tarantino junto con Matt Wagner. Se desconocen los detalles de la trama, aunque de seguro mantendr\u00e1 la premisa de la historieta, en la que el cazarrecompensas Django forma una alianza con el justiciero enmascarado Zorro en la California del siglo XIX.<\/p>\n<p>El reporte de Variety no menciona si Foxx volver\u00e1 a interpretar a Django en esta adaptaci\u00f3n ni si Antonio Banderas volver\u00e1 a encarnar al Zorro, personaje al que dio vida en dos pel\u00edculas, \u201cThe Mask of Zorro\u201d (1998) y \u201cThe Legend of Zorro\u201d (2005).<\/p>\n<p>Sony Pictures, a cargo del proyecto, no ha anunciado qui\u00e9n ser\u00e1 el director de la pel\u00edcula, que cuenta con la aprobaci\u00f3n de Tarantino, seg\u00fan un reporte del sitio web de cine <a href=\"https:\/\/theplaylist.net\/django-zorro-crossover-film-at-sony-update-20260427\/?utm_source=theplaylist.beehiiv.com&#038;utm_medium=newsletter&#038;utm_campaign=james-gunn-shelves-the-authority-django-zorro-crossover-movie-in-the-works-house-of-the-dragon-season-3-teaser&#038;_bhlid=e231243415e6c30050928f6eafc4d42a28385b8d\">The Playlist<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los cruces o \u201ccrossovers\u201d m\u00e1s famosos de los comics ser\u00e1 llevado al cine: seg\u00fan un reporte de Variety, Brian Helgeland escribir\u00e1 el guion de una pel\u00edcula basada en la popular historieta del Zorro y Django. El Zorro es el popular h\u00e9roe enmascarado creado por el escritor Johnston McCulley en 1919, que, desde su [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473627","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic - Noticias\" \/>\n<meta property=\"og:description\" content=\"Uno de los cruces o \u201ccrossovers\u201d m\u00e1s famosos de los comics ser\u00e1 llevado al cine: seg\u00fan un reporte de Variety, Brian Helgeland escribir\u00e1 el guion de una pel\u00edcula basada en la popular historieta del Zorro y Django. El Zorro es el popular h\u00e9roe enmascarado creado por el escritor Johnston McCulley en 1919, que, desde su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-29T12:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic\",\"datePublished\":\"2026-04-29T12:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/\",\"name\":\"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-29T12:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic - Noticias","og_description":"Uno de los cruces o \u201ccrossovers\u201d m\u00e1s famosos de los comics ser\u00e1 llevado al cine: seg\u00fan un reporte de Variety, Brian Helgeland escribir\u00e1 el guion de una pel\u00edcula basada en la popular historieta del Zorro y Django. El Zorro es el popular h\u00e9roe enmascarado creado por el escritor Johnston McCulley en 1919, que, desde su [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-29T12:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/"},"author":{"name":"","@id":""},"headline":"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic","datePublished":"2026-04-29T12:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/","name":"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-29T12:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Zorro y Django juntos: hay reportes sobre una nueva pel\u00edcula basada en el popular c\u00f3mic","url":"http:\/\/noticiasya.com\/laredo\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/04\/29\/zorro-django-pelicula-comic-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-29T12:03:46Z","datePublished":"2026-04-29T12:03:46Z","dateModified":"2026-04-29T12:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Zorro y Django juntos: hay reportes sobre una nueva pel\\u00edcula basada en el popular c\\u00f3mic\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/04\\\/29\\\/zorro-django-pelicula-comic-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/04\\\/29\\\/zorro-django-pelicula-comic-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-29T12:03:46Z\",\"datePublished\":\"2026-04-29T12:03:46Z\",\"dateModified\":\"2026-04-29T12:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473662,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/30\/5-cosas-30-abril-orix\/","url_meta":{"origin":1473627,"position":0},"title":"Las 5 cosas que debes saber este 30 de abril","author":"","date":"abril 30, 2026","format":false,"excerpt":"El Cangrejo, el hombre en Cuba con quien el Gobierno de Trump habla. Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico. James Comey se entrega. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465681,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/20\/quentin-tarantino-revela-mejor-pelicula-trax\/","url_meta":{"origin":1473627,"position":1},"title":"Quentin Tarantino revela cu\u00e1l es su &#171;mejor&#187; pel\u00edcula","author":"","date":"agosto 20, 2025","format":false,"excerpt":"El cineasta de Hollywood Quentin Tarantino revel\u00f3 cu\u00e1l de sus pel\u00edculas cree que es la mejor, y probablemente no es la que esperar\u00edas.El director estadounidense tiene dos premios de la Academia a su nombre: uno por el guion de \u201cPulp Fiction\u201d en 1994 y otro por el guion de \u201cDjango\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465562,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/16\/2025-mejores-peliculas-terror-weapons-orix\/","url_meta":{"origin":1473627,"position":2},"title":"2025 est\u00e1 siendo un gran a\u00f1o para el cine de terror: las mejores pel\u00edculas que se han estrenado","author":"","date":"agosto 16, 2025","format":false,"excerpt":"En Hollywood, los gustos cambian con los a\u00f1os. Ya los westerns y los musicales no dominan las carteleras, desplazados recientemente por pel\u00edculas de superh\u00e9roes. Pero un g\u00e9nero parece resistir las modas: el cine de terror, siempre reinvent\u00e1ndose desde los monstruos cl\u00e1sicos como \u201cFrankenstein\u201d y \u201cDr\u00e1cula\u201d en la d\u00e9cada de 1930\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467872,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/30\/hello-kitty-pelicula-2028-orix\/","url_meta":{"origin":1473627,"position":3},"title":"Hello Kitty tendr\u00e1 su propia pel\u00edcula en 2028","author":"","date":"octubre 30, 2025","format":false,"excerpt":"Warner Bros. anunci\u00f3 este jueves que producir\u00e1 una pel\u00edcula basada en Hello Kitty, el popular personaje de la marca japonesa Sanrio creado por el dise\u00f1ador Yuko Shimizu en 1974. (Warner Bros. es parte de la corporaci\u00f3n Warner Bros. Discovery, de la que tambi\u00e9n forma parte CNN en Espa\u00f1ol).El anuncio fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469904,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/08\/cine-2026-superheroes-secuelas-the-odyssey-trax\/","url_meta":{"origin":1473627,"position":4},"title":"El cine que se viene en 2026: superh\u00e9roes, secuelas y &#171;The Odyssey&#187;","author":"","date":"enero 8, 2026","format":false,"excerpt":"El siempre amenazado cine est\u00e1 haciendo otro fuerte intento por atraer la asistencia a las salas de los espectadores en 2026.Muchas de las pel\u00edculas m\u00e1s esperadas del a\u00f1o son, como era de esperarse, secuelas o actualizaciones de material previamente querido, aunque tambi\u00e9n hay algunas propuestas frescas para equilibrar la oferta.Aqu\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449619,"url":"https:\/\/noticiasya.com\/laredo\/2024\/05\/21\/the-apprentice-pelicula-negocios-trump-aplausos-polemica-festival-cine-cannes-trax\/","url_meta":{"origin":1473627,"position":5},"title":"&#171;El Apprentice&#187;, una pel\u00edcula sobre los negocios de Trump, se estrena entre aplausos y pol\u00e9mica en el Festival de Cine de Cannes","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) -- \"The Apprentice\", una nueva pel\u00edcula sobre los negocios inmobiliarios del expresidente Donald Trump en Nueva York en los a\u00f1os 80, se estren\u00f3 con una gran ovaci\u00f3n en el Festival de Cannes y cr\u00edticas por parte de su campa\u00f1a.La pel\u00edcula sobre el posible candidato republicano para la presidencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1473627"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473627\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1473627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1473627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1473627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}