{"id":1473682,"date":"2026-04-30T13:03:38","date_gmt":"2026-04-30T20:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/"},"modified":"2026-04-30T13:03:38","modified_gmt":"2026-04-30T20:03:38","slug":"trump-amenaza-retirar-soldados-alemania-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","title":{"rendered":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n"},"content":{"rendered":"<p>Una disputa entre Estados Unidos y Alemania ha alcanzado nuevos niveles, con el presidente de EE.UU., Donald Trump, amenazando con retirar algunos soldados estadounidenses del pa\u00eds en medio de desacuerdos sobre la campa\u00f1a liderada por Estados Unidos en Ir\u00e1n.<\/p>\n<p>\u201cEstados Unidos est\u00e1 estudiando y revisando la posible reducci\u00f3n de efectivos en Alemania, y se tomar\u00e1 una determinaci\u00f3n en el pr\u00f3ximo corto per\u00edodo de tiempo\u201d, escribi\u00f3 Trump en su plataforma Truth Social la noche del mi\u00e9rcoles.<\/p>\n<p>Esto ocurre mientras Berl\u00edn y Washington han estado enfrentados por el enfoque de Estados Unidos respecto a la guerra con Ir\u00e1n. El canciller alem\u00e1n Friedrich Merz provoc\u00f3 la ira de Trump esta semana por comentarios que hizo el lunes, en los que dijo que Estados Unidos estaba siendo \u201chumillado\u201d por Ir\u00e1n y critic\u00f3 al Gobierno por no tener una estrategia eficaz para poner fin a la guerra.<\/p>\n<p>Hay 36.436 militares estadounidenses en servicio activo estacionados permanentemente en Alemania, seg\u00fan datos del Centro de Datos de Personal del Departamento de Defensa de Estados Unidos (DMDC, por sus siglas en ingl\u00e9s) publicados en diciembre de 2025, una cifra notablemente m\u00e1s alta que en otros pa\u00edses europeos. Trump ya hab\u00eda amenazado con reducir el n\u00famero de tropas en el pa\u00eds en 2020, durante su primer mandato y mientras Angela Merkel ocupaba la canciller\u00eda alemana.<\/p>\n<p>La fricci\u00f3n entre los l\u00edderes europeos y el Gobierno de Trump se ha intensificado debido a la guerra entre Estados Unidos e Israel, que Estados Unidos lanz\u00f3 sin notificar a la mayor\u00eda de los aliados de la OTAN. Alemania fue informada con antelaci\u00f3n de los ataques iniciales, dijo un portavoz del Gobierno a The Associated Press. Los pa\u00edses europeos se han negado a involucrarse directamente en el conflicto y, en su lugar, han subrayado la importancia de encontrar una soluci\u00f3n diplom\u00e1tica. Trump, a su vez, ha amenazado con reconsiderar la pertenencia de Estados Unidos a la OTAN y se ha referido a la alianza militar como un \u201ctigre de papel\u201d.<\/p>\n<p>Al igual que algunos otros pa\u00edses europeos, Alemania ha ofrecido un apoyo militar limitado a Estados Unidos, en particular permitiendo el uso de su infraestructura militar, como bases a\u00e9reas, para operaciones relacionadas con el conflicto, aunque no ha permitido que estas se utilicen como plataformas para ataques ofensivos directos.<\/p>\n<p>Merz tambi\u00e9n ha prometido m\u00e1s ayuda alemana con la condici\u00f3n de que el conflicto pase a una fase de posguerra. Esto podr\u00eda incluir la participaci\u00f3n en una posible misi\u00f3n internacional de estabilizaci\u00f3n.<\/p>\n<p>Con ese fin, Berl\u00edn anunci\u00f3 recientemente que se desplegar\u00e1 un dragaminas naval en el mar Mediterr\u00e1neo en preparaci\u00f3n para los esfuerzos por reabrir el estrecho de Ormuz, una vez que se alcance un fin duradero de las hostilidades. Esta medida sigui\u00f3 a los llamados de Trump para que los aliados env\u00eden buques de guerra y dragaminas para ayudar a asegurar el estrecho. Alemania forma parte de una coalici\u00f3n liderada por Gran Breta\u00f1a y Francia que busca garantizar el paso seguro de los buques por esta crucial v\u00eda mar\u00edtima. Sin embargo, estas acciones no han logrado satisfacer a Trump.<\/p>\n<p>La actitud de Merz hacia la guerra tambi\u00e9n ha cambiado. En las horas posteriores al inicio de la campa\u00f1a, insisti\u00f3 en que \u201ceste no es el momento de dar lecciones a los aliados\u201d. Su tono cambi\u00f3 tras una visita a Estados Unidos en marzo, cuando dijo que no pod\u00eda \u201cver ninguna estrategia clara\u201d.<\/p>\n<p>El desacuerdo entre Berl\u00edn y Washington se profundiz\u00f3 a\u00fan m\u00e1s el lunes, cuando Merz critic\u00f3 duramente los intentos de Estados Unidos de desvincularse de una guerra en la que entr\u00f3 sin establecer objetivos claros.<\/p>\n<p>\u201cTodo el asunto est\u00e1 mal concebido, por decir lo menos\u201d, dijo, al tiempo que enfatiz\u00f3 el deseo de Berl\u00edn de que la guerra termine lo antes posible. \u201cEn este momento, no puedo ver qu\u00e9 salida estrat\u00e9gica est\u00e1n optando ahora los estadounidenses\u201d.<\/p>\n<p>El martes, Trump arremeti\u00f3 directamente contra Merz en una publicaci\u00f3n en Truth Social, escribiendo: \u201cel Canciller de Alemania, Friedrich Merz, cree que est\u00e1 bien que Ir\u00e1n tenga un arma nuclear. \u00a1No sabe de lo que est\u00e1 hablando!\u201d<\/p>\n<p>Continu\u00f3: \u201c\u00a1No es de extra\u00f1ar que Alemania est\u00e9 yendo tan mal, tanto econ\u00f3micamente como en otros aspectos!\u201d<\/p>\n<p>Merz, al igual que otros aliados europeos, ha reconocido anteriormente la amenaza que representa Teher\u00e1n y ha sostenido que Ir\u00e1n no debe poseer armas nucleares.<\/p>\n<p>El canciller alem\u00e1n ha intentado posteriormente restar importancia a la disputa con su hom\u00f3logo estadounidense y adoptar un tono m\u00e1s conciliador, insistiendo el mi\u00e9rcoles en que su relaci\u00f3n con Trump es \u201cbuena\u201d.<\/p>\n<p>\u201cDesde mi perspectiva, mi relaci\u00f3n personal con el presidente de Estados Unidos sigue siendo buena\u201d, dijo Merz a los periodistas, al tiempo que destac\u00f3 el impacto negativo que la guerra est\u00e1 teniendo en la econom\u00eda de Alemania y en sus suministros energ\u00e9ticos.<\/p>\n<p>El jueves, tras el anuncio de Trump de que podr\u00eda retirar a algunos soldados de Alemania, Merz reiter\u00f3 de nuevo cu\u00e1n importante es para Berl\u00edn la alianza transatl\u00e1ntica.<\/p>\n<p>\u201cComo saben, esta asociaci\u00f3n transatl\u00e1ntica nos llega especialmente al coraz\u00f3n \u2014y a m\u00ed personalmente\u201d, dijo a los periodistas en una base militar en M\u00fcnster.<\/p>\n<p>Desde el regreso de Trump al cargo, los funcionarios alemanes hab\u00edan logrado en gran medida mantenerse fuera de su l\u00ednea de fuego y evitar las cr\u00edticas mordaces dirigidas a muchos otros aliados tradicionales. En medio de las recientes repercusiones, esto parece haber cambiado dr\u00e1sticamente.<\/p>\n<p>Lizzie McBride e Issy Ronald, de CNN, contribuyeron a este reportaje.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una disputa entre Estados Unidos y Alemania ha alcanzado nuevos niveles, con el presidente de EE.UU., Donald Trump, amenazando con retirar algunos soldados estadounidenses del pa\u00eds en medio de desacuerdos sobre la campa\u00f1a liderada por Estados Unidos en Ir\u00e1n. \u201cEstados Unidos est\u00e1 estudiando y revisando la posible reducci\u00f3n de efectivos en Alemania, y se tomar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473682","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una disputa entre Estados Unidos y Alemania ha alcanzado nuevos niveles, con el presidente de EE.UU., Donald Trump, amenazando con retirar algunos soldados estadounidenses del pa\u00eds en medio de desacuerdos sobre la campa\u00f1a liderada por Estados Unidos en Ir\u00e1n. \u201cEstados Unidos est\u00e1 estudiando y revisando la posible reducci\u00f3n de efectivos en Alemania, y se tomar\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T20:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n\",\"datePublished\":\"2026-04-30T20:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/\"},\"wordCount\":1005,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/\",\"name\":\"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-30T20:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n - Noticias","og_description":"Una disputa entre Estados Unidos y Alemania ha alcanzado nuevos niveles, con el presidente de EE.UU., Donald Trump, amenazando con retirar algunos soldados estadounidenses del pa\u00eds en medio de desacuerdos sobre la campa\u00f1a liderada por Estados Unidos en Ir\u00e1n. \u201cEstados Unidos est\u00e1 estudiando y revisando la posible reducci\u00f3n de efectivos en Alemania, y se tomar\u00e1 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-30T20:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/"},"author":{"name":"","@id":""},"headline":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n","datePublished":"2026-04-30T20:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/"},"wordCount":1005,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","name":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-30T20:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n","url":"http:\/\/noticiasya.com\/laredo\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-30T20:03:38Z","datePublished":"2026-04-30T20:03:38Z","dateModified":"2026-04-30T20:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/04\\\/30\\\/trump-amenaza-retirar-soldados-alemania-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/04\\\/30\\\/trump-amenaza-retirar-soldados-alemania-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-30T20:03:38Z\",\"datePublished\":\"2026-04-30T20:03:38Z\",\"dateModified\":\"2026-04-30T20:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473756,"url":"https:\/\/noticiasya.com\/laredo\/2026\/05\/03\/trump-soldados-alemania-europa-crisis-trax\/","url_meta":{"origin":1473682,"position":0},"title":"La p\u00e9rdida de 5.000 soldados estadounidenses en Alemania es solo la punta del iceberg del desaf\u00edo al que se enfrenta Europa","author":"","date":"mayo 3, 2026","format":false,"excerpt":"Pr\u00e1cticamente no pasa una semana sin que surja alguna nueva disputa entre la administraci\u00f3n de Trump y Europa.Pero en un a\u00f1o marcado por una importante disputa sobre aranceles, la amenaza del presidente de Estados Unidos, Donald Trump, de anexionarse Groenlandia y desacuerdos sobre la ayuda a Ucrania, la amenaza m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444395,"url":"https:\/\/noticiasya.com\/laredo\/2024\/01\/25\/ee-uu-e-iran-se-acercan-peligrosamente-a-un-enfrentamiento-en-medio-oriente-mira-donde-opera-cada-uno\/","url_meta":{"origin":1473682,"position":1},"title":"EE.UU. e Ir\u00e1n se acercan peligrosamente a un enfrentamiento en Medio Oriente. Mira d\u00f3nde opera cada uno","author":"","date":"enero 25, 2024","format":false,"excerpt":"Abu Dhabi, Emiratos \u00c1rabes Unidos (CNN) -- La guerra entre Israel y Hamas ya se ha extendido a todo el Medio Oriente, y las perspectivas de un enfrentamiento entre las potencias regionales y mundiales son cada vez m\u00e1s probables.Los combates en el Medio Oriente se han limitado en gran medida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472078,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/10\/analisis-estados-unidos-iran-guerras-diferentes-trax\/","url_meta":{"origin":1473682,"position":2},"title":"Por qu\u00e9 Estados Unidos e Ir\u00e1n libran dos guerras diferentes","author":"","date":"marzo 10, 2026","format":false,"excerpt":"Los principales asesores del presidente Donald Trump ya est\u00e1n preparando un relato de victoria en Ir\u00e1n para el inevitable d\u00eda en que intente liberarse de la guerra.La Casa Blanca est\u00e1 imaginando un escenario surrealista en el que \u00e9l personalmente certificar\u00e1 una rendici\u00f3n incondicional de la Rep\u00fablica Isl\u00e1mica, incluso si no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473721,"url":"https:\/\/noticiasya.com\/laredo\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/","url_meta":{"origin":1473682,"position":3},"title":"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n","author":"","date":"mayo 1, 2026","format":false,"excerpt":"El Pent\u00e1gono dijo este viernes que EE.UU. retirar\u00e1 aproximadamente 5.000 soldados de Alemania durante el pr\u00f3ximo a\u00f1o.La medida, que se produce despu\u00e9s de que el presidente Donald Trump arremetiera contra el canciller alem\u00e1n por sus cr\u00edticas a la guerra de EE.UU. con Ir\u00e1n, a\u00fan dejar\u00eda a m\u00e1s de 30.000 efectivos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471957,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/06\/bases-eeuu-rota-moron-espana-orix\/","url_meta":{"origin":1473682,"position":4},"title":"Estas son las bases de EE.UU. en Espa\u00f1a en medio del conflicto entre Trump y S\u00e1nchez","author":"","date":"marzo 6, 2026","format":false,"excerpt":"El conflicto b\u00e9lico iniciado el s\u00e1bado por EE.UU e Israel contra Ir\u00e1n no genera tensi\u00f3n solo en Medio Oriente: tambi\u00e9n ha provocado repercusiones en todo el mundo, e incluso entre aliados, a medida que los pa\u00edses adoptan una u otra posici\u00f3n, o intentan mantenerse al margen.El \u00faltimo actor en sumarse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473041,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/10\/trump-otan-apoyo-estadounidenses-iran-analisis-trax\/","url_meta":{"origin":1473682,"position":5},"title":"Trump amenaza a la OTAN por Ir\u00e1n, pero las encuestas apoyan m\u00e1s a la alianza que a la guerra","author":"","date":"abril 10, 2026","format":false,"excerpt":"Por segunda vez en el todav\u00eda bastante joven a\u00f1o calendario 2026, el presidente Donald Trump amenaza con dinamitar la Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte (OTAN, por sus siglas en ingl\u00e9s), que es vista de manera favorable por los estadounidenses, por una aventura de pol\u00edtica exterior que, definitivamente, no respaldan.Primero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1473682"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473682\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1473682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1473682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1473682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}