{"id":1473708,"date":"2026-05-01T07:03:47","date_gmt":"2026-05-01T14:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/"},"modified":"2026-05-01T07:03:47","modified_gmt":"2026-05-01T14:03:47","slug":"analisis-tmec-cia-rocha-eeuu-sheinbaum-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","title":{"rendered":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa"},"content":{"rendered":"<p>Con la renegociaci\u00f3n del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 en puerta, el Gobierno de la presidenta mexicana, Claudia Sheinbaum, ya ten\u00eda un desaf\u00edo este a\u00f1o en su relaci\u00f3n con la administraci\u00f3n de su hom\u00f3logo estadounidense, Donald Trump. Sin embargo, el panorama se le ha complicado m\u00e1s en solo unas cuantas semanas, debido a la entrada al juego de otro factor que con frecuencia genera tensiones entre ambos pa\u00edses: la seguridad y el combate al crimen.<\/p>\n<p>El primer hecho que abri\u00f3 otro frente para el Gobierno de Sheinbaum fue la revelaci\u00f3n sobre la presencia de agentes de la Agencia Central de Inteligencia de Estados Unidos (CIA, por sus siglas en ingl\u00e9s) durante un operativo en el estado de Chihuahua, en el norte de M\u00e9xico, para desmantelar laboratorios clandestinos de drogas.<\/p>\n<p>La Fiscal\u00eda de Chihuahua <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/19\/mexico\/mueren-instructores-embajada-eeuu-agentes-mexicanos-accidente-operativo-antidrogas-chihuahua-orix\">inform\u00f3 el 19 de abril<\/a> que dos estadounidenses, a quienes identific\u00f3 como instructores de la Embajada de ese pa\u00eds, murieron junto con dos funcionarios mexicanos en un accidente automovil\u00edstico cuando regresaban de esa operaci\u00f3n antidrogas en el municipio de Morelos.<\/p>\n<p>CNN y otros medios confirmaron d\u00edas despu\u00e9s que los fallecidos <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/eeuu\/estadounidenses-muertos-chihuahua-mexico-cia-orix\">eran dos agentes de la CIA<\/a> que trabajaban con autoridades mexicanas en operaciones contra el narcotr\u00e1fico.<\/p>\n<p>Desde que se dio a conocer la muerte de estas personas, Sheinbaum lament\u00f3 lo sucedido pero, al mismo tiempo, dijo que su Gobierno <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/20\/mexico\/sheinbaum-operativo-chihuahua-muerte-agentes-eeuu-orix\">no estaba enterado<\/a> de su presencia en territorio mexicano y reclam\u00f3 al Gobierno de Chihuahua por la situaci\u00f3n. Incluso, se\u00f1al\u00f3 que debe investigarse si hubo una posible violaci\u00f3n a la Ley de Seguridad Nacional, que establece l\u00edmites a la cooperaci\u00f3n entre funcionarios mexicanos e instancias internacionales.<\/p>\n<p>Pero no solo eso. Sheinbaum tambi\u00e9n asegur\u00f3 que pedir\u00eda explicaciones al embajador de Estados Unidos, Ronald Johnson, e insisti\u00f3 en que su Gobierno no tolerar\u00e1 vulneraciones a la soberan\u00eda de M\u00e9xico.<\/p>\n<p>Jos\u00e9 Luis Vald\u00e9s Ugalde, acad\u00e9mico del Centro de Investigaciones sobre Am\u00e9rica del Norte de la Universidad Nacional Aut\u00f3noma de M\u00e9xico, dijo a CNN que este episodio apunta cuando menos a dos escenarios. El primero, que el Gobierno de Chihuahua probablemente ten\u00eda trato directo con los agentes de la CIA, aunque la gobernadora Mar\u00eda Eugenia Campos lo niegue. El segundo, que algunas autoridades de Estados Unidos desconf\u00edan del Gobierno de M\u00e9xico.<\/p>\n<p>\u201cEso de que lo hayan hecho por la esquina, por el lado chihuahuense, estatalmente hablando, sin necesidad de recurrir al Gobierno federal, habla de la muy mala relaci\u00f3n que M\u00e9xico tiene con Estados Unidos en t\u00e9rminos de los grupos de inteligencia que participan en los operativos o no participan en los operativos mexicanos en contra de los c\u00e1rteles\u201d, expuso.<\/p>\n<p>A la fecha, tanto la Fiscal\u00eda General de la Rep\u00fablica (FGR) como la Fiscal\u00eda de Chihuahua <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/28\/mexico\/chihuahua-agentes-cia-informe-oficial-orix\">tienen investigaciones abiertas<\/a> para determinar bajo qu\u00e9 par\u00e1metros se produjo la presencia de los agentes de la CIA en el pa\u00eds.<\/p>\n<p>A las tensiones causadas por la presencia de agentes de la CIA se sum\u00f3 otro elemento esta semana.<\/p>\n<p>El Departamento de Justicia de Estados Unidos public\u00f3 este mi\u00e9rcoles <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/29\/mexico\/acusacion-gobernador-sinaloa-ruben-rocha-orix\">una acusaci\u00f3n formal en contra del gobernador del estado de Sinaloa, Rub\u00e9n Rocha<\/a>, as\u00ed como de otros nueve funcionarios y exfuncionarios, a quienes atribuye delitos de narcotr\u00e1fico y armas por su presunta alianza con el Cartel de Sinaloa para traficar drogas a territorio estadounidense. Rocha y los dem\u00e1s implicados rechazan los cargos.<\/p>\n<p>Las acusaciones contra Rocha representan un duro golpe no solo para \u00e9l, sino tambi\u00e9n para Sheinbaum y el oficialista partido Morena, al que ambos pertenecen. La propia presidenta encar\u00f3 la situaci\u00f3n este jueves, cuando en su conferencia de prensa diaria se\u00f1al\u00f3 que la FGR revisar\u00e1 las solicitudes de detenci\u00f3n con fines de extradici\u00f3n enviadas por Estados Unidos y actuar\u00e1 contra Rocha <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/30\/mexico\/sheinbaum-acusacion-gobernador-sinaloa-eeuu-pruebas-orix\">solo si considera que hay evidencia suficiente para ello<\/a>.<\/p>\n<p>\u201cNosotros no vamos a cubrir a nadie que haya cometido un delito. Sin embargo, si no existen pruebas claras, es evidente que el objetivo de estas imputaciones por parte del Departamento de Justicia es pol\u00edtico. Debe quedar sumamente claro: bajo ning\u00fan motivo vamos a permitir la intromisi\u00f3n o injerencia de un Gobierno extranjero en las decisiones que le competen exclusivamente al pueblo de M\u00e9xico\u201d, dijo.<\/p>\n<p>Analistas consultados consideran que las acusaciones contra Rocha representan un incremento de la presi\u00f3n de Trump hacia Sheinbaum en materia de seguridad y plantean una disyuntiva a la mandataria: ignorar los se\u00f1alamientos del Departamento de Justicia o respaldar un eventual proceso penal contra el gobernador.<\/p>\n<p>\u201cEsto pone a la administraci\u00f3n de Sheinbaum frente a una atadura. Si act\u00faa contra la acusaci\u00f3n y deja que Rocha siga en el cargo y no act\u00faa para extraditarlo a Estados Unidos, Estados Unidos se molestar\u00e1 y esto podr\u00eda influir en las negociaciones sobre el T-MEC, que la administraci\u00f3n de Trump al menos impl\u00edcitamente liga a mejoras en seguridad y cooperaci\u00f3n anticrimen\u201d, dijo Vanda Felbab-Brown, acad\u00e9mica de Brookings Institution especializada en pol\u00edtica exterior y crimen organizado.<\/p>\n<p>\u201cPor otro lado, si Sheinbaum act\u00faa a partir de la acusaci\u00f3n y pone presi\u00f3n sobre Rocha para que deje el cargo, esto complicar\u00eda su relaci\u00f3n con Morena, en especial con las fracciones cercanas al expresidente Andr\u00e9s Manuel L\u00f3pez Obrador\u201d, agreg\u00f3.<\/p>\n<p>X\u00f3chtil Pimienta, profesora de Relaciones Internacionales del Tecnol\u00f3gico de Monterrey, coincidi\u00f3 en que Sheinbaum enfrenta \u201cuna situaci\u00f3n muy compleja\u201d porque no puede pasar por alto una acusaci\u00f3n de este nivel, pero tampoco puede respaldarla de forma inmediata porque eso atentar\u00eda contra las leyes y el debido proceso en M\u00e9xico.<\/p>\n<p>Despu\u00e9s de los hechos de las \u00faltimas semanas y de la acusaci\u00f3n contra Rocha en particular, los analistas coinciden en que la presi\u00f3n de Estados Unidos hacia M\u00e9xico probablemente crezca durante los pr\u00f3ximos meses y afecte transversalmente todos los aspectos de la relaci\u00f3n bilateral, desde la seguridad hasta el comercio pasando por la migraci\u00f3n.<\/p>\n<p>Seg\u00fan Felbab-Brown, incluso ser\u00eda posible observar otras acciones de Estados Unidos contra figuras de la pol\u00edtica mexicana, ya sean funcionarios en activo o retirados del cargo.<\/p>\n<p>Para el Gobierno de Sheinbaum, las tensiones con Estados Unidos no son algo nuevo. Desde que Trump inici\u00f3 su segundo mandato presidencial el 20 de enero de 2025, ambos pa\u00edses han tenido desencuentros por temas como los aranceles o la propuesta de Trump para hacer operativos militares contra los carteles en territorio mexicano.<\/p>\n<p>Frente a estos episodios, Sheinbaum repetidamente ha dicho que <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/24\/mexico\/cabeza-fria-subir-tono-sheinbaum-retos-relacion-trump-orix\">mantendr\u00e1 \u201ccabeza fr\u00eda\u201d con Estados Unidos<\/a>, pero algunos especialistas subrayan que la acusaci\u00f3n contra Rocha implica un salto cualitativo en las acciones de Washington y dudan sobre la efectividad de la estrategia que la mandataria ha seguido hasta ahora.<\/p>\n<p>\u201cCreo que la cabeza fr\u00eda en este momento se est\u00e1 acabando. La diplomacia telef\u00f3nica, personal, que ten\u00eda con Trump ya no importa. Trump est\u00e1 decidido a lanzar la presi\u00f3n hasta donde sea posible para que M\u00e9xico responda\u201d, dijo Vald\u00e9s Ugalde, para quien Sheinbaum atraviesa por un momento clave en el que debe decidir si se deslinda o no de figuras cuestionadas de Morena, aunque algunas de ellas sean cercanas a L\u00f3pez Obrador.<\/p>\n<p>Por su parte, Pimienta consider\u00f3 que Sheinbaum por lo pronto hizo lo correcto al decir que la Fiscal\u00eda de M\u00e9xico ser\u00e1 la que revise si las solicitudes de Estados Unidos tienen sustento para proceder o no. Sin embargo, advirti\u00f3, el final de este episodio y sus efectos a\u00fan est\u00e1n por verse.<\/p>\n<p>\u201cAhora, la pregunta cr\u00edtica es si el Gobierno mexicano va a actuar con rapidez, transparencia y autonom\u00eda o si la percepci\u00f3n va a ser que se est\u00e1 protegiendo a alguien\u201d, dijo la especialista.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la renegociaci\u00f3n del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 en puerta, el Gobierno de la presidenta mexicana, Claudia Sheinbaum, ya ten\u00eda un desaf\u00edo este a\u00f1o en su relaci\u00f3n con la administraci\u00f3n de su hom\u00f3logo estadounidense, Donald Trump. Sin embargo, el panorama se le ha complicado m\u00e1s en solo unas cuantas semanas, debido a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473708","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa - Noticias\" \/>\n<meta property=\"og:description\" content=\"Con la renegociaci\u00f3n del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 en puerta, el Gobierno de la presidenta mexicana, Claudia Sheinbaum, ya ten\u00eda un desaf\u00edo este a\u00f1o en su relaci\u00f3n con la administraci\u00f3n de su hom\u00f3logo estadounidense, Donald Trump. Sin embargo, el panorama se le ha complicado m\u00e1s en solo unas cuantas semanas, debido a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-01T14:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa\",\"datePublished\":\"2026-05-01T14:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/\"},\"wordCount\":1375,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/\",\"name\":\"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-01T14:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa - Noticias","og_description":"Con la renegociaci\u00f3n del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 en puerta, el Gobierno de la presidenta mexicana, Claudia Sheinbaum, ya ten\u00eda un desaf\u00edo este a\u00f1o en su relaci\u00f3n con la administraci\u00f3n de su hom\u00f3logo estadounidense, Donald Trump. Sin embargo, el panorama se le ha complicado m\u00e1s en solo unas cuantas semanas, debido a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","og_site_name":"Noticias","article_published_time":"2026-05-01T14:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/"},"author":{"name":"","@id":""},"headline":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa","datePublished":"2026-05-01T14:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/"},"wordCount":1375,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","url":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","name":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-01T14:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa","url":"http:\/\/noticiasya.com\/laredo\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-01T14:03:47Z","datePublished":"2026-05-01T14:03:47Z","dateModified":"2026-05-01T14:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. suma presi\\u00f3n y pone en aprietos a Sheinbaum con la acusaci\\u00f3n contra el Gobernador de Sinaloa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/05\\\/01\\\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/05\\\/01\\\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-01T14:03:47Z\",\"datePublished\":\"2026-05-01T14:03:47Z\",\"dateModified\":\"2026-05-01T14:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466596,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/18\/sheinbaum-carney-t-mec-canada-mexico-orix\/","url_meta":{"origin":1473708,"position":0},"title":"Bajo cr\u00edticas de que cede ante Trump, Sheinbaum recibe a Carney para empezar a renegociar el T-MEC","author":"","date":"septiembre 18, 2025","format":false,"excerpt":"Cuando est\u00e1 por cumplir su primer a\u00f1o de Gobierno y ocho meses de un continuo estira y afloja con Estados Unidos, la presidenta de M\u00e9xico, Claudia Sheinbaum, sostiene este jueves un encuentro con su otro socio en Am\u00e9rica del Norte: Canad\u00e1.Sheinbaum recibe esta tarde al primer ministro de Canad\u00e1, Mark\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465808,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/24\/cabeza-fria-subir-tono-sheinbaum-retos-relacion-trump-orix\/","url_meta":{"origin":1473708,"position":1},"title":"De mantener &#171;cabeza fr\u00eda&#187; a subir el tono, las declaraciones de Sheinbaum muestran los retos de M\u00e9xico para enfrentar a Trump","author":"","date":"agosto 24, 2025","format":false,"excerpt":"Un d\u00eda despu\u00e9s de que Donald Trump inici\u00f3 su segundo mandato en la Casa Blanca, la presidenta de M\u00e9xico, Claudia Sheinbaum, expres\u00f3 el principio que \u2014seg\u00fan dijo\u2014 guiar\u00eda la actitud de su Gobierno frente al presidente de Estados Unidos: \u201ccabeza fr\u00eda\u201d.Sheinbaum repiti\u00f3 esa frase en seis ocasiones durante su conferencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449957,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/03\/biden-felicita-sheinbaum-eleccion-historica-orix\/","url_meta":{"origin":1473708,"position":2},"title":"Joe Biden felicita a Claudia Sheinbaum por su elecci\u00f3n &#171;hist\u00f3rica&#187;","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Estados Unidos, Joe Biden, felicit\u00f3 este lunes a Claudia Sheinbaum por sus resultados en la elecci\u00f3n presidencial en M\u00e9xico, que calific\u00f3 de \"hist\u00f3rica\" en un comunicado difundido por la Casa Blanca.\"Felicito a Claudia Sheinbaum por su hist\u00f3rica elecci\u00f3n como la primera mujer presidenta de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469034,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/06\/sheinbaum-confia-mantener-relacion-comercial-eeuu-orix\/","url_meta":{"origin":1473708,"position":3},"title":"Sheinbaum conf\u00eda en que M\u00e9xico mantendr\u00e1 relaci\u00f3n comercial con EE.UU.: &#171;Ambas econom\u00edas nos necesitamos&#187;","author":"","date":"diciembre 6, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este s\u00e1bado que conf\u00eda en que su pa\u00eds mantendr\u00e1 la relaci\u00f3n comercial que tiene con Estados Unidos, de cara a que el pr\u00f3ximo a\u00f1o se revise el tratado que ambos pa\u00edses tienen junto con Canad\u00e1, el T-MEC.\u201cEn nuestra relaci\u00f3n comercial, estoy convencida que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472229,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/15\/sheinbaum-respalda-lopez-obrador-apoyar-cuba-efe\/","url_meta":{"origin":1473708,"position":4},"title":"Sheinbaum respalda el llamado del expresidente L\u00f3pez Obrador para apoyar al pueblo de Cuba","author":"","date":"marzo 15, 2026","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, respald\u00f3 este domingo el llamado que hizo el s\u00e1bado por la noche el expresidente Andr\u00e9s Manuel L\u00f3pez Obrador para apoyar al pueblo de Cuba frente al bloqueo econ\u00f3mico y de combustible impuesto por Estados Unidos.\u201cEl d\u00eda de ayer el presidente L\u00f3pez Obrador, que est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472246,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/16\/sheinbaum-amlo-apoyo-cuba-aporte-personal-orix\/","url_meta":{"origin":1473708,"position":5},"title":"Sheinbaum reitera su respaldo al llamado de AMLO a apoyar a Cuba y dice que ella misma har\u00e1 un aporte personal","author":"","date":"marzo 16, 2026","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, volvi\u00f3 a respaldar este lunes el llamado del expresidente Andr\u00e9s Manuel L\u00f3pez Obrador (AMLO) a apoyar al pueblo de Cuba frente al bloqueo econ\u00f3mico y de combustible impuesto por Estados Unidos.\u201cM\u00e9xico fue el \u00fanico pa\u00eds, entre todas las presiones, que se opuso al bloqueo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1473708"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473708\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1473708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1473708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1473708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}