{"id":1473714,"date":"2026-05-01T14:04:02","date_gmt":"2026-05-01T21:04:02","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/"},"modified":"2026-05-01T14:04:02","modified_gmt":"2026-05-01T21:04:02","slug":"jueza-reprende-fiscales-audiencia-atacante-cena-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/","title":{"rendered":"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa"},"content":{"rendered":"<p>Una jueza federal reprendi\u00f3 en privado a los fiscales por intentar hacer alarde el jueves en una audiencia de detenci\u00f3n del atacante de la Cena de Corresponsales de la Casa Blanca, seg\u00fan una transcripci\u00f3n obtenida por CNN.<\/p>\n<p>\u201cNo s\u00e9 qu\u00e9 est\u00e1 pasando aqu\u00ed. S\u00e9 que quieren presentar su caso, supongo, ante alg\u00fan p\u00fablico distinto al de este tribunal\u201d, dijo la jueza magistrada Moxila Upadhyaya a tres fiscales en la sala del tribunal el jueves, fuera del alcance del o\u00eddo del p\u00fablico y la prensa. \u201cNo quiero que esto se convierta en un circo\u201d.<\/p>\n<p>Los comentarios de Upadhyaya destacan una din\u00e1mica que ha surgido en los seis d\u00edas desde que Cole Tomas Allen fue puesto bajo custodia \u2014despu\u00e9s de que un agente federal le disparara \u2014 un per\u00edodo en el que funcionarios del Gobierno de Trump describieron de forma agresiva su teor\u00eda del presunto intento de asesinato del presidente en entrevistas de medios y documentos judiciales no solicitados.<\/p>\n<p>En varias ocasiones, la fiscal federal del Distrito de Columbia, Jeanine Pirro, y otros funcionarios han ido mucho m\u00e1s all\u00e1 en sus entrevistas televisivas, ofreciendo descripciones del tiroteo mucho m\u00e1s categ\u00f3ricas y detalladas que las presentadas ante el tribunal por el FBI y los fiscales de l\u00ednea del Departamento de Justicia.<\/p>\n<p>Abogados del presunto atacante en la cena con la prensa aceptan mantenerlo en la c\u00e1rcel antes del juicio<\/p>\n<p>El director del Servicio Secreto, Sean M. Curran, declar\u00f3 el jueves que Allen dispar\u00f3 a un agente a quemarropa. Por su parte, Pirro afirm\u00f3 ese mismo jueves en Fox News que el sospechoso dispar\u00f3 contra el agente del Servicio Secreto.<br \/>Los documentos judiciales que describen los hechos han sido menos concluyentes.<\/p>\n<p>En la audiencia del jueves, los fiscales estaban preparados para mostrar en el tribunal nuevos videos y fotos que ten\u00edan del tiroteo, de las armas de Allen y de la escena del crimen en el hotel. Upadhyaya les impidi\u00f3 hacerlo en el tribunal, porque no era necesario despu\u00e9s de que los abogados de Allen dijeron que \u00e9l acept\u00f3 permanecer detenido mientras esperaba el juicio, dictamin\u00f3 ella.<\/p>\n<p>Visiblemente molesta, la jueza convoc\u00f3 a los fiscales y al equipo de la defensa a acercarse al estrado para hablar con ellos en privado; all\u00ed, la jueza continu\u00f3 cuestionando el enfoque adoptado por el Departamento de Justicia.<\/p>\n<p>El intercambio tambi\u00e9n destaca lo temprana e incompleta que sigue siendo la investigaci\u00f3n.<\/p>\n<p>\u201cEstamos a cinco d\u00edas de esta investigaci\u00f3n\u201d, respondi\u00f3 la fiscal Jocelyn Ballantine a la jueza, seg\u00fan la transcripci\u00f3n. \u201cTan pronto como hayamos finalizado los informes y el descubrimiento\u201d \u2014es decir, la evidencia que el equipo de la defensa puede revisar\u2014 \u201cy que estemos en condiciones de poder proporcionar con precisi\u00f3n al abogado, lo haremos. Nos tomamos en serio nuestras obligaciones en materia de descubrimiento de pruebas\u201d.<\/p>\n<p>A continuaci\u00f3n, Ballantine se\u00f1al\u00f3 que la Fiscal\u00eda Federal no estaba preparada para debatir en audiencia p\u00fablica los documentos que, hasta el momento, tienen como resultado de la investigaci\u00f3n.<\/p>\n<p>Tras la audiencia, la Oficina del Fiscal de Estados Unidos incorpor\u00f3 al expediente judicial y public\u00f3 en redes sociales los videos y fotos que hab\u00edan preparado.<\/p>\n<p>En una carta dirigida al juez, la Fiscal\u00eda declar\u00f3 que el Departamento de Justicia \u201cda por formalmente completado el expediente\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una jueza federal reprendi\u00f3 en privado a los fiscales por intentar hacer alarde el jueves en una audiencia de detenci\u00f3n del atacante de la Cena de Corresponsales de la Casa Blanca, seg\u00fan una transcripci\u00f3n obtenida por CNN. \u201cNo s\u00e9 qu\u00e9 est\u00e1 pasando aqu\u00ed. S\u00e9 que quieren presentar su caso, supongo, ante alg\u00fan p\u00fablico distinto al [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473714","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una jueza federal reprendi\u00f3 en privado a los fiscales por intentar hacer alarde el jueves en una audiencia de detenci\u00f3n del atacante de la Cena de Corresponsales de la Casa Blanca, seg\u00fan una transcripci\u00f3n obtenida por CNN. \u201cNo s\u00e9 qu\u00e9 est\u00e1 pasando aqu\u00ed. S\u00e9 que quieren presentar su caso, supongo, ante alg\u00fan p\u00fablico distinto al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-01T21:04:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa\",\"datePublished\":\"2026-05-01T21:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/\"},\"wordCount\":603,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/\",\"name\":\"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-01T21:04:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa - Noticias","og_description":"Una jueza federal reprendi\u00f3 en privado a los fiscales por intentar hacer alarde el jueves en una audiencia de detenci\u00f3n del atacante de la Cena de Corresponsales de la Casa Blanca, seg\u00fan una transcripci\u00f3n obtenida por CNN. \u201cNo s\u00e9 qu\u00e9 est\u00e1 pasando aqu\u00ed. S\u00e9 que quieren presentar su caso, supongo, ante alg\u00fan p\u00fablico distinto al [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-01T21:04:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/"},"author":{"name":"","@id":""},"headline":"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa","datePublished":"2026-05-01T21:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/"},"wordCount":603,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/","name":"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-01T21:04:02+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa","url":"http:\/\/noticiasya.com\/laredo\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/05\/01\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-01T21:04:02Z","datePublished":"2026-05-01T21:04:02Z","dateModified":"2026-05-01T21:04:02Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Primero en CNN: jueza reprende en privado a fiscales por hacer alarde en audiencia previa del atacante de la cena de prensa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/05\\\/01\\\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/05\\\/01\\\/jueza-reprende-fiscales-audiencia-atacante-cena-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-01T21:04:02Z\",\"datePublished\":\"2026-05-01T21:04:02Z\",\"dateModified\":\"2026-05-01T21:04:02Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473681,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/30\/abogados-atacante-trump-confinamiento-total-trax\/","url_meta":{"origin":1473714,"position":0},"title":"Abogados del presunto atacante en la Cena de Corresponsales dicen que ha estado en confinamiento total en la c\u00e1rcel","author":"","date":"abril 30, 2026","format":false,"excerpt":"El hombre acusado de intentar asesinar al presidente Donald Trump durante el fin de semana no impugnar\u00e1 su detenci\u00f3n mientras el caso avanza, dijeron sus abogados a un juez federal este jueves.Cole Tomas Allen, quien habl\u00f3 poco durante la audiencia del jueves, est\u00e1 acusado de irrumpir en un punto de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462382,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/15\/manifestantes-apoyo-jueza-acusada-trax\/","url_meta":{"origin":1473714,"position":1},"title":"Manifestantes se concentran en apoyo a jueza acusada de ayudar a un hombre a huir de los agentes de inmigraci\u00f3n","author":"","date":"mayo 15, 2025","format":false,"excerpt":"Alrededor de 100 manifestantes se concentraron este jueves por la ma\u00f1ana frente al tribunal y edificio federal del centro de Milwaukee antes de la lectura de cargos contra una jueza de Wisconsin acusada de ayudar a un hombre que est\u00e1 en el pa\u00eds ilegalmente a evadir a los agentes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443552,"url":"https:\/\/noticiasya.com\/laredo\/2024\/01\/11\/hunter-biden-se-declara-inocente-de-cargos-fiscales-en-un-caso-federal-sobre-evasion-de-impuestos\/","url_meta":{"origin":1473714,"position":2},"title":"Hunter Biden se declara inocente de cargos fiscales en un caso federal sobre evasi\u00f3n de impuestos","author":"","date":"enero 11, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Hunter Biden, hijo del presidente Joe Biden, se declar\u00f3 inocente este jueves de los cargos fiscales que enfrenta en un caso federal en California por supuestamente no pagar m\u00e1s de un mill\u00f3n de d\u00f3lares en impuestos.A Hunter Biden lo acusaron de nueve cargos relacionados con una conspiraci\u00f3n para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463978,"url":"https:\/\/noticiasya.com\/laredo\/2025\/06\/26\/audiencia-emergencia-evitar-otra-deportacion-abrego-garcia-trax\/","url_meta":{"origin":1473714,"position":3},"title":"Jueza celebrar\u00e1 audiencia de emergencia a solicitud para evitar otra deportaci\u00f3n de \u00c1brego Garc\u00eda","author":"","date":"junio 26, 2025","format":false,"excerpt":"Una jueza federal en Maryland celebrar\u00e1 una audiencia de emergencia esta tarde a la 1 p.m. (hora de Miami) sobre la situaci\u00f3n de Kilmar \u00c1brego Garc\u00eda, debido a que sus abogados temen que el Gobierno de Trump pueda intentar deportarlo nuevamente a El Salvador.Los abogados del inmigrante deportado injustamente y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463210,"url":"https:\/\/noticiasya.com\/laredo\/2025\/06\/04\/funcionario-dhs-dice-migrante-no-esta-investigacion-amenaza-trump-trax\/","url_meta":{"origin":1473714,"position":4},"title":"Funcionario del DHS dice que inmigrante indocumentado ya no est\u00e1 bajo investigaci\u00f3n por caso de amenaza a Trump","author":"","date":"junio 4, 2025","format":false,"excerpt":"Un funcionario del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) admiti\u00f3 este mi\u00e9rcoles que un migrante indocumentado, al que se cree fue incriminado por amenazar con matar al presidente Donald Trump, ya no est\u00e1 bajo investigaci\u00f3n.El DHS y la secretaria de Seguridad Nacional, Kristi Noem, inicialmente destacaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463025,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/30\/cronologia-escandalo-anulacion-juicio-muerte-diego-maradona-orix\/","url_meta":{"origin":1473714,"position":5},"title":"&#171;Justicia Divina&#187;: cronolog\u00eda del esc\u00e1ndalo que llev\u00f3 a la anulaci\u00f3n del juicio por la muerte de Diego Maradona","author":"","date":"mayo 30, 2025","format":false,"excerpt":"Podr\u00eda haber sido un d\u00eda m\u00e1s del debate que hab\u00eda iniciado dos meses antes y en el que ya hab\u00edan declarado alrededor de 40 testigos. Pero la audiencia del 15 de mayo del juicio por la muerte de Diego Armando Maradona se transform\u00f3 en un punto de quiebre y llev\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1473714"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473714\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1473714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1473714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1473714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}