{"id":1473717,"date":"2026-05-01T16:03:42","date_gmt":"2026-05-01T23:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/"},"modified":"2026-05-01T16:03:42","modified_gmt":"2026-05-01T23:03:42","slug":"fed-recortes-tasas-protestas-funcionarios-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/","title":{"rendered":"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios"},"content":{"rendered":"<p>Una palabra en el extenso comunicado de pol\u00edtica de la Reserva Federal (Fed) publicado esta semana est\u00e1 causando consternaci\u00f3n entre sus funcionarios, algunos de los cuales advierten que podr\u00eda terminar cost\u00e1ndole caro a la econom\u00eda de Estados Unidos.<\/p>\n<p>Esa palabra es \u201cadicional\u201d.<\/p>\n<p>Desde principios de la d\u00e9cada de 2000, la Fed ha se\u00f1alado si las tasas de inter\u00e9s podr\u00edan subir, bajar o mantenerse sin cambios \u2014lo que se conoce como \u201corientaci\u00f3n futura\u201d\u2014 mediante comentarios p\u00fablicos de los funcionarios y comunicados de pol\u00edtica emitidos tras cada reuni\u00f3n.<\/p>\n<p>El mi\u00e9rcoles, su m\u00e1s <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/30\/eeuu\/inflacion-reserva-federal-nivel-alto-tres-anos-trax\">reciente orientaci\u00f3n futura<\/a> insinu\u00f3 que tasas de inter\u00e9s m\u00e1s bajas podr\u00edan ser la \u00fanica posibilidad en adelante, al se\u00f1alar que considerar\u00e1 \u201cajustes adicionales al rango objetivo de la tasa de fondos federales\u201d. En su decisi\u00f3n m\u00e1s reciente, la Fed mantuvo sin cambios esta semana su tasa de inter\u00e9s clave por tercera reuni\u00f3n consecutiva.<\/p>\n<p>La palabra \u201cadicional\u201d en particular suscit\u00f3 objeciones. Los presidentes de la Fed, Lorie Logan, de Dallas; Beth Hammack, de Cleveland; y Neel Kashkari, de Minneapolis, \u201cno apoyaron la inclusi\u00f3n de un sesgo hacia la flexibilizaci\u00f3n en el comunicado en este momento\u201d, inform\u00f3 la Fed el mi\u00e9rcoles, por lo que los tres emitieron votos disidentes. Este viernes, los tres presidentes de la Fed publicaron comunicados en los que detallaron por qu\u00e9 eso fue un error.<\/p>\n<p>Desde 2024, los \u00fanicos ajustes que la Fed ha hecho al rango objetivo han sido a la baja, impulsados en gran medida por se\u00f1ales de debilitamiento de la econom\u00eda. Sin embargo, la situaci\u00f3n econ\u00f3mica ha cambiado dr\u00e1sticamente este a\u00f1o: la guerra entre Estados Unidos e Israel con Ir\u00e1n, que comenz\u00f3 el 28 de febrero, ha mantenido los precios mundiales del petr\u00f3leo rondando los US$ 100 por gal\u00f3n durante semanas y ha mantenido elevados los precios de la gasolina en Estados Unidos.<\/p>\n<p>Puede haber consecuencias econ\u00f3micas graves si la Fed interpreta err\u00f3neamente la econom\u00eda \u2014incluso comunicar la direcci\u00f3n equivocada de las tasas de inter\u00e9s puede ser arriesgado\u2014, dijeron los funcionarios de la Fed.<\/p>\n<p>La orientaci\u00f3n futura de la Fed \u201cinfluye en las condiciones financieras y en la econom\u00eda\u201d, afirm\u00f3 Logan en un comunicado este viernes, \u201cy afecta el logro de los objetivos (de la Fed) de m\u00e1ximo empleo y estabilidad de precios\u201d. Kashkari se hizo eco de eso en un comunicado separado este viernes.<\/p>\n<p>Los funcionarios se rigen por su orientaci\u00f3n prospectiva para contribuir a mantener la estabilidad de los mercados, aumentar la eficacia de la pol\u00edtica monetaria e influir en las condiciones financieras.<\/p>\n<p>Los observadores de la Fed interpretaron el uso de \u201cadicional\u201d en el comunicado de pol\u00edtica como evidencia de un \u201csesgo hacia la flexibilizaci\u00f3n\u201d, es decir, que los funcionarios se inclinan hacia la reducci\u00f3n de las tasas en el corto plazo, al tiempo que se\u00f1alan que no es probable que haya aumentos de tasas. Fue un tipo raro de disenso sobre el lenguaje, no sobre el nivel de las tasas de inter\u00e9s, dentro de un comunicado de pol\u00edtica monetaria.<\/p>\n<p>Kevin Warsh, el elegido del presidente Donald Trump para dirigir la Fed, va camino de tomar las riendas en apenas unas semanas, y Warsh podr\u00eda presionar para reducir las tasas, dado que fue elegido por un presidente que desde hace tiempo ha insistido en recortes de los tipos de inter\u00e9s. Eso tambi\u00e9n est\u00e1 alimentando la percepci\u00f3n de que la Fed se inclina a bajar las tasas, una postura a la que se oponen firmemente los tres presidentes de la Fed que manifestaron su disidencia.<\/p>\n<p>Estas disidencias \u2014m\u00e1s la separada de Miran, quien abog\u00f3 esta semana por la reducci\u00f3n de las tasas\u2014 resultaron en un total de cuatro votos discrepantes, la cifra m\u00e1s alta desde octubre de 1992.<\/p>\n<p>El comunicado de Hammack explic\u00f3 que \u201ceste claro sesgo hacia la flexibilizaci\u00f3n\u201d \u201cya no es apropiado dado el panorama\u201d porque no solo la guerra con Ir\u00e1n est\u00e1 avivando presiones inflacionarias, sino que el mercado laboral de Estados Unidos parece haberse estabilizado, lo que significa que no hay urgencia por aplicar recortes de tasas para estimular la econom\u00eda.<\/p>\n<p>El propio Warsh ha declarado que no es partidario de la \u201corientaci\u00f3n prospectiva\u201d.<\/p>\n<p>\u201cA diferencia de muchos de mis colegas, pasados y presentes, no creo en la orientaci\u00f3n futura\u201d, dijo durante su audiencia de confirmaci\u00f3n la semana pasada. \u201cNo creo que deba adelantarles cu\u00e1l podr\u00eda ser una decisi\u00f3n futura. Creo que es esencial que la Fed tome decisiones en las reuniones\u201d.<\/p>\n<p>Warsh no indic\u00f3 durante su audiencia de confirmaci\u00f3n hacia d\u00f3nde deber\u00edan dirigirse las tasas de inter\u00e9s.<\/p>\n<p>No obstante, la serie de disidencias registrada esta semana sugiere que, de ser confirmado en el cargo, a Warsh probablemente le resultar\u00e1 dif\u00edcil convencer a sus colegas de reducir las tasas.<\/p>\n<p>\u201cKevin Warsh asumir\u00e1 como presidente para la pr\u00f3xima reuni\u00f3n de la Fed a mediados de junio, pero el resto de los dirigentes de la Fed mantiene un list\u00f3n alto para aprobar un recorte de tasas\u201d, dijo Bill Adams, economista jefe de Estados Unidos en Fifth Third Commercial Bank, en una nota de an\u00e1lisis esta semana.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una palabra en el extenso comunicado de pol\u00edtica de la Reserva Federal (Fed) publicado esta semana est\u00e1 causando consternaci\u00f3n entre sus funcionarios, algunos de los cuales advierten que podr\u00eda terminar cost\u00e1ndole caro a la econom\u00eda de Estados Unidos. Esa palabra es \u201cadicional\u201d. Desde principios de la d\u00e9cada de 2000, la Fed ha se\u00f1alado si las [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473717","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una palabra en el extenso comunicado de pol\u00edtica de la Reserva Federal (Fed) publicado esta semana est\u00e1 causando consternaci\u00f3n entre sus funcionarios, algunos de los cuales advierten que podr\u00eda terminar cost\u00e1ndole caro a la econom\u00eda de Estados Unidos. Esa palabra es \u201cadicional\u201d. Desde principios de la d\u00e9cada de 2000, la Fed ha se\u00f1alado si las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-01T23:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios\",\"datePublished\":\"2026-05-01T23:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/\"},\"wordCount\":935,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/\",\"name\":\"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-01T23:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios - Noticias","og_description":"Una palabra en el extenso comunicado de pol\u00edtica de la Reserva Federal (Fed) publicado esta semana est\u00e1 causando consternaci\u00f3n entre sus funcionarios, algunos de los cuales advierten que podr\u00eda terminar cost\u00e1ndole caro a la econom\u00eda de Estados Unidos. Esa palabra es \u201cadicional\u201d. Desde principios de la d\u00e9cada de 2000, la Fed ha se\u00f1alado si las [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-01T23:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/"},"author":{"name":"","@id":""},"headline":"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios","datePublished":"2026-05-01T23:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/"},"wordCount":935,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/","name":"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-01T23:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Fed insin\u00faa sutilmente que solo est\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios","url":"http:\/\/noticiasya.com\/laredo\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/05\/01\/fed-recortes-tasas-protestas-funcionarios-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-01T23:03:42Z","datePublished":"2026-05-01T23:03:42Z","dateModified":"2026-05-01T23:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Fed insin\\u00faa sutilmente que solo est\\u00e1n sobre la mesa recortes de tasas en medio de desacuerdos de algunos funcionarios\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/05\\\/01\\\/fed-recortes-tasas-protestas-funcionarios-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/05\\\/01\\\/fed-recortes-tasas-protestas-funcionarios-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-01T23:03:42Z\",\"datePublished\":\"2026-05-01T23:03:42Z\",\"dateModified\":\"2026-05-01T23:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473400,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/22\/fed-kevin-warsh-postura-trax\/","url_meta":{"origin":1473717,"position":0},"title":"\u00bfConfundido sobre la postura pol\u00edtica de Kevin Warsh, el designado para la Fed? Acost\u00fambrate","author":"","date":"abril 22, 2026","format":false,"excerpt":"Es una pr\u00e1ctica est\u00e1ndar que los funcionarios de la Reserva Federal se mantengan al margen de la pol\u00edtica y \u201cse mantengan en su carril\u201d, como lo describi\u00f3 el martes en su audiencia de confirmaci\u00f3n Kevin Warsh, el designado del presidente Donald Trump para presidir la Fed.Ese carril est\u00e1 destinado a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467846,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/29\/reserva-federal-recorta-tasas-interes-trax\/","url_meta":{"origin":1473717,"position":1},"title":"La Fed recorta las tasas de inter\u00e9s por segunda vez este a\u00f1o","author":"","date":"octubre 29, 2025","format":false,"excerpt":"La Reserva Federal (Fed) recort\u00f3 este mi\u00e9rcoles las tasas de inter\u00e9s por segunda vez este a\u00f1o, en un intento por frenar el aumento del desempleo en Estados Unidos.Los funcionarios de la Fed votaron a favor de otro recorte de un cuarto de punto porcentual, lo que reduce su tipo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463707,"url":"https:\/\/noticiasya.com\/laredo\/2025\/06\/18\/fed-tipos-interes-efectos-aranceles-trump-trax\/","url_meta":{"origin":1473717,"position":2},"title":"La Fed vuelve a mantener los tipos de inter\u00e9s a la espera de los efectos de los aranceles de Trump","author":"","date":"junio 18, 2025","format":false,"excerpt":"La Reserva Federal (Fed) mantuvo nuevamente las tasas de inter\u00e9s sin cambios este mi\u00e9rcoles, mientras los funcionarios esperan el impacto de los amplios cambios de pol\u00edtica del presidente Donald Trump y las tensiones en Medio Oriente.El banco central dej\u00f3 su tasa de inter\u00e9s de referencia sin cambios, en un rango\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463892,"url":"https:\/\/noticiasya.com\/laredo\/2025\/06\/24\/powell-descarta-recorte-tasas-julio-trax\/","url_meta":{"origin":1473717,"position":3},"title":"A pesar de la creciente divisi\u00f3n en la Fed, Powell parece descartar un recorte de tasas en julio","author":"","date":"junio 24, 2025","format":false,"excerpt":"A\u00fan es demasiado pronto para que la Reserva Federal considere bajar las tasas de inter\u00e9s, declar\u00f3 este martes su presidente, Jerome Powell.\u201cLos cambios de pol\u00edticas siguen evolucionando y sus efectos en la econom\u00eda siguen siendo inciertos\u201d, declar\u00f3 Powell en su testimonio preparado para su informe semestral de pol\u00edtica monetaria ante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460138,"url":"https:\/\/noticiasya.com\/laredo\/2025\/03\/19\/fed-mantiene-tasas-interes-guerra-comercial-trump-trax\/","url_meta":{"origin":1473717,"position":4},"title":"La Reserva Federal mantiene estables las tasas de inter\u00e9s en medio de la ca\u00f3tica guerra comercial de Trump","author":"","date":"marzo 19, 2025","format":false,"excerpt":"La Reserva Federal mantuvo sin cambios las tasas de inter\u00e9s este mi\u00e9rcoles, mientras los funcionarios del banco central eval\u00faan el impacto de la agresiva agenda econ\u00f3mica del presidente Donald Trump.La decisi\u00f3n del mi\u00e9rcoles, que se produjo al t\u00e9rmino de la reuni\u00f3n de pol\u00edtica monetaria de dos d\u00edas de la Fed,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456723,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/18\/fed-recorta-tasas-de-interes-trax\/","url_meta":{"origin":1473717,"position":5},"title":"La Fed recorta las tasas de inter\u00e9s por tercera vez en el a\u00f1o","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"La Reserva Federal recort\u00f3 este mi\u00e9rcoles las tasas de inter\u00e9s en un cuarto de punto, en el que es el tercer recorte de tasas desde que comenz\u00f3 la reducci\u00f3n de los costos de los pr\u00e9stamos en septiembre.En un movimiento que no fue un\u00e1nime, el banco central de Estados Unidos est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1473717"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1473717\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1473717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1473717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1473717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}