{"id":1443312,"date":"2024-01-07T19:33:34","date_gmt":"2024-01-08T03:33:34","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443312"},"modified":"2024-01-07T19:33:34","modified_gmt":"2024-01-08T03:33:34","slug":"el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/","title":{"rendered":"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La tercera ronda de la FA Cup -el torneo m\u00e1s antiguo del mundo- llega casi a su final este domingo despu\u00e9s de decenas de partidos jugados desde el viernes 5 de enero, en los cuales hemos visto momentos futbol\u00edsticos cargados de emoci\u00f3n, en donde destaca el golazo del espa\u00f1ol Pedro Porro y el tanto de la victoria del colombiano Luis D\u00edaz para eliminar de la competici\u00f3n al poderoso Arsenal.<\/p>\n<p>Del 5 de enero al lunes 8 de enero, se lleva a cabo en territorio brit\u00e1nico la tercera ronda de la FA Cup 2023\/2024. En ese lapso, se agendaron 32 partidos, en donde 64 equipos buscan el pase a la cuarta ronda (la de los 32 mejores clubes).<\/p>\n<p>Hasta este domingo por la tarde, se hab\u00edan jugado 31 partidos de los 32 en total. \u00danicamente falta disputarse el Wigan vs. Manchester United para completar la agenda, lo que ocurrir\u00e1 este lunes.\u00a0 Asimismo, de los encuentros ya realizados, se volver\u00e1n a jugar cinco de ellos porque en el primer partido quedaron empate, as\u00ed que la llave de tercera ronda se tiene que definir en un enfrentamiento repetido (o &#171;replay&#187; en la jerga inglesa) que se disputar\u00e1 en la semana del 15 de enero.<\/p>\n<p>Pese a esto, hay equipos que lograron avanzar a la cuarta ronda de la FA Cup desde el primer partido de tercera ronda, como lo hizo el Tottenham -ocho veces campe\u00f3n de esta competencia- frente al Burnley el pasado 5 de enero.<\/p>\n<p>Si bien el juego parec\u00eda sencillo para los Spurs, pues marchan en el lugar 5 de la Premier League y el rival se encuentra en puestos de descenso, esto no fue as\u00ed. El Burnley plant\u00f3 cara a los de Londres e incluso tuvo oportunidades para adelantarse en el marcador.<\/p>\n<p>Sin embargo, en un partido que parec\u00eda destinado a repetirse, el espa\u00f1ol Pedro Porro dispar\u00f3 desde fuera del \u00e1rea para marcar un golazo que se incrust\u00f3 en el \u00e1ngulo superior derecho del portero Arijanet Muric.<\/p>\n<p>Esta anotaci\u00f3n espectacular al minuto 78 fue suficiente para que el Tottenham venciera y avanzara a la ronda de dieciseisavos de final (cuarta ronda de FA Cup o fase del torneo a la que avanzan los mejores 32 clubes del torneo).<\/p>\n<p>&#171;(Porro) dispara mucho en los entrenamientos, falla mucho, pero hoy le sali\u00f3 y fue un gol incre\u00edble&#187;, declar\u00f3 a ITV un sonriente Brennan Johnson, delantero de los Spurs, seg\u00fan Reuters.<\/p>\n<p>OH MY \ud83e\udd2f<br \/>\nA moment of brilliance from @Pedroporro29_ for @SpursOfficial \ud83d\udca5#EmiratesFACup pic.twitter.com\/XYtGcPcTf7<br \/>\n\u2014 Emirates FA Cup (@EmiratesFACup) January 5, 2024<\/p>\n<p>Por otro lado, este domingo se jug\u00f3 el partido m\u00e1s esperado de la tercera ronda de FA Cup: Arsenal vs. Liverpool.<\/p>\n<p>En la Premier League, ambos clubes son contendientes claros para ganar, aunque el club de Mikel Arteta viene en declive en la liga y el conjunto de Klopp mantiene una racha positiva que los ubica como l\u00edderes de la competencia.<\/p>\n<p>Esto le dio un sabor especial al encuentro, que en el primer tiempo fue dominado por el Arsenal pero sin hacerse presente en el marcador.<\/p>\n<p>De hecho, el equipo londinense nunca pudo poner el bal\u00f3n en las redes a pesar de los intentos. Y, en contraste, fue Liverpool el que tuvo mayor contundencia al frente.<\/p>\n<p>Los Reds ganaron el encuentro 2-0 en la casa de los rivales gracias a un autogol de Jakub Kiwior y a un gol del colombiano Luis D\u00edaz, quien finaliz\u00f3 un contraataque letal al minuto 95.<\/p>\n<p>Signed \u270d\ufe0fSealed \u2709\ufe0fInto the fourth round \ud83c\udfc6<br \/>\nLuis D\u00edaz books @LFC&#8217;s spot!#EmiratesFACup pic.twitter.com\/lwRYLVJYoh<br \/>\n\u2014 Emirates FA Cup (@EmiratesFACup) January 7, 2024<\/p>\n<p>Con esta victoria, los dirigidos por Klopp se mantienen con esperanzas de ganar sus cuatro torneos del a\u00f1o: la FA Cup (donde juegan 729 clubes del f\u00fatbol ingl\u00e9s), la Carabao Cup (copa de liga), la Premier League (liga dom\u00e9stica) y la UEFA Europa League (liga europea).<\/p>\n<p>Da clic aqu\u00ed para ver todos los resultados de la tercera ronda de la FA Cup.<\/p>\n<p>Con informaci\u00f3n de Matias Grez, de CNN, y de Reuters.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La tercera ronda de la FA Cup -el torneo m\u00e1s antiguo del mundo- llega casi a su final este domingo despu\u00e9s de decenas de partidos jugados desde el viernes 5 de enero, en los cuales hemos visto momentos futbol\u00edsticos cargados de emoci\u00f3n, en donde destaca el golazo del espa\u00f1ol Pedro Porro y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443312","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La tercera ronda de la FA Cup -el torneo m\u00e1s antiguo del mundo- llega casi a su final este domingo despu\u00e9s de decenas de partidos jugados desde el viernes 5 de enero, en los cuales hemos visto momentos futbol\u00edsticos cargados de emoci\u00f3n, en donde destaca el golazo del espa\u00f1ol Pedro Porro y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T03:33:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra\",\"datePublished\":\"2024-01-08T03:33:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/\"},\"wordCount\":718,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/\",\"name\":\"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-08T03:33:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/","og_locale":"es_ES","og_type":"article","og_title":"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La tercera ronda de la FA Cup -el torneo m\u00e1s antiguo del mundo- llega casi a su final este domingo despu\u00e9s de decenas de partidos jugados desde el viernes 5 de enero, en los cuales hemos visto momentos futbol\u00edsticos cargados de emoci\u00f3n, en donde destaca el golazo del espa\u00f1ol Pedro Porro y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/","og_site_name":"Noticias","article_published_time":"2024-01-08T03:33:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/"},"author":{"name":"","@id":""},"headline":"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra","datePublished":"2024-01-08T03:33:34+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/"},"wordCount":718,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/","url":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/","name":"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-08T03:33:34+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El golazo de Pedro Porro y el tanto de la victoria de Luis D\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/07\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-08T03:33:34Z","datePublished":"2024-01-08T03:33:34Z","dateModified":"2024-01-08T03:33:34Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El golazo de Pedro Porro y el tanto de la victoria de Luis D\\u00edaz destacan en la tercera ronda de la FA Cup de Inglaterra\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/07\\\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/07\\\/el-golazo-de-pedro-porro-y-el-tanto-de-la-victoria-de-luis-diaz-destacan-en-la-tercera-ronda-de-la-fa-cup-de-inglaterra\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-08T03:33:34Z\",\"datePublished\":\"2024-01-08T03:33:34Z\",\"dateModified\":\"2024-01-08T03:33:34Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452315,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/08\/31\/se-ha-producido-otra-gran-sorpresa-en-el-us-open\/","url_meta":{"origin":1443312,"position":0},"title":"Otra gran sorpresa sacude el US Open","author":"","date":"agosto 31, 2024","format":false,"excerpt":"(CNN) -- Una noche despu\u00e9s de que el No. 3 Carlos Alcaraz fuera sorprendido por el no sembrado Botic van de Zandschulp en sets corridos, el No. 2 Novak Djokovic ha sido eliminado por el No. 28 australiano Alexei Popyrin en la tercera ronda en el Estadio Arthur Ashe.Popyrin se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464975,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/07\/30\/luis-diaz-se-va-al-bayern-munich-en-un-fichaje-millonario-plagado-de-records\/","url_meta":{"origin":1443312,"position":1},"title":"Luis D\u00edaz se va al Bayern Munich en un fichaje millonario plagado de r\u00e9cords","author":"","date":"julio 30, 2025","format":false,"excerpt":"Fue un secreto a voces durante la ventana del mercado de fichajes y finalmente este mi\u00e9rcoles el Bayern Munich oficializ\u00f3 la llegada de Luis D\u00edaz.El colombiano llega al equipo b\u00e1varo, procedente del Liverpool, con una mejora salarial y una serie de r\u00e9cords econ\u00f3micos en su traspaso.D\u00edaz, quien firm\u00f3 contrato hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458484,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/02\/09\/liverpool-derrota-plymouth-argyle-segunda-division-fa-cup-trax\/","url_meta":{"origin":1443312,"position":2},"title":"Liverpool sufre sorprendente derrota ante el Plymouth Argyle de segunda divisi\u00f3n en la FA Cup","author":"","date":"febrero 9, 2025","format":false,"excerpt":"Liverpool sufri\u00f3 una sorprendente derrota por 1-0 contra el Plymouth Argyle en la FA Cup este domingo, un gran tropiezo en la excelente temporada del club hasta ahora.La derrota en la cuarta ronda pone fin a las esperanzas de Liverpool de ganar un cu\u00e1druple sin precedentes este a\u00f1o de manera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450937,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/07\/07\/iga-swiatek-eliminada-wimbledon-sorpresiva-derrota-yulia-putintseva-trax\/","url_meta":{"origin":1443312,"position":3},"title":"Eliminan a Iga \u015awi\u0105tek de Wimbledon en una sorpresiva derrota en tercera ronda ante Yulia Putintseva","author":"","date":"julio 7, 2024","format":false,"excerpt":"(CNN) -- La n\u00famero 1 del mundo, Iga \u015awi\u0105tek, se despidi\u00f3 de Wimbledon el s\u00e1bado al sufrir una sorprendente derrota en tercera ronda ante la kazaja Yulia Putintseva, con lo que puso fin a su racha de 21 partidos ganados.\u015awi\u0105tek llevaba casi tres meses sin perder un partido, una racha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472852,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/03\/regresa-futbol-europeo-clubes-claves-orix\/","url_meta":{"origin":1443312,"position":4},"title":"Regresa el f\u00fatbol europeo de clubes: las claves para este fin de semana","author":"","date":"abril 3, 2026","format":false,"excerpt":"La fecha FIFA de selecciones nacionales qued\u00f3 atr\u00e1s y el f\u00fatbol a nivel de clubes en Europa se prepara para volver este fin de semana.En LaLiga de Espa\u00f1a, el Atl\u00e9tico de Madrid recibe la visita del FC Barcelona en el juego m\u00e1s atractivo de la jornada 30. Este ser\u00e1 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451548,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/08\/01\/por-que-no-juega-america-fase-grupos-leagues-cup-2024-orix\/","url_meta":{"origin":1443312,"position":5},"title":"\u00bfPor qu\u00e9 no juega el Am\u00e9rica la fase de grupos de la Leagues Cup 2024?","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Leagues Cup 2024 ser\u00e1 la cuarta edici\u00f3n de este torneo que es organizado por la Confederaci\u00f3n de Norteam\u00e9rica, Centroam\u00e9rica y el Caribe de F\u00fatbol (Concacaf).Esta competencia re\u00fane a todos los equipos de la MLS y de la Liga MX: por la Major League Soccer participan 29\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443312"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443312\/revisions"}],"predecessor-version":[{"id":1443329,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443312\/revisions\/1443329"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}