{"id":1443462,"date":"2024-01-10T05:33:49","date_gmt":"2024-01-10T13:33:49","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443462"},"modified":"2024-01-10T05:33:49","modified_gmt":"2024-01-10T13:33:49","slug":"muere-la-madre-de-melania-trump-amalija-knavs","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/","title":{"rendered":"Muere la madre de Melania Trump, Amalija Knavs"},"content":{"rendered":"<p>(CNN) \u2013\u2013Amalija Knavs, la madre de la ex primera dama Melania Trump , muri\u00f3, public\u00f3 Trump en sus cuentas de redes sociales.<\/p>\n<p>\u201cAmalija Knavs fue una mujer fuerte que siempre se comport\u00f3 con gracia, calidez y dignidad. Estaba enteramente dedicada a su marido, sus hijas, su nieto y su yerno. La extra\u00f1aremos sin medida y continuaremos honrando y amando su legado\u201d, escribi\u00f3 en X.<\/p>\n<p>Un asesor de campa\u00f1a del expresidente Donald Trump confirm\u00f3 la muerte de Knavs a CNN.<\/p>\n<p>Knavs era de Eslovenia, anteriormente Yugoslavia comunista, y era trabajador textil. Ella y su esposo, Viktor, hab\u00edan residido en los Estados Unidos y fueron vistos con frecuencia en Washington despu\u00e9s de que su yerno asumiera la presidencia en 2017.<\/p>\n<p>La pareja de jubilados mantuvo contacto regular con la familia Trump durante la administraci\u00f3n, viajando a menudo con la primera familia en viajes a Mar-a-Lago y Bedminster, Nueva Jersey.<\/p>\n<p>En 2016, los Knavs eran propietarios de una casa en Sevnica , una tranquila ciudad industrial de 5.000 habitantes ubicada en un exuberante valle arbolado a orillas del r\u00edo Sava en el centro de Eslovenia, donde Melania Trump asisti\u00f3 a la escuela primaria. Pero desde que naci\u00f3 su nieto Barron Trump en 2006, pasaban la mayor parte del tiempo en Nueva York, dijeron los vecinos en ese momento.<\/p>\n<p>Los Knavs se convirtieron en ciudadanos estadounidenses en 2018 , obteniendo pol\u00e9micamente su ciudadan\u00eda a trav\u00e9s del patrocinio de su hija adulta, una categor\u00eda de visa que la administraci\u00f3n Trump hab\u00eda tratado de poner fin. Donald Trump hab\u00eda criticado duramente la migraci\u00f3n familiar, refiri\u00e9ndose regularmente a ella como \u201cmigraci\u00f3n en cadena\u201d.<\/p>\n<p>Melania Trump, quien se convirti\u00f3 en ciudadana estadounidense en 2006, es apenas la segunda primera dama nacida en el extranjero. Ha evitado en gran medida la atenci\u00f3n del p\u00fablico desde que dej\u00f3 Washington en enero de 2021, incluso cuando su esposo busca otra candidatura a la Casa Blanca.<\/p>\n<p>Esta historia se ha actualizado con detalles adicionales.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013Amalija Knavs, la madre de la ex primera dama Melania Trump , muri\u00f3, public\u00f3 Trump en sus cuentas de redes sociales. \u201cAmalija Knavs fue una mujer fuerte que siempre se comport\u00f3 con gracia, calidez y dignidad. Estaba enteramente dedicada a su marido, sus hijas, su nieto y su yerno. La extra\u00f1aremos sin medida y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443462","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere la madre de Melania Trump, Amalija Knavs - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere la madre de Melania Trump, Amalija Knavs - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013Amalija Knavs, la madre de la ex primera dama Melania Trump , muri\u00f3, public\u00f3 Trump en sus cuentas de redes sociales. \u201cAmalija Knavs fue una mujer fuerte que siempre se comport\u00f3 con gracia, calidez y dignidad. Estaba enteramente dedicada a su marido, sus hijas, su nieto y su yerno. La extra\u00f1aremos sin medida y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-10T13:33:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere la madre de Melania Trump, Amalija Knavs\",\"datePublished\":\"2024-01-10T13:33:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/\",\"name\":\"Muere la madre de Melania Trump, Amalija Knavs - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-10T13:33:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere la madre de Melania Trump, Amalija Knavs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere la madre de Melania Trump, Amalija Knavs - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/","og_locale":"es_ES","og_type":"article","og_title":"Muere la madre de Melania Trump, Amalija Knavs - Noticias","og_description":"(CNN) \u2013\u2013Amalija Knavs, la madre de la ex primera dama Melania Trump , muri\u00f3, public\u00f3 Trump en sus cuentas de redes sociales. \u201cAmalija Knavs fue una mujer fuerte que siempre se comport\u00f3 con gracia, calidez y dignidad. Estaba enteramente dedicada a su marido, sus hijas, su nieto y su yerno. La extra\u00f1aremos sin medida y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/","og_site_name":"Noticias","article_published_time":"2024-01-10T13:33:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/"},"author":{"name":"","@id":""},"headline":"Muere la madre de Melania Trump, Amalija Knavs","datePublished":"2024-01-10T13:33:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/","url":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/","name":"Muere la madre de Melania Trump, Amalija Knavs - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-10T13:33:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere la madre de Melania Trump, Amalija Knavs"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere la madre de Melania Trump, Amalija Knavs","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/10\/muere-la-madre-de-melania-trump-amalija-knavs\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-10T13:33:49Z","datePublished":"2024-01-10T13:33:49Z","dateModified":"2024-01-10T13:33:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere la madre de Melania Trump, Amalija Knavs\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/10\\\/muere-la-madre-de-melania-trump-amalija-knavs\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/10\\\/muere-la-madre-de-melania-trump-amalija-knavs\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-10T13:33:49Z\",\"datePublished\":\"2024-01-10T13:33:49Z\",\"dateModified\":\"2024-01-10T13:33:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470697,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/01\/31\/melania-trump-documental-trax\/","url_meta":{"origin":1443462,"position":0},"title":"He cubierto a Melania Trump durante m\u00e1s de una d\u00e9cada. Esto aprend\u00ed con su documental","author":"","date":"enero 31, 2026","format":false,"excerpt":"\u201cMelania\u201d es una pel\u00edcula que parece un gran y precioso libro de mesa, repleta de im\u00e1genes brillantes, alta costura y una banda sonora cautivadora.Pero, al igual que su protagonista, notoriamente reservada, la pel\u00edcula que se estrena el viernes est\u00e1 cuidadosamente curada y es escasa en contenido, carente de pistas que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470604,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/01\/29\/esperar-documental-melania-trump-trax\/","url_meta":{"origin":1443462,"position":1},"title":"\u00bfQu\u00e9 esperar del documental de Melania Trump? Esto debes saber","author":"","date":"enero 29, 2026","format":false,"excerpt":"Durante d\u00e9cadas, la regla no escrita del ala este de la Casa Blanca fue que la vida privada de una primera dama estadounidense era un regalo para los archivos nacionales, eventualmente intercambiado por unas autobiograf\u00eda pospresidencial.Pero mientras Melania Trump se prepara para caminar por la alfombra roja del recientemente rebautizado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470716,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/01\/31\/reacciones-documental-melania-trump-politica-trax\/","url_meta":{"origin":1443462,"position":2},"title":"De salas vac\u00edas a llenos totales, la respuesta al documental sobre Melania Trump refleja la divisi\u00f3n pol\u00edtica de EE.UU.","author":"","date":"enero 31, 2026","format":false,"excerpt":"Marla Ailor asisti\u00f3 a la investidura del presidente Donald Trump el a\u00f1o pasado con su familia y record\u00f3 haber pensado que fue un d\u00eda largo.As\u00ed que el viernes suspir\u00f3 aliviada mientras ve\u00eda el documental sobre Melania Trump y observaba que, despu\u00e9s de un d\u00eda que incluy\u00f3 tres bailes y regresar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471602,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/02\/24\/melania-trump-invitados-discurso-estado-union-trax\/","url_meta":{"origin":1443462,"position":3},"title":"Melania y Donald Trump rompen la tradici\u00f3n al llevar invitados por separado al discurso del Estado de la Uni\u00f3n","author":"","date":"febrero 24, 2026","format":false,"excerpt":"La primera dama Melania Trump llevar\u00e1 invitados al discurso del Estado de la Uni\u00f3n (SOTU, por sus siglas en ingl\u00e9s) en representaci\u00f3n de sus plataformas sobre el sistema de acogida y la inteligencia artificial responsable, mientras que el presidente Donald Trump ha invitado a su propio grupo de asistentes que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459417,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/03\/03\/melania-trump-declaraciones-victimas-pornografia-trax\/","url_meta":{"origin":1443462,"position":4},"title":"Melania Trump hablar\u00e1 sobre las v\u00edctimas del porno deepfake en sus primeras declaraciones p\u00fablicas del actual mandato","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Se espera que la primera dama Melania Trump hable p\u00fablicamente este lunes por primera vez desde que su marido volvi\u00f3 al cargo, destacando su apoyo a un proyecto de ley destinado a proteger a los estadounidenses de la pornograf\u00eda deepfake y de venganza.Trump celebrar\u00e1 una mesa redonda este lunes en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457748,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/01\/22\/melania-trump-planes-trax\/","url_meta":{"origin":1443462,"position":5},"title":"Melania Trump est\u00e1 llena de planes para el segundo mandato","author":"","date":"enero 22, 2025","format":false,"excerpt":"La primera dama Melania Trump regresa al ala este de la Casa Blanca reforzada por las lecciones de cuatro a\u00f1os en un puesto no electo que, seg\u00fan ha reconocido en privado, fue un torbellino de responsabilidades de las que en gran medida no era consciente.Esta vez, dice, ser\u00e1 diferente.El presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443462"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443462\/revisions"}],"predecessor-version":[{"id":1443478,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443462\/revisions\/1443478"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}