{"id":1443509,"date":"2024-01-11T01:33:41","date_gmt":"2024-01-11T09:33:41","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443509"},"modified":"2024-01-11T01:33:41","modified_gmt":"2024-01-11T09:33:41","slug":"la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","title":{"rendered":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin"},"content":{"rendered":"<p>Nueva York (CNN) &#8212; Despu\u00e9s de una salida en falso el martes, la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s) dio su aprobaci\u00f3n este mi\u00e9rcoles para que algunas empresas de inversi\u00f3n ofrezcan fondos cotizados (ETF) en bolsa de &#171;bitcoin al contado&#187;.<\/p>\n<p>Con esta medida tan esperada, se busca que la inversi\u00f3n en bitcoin sea m\u00e1s accesible para los inversores de a pie, sin necesidad de que posean el activo digital directamente.<\/p>\n<p>El bitcoin se dispara y supera los US$ 40.000<\/p>\n<p>El presidente de la SEC, Gary Gensler, manifest\u00f3 claramente en un comunicado publicado en el sitio web de la SEC que la agencia sigue siendo cautelosa. &#171;Aunque hoy aprobamos la cotizaci\u00f3n y negociaci\u00f3n de determinadas acciones de productos de fondos cotizados de bitcoin al contado, no aprobamos ni respaldamos el bitcoin. Los inversores deben mantener la cautela ante los innumerables riesgos asociados al bitcoin y a los productos cuyo valor est\u00e1 vinculado a las criptomonedas&#187;, escribi\u00f3.<\/p>\n<p>La SEC ten\u00eda de plazo hasta el 10 de enero para ofrecer una decisi\u00f3n a una sola de las 11 empresas que solicitaron ofrecer ETF de bitcoin. El mi\u00e9rcoles ofreci\u00f3 su aprobaci\u00f3n a todas ellas.<\/p>\n<p>Bitcoin, la principal criptomoneda, tiene una capitalizaci\u00f3n de mercado actual de unos US$ 900.000 millones.<\/p>\n<p>A lo largo de sus 15 a\u00f1os de historia ha experimentado oscilaciones vol\u00e1tiles. Recientemente, tras alcanzar un m\u00e1ximo hist\u00f3rico de casi US$ 69.000 en noviembre de 2021, cay\u00f3 por debajo de los US$ 17.000 durante el &#171;criptoinvierno&#187; de 2022 y ha estado cotizando principalmente por encima de los US$ 45.000 en el per\u00edodo previo a la decisi\u00f3n de la SEC.<\/p>\n<p>Aproximadamente una hora despu\u00e9s de la noticia del mi\u00e9rcoles, el precio del bitcoin subi\u00f3 un 0,3%% a casi US$ 46.000, seg\u00fan datos de coinmarketcap.com.<\/p>\n<p>La SEC desmiente informaci\u00f3n publicada por piratas inform\u00e1ticos<\/p>\n<p>Tras el cierre del mercado burs\u00e1til el martes, una publicaci\u00f3n en la cuenta X de la SEC afirmaba falsamente que la agencia reguladora hab\u00eda aprobado la cotizaci\u00f3n y negociaci\u00f3n de productos al contado de bitcoin cotizados en bolsa.<\/p>\n<p>Gensler lo desminti\u00f3 r\u00e1pidamente y la SEC retir\u00f3 el mensaje. Seg\u00fan X, un &#171;individuo no identificado que obtuvo el control de un n\u00famero de tel\u00e9fono asociado a la cuenta @SECGov a trav\u00e9s de un tercero&#187; fue el responsable del mensaje. El mi\u00e9rcoles, la SEC dijo que el FBI estaba investigando el asunto.<\/p>\n<p>Los ETF de bitcoin, como el bitcoin, conllevan riesgos<\/p>\n<p>Para quienes est\u00e9n pensando en subirse al tren del bitcoin, es importante tener en cuenta que el precio del bitcoin ser\u00e1 igual de vol\u00e1til tanto si se invierte directamente en \u00e9l como si se hace a trav\u00e9s de un ETF.<\/p>\n<p>A principios de esta semana, Gensler public\u00f3 un hilo en X en el que advert\u00eda a los inversores de los riesgos de la inversi\u00f3n en criptoactivos en general. &#171;Las inversiones en criptoactivos tambi\u00e9n pueden ser excepcionalmente arriesgadas y a menudo vol\u00e1tiles. Varias plataformas y criptoactivos importantes se han declarado insolventes o han perdido valor. Las inversiones en criptoactivos siguen estando sujetas a un riesgo significativo&#187;.<\/p>\n<p>Esta opini\u00f3n ha sido compartida por muchos asesores financieros y por el grupo de vigilancia de los inversores Better Markets, que se opuso firmemente a la aprobaci\u00f3n de los ETF de bitcoin por parte de la SEC. Entre sus objeciones est\u00e1 el historial del mercado de bitcoins de vol\u00famenes de negociaci\u00f3n inflados artificialmente, conocidos como operaciones de &#171;lavado&#187;.<\/p>\n<p>En una mordaz declaraci\u00f3n tras el anuncio de la SEC, el presidente y CEO del grupo, Dennis Kelleher, no se anduvo con rodeos. &#171;Con la industria de las criptomonedas flagrantemente fuera de la ley estrell\u00e1ndose y ardiendo debido a una monta\u00f1a de arrestos, condenas penales, quiebras, demandas, esc\u00e1ndalos, p\u00e9rdidas masivas y millones de v\u00edctimas de inversores y clientes, \u00bfqui\u00e9n habr\u00eda pensado que la SEC vendr\u00eda a su rescate aprobando un veh\u00edculo de inversi\u00f3n confiable y familiar que permitir\u00e1 la comercializaci\u00f3n masiva de un producto financiero conocido sin valor, vol\u00e1til y lleno de fraude a los estadounidenses de a pie?&#187;.<\/p>\n<p>Por supuesto, hay muchos defensores de las criptomonedas que est\u00e1n muy contentos con la medida. &#171;Un ETF de bitcoin al contado es un puente entre las finanzas tradicionales y el floreciente mundo de las criptomonedas. Permitir a los inversores participar en el viaje de bitcoin sin los obst\u00e1culos t\u00e9cnicos de la propiedad directa es un paso significativo hacia la inclusi\u00f3n&#187;, dijo Sheila Warren, CEO del Crypto Council for Innovation en una declaraci\u00f3n enviada por correo electr\u00f3nico.<\/p>\n<p>La lista completa de empresas que obtuvieron la aprobaci\u00f3n de la SEC para lanzar ETF de bitcoin son: Ark Invest junto con 21 Shares; Bitwise, BlackRock, Fidelity, Franklin Templeton, Grayscale, Hashdex, Invesco, WisdomTree, Valkyrie y VanEck. Algunos de sus ETF empezar\u00e1n a cotizar ma\u00f1ana mismo.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva York (CNN) &#8212; Despu\u00e9s de una salida en falso el martes, la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s) dio su aprobaci\u00f3n este mi\u00e9rcoles para que algunas empresas de inversi\u00f3n ofrezcan fondos cotizados (ETF) en bolsa de &#171;bitcoin al contado&#187;. Con esta medida tan esperada, se busca que la inversi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443509","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nueva York (CNN) &#8212; Despu\u00e9s de una salida en falso el martes, la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s) dio su aprobaci\u00f3n este mi\u00e9rcoles para que algunas empresas de inversi\u00f3n ofrezcan fondos cotizados (ETF) en bolsa de &#171;bitcoin al contado&#187;. Con esta medida tan esperada, se busca que la inversi\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-11T09:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin\",\"datePublished\":\"2024-01-11T09:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/\"},\"wordCount\":872,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/\",\"name\":\"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-11T09:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","og_locale":"es_ES","og_type":"article","og_title":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin - Noticias","og_description":"Nueva York (CNN) &#8212; Despu\u00e9s de una salida en falso el martes, la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s) dio su aprobaci\u00f3n este mi\u00e9rcoles para que algunas empresas de inversi\u00f3n ofrezcan fondos cotizados (ETF) en bolsa de &#171;bitcoin al contado&#187;. Con esta medida tan esperada, se busca que la inversi\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","og_site_name":"Noticias","article_published_time":"2024-01-11T09:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/"},"author":{"name":"","@id":""},"headline":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin","datePublished":"2024-01-11T09:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/"},"wordCount":872,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","url":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","name":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-11T09:33:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-11T09:33:41Z","datePublished":"2024-01-11T09:33:41Z","dateModified":"2024-01-11T09:33:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Comisi\\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/11\\\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/11\\\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-11T09:33:41Z\",\"datePublished\":\"2024-01-11T09:33:41Z\",\"dateModified\":\"2024-01-11T09:33:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446087,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/28\/bitcoin-maximo-historico-precio-trax\/","url_meta":{"origin":1443509,"position":0},"title":"\u00bfBitcoin en la luna? Las razones por las que est\u00e1 cerca de un m\u00e1ximo hist\u00f3rico","author":"","date":"febrero 28, 2024","format":false,"excerpt":"(CNN) -- El mes pasado, cuando el bitcoin se acercaba a los US$ 45.000, el director ejecutivo de JPMorgan Chase, Jamie Dimon, compar\u00f3 la criptomoneda con una Pet Rock y dijo que la gente deb\u00eda \u201cdejar de hablar de esa m\u2026\u201d.Ahora, los inversores en bitcoin se est\u00e1n riendo a carcajadas.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455950,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/11\/20\/bitcoin-rompiendo-records-invertir-trax\/","url_meta":{"origin":1443509,"position":1},"title":"El bitcoin rompe r\u00e9cords, \u00bfes buen momento para invertir?","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) -- En el primer trimestre de este a\u00f1o, el precio del bitcoin bati\u00f3 r\u00e9cords tras la aprobaci\u00f3n por parte de la Comisi\u00f3n del Mercado de Valores de los primeros fondos de bitcoin al contado cotizados en bolsa. La criptomoneda super\u00f3 los US$ 70.000 en marzo, seg\u00fan coinmarketcap.com.Despu\u00e9s, con los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456272,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/12\/04\/bitcoin-alcanza-100000-la-administracion-pro-cripto-trump-trax\/","url_meta":{"origin":1443509,"position":2},"title":"Bitcoin alcanza los US$ 100.000 mientras se forma la administraci\u00f3n pro-cripto de Trump","author":"","date":"diciembre 4, 2024","format":false,"excerpt":"Bitcoin alcanz\u00f3 los US$ 100.000 por primera vez este mi\u00e9rcoles, subiendo a un nuevo r\u00e9cord despu\u00e9s de que el presidente electo de Estados Unidos, Donald Trump, revelara selecciones para su administraci\u00f3n que se consideran claves para introducir pol\u00edticas favorables a las criptomonedas cuando asuma el cargo en enero.Entre las selecciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456297,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/12\/05\/nayib-bukele-celebra-aumento-valor-bitcoin-orix\/","url_meta":{"origin":1443509,"position":3},"title":"Presidente de El Salvador, Nayib Bukele, celebra el aumento del valor del bitcoin","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"El presidente de El Salvador, Nayib Bukele, celebr\u00f3 este jueves el aumento de la cotizaci\u00f3n del bitcoin, que alcanz\u00f3 los US$ 100.000 este mi\u00e9rcoles.\u201cLas reservas de Bitcoin de nuestro pa\u00eds ahora valen un 127,30% m\u00e1s de lo que pagamos por ellas, lo que significa un incremento de m\u00e1s de US$\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468471,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","url_meta":{"origin":1443509,"position":4},"title":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"El bitcoin y las acciones est\u00e1n en ca\u00edda y los inversionistas dicen que podr\u00eda haber m\u00e1s turbulencia en el futuro.Las acciones en EE.UU. bajaron el martes, extendiendo una reciente racha de ca\u00eddas.El Dow cay\u00f3 413 puntos, o 0,89 %. El S&P 500 baj\u00f3 0,6 %. El Nasdaq Composite, de fuerte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459464,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/03\/04\/trump-cripto-presidente-reserva-estrategica-trax\/","url_meta":{"origin":1443509,"position":5},"title":"El criptopresidente tiene algunas ideas para tus impuestos","author":"","date":"marzo 4, 2025","format":false,"excerpt":"Cuando el presidente Donald Trump se dirija a la naci\u00f3n desde el Capitolio este martes, tendr\u00e1 la primera oportunidad de vender a los estadounidenses y al Congreso su nueva propuesta de que Estados Unidos necesita crear una reserva estrat\u00e9gica de criptodivisas.Se trata de un plan \u2013desvelado el domingo en un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443509"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443509\/revisions"}],"predecessor-version":[{"id":1443525,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443509\/revisions\/1443525"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}