{"id":1443516,"date":"2024-01-11T05:33:29","date_gmt":"2024-01-11T13:33:29","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443516"},"modified":"2024-01-11T05:33:29","modified_gmt":"2024-01-11T13:33:29","slug":"cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/","title":{"rendered":"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La situaci\u00f3n de violencia e inseguridad en Ecuador escal\u00f3 a tal punto que el Gobierno de Daniel Noboa decret\u00f3 el estado de excepci\u00f3n y la existencia de un conflicto armado interno en el pa\u00eds, despu\u00e9s de que el l\u00edder de un grupo criminal se fugara de la c\u00e1rcel y se desataran incidentes en varias prisiones. Pero eso fue solo el principio.<\/p>\n<p>\u00daltima hora de la violencia en Ecuador y el conflicto armado interno, en vivo: noticias y m\u00e1s<\/p>\n<p>As\u00ed ha sido, d\u00eda a d\u00eda, la escalada de violencia en Ecuador:<\/p>\n<p>Domingo 7 de enero: la fuga de Adolfo Mac\u00edas, alias \u201cFito\u201d, enciende las alarmas en Ecuador<\/p>\n<p>La Fiscal\u00eda y el Gobierno de Ecuador confirmaron la fuga de Adolfo Mac\u00edas, alias \u201cFito\u201d, de la c\u00e1rcel regional de Guayaquil. &#171;Fito&#187; es es el presunto l\u00edder del grupo criminal Los Choneros, una de las bandas m\u00e1s temidas de las que operan en Ecuador, vinculada al tr\u00e1fico mar\u00edtimo de drogas hacia M\u00e9xico y Estados Unidos en coordinaci\u00f3n con el c\u00e1rtel de Sinaloa en M\u00e9xico y el Frente Oliver Sinisterra en Colombia, seg\u00fan el centro de investigaci\u00f3n Insight Crime.<\/p>\n<p>Foto de Adolfo Mac\u00edas, alias &#171;Fito&#187;, difundida por el Ministerio del Interior de Ecuador en 2013. (Cr\u00e9dito: Gobierno ecuatoriano)<\/p>\n<p>M\u00e1s de 3.000 polic\u00edas y miembros de las Fuerzas Armadas fueron desplegados para buscarlo, dijo el Gobierno.<\/p>\n<p>Tras la fuga del narcotraficante, Noboa convoc\u00f3 a los funcionarios del Consejo de Seguridad P\u00fablica y del Estado a una reuni\u00f3n urgente para abordar la situaci\u00f3n de seguridad en el pa\u00eds.<\/p>\n<p>\u00bfQui\u00e9n es &#171;Fito&#187;, el pr\u00f3fugo m\u00e1s buscado de Ecuador?<\/p>\n<p>Al terminar el encuentro, el Servicio de Atenci\u00f3n a Personas Privadas de la Libertad (SNAI) puso en marcha, en coordinaci\u00f3n con la Polic\u00eda y las Fuerzas Armadas, una intervenci\u00f3n en la c\u00e1rcel regional de Guayaquil para el control y decomiso de armas y art\u00edculos prohibidos.<\/p>\n<p>Lunes 8 de enero: Noboa decreta el estado de excepci\u00f3n y toque de queda<\/p>\n<p>Noboa firma un decreto de estado de excepci\u00f3n para todo el pa\u00eds, incluidas las c\u00e1rceles, argumentando &#171;grave conmoci\u00f3n interna&#187;.<\/p>\n<p>El estado de excepci\u00f3n incluye, adem\u00e1s, el toque de queda para limitar las reuniones y acciones que puedan atentar contra el orden p\u00fablico. Restringe la libertad de tr\u00e1nsito todos los d\u00edas desde las 11:00 p.m. hasta las 5:00 a.m.<\/p>\n<p>En tanto, el SNAI informa incidentes, disturbios y retenci\u00f3n de agentes penitenciarios en al menos seis c\u00e1rceles del pa\u00eds.<\/p>\n<p>As\u00ed funciona el estado de excepci\u00f3n en Ecuador: restricciones, horarios y duraci\u00f3n<\/p>\n<p>Por su parte, las Fuerzas Armadas realizan operativos de control de armas, municiones y explosivos al interior de la C\u00e1rcel Regional de Guayaquil, penal del que se fug\u00f3 alias \u201cFito\u201d.<\/p>\n<p>Algunos ciudadanos que hablaron con CNN describieron &#171;una noche de terror&#187; en varias regiones de Ecuador la noche del lunes y madrugada del martes.<\/p>\n<p>Martes 9 de enero: hombres encapuchados irrumpen en vivo en un canal de televisi\u00f3n<\/p>\n<p>Hombres armados y encapuchados irrumpen en el canal TC Televisi\u00f3n, en Guayaquil, durante una transmisi\u00f3n en vivo.<\/p>\n<p>Las im\u00e1genes transmitidas por la cadena de televisi\u00f3n la tarde de este martes parec\u00edan mostrar que los individuos secuestraron a varias personas que ser\u00edan empleados del lugar. Los hombres encapuchados obligaron al personal a tirarse al suelo mientras se escuchaban disparos y gritos, seg\u00fan muestra un video difundido en redes sociales.<\/p>\n<p>Hombres encapuchados toman las instalaciones de TC Televisi\u00f3n en Ecuador. La Polic\u00eda arresta a varias personas<\/p>\n<p>La Polic\u00eda de Ecuador activ\u00f3 un importante operativo y logr\u00f3 &#171;la aprehensi\u00f3n de varios sujetos e indicios vinculados&#187; a la situaci\u00f3n, seg\u00fan inform\u00f3 en redes sociales.<\/p>\n<p>Momentos despu\u00e9s de la toma del canal, Noboa decreta la existencia de un &#171;conflicto armado interno&#187;, adicional al estado de excepci\u00f3n, que habilita la movilizaci\u00f3n inmediata y la intervenci\u00f3n de las Fuerzas Armadas contra el crimen organizado en el territorio nacional.<\/p>\n<p>Mediante este decreto, el presidente de Ecuador ordena &#171;neutralizar&#187; a 22 organizaciones a las que calific\u00f3 de &#171;terroristas y actores no estatales&#187; beligerantes.<\/p>\n<p>Al menos ocho personas mueren tras los violentos ataques en Guayaquil, aseguraron funcionarios en conferencia de prensa.<\/p>\n<p>Tambi\u00e9n se produjeron explosiones e incendios de veh\u00edculos\u00a0en distintos lugares del pa\u00eds, y las autoridades anuncian la fuga de la prisi\u00f3n de Riobamba de Fabricio Col\u00f3n Pico, alias \u201cCapit\u00e1n Pico\u201d, presunto cabecilla de la banda Los Lobos.<\/p>\n<p>El crudo relato de un conductor tras el asalto a TC Televisi\u00f3n 3:02<\/p>\n<p>Mi\u00e9rcoles 10 de enero: detienen a m\u00e1s de 300 \u201cterroristas\u201d y sigue la b\u00fasqueda de &#171;Fito&#187; y Col\u00f3n Pico<\/p>\n<p>Noboa asegura en Radio Canela que su Gobierno est\u00e1 &#171;en cacer\u00eda activa por Col\u00f3n Pico, por &#8216;Fito&#8217; y otros objetivos de alto valor&#187;. Adem\u00e1s, el presidente reitera que en Ecuador hay un estado de guerra y que no se puede &#171;ceder ante estos grupos terroristas&#187;.<\/p>\n<p>Horas m\u00e1s tarde, las Fuerzas Armadas aseguran que, tras varios operativos en todo el territorio nacional, abatieron a cinco &#171;terroristas&#187; y capturaron a otros 329.<\/p>\n<p>Con informaci\u00f3n de Ana Mar\u00eda Ca\u00f1izares, Karol Su\u00e1rez, Michael R\u00edos y Hande Atay Alam<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La situaci\u00f3n de violencia e inseguridad en Ecuador escal\u00f3 a tal punto que el Gobierno de Daniel Noboa decret\u00f3 el estado de excepci\u00f3n y la existencia de un conflicto armado interno en el pa\u00eds, despu\u00e9s de que el l\u00edder de un grupo criminal se fugara de la c\u00e1rcel y se desataran incidentes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443516","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La situaci\u00f3n de violencia e inseguridad en Ecuador escal\u00f3 a tal punto que el Gobierno de Daniel Noboa decret\u00f3 el estado de excepci\u00f3n y la existencia de un conflicto armado interno en el pa\u00eds, despu\u00e9s de que el l\u00edder de un grupo criminal se fugara de la c\u00e1rcel y se desataran incidentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-11T13:33:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado\",\"datePublished\":\"2024-01-11T13:33:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/\"},\"wordCount\":938,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/\",\"name\":\"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-11T13:33:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/","og_locale":"es_ES","og_type":"article","og_title":"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La situaci\u00f3n de violencia e inseguridad en Ecuador escal\u00f3 a tal punto que el Gobierno de Daniel Noboa decret\u00f3 el estado de excepci\u00f3n y la existencia de un conflicto armado interno en el pa\u00eds, despu\u00e9s de que el l\u00edder de un grupo criminal se fugara de la c\u00e1rcel y se desataran incidentes [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/","og_site_name":"Noticias","article_published_time":"2024-01-11T13:33:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/"},"author":{"name":"","@id":""},"headline":"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado","datePublished":"2024-01-11T13:33:29+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/"},"wordCount":938,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/","name":"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-11T13:33:29+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-11T13:33:29Z","datePublished":"2024-01-11T13:33:29Z","dateModified":"2024-01-11T13:33:29Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cronolog\\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/11\\\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/11\\\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-11T13:33:29Z\",\"datePublished\":\"2024-01-11T13:33:29Z\",\"dateModified\":\"2024-01-11T13:33:29Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443510,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/11\/cronologia-de-la-escalada-de-violencia-en-ecuador-esto-es-lo-que-ha-pasado\/","url_meta":{"origin":1443516,"position":0},"title":"Cronolog\u00eda de la escalada de violencia en Ecuador: esto es lo que ha pasado","author":"","date":"enero 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La situaci\u00f3n de violencia e inseguridad en Ecuador escal\u00f3 a tal punto que el Gobierno de Daniel Noboa decret\u00f3 el estado de excepci\u00f3n y la existencia de un conflicto armado interno en el pa\u00eds, despu\u00e9s de que el l\u00edder de un grupo criminal se fugara de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459707,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/","url_meta":{"origin":1443516,"position":1},"title":"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &#171;Fito&#187;, el m\u00e1s buscado del pa\u00eds","author":"","date":"marzo 9, 2025","format":false,"excerpt":"El Ministerio del Interior de Ecuador inform\u00f3 este domingo que subi\u00f3 a U$ 1 mill\u00f3n el monto de la recompensa para quien proporcione informaci\u00f3n sobre el paradero de Adolfo Mac\u00edas, alias \u201cFito\u201d, l\u00edder de la banda delictiva de Los Choneros y el pr\u00f3fugo m\u00e1s buscado de Ecuador desde enero de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463956,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/06\/25\/capturan-adolfo-macias-fito-lider-banda-choneros-ecuador-orix\/","url_meta":{"origin":1443516,"position":2},"title":"Capturan a &#171;Fito&#187;, l\u00edder de la banda Los Choneros y uno de los criminales m\u00e1s buscados de Ecuador","author":"","date":"junio 25, 2025","format":false,"excerpt":"Adolfo Mac\u00edas, alias \u201cFito\u201d, l\u00edder de la temida banda delictiva Los Choneros y uno de los hombres m\u00e1s buscados del pa\u00eds ha sido capturado, seg\u00fan dijo este mi\u00e9rcoles el presidente Daniel Noboa.\u201cFito\u201d se encontraba pr\u00f3fugo desde enero de 2024 cuando se conoci\u00f3 que huy\u00f3 de la C\u00e1rcel Regional de Guayaquil,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463955,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/06\/25\/quien-es-alias-fito-lider-choneros-ecuador-orix\/","url_meta":{"origin":1443516,"position":3},"title":"\u00bfQui\u00e9n es alias Fito? Estos son los hechos que han marcado su vida criminal en Ecuador","author":"","date":"junio 25, 2025","format":false,"excerpt":"Hablar de Jos\u00e9 Adolfo Mac\u00edas Villamar, m\u00e1s conocido como Fito, es hablar de uno de los criminales m\u00e1s temidos del Ecuador. Fue capturado por las autoridades de Ecuador el 25 de junio, seg\u00fan inform\u00f3 el presidente Daniel Noboa.El criminal logr\u00f3 poner en jaque al sistema de seguridad desde hace varios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449417,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/05\/12\/argentina-expulsa-personas-vinculadas-fito-profugo-orix\/","url_meta":{"origin":1443516,"position":4},"title":"Argentina expulsa a dos personas presuntamente vinculadas a alias &#171;Fito&#187;, el pr\u00f3fugo m\u00e1s buscado de Ecuador","author":"","date":"mayo 12, 2024","format":false,"excerpt":"(CNN) -- Argentina expuls\u00f3 hacia Ecuador a dos personas por presuntamente estar vinculadas directamente con Jos\u00e9 Adolfo Mac\u00edas Villamar, alias \u201cFito\u201d, el l\u00edder de la banda criminal Los Choneros y considerado como el pr\u00f3fugo m\u00e1s buscado en territorio ecuatoriano tras fugarse de una prisi\u00f3n en enero.En un comunicado conjunto, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463957,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/06\/25\/los-choneros-banda-criminal-fito-orix\/","url_meta":{"origin":1443516,"position":5},"title":"\u00bfQui\u00e9nes son Los Choneros, la banda criminal de alias Fito?","author":"","date":"junio 25, 2025","format":false,"excerpt":"Las autoridades de Ecuador capturaron este mi\u00e9rcoles a Adolfo Mac\u00edas, alias Fito, quien se fug\u00f3 de una c\u00e1rcel de Guayaquil en 2024, inform\u00f3 el presidente Daniel Noboa.Mac\u00edas es el presunto l\u00edder de la temida banda delictiva Los Choneros, una de las pandillas m\u00e1s temidas de Ecuador, y uno de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443516"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443516\/revisions"}],"predecessor-version":[{"id":1443532,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443516\/revisions\/1443532"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}