{"id":1443559,"date":"2024-01-12T01:33:28","date_gmt":"2024-01-12T09:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443559"},"modified":"2024-01-12T01:33:28","modified_gmt":"2024-01-12T09:33:28","slug":"crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/","title":{"rendered":"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos?"},"content":{"rendered":"<p>(CNN) &#8212; Los rebeldes hut\u00edes de Yemen, respaldados por Ir\u00e1n, est\u00e1n intensificando sus ataques contra barcos en el mar Rojo, que, seg\u00fan dicen, son una venganza contra Israel por su campa\u00f1a militar en Gaza.<\/p>\n<p>Los ataques han obligado a algunas de las compa\u00f1\u00edas navieras y petroleras m\u00e1s grandes del mundo a suspender el tr\u00e1nsito a trav\u00e9s de una de las rutas comerciales mar\u00edtimas m\u00e1s importantes del mundo, lo que podr\u00eda causar un shock a la econom\u00eda global.<\/p>\n<p>Se cree que los hut\u00edes han sido armados y entrenados por Ir\u00e1n, y se teme que sus ataques puedan llevar la guerra de Israel contra Hamas a un conflicto regional m\u00e1s amplio.<\/p>\n<p>Suben los precios del petr\u00f3leo y el gas, al tiempo que BP frena sus env\u00edos en el mar Rojo tras los ataques de los hut\u00edes<\/p>\n<p>Esto es lo que sabemos sobre los hut\u00edes y por qu\u00e9 se est\u00e1n involucrando en la guerra.<\/p>\n<p>\u00bfQui\u00e9nes son los hut\u00edes?<\/p>\n<p>El movimiento hut\u00ed, tambi\u00e9n conocido como Ansarallah (Partidarios de Dios), es un bando de la guerra civil yemen\u00ed que se ha prolongado durante casi una d\u00e9cada. Surgi\u00f3 en la d\u00e9cada de 1990, cuando su l\u00edder, Hussein al-Houthi, lanz\u00f3 la \u201cJuventud Creyente\u201d, un movimiento de resurgimiento religioso de una subsecta centenaria del Islam chiita llamada zaidismo.<\/p>\n<p>Los zaidis gobernaron Yemen durante siglos, pero fueron marginados bajo el r\u00e9gimen sunita que lleg\u00f3 al poder despu\u00e9s de la guerra civil de 1962. El movimiento de Al-Houthi fue fundado para representar a los zaidis y resistir al sunnismo radical, en particular a las ideas wahab\u00edes de Arabia Saudita. Sus seguidores m\u00e1s cercanos pasaron a ser conocidos como hut\u00edes.<\/p>\n<p>Combatientes reci\u00e9n reclutados que se unieron a una fuerza hut\u00ed destinada a ser enviada a luchar en apoyo de los palestinos en Gaza marchan en Sana, Yemen, el 2 de diciembre de 2023. (Cr\u00e9dito: Khaled Abdullah\/Reuters)<\/p>\n<p>\u00bfC\u00f3mo llegaron al poder?<\/p>\n<p>Ali Abdullah Saleh, el primer presidente de Yemen despu\u00e9s de la unificaci\u00f3n de Yemen del Norte y del Sur en 1990, inicialmente apoy\u00f3 a la Juventud Creyente. Pero a medida que la popularidad del movimiento creci\u00f3 y la ret\u00f3rica antigubernamental se agudiz\u00f3, se convirti\u00f3 en una amenaza para Saleh. Las cosas llegaron a un punto cr\u00edtico en 2003, cuando Saleh apoy\u00f3 la invasi\u00f3n estadounidense de Iraq, a la que muchos yemen\u00edes se opusieron.<\/p>\n<p>\u00bfPor qu\u00e9 hay guerra en Yemen? De la crisis humanitaria a la creciente conexi\u00f3n con el conflicto entre Israel y Hamas<\/p>\n<p>Para al-Houthi, la ruptura fue una oportunidad. Aprovechando la indignaci\u00f3n p\u00fablica, organiz\u00f3 manifestaciones masivas. Despu\u00e9s de meses de desorden, Saleh emiti\u00f3 una orden de arresto.<\/p>\n<p>Los combatientes hut\u00edes tomaron el control del carguero Galaxy Leader en el mar Rojo el 20 de noviembre de 2023. (Cr\u00e9dito: Houthi Movement via Getty Images)<\/p>\n<p>Al-Houthi fue asesinado en septiembre de 2004 por las fuerzas yemen\u00edes, pero su movimiento sigui\u00f3 vivo. El ala militar hut\u00ed creci\u00f3 a medida que m\u00e1s combatientes se unieron a la causa. Envalentonados por las primeras protestas de la Primavera \u00c1rabe en 2011, tomaron el control de la provincia norte\u00f1a de Saada y pidieron el fin del r\u00e9gimen de Saleh.<\/p>\n<p>\u00bfLos hut\u00edes controlan Yemen?<\/p>\n<p>Saleh acord\u00f3 en 2011 entregar el poder a su vicepresidente Abd-Rabbu Mansour Hadi, pero este Gobierno no era m\u00e1s popular. Los hut\u00edes atacaron nuevamente en 2014, tomando el control de partes de Sana, la capital de Yemen, antes de finalmente asaltar el palacio presidencial a principios del a\u00f1o siguiente.<\/p>\n<p>Hadi huy\u00f3 a Arabia Saudita, que lanz\u00f3 una guerra contra los hut\u00edes a petici\u00f3n suya en marzo de 2015. Lo que se esperaba que fuera una campa\u00f1a r\u00e1pida dur\u00f3 a\u00f1os: finalmente se firm\u00f3 un alto el fuego en 2022. Caduc\u00f3 despu\u00e9s de seis meses, pero las partes en conflicto no lo han hecho. Regres\u00f3 al conflicto a gran escala.<\/p>\n<p>Las Naciones Unidas han dicho que la guerra en Yemen se ha convertido en la peor crisis humanitaria del mundo. Seg\u00fan estad\u00edsticas de la ONU, casi un cuarto de mill\u00f3n de personas han muerto durante el conflicto.<\/p>\n<p>Desde el alto el fuego, los hut\u00edes han consolidado su control sobre la mayor parte del norte de Yemen. Tambi\u00e9n han buscado un acuerdo con los saud\u00edes que pondr\u00eda fin permanentemente a la guerra y consolidar\u00eda su papel como gobernantes del pa\u00eds.<\/p>\n<p>\u00bfQui\u00e9nes son sus aliados?<\/p>\n<p>Los hut\u00edes cuentan con el respaldo de Ir\u00e1n, que comenz\u00f3 a aumentar su ayuda al grupo en 2014 a medida que se intensificaba la guerra civil y se intensificaba su rivalidad con Arabia Saudita. Ir\u00e1n ha proporcionado al grupo armas y tecnolog\u00eda para, entre otras cosas, minas marinas, misiles bal\u00edsticos y de crucero y veh\u00edculos a\u00e9reos no tripulados (UAV o drones), seg\u00fan un informe de 2021 del Centro de Estudios Estrat\u00e9gicos e Internacionales.<\/p>\n<p>Combatientes hut\u00edes marchan en apoyo de los palestinos en Gaza, en un desfile en Sana, Yemen, el 2 de diciembre de 2023. (Cr\u00e9dito: Khaled Abdullah\/Reuters)<\/p>\n<p>Los hut\u00edes forman parte del llamado \u201cEje de Resistencia\u201d de Ir\u00e1n, una alianza de milicias regionales antiisrael\u00edes y antioccidentales liderada por Ir\u00e1n y respaldada por la Rep\u00fablica Isl\u00e1mica. Junto con Hamas en Gaza y Hezbollah en el L\u00edbano, los hut\u00edes son una de las tres milicias prominentes respaldadas por Ir\u00e1n que han lanzado ataques contra Israel en las \u00faltimas semanas.<\/p>\n<p>\u00bfQu\u00e9 tan poderosos son los hut\u00edes?<\/p>\n<p>Los funcionarios estadounidenses han estado siguiendo mejoras iterativas en el alcance, la precisi\u00f3n y la letalidad de los misiles de producci\u00f3n nacional de los hut\u00edes. Inicialmente, las armas hut\u00edes de cosecha propia se ensamblaban en gran medida con componentes iran\u00edes introducidos de contrabando en Yemen en piezas, dijo anteriormente a CNN un funcionario familiarizado con la inteligencia estadounidense.<\/p>\n<p>Pero han realizado modificaciones progresivas que han resultado en grandes mejoras generales, dijo el funcionario. En un hecho novedoso, los hut\u00edes han utilizado misiles bal\u00edsticos de mediano alcance contra Israel, disparando una andanada de proyectiles contra la regi\u00f3n meridional de Eilat en Israel a principios de diciembre, que Israel dijo haber interceptado.<\/p>\n<p>Guerra entre Israel y Hamas en vivo: combates en Gaza, situaci\u00f3n de los civiles y m\u00e1s<\/p>\n<p>Si bien es posible que los hut\u00edes no puedan representar una amenaza grave para Israel, su tecnolog\u00eda puede causar estragos en el mar Rojo. Han utilizado drones y misiles antibuque para atacar barcos comerciales (algunos de los cuales no se cree que est\u00e9n vinculados con Israel), lo que llev\u00f3 al USS Carney, un buque de guerra en el mar Rojo, a responder a las llamadas de socorro.<\/p>\n<p>\u00bfPor qu\u00e9 los hut\u00edes atacan barcos en el mar Rojo?<\/p>\n<p>Si bien, debido a una combinaci\u00f3n de geograf\u00eda y tecnolog\u00eda, los hut\u00edes pueden carecer de las capacidades de Hamas y Hezbollah, sus ataques a buques comerciales en el mar Rojo pueden infligir un tipo diferente de dolor a Israel y sus aliados.<\/p>\n<p>La econom\u00eda mundial ha recibido una serie de dolorosos recordatorios de la importancia de esta estrecha franja de mar, que se extiende desde el estrecho de Bab-el-Mandeb frente a la costa de Yemen hasta el Canal de Suez en el norte de Egipto; a trav\u00e9s del cual pasa el 12% de los\u00a0flujos comerciales globales, incluido el 30% del tr\u00e1fico mundial de contenedores.<\/p>\n<p>En 2021, un barco llamado Ever Given encall\u00f3 en el Canal de Suez, bloqueando la vital arteria comercial durante casi una semana (reteniendo hasta US$ 10.000 millones en carga cada d\u00eda) y causando interrupciones en las cadenas de suministro globales que duraron mucho m\u00e1s.<\/p>\n<p>Se teme que los ataques con aviones no tripulados y misiles hut\u00edes contra buques comerciales, que se han producido casi a diario desde el 9 de diciembre, puedan causar un shock a\u00fan mayor a la econom\u00eda mundial.<\/p>\n<p>Cuatro de las cinco principales empresas navieras del mundo (Maersk, Hapag-Lloyd, CMA CGM Group y Evergreen) han anunciado que suspender\u00e1n los env\u00edos a trav\u00e9s del mar Rojo en medio de temores de ataques hut\u00edes. El gigante petrolero BP dijo este lunes que har\u00eda lo mismo, una medida que provoc\u00f3 un aumento en los precios del petr\u00f3leo y el gas.<\/p>\n<p>Los ataques podr\u00edan obligar a los barcos a tomar una ruta mucho m\u00e1s larga alrededor de \u00c1frica y provocar que los costos de los seguros se disparen. Las empresas podr\u00edan trasladar el mayor costo de transportar sus productos a los consumidores, elevando nuevamente los precios en un momento en que los gobiernos de todo el mundo han luchado por controlar la inflaci\u00f3n pospand\u00e9mica.<\/p>\n<p>Los hut\u00edes dicen que s\u00f3lo ceder\u00e1n cuando Israel permita la entrada de alimentos y medicinas a Gaza; sus ataques podr\u00edan tener como objetivo infligir dolor econ\u00f3mico a los aliados de Israel con la esperanza de que lo presionen para que cese el bombardeo del enclave.<\/p>\n<p>Defender la causa palestina tambi\u00e9n podr\u00eda ser un intento de ganar legitimidad en casa y en la regi\u00f3n mientras buscan controlar el norte de Yemen. Tambi\u00e9n podr\u00eda darles ventaja frente a sus adversarios \u00e1rabes, Arabia Saudita y los Emiratos \u00c1rabes Unidos, a quienes acusan de ser lacayos de Estados Unidos e Israel.<\/p>\n<p>\u00bfC\u00f3mo ha reaccionado el mundo?<\/p>\n<p>Los ataques podr\u00edan tener como objetivo arrastrar a m\u00e1s pa\u00edses al conflicto. Israel ha advertido que est\u00e1 dispuesto a actuar contra los hut\u00edes si la comunidad internacional no lo hace. El asesor de seguridad nacional, Tzachi Hanegbi, dijo este mes que es necesario un \u201cacuerdo global\u201d para abordar la amenaza \u201cporque es un problema global\u201d, refiri\u00e9ndose a los ataques hut\u00edes como un \u201casedio naval\u201d.<\/p>\n<p>Estados Unidos anunci\u00f3 el lunes un nuevo grupo de trabajo naval multinacional compuesto por el Reino Unido, Bahr\u00e9in, Canad\u00e1, Francia, Noruega y otros, para &#171;afrontar el desaf\u00edo planteado por este actor no estatal&#187; que &#171;amenaza el libre flujo del comercio, pone en peligro a personas inocentes y marineros y viola el derecho internacional\u201d.<\/p>\n<p>Mohammed al-Bukhaiti, un portavoz hut\u00ed, dijo a Al Jazeera el lunes que el grupo se enfrentar\u00eda a cualquier coalici\u00f3n liderada por Estados Unidos en el Mar Rojo.<\/p>\n<p>Justo cuando la administraci\u00f3n Biden est\u00e1 empezando a ceder a la presi\u00f3n para que presione a Israel para que ponga fin a su campa\u00f1a en Gaza, Estados Unidos puede verse arrastrado m\u00e1s profundamente hacia el Medio Oriente por los heterog\u00e9neos \u2013pero efectivos\u2013 rebeldes hut\u00edes que se han hecho a s\u00ed mismos imposibles de ignorar.<\/p>\n<p>Katie Bo Lillis y Natasha Bertrand de CNN contribuyeron con el reportaje.<\/p>\n<p>Este art\u00edculo fue publicado el 19 de diciembre de 2023 y ha sido actualizado<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los rebeldes hut\u00edes de Yemen, respaldados por Ir\u00e1n, est\u00e1n intensificando sus ataques contra barcos en el mar Rojo, que, seg\u00fan dicen, son una venganza contra Israel por su campa\u00f1a militar en Gaza. Los ataques han obligado a algunas de las compa\u00f1\u00edas navieras y petroleras m\u00e1s grandes del mundo a suspender el tr\u00e1nsito a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443559","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los rebeldes hut\u00edes de Yemen, respaldados por Ir\u00e1n, est\u00e1n intensificando sus ataques contra barcos en el mar Rojo, que, seg\u00fan dicen, son una venganza contra Israel por su campa\u00f1a militar en Gaza. Los ataques han obligado a algunas de las compa\u00f1\u00edas navieras y petroleras m\u00e1s grandes del mundo a suspender el tr\u00e1nsito a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-12T09:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos?\",\"datePublished\":\"2024-01-12T09:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/\"},\"wordCount\":1874,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/\",\"name\":\"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-12T09:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/","og_locale":"es_ES","og_type":"article","og_title":"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos? - Noticias","og_description":"(CNN) &#8212; Los rebeldes hut\u00edes de Yemen, respaldados por Ir\u00e1n, est\u00e1n intensificando sus ataques contra barcos en el mar Rojo, que, seg\u00fan dicen, son una venganza contra Israel por su campa\u00f1a militar en Gaza. Los ataques han obligado a algunas de las compa\u00f1\u00edas navieras y petroleras m\u00e1s grandes del mundo a suspender el tr\u00e1nsito a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/","og_site_name":"Noticias","article_published_time":"2024-01-12T09:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/"},"author":{"name":"","@id":""},"headline":"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos?","datePublished":"2024-01-12T09:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/"},"wordCount":1874,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/","url":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/","name":"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-12T09:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos?","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-12T09:33:28Z","datePublished":"2024-01-12T09:33:28Z","dateModified":"2024-01-12T09:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Crisis del mar Rojo: \\u00bfqui\\u00e9nes son los hut\\u00edes y por qu\\u00e9 atacan a los barcos?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/12\\\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/12\\\/crisis-del-mar-rojo-quienes-son-los-huties-y-por-que-atacan-a-los-barcos\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-12T09:33:28Z\",\"datePublished\":\"2024-01-12T09:33:28Z\",\"dateModified\":\"2024-01-12T09:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459971,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/03\/15\/trump-accion-militar-contra-huties-yemen-orix\/","url_meta":{"origin":1443559,"position":0},"title":"Trump dice que est\u00e1 en marcha una acci\u00f3n militar &#171;decisiva&#187; contra los hut\u00edes en Yemen","author":"","date":"marzo 15, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, dice que orden\u00f3 una acci\u00f3n militar \u201cdecisiva\u201d contra los rebeldes hut\u00edes en Yemen, abriendo un nuevo ataque contra el grupo respaldado por Ir\u00e1n que ha apuntado a las rutas de navegaci\u00f3n en el mar Rojo.Trump dijo que EE.UU. desplegar\u00e1 una \u201cfuerza letal abrumadora\u201d contra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443576,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/estados-unidos-y-reino-unido-lanzan-ataques-en-yemen-contra-huties-respaldados-por-iran-4\/","url_meta":{"origin":1443559,"position":1},"title":"Estados Unidos y Reino Unido lanzan ataques en Yemen contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443584,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran\/","url_meta":{"origin":1443559,"position":2},"title":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443603,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/","url_meta":{"origin":1443559,"position":3},"title":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445899,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/21\/ee-uu-realiza-ataques-buque-submarino-huties-primera-vez-mar-rojo-trax\/","url_meta":{"origin":1443559,"position":4},"title":"EE.UU. ataca dron sumergible de los hut\u00edes por primera vez desde que comenzaron los embates en el mar Rojo","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Estados Unidos realiz\u00f3 el s\u00e1bado ataques contra misiles de crucero antibuque y barcos de los hut\u00edes, incluido la primera nave sumergible no tripulada que el grupo rebelde respaldado por Ir\u00e1n ha utilizado desde que comenzaron los ataques en el mar Rojo, seg\u00fan el Comando Central estadounidense (CENTCOM, por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443564,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/estados-unidos-y-reino-unido-lanzan-ataques-en-yemen-contra-huties-respaldados-por-iran\/","url_meta":{"origin":1443559,"position":5},"title":"Estados Unidos y Reino Unido lanzan ataques en Yemen contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Los ej\u00e9rcitos de Estados Unidos y Reino Unido lanzaron ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, dijeron a CNN un funcionario estadounidense y un funcionario brit\u00e1nicoLos ataques se realizaron con aviones de combate y misiles Tomahawk. M\u00e1s de una docena de objetivos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443559"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443559\/revisions"}],"predecessor-version":[{"id":1443575,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443559\/revisions\/1443575"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}