{"id":1443599,"date":"2024-01-12T19:33:32","date_gmt":"2024-01-13T03:33:32","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443599"},"modified":"2024-01-12T19:33:32","modified_gmt":"2024-01-13T03:33:32","slug":"analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/","title":{"rendered":"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial"},"content":{"rendered":"<p>Londres (CNN) &#8212; Los ataques de combatientes apoyados por Ir\u00e1n en el mar Rojo han bloqueado una de las principales rutas comerciales del mundo para la mayor\u00eda de los cargueros de contenedores, buques que transportan desde piezas de autom\u00f3viles hasta Crocs de un rinc\u00f3n a otro del planeta.<\/p>\n<p>Un cierre prolongado de la v\u00eda navegable, que conecta con el canal de Suez, podr\u00eda paralizar las cadenas de suministro mundiales y hacer subir los precios de los productos manufacturados en un momento crucial de la batalla contra la inflaci\u00f3n. El canal de Suez representa entre el 10% y el 15% del comercio mundial, que incluye las exportaciones de petr\u00f3leo, y el 30% del volumen mundial de transporte de contenedores.<\/p>\n<p>AN\u00c1LISIS | \u00bfQu\u00e9 tipo de armas est\u00e1n utilizando Estados Unidos y el Reino Unido para atacar a los hut\u00edes de Yemen?<\/p>\n<p>Los combatientes hut\u00edes, con base en Yemen, dicen vengarse de la guerra de Israel contra Hamas en Gaza. El ej\u00e9rcito estadounidense y sus aliados han reforzado la seguridad mar\u00edtima, pero los ataques contin\u00faan: 21 misiles hut\u00edes y drones fueron derribados a \u00faltima hora del martes.<\/p>\n<p>Las fuerzas estadounidenses y brit\u00e1nicas subieron la apuesta el jueves cuando atacaron m\u00e1s de 60 objetivos hut\u00edes en lo que el presidente Joe Biden dijo que era una respuesta directa a la amenaza planteada a la &#171;libertad de navegaci\u00f3n en una de las v\u00edas navegables m\u00e1s vitales del mundo&#187;.<\/p>\n<p>A medida que la crisis persiste, aumentan los riesgos para la econom\u00eda mundial. Los minoristas ya est\u00e1n advirtiendo de retrasos, y el costo del env\u00edo de mercanc\u00edas est\u00e1 aumentando.<\/p>\n<p>Tesla dijo que paralizar\u00eda la mayor parte de la producci\u00f3n de su gigantesca f\u00e1brica de coches el\u00e9ctricos en Alemania porque los ataques han interrumpido el suministro de piezas. Los minoristas advierten de retrasos en los env\u00edos, y el coste del transporte mar\u00edtimo de mercanc\u00edas est\u00e1 aumentando.<\/p>\n<p>Los precios del petr\u00f3leo tambi\u00e9n est\u00e1n subiendo \u2014el Brent y el crudo estadounidense subieron cerca de un 3% el viernes\u2014 por el temor a una guerra regional m\u00e1s amplia que podr\u00eda interrumpir el suministro. Los mercados energ\u00e9ticos ya estaban en vilo despu\u00e9s de que Ir\u00e1n se apoderara el jueves de un petrolero en el golfo de Om\u00e1n.<\/p>\n<p>En un informe semestral publicado el martes, el Banco Mundial advert\u00eda que la interrupci\u00f3n de las principales rutas mar\u00edtimas estaba &#171;erosionando la holgura en las redes de suministro y aumentando la probabilidad de puntos de estrangulamiento inflacionistas&#187;.<\/p>\n<p>Seis de las 10 mayores compa\u00f1\u00edas de transporte mar\u00edtimo de contenedores a saber, Maersk, MSC, Hapag-Lloyd, CMA CGM, ZIM y ONE, est\u00e1n evitando en gran medida o por completo el mar Rojo debido a la amenaza de los combatientes hut\u00edes.<\/p>\n<p>El peligro para la tripulaci\u00f3n, la carga y los buques ha obligado a los transportistas a desviar los buques alrededor del Cabo de Buena Esperanza, en Sud\u00e1frica, lo que ha provocado retrasos de hasta tres semanas.<\/p>\n<p>Los costos de env\u00edo aumentan tras ataques en el mar Rojo que obligaron a los buques a tomar rutas m\u00e1s largas<\/p>\n<p>Esto ya ha incrementado significativamente los gastos de transporte, lo que en \u00faltima instancia podr\u00eda repercutir en los precios al consumo. &#171;Cuanto m\u00e1s persistan las perturbaciones, mayores ser\u00e1n los efectos estanflacionarios para la econom\u00eda mundial&#187;, escribi\u00f3 la semana pasada en X el economista jefe de Allianz, Mohamed A. El Erian, refiri\u00e9ndose a una combinaci\u00f3n t\u00f3xica de bajo o nulo crecimiento econ\u00f3mico y alta inflaci\u00f3n.<\/p>\n<p>Si la guerra entre Israel y Hamas se convierte en un conflicto regional m\u00e1s amplio o los hut\u00edes deciden redirigir sus ataques contra petroleros y buques cargueros, que transportan materias primas cruciales como mineral de hierro, grano y madera, las consecuencias para la econom\u00eda mundial ser\u00edan a\u00fan m\u00e1s graves.<\/p>\n<p>&#171;En un contexto de escalada de los conflictos, el suministro de energ\u00eda tambi\u00e9n podr\u00eda verse interrumpido de forma sustancial, lo que provocar\u00eda un repunte de los precios de la energ\u00eda&#187;, a\u00f1ade el informe del Banco Mundial. &#171;Esto tendr\u00eda importantes repercusiones en los precios de otros productos b\u00e1sicos&#187;.<\/p>\n<p>La amenaza para los precios de la energ\u00eda es el mayor riesgo, seg\u00fan Capital Economics.<\/p>\n<p>&#171;Aunque es improbable que las actuales interrupciones del transporte mar\u00edtimo alteren por s\u00ed mismas la tendencia mundial a la baja de la inflaci\u00f3n, una marcada escalada del conflicto militar subyacente podr\u00eda disparar los precios de la energ\u00eda, lo que repercutir\u00eda en los consumidores&#187;, escribieron Simon MacAdam y Lily Millard, economistas de la consultora, en una nota la semana pasada.<\/p>\n<p>Suben los precios del petr\u00f3leo y el gas, al tiempo que BP frena sus env\u00edos en el mar Rojo tras los ataques de los hut\u00edes<\/p>\n<p>Oxford Economics tambi\u00e9n espera que la inflaci\u00f3n siga moder\u00e1ndose, pero sigue viendo un riesgo al alza para los precios. Si los costos del transporte de contenedores se mantienen en sus niveles actuales, casi el doble del nivel de principios de diciembre, la inflaci\u00f3n mundial podr\u00eda aumentar unos 0,6 puntos porcentuales, seg\u00fan Ben May, director de investigaci\u00f3n macroecon\u00f3mica mundial de la empresa, en una nota del 4 de enero.<\/p>\n<p>Retrasos en las entregas<\/p>\n<p>Algunos fabricantes de autom\u00f3viles europeos han desviado sus env\u00edos por el Cabo de Buena Esperanza. &#171;Esto ha supuesto un aumento de los costos y retrasos de unas dos semanas&#187;, dijo un portavoz de la Asociaci\u00f3n Europea de Fabricantes de Autom\u00f3viles.<\/p>\n<p>Y minoristas como la empresa sueca de muebles Ikea han advertido de retrasos en los env\u00edos y posible escasez de ciertos productos. Del mismo modo, el minorista brit\u00e1nico de ropa Next declar\u00f3 la semana pasada: &#171;Si contin\u00faan las dificultades de acceso al canal de Suez, es probable que se produzcan algunos retrasos en las entregas de existencias a principios de a\u00f1o&#187;.<\/p>\n<p>Crocs tambi\u00e9n comunic\u00f3 que los art\u00edculos destinados a Europa est\u00e1n tardando dos semanas m\u00e1s de lo habitual en llegar. El fabricante de calzado no espera un &#171;impacto material&#187; en su negocio por ahora, pero dijo a CNN que &#171;seguir\u00eda vigilando de cerca la situaci\u00f3n&#187;.<\/p>\n<p>No es el \u00fanico. Empresas de todo el mundo est\u00e1n en vilo, con la esperanza de que la interrupci\u00f3n termine pronto, pero empezando a desempolvar los planes de contingencia desplegados por \u00faltima vez durante la pandemia si no es as\u00ed.<\/p>\n<p>Abercrombie &amp; Fitch planea utilizar el transporte a\u00e9reo siempre que sea posible para evitar retrasos, seg\u00fan un correo electr\u00f3nico a los proveedores visto por Bloomberg. &#171;Cambiamos los modos de transporte y\/o las rutas de env\u00edo cuando es necesario para mantener el flujo de mercanc\u00edas&#187;, declar\u00f3 un portavoz de la empresa a CNN.<\/p>\n<p>Ikea ha advertido de retrasos en los env\u00edos y de la posible escasez de algunos productos debido a las perturbaciones en el mar Rojo. Cr\u00e9dito: Nathan Howard\/Bloomberg\/Getty Images<\/p>\n<p>La situaci\u00f3n podr\u00eda empeorar en las pr\u00f3ximas semanas, ya que los transportistas se apresuran a sacar los pedidos de China antes de que las f\u00e1bricas cierren por las vacaciones del A\u00f1o Nuevo Lunar en el pa\u00eds.<\/p>\n<p>&#171;Las pr\u00f3ximas cinco semanas previas al A\u00f1o Nuevo chino, el 10 de febrero, van a ser muy dif\u00edciles para los transportistas y el transporte mar\u00edtimo&#187;, afirm\u00f3 Philip Damas, director de Drewry Supply Chain Advisors, en comentarios grabados y publicados en Internet el lunes.<\/p>\n<p>Se\u00f1al\u00f3, sin embargo, que el exceso de capacidad de transporte mar\u00edtimo en general significaba que las tarifas al contado (el precio de los env\u00edos puntuales de mercanc\u00edas en contraposici\u00f3n a los precios acordados de antemano) &#171;volver\u00e1n a bajar despu\u00e9s del A\u00f1o Nuevo chino&#187;.<\/p>\n<p>\u00bfPor qu\u00e9 el mar Rojo, asediado por los hut\u00edes, es tan importante para el mundo?<\/p>\n<p>Crisis total<\/p>\n<p>Adem\u00e1s de la subida de los fletes al contado por los ataques en el mar Rojo, los transportistas est\u00e1n a\u00f1adiendo recargos de emergencia.<\/p>\n<p>Seg\u00fan las estimaciones de Judah Levine, jefe de investigaci\u00f3n de la empresa de log\u00edstica Freightos, los &#171;precios totales&#187; de entre US$ 5.000 y 8.000 por contenedor para las principales rutas comerciales con origen en Asia son entre 2,5 y 4 veces superiores a los &#171;niveles normales&#187; para esta \u00e9poca del a\u00f1o.<\/p>\n<p>Sin embargo, esta cifra sigue estando entre un 45% y un 75% por debajo de su &#171;pico pand\u00e9mico&#187; de finales de 2021, se\u00f1al\u00f3 Levine. Por aquel entonces, el aumento de la demanda de bienes por parte de los consumidores que no pod\u00edan salir de casa se encontr\u00f3 con embotellamientos en la oferta, desde la escasez de contenedores hasta la congesti\u00f3n de los puertos.<\/p>\n<p>El puerto de Los \u00c1ngeles, en Estados Unidos, el 4 de diciembre de 2023. Cr\u00e9dito: Eric Thayer\/Bloomberg\/Getty Images<\/p>\n<p>La debacle del canal de Suez se suma a los problemas existentes en el transporte mar\u00edtimo, con el tr\u00e1fico a trav\u00e9s del vital canal de Panam\u00e1 ya restringido debido a una grave sequ\u00eda.<\/p>\n<p>&#171;Las empresas que intentan transportar mercanc\u00edas por todo el mundo se encuentran en una situaci\u00f3n de crisis total: no pueden confiar en el canal de Panam\u00e1 ni en el de Suez&#187;, afirma Carolina Klint, Directora Comercial para Europa de Marsh McLennan, una empresa de servicios profesionales.<\/p>\n<p>Algunos transportistas mar\u00edtimos que habitualmente transitan por el canal de Panam\u00e1 se hab\u00edan desviado al canal de Suez antes de que se intensificaran los ataques en el mar Rojo, seg\u00fan la empresa de log\u00edstica C.H. Robinson.<\/p>\n<p>Matthew Burgess, vicepresidente de servicios oce\u00e1nicos globales de la empresa, afirm\u00f3 que la capacidad mundial de transporte mar\u00edtimo seguir\u00e1 limitada durante un tiempo. &#171;Habr\u00e1 escasez de espacio entre Asia y Europa durante, como m\u00ednimo, las pr\u00f3ximas ocho semanas, debido al tiempo adicional necesario para utilizar la ruta del Cabo de Buena Esperanza&#187;, declar\u00f3 a CNN.<\/p>\n<p>&#171;Como observamos en anteriores interrupciones del transporte mar\u00edtimo mundial, es probable que la escasez de contenedores vac\u00edos se produzca r\u00e1pidamente, lo que aumentar\u00e1 a\u00fan m\u00e1s los retrasos, ya que las empresas podr\u00edan tener que esperar dos o tres semanas m\u00e1s para disponer de un contenedor vac\u00edo&#187;.<\/p>\n<p>Al menos por ahora, los principales puertos de Europa y Estados Unidos, incluidos el puerto de Rotterdam, el de Los \u00c1ngeles y el de Nueva York y Nueva Jersey, han visto un impacto limitado derivado de la crisis del mar Rojo. Pero est\u00e1n en alerta m\u00e1xima ante posibles consecuencias.<\/p>\n<p>&#171;Es otra interrupci\u00f3n en la cadena de suministro&#187;, declar\u00f3 a CNN Gene Seroka, director ejecutivo del puerto de Los \u00c1ngeles. &#171;Esto no va a desaparecer en tres o cuatro semanas&#187;.<\/p>\n<p>E incluso si los ataques se detuvieran hoy, permitiendo a la mayor\u00eda de los buques transitar por el mar Rojo, los impactos precedentes a\u00fan podr\u00edan reverberar durante alg\u00fan tiempo, seg\u00fan Burgess, de C.H. Robinson. &#171;Los trastornos y retrasos que ya se est\u00e1n produciendo tardar\u00e1n bastante tiempo en resolverse&#187;.<\/p>\n<p>Nota del editor: este art\u00edculo fue actualizado el viernes 12 de enero.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Londres (CNN) &#8212; Los ataques de combatientes apoyados por Ir\u00e1n en el mar Rojo han bloqueado una de las principales rutas comerciales del mundo para la mayor\u00eda de los cargueros de contenedores, buques que transportan desde piezas de autom\u00f3viles hasta Crocs de un rinc\u00f3n a otro del planeta. Un cierre prolongado de la v\u00eda navegable, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443599","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial - Noticias\" \/>\n<meta property=\"og:description\" content=\"Londres (CNN) &#8212; Los ataques de combatientes apoyados por Ir\u00e1n en el mar Rojo han bloqueado una de las principales rutas comerciales del mundo para la mayor\u00eda de los cargueros de contenedores, buques que transportan desde piezas de autom\u00f3viles hasta Crocs de un rinc\u00f3n a otro del planeta. Un cierre prolongado de la v\u00eda navegable, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-13T03:33:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial\",\"datePublished\":\"2024-01-13T03:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/\"},\"wordCount\":1941,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/\",\"name\":\"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-13T03:33:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial - Noticias","og_description":"Londres (CNN) &#8212; Los ataques de combatientes apoyados por Ir\u00e1n en el mar Rojo han bloqueado una de las principales rutas comerciales del mundo para la mayor\u00eda de los cargueros de contenedores, buques que transportan desde piezas de autom\u00f3viles hasta Crocs de un rinc\u00f3n a otro del planeta. Un cierre prolongado de la v\u00eda navegable, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/","og_site_name":"Noticias","article_published_time":"2024-01-13T03:33:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial","datePublished":"2024-01-13T03:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/"},"wordCount":1941,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/","url":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/","name":"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-13T03:33:32+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-13T03:33:32Z","datePublished":"2024-01-13T03:33:32Z","dateModified":"2024-01-13T03:33:32Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | C\\u00f3mo la crisis del mar Rojo podr\\u00eda golpear la econom\\u00eda mundial\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/12\\\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/12\\\/analisis-como-la-crisis-del-mar-rojo-podria-golpear-la-economia-mundial\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-13T03:33:32Z\",\"datePublished\":\"2024-01-13T03:33:32Z\",\"dateModified\":\"2024-01-13T03:33:32Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443235,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/06\/los-ataques-huties-bloquean-una-ruta-vital-en-el-mar-rojo-para-los-portacontenedores-de-maersk\/","url_meta":{"origin":1443599,"position":0},"title":"Los ataques hut\u00edes bloquean una ruta vital en el mar Rojo para los portacontenedores de Maersk","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN) --\u00a0Maersk anunci\u00f3 este viernes que suspender\u00e1 todos los env\u00edos a trav\u00e9s del mar Rojo durante el \"futuro previsible\" debido a la amenaza de ataques a buques que utilizan la vital ruta comercial mar\u00edtima.La medida se produce despu\u00e9s de que la compa\u00f1\u00eda danesa detuviera los tr\u00e1nsitos por la zona \"hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443239,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/06\/los-ataques-huties-bloquean-una-ruta-vital-en-el-mar-rojo-para-los-portacontenedores-de-maersk-2\/","url_meta":{"origin":1443599,"position":1},"title":"Los ataques hut\u00edes bloquean una ruta vital en el mar Rojo para los portacontenedores de Maersk","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN) --\u00a0Maersk anunci\u00f3 este viernes que suspender\u00e1 todos los env\u00edos a trav\u00e9s del mar Rojo durante el \"futuro previsible\" debido a la amenaza de ataques a buques que utilizan la vital ruta comercial mar\u00edtima.La medida se produce despu\u00e9s de que la compa\u00f1\u00eda danesa detuviera los tr\u00e1nsitos por la zona \"hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443241,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/06\/los-ataques-huties-bloquean-una-ruta-vital-en-el-mar-rojo-para-los-portacontenedores-de-maersk-3\/","url_meta":{"origin":1443599,"position":2},"title":"Los ataques hut\u00edes bloquean una ruta vital en el mar Rojo para los portacontenedores de Maersk","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN) --\u00a0Maersk anunci\u00f3 este viernes que suspender\u00e1 todos los env\u00edos a trav\u00e9s del mar Rojo durante el \"futuro previsible\" debido a la amenaza de ataques a buques que utilizan la vital ruta comercial mar\u00edtima.La medida se produce despu\u00e9s de que la compa\u00f1\u00eda danesa detuviera los tr\u00e1nsitos por la zona \"hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443243,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/06\/los-ataques-huties-bloquean-una-ruta-vital-en-el-mar-rojo-para-los-portacontenedores-de-maersk-4\/","url_meta":{"origin":1443599,"position":3},"title":"Los ataques hut\u00edes bloquean una ruta vital en el mar Rojo para los portacontenedores de Maersk","author":"","date":"enero 6, 2024","format":false,"excerpt":"(CNN) --\u00a0Maersk anunci\u00f3 este viernes que suspender\u00e1 todos los env\u00edos a trav\u00e9s del mar Rojo durante el \"futuro previsible\" debido a la amenaza de ataques a buques que utilizan la vital ruta comercial mar\u00edtima.La medida se produce despu\u00e9s de que la compa\u00f1\u00eda danesa detuviera los tr\u00e1nsitos por la zona \"hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443080,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/03\/maersk-suspende-transporte-maritimo-a-traves-del-mar-rojo-hasta-nuevo-aviso\/","url_meta":{"origin":1443599,"position":4},"title":"Maersk suspende transporte mar\u00edtimo a trav\u00e9s del mar Rojo &#171;hasta nuevo aviso&#187;","author":"","date":"enero 3, 2024","format":false,"excerpt":"Londres (CNN) --\u00a0Maersk suspendi\u00f3 el transporte mar\u00edtimo a trav\u00e9s del mar Rojo y el canal de Suez \u201chasta nuevo aviso\u201d y continuar\u00e1 revisando la seguridad tras un ataque a uno de sus buques, al tiempo que una de las rutas comerciales mar\u00edtimas m\u00e1s importantes del mundo sufre crecientes ataques a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442516,"url":"https:\/\/noticiasya.com\/las-vegas\/2023\/12\/23\/los-costos-de-envio-aumentan-tras-ataques-en-el-mar-rojo-que-obligaron-a-los-buques-a-tomar-rutas-mas-largas\/","url_meta":{"origin":1443599,"position":5},"title":"Los costos de env\u00edo aumentan tras ataques en el mar Rojo que obligaron a los buques a tomar rutas m\u00e1s largas","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"Londres (CNN) -- Maersk y CMA CGN implementaron nuevos cargos para el transporte de mercanc\u00edas a lo largo de muchas de las rutas mar\u00edtimas m\u00e1s transitadas del mundo despu\u00e9s de tener que desviar sus buques lejos del mar Rojo debido a los ataques.La compa\u00f1\u00eda danesa Maersk dijo este jueves que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443599"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443599\/revisions"}],"predecessor-version":[{"id":1443618,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443599\/revisions\/1443618"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}