{"id":1443603,"date":"2024-01-12T20:33:33","date_gmt":"2024-01-13T04:33:33","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443603"},"modified":"2024-01-12T20:33:33","modified_gmt":"2024-01-13T04:33:33","slug":"yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/","title":{"rendered":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los repetidos ataques con drones y misiles contra la navegaci\u00f3n comercial en el mar Rojo.<\/p>\n<p>Crisis del mar Rojo: \u00bfqui\u00e9nes son los hut\u00edes y por qu\u00e9 atacan a los barcos?<\/p>\n<p>Un video publicado por Al-Masira TV, dirigido por los hut\u00edes, supuestamente muestra el momento del bombardeo en San\u00e1, Yemen. (Al-Masira TV)<\/p>\n<p>El presidente de Estados Unidos, Joe Biden, asegur\u00f3 que los ataques contra \u00e1reas controladas por los hut\u00edes en Yemen son \u201cuna respuesta directa a ataques hut\u00edes sin precedentes contra buques mar\u00edtimos internacionales en el mar Rojo\u201d.<\/p>\n<p>En una declaraci\u00f3n emitida este jueves, el mandatario asegur\u00f3 que, bajo su direcci\u00f3n &#171;las fuerzas militares estadounidenses, junto con Reino Unido y el apoyo de Australia, Bahrein, Canad\u00e1 y los Pa\u00edses Bajos, llevaron a cabo con \u00e9xito ataques contra varios objetivos en Yemen utilizados por los rebeldes hut\u00edes para poner en peligro la libertad de navegaci\u00f3n a lo largo de una de las v\u00edas fluviales m\u00e1s vitales del mundo&#187;.<\/p>\n<p>AN\u00c1LISIS | C\u00f3mo la crisis del mar Rojo podr\u00eda golpear la econom\u00eda mundial<\/p>\n<p>&#171;La respuesta de la comunidad internacional a estos ataques imprudentes ha sido unida y decidida. El mes pasado, Estados Unidos lanz\u00f3 la Operaci\u00f3n Guardi\u00e1n de la Prosperidad, una coalici\u00f3n de m\u00e1s de 20 naciones comprometidas con la defensa del transporte mar\u00edtimo internacional y la disuasi\u00f3n de los ataques hut\u00edes en el mar Rojo. Tambi\u00e9n nos unimos a m\u00e1s de 40 naciones para condenar las amenazas hut\u00edes&#187;, asegur\u00f3 Biden.<\/p>\n<p>Las fuerzas estadounidenses y de la coalici\u00f3n &#171;ejecutaron ataques deliberados contra m\u00e1s de 60 objetivos en 16 emplazamientos de militantes hut\u00edes respaldados por Ir\u00e1n, incluidos nodos de mando y control, dep\u00f3sitos de municiones, sistemas de lanzamiento, instalaciones de producci\u00f3n y sistemas de radar de defensa a\u00e9rea&#187;, seg\u00fan un comunicado del teniente general Alex Grynkewich, comandante central de las fuerzas a\u00e9reas estadounidenses. Se utilizaron m\u00e1s de 100 municiones guiadas de precisi\u00f3n &#171;de diversos tipos&#187;, a\u00f1adi\u00f3.<\/p>\n<p>\u00bfPor qu\u00e9 el mar Rojo, asediado por los hut\u00edes, es tan importante?<\/p>\n<p>Una imagen fija de un v\u00eddeo muestra m\u00faltiples explosiones en la provincia de Saada, al norte de San\u00e1, Yemen, el 12 de enero, hora local. De las redes sociales<\/p>\n<p>Los ataques tambi\u00e9n son una se\u00f1al de la creciente alarma internacional sobre la amenaza a una de las principales v\u00edas fluviales del mundo. Durante semanas, Estados Unidos hab\u00eda tratado de evitar ataques directos contra Yemen debido al riesgo de una escalada en una regi\u00f3n que ya hierve de tensi\u00f3n, pero los ataques hut\u00edes en curso contra el transporte mar\u00edtimo internacional obligaron a la coalici\u00f3n a actuar.<\/p>\n<p>Los ataques hut\u00edes bloquean una ruta vital en el mar Rojo para los portacontenedores de Maersk<\/p>\n<p>Los ataques ocurren mientras el secretario de Defensa, Lloyd Austin, permanece hospitalizado tras complicaciones de una cirug\u00eda por c\u00e1ncer de pr\u00f3stata.<\/p>\n<p>El primer ataque contra hut\u00edes en Yemen conocido desde que estall\u00f3 la guerra en Gaza<\/p>\n<p>Aunque Estados Unidos ha ejecutado ataques en Iraq y Siria contra grupos respaldados por Ir\u00e1n desde el estallido de la guerra en Gaza, este es el primer ataque conocido contra los hut\u00edes en Yemen. Y se produce en un momento de enorme tensi\u00f3n en Medio Oriente, mientras Estados Unidos busca garantizar que la guerra en Gaza no se extienda a la regi\u00f3n en general.<\/p>\n<p>De hecho, el Gobierno de Biden manten\u00eda una posici\u00f3n cautelosa respecto a atacar a los hut\u00edes, temiendo que pudiera alterar un delicado alto el fuego entre el grupo combatiente y Arabia Saudita que se logr\u00f3 despu\u00e9s de a\u00f1os de guerra.<\/p>\n<p>EE.UU. y sus aliados se apresuran a responder a los ataques de los hut\u00edes en las rutas mar\u00edtimas clave del mar Rojo<\/p>\n<p>Sn embargo, la Casa Blanca hab\u00eda dejado claro que los repetidos ataques hut\u00edes a las rutas mar\u00edtimas internacionales en el sur del mar Rojo no se pod\u00edan tolerar. De hecho, los ataques han obligado a algunas de las compa\u00f1\u00edas navieras m\u00e1s grandes del mundo a eludir la v\u00eda fluvial, lo que implica sumar miles de kil\u00f3metros a las rutas mar\u00edtimas internacionales navegando alrededor del continente africano.<\/p>\n<p>Horas antes del ataque del jueves, el portavoz del Pent\u00e1gono, mayor general Pat Ryder, dijo que Ir\u00e1n \u201ctiene una tarea que hacer\u201d para lograr que los hut\u00edes detengan su \u201cactividad imprudente, peligrosa e ilegal\u201d. Si no lo hac\u00edan, dijo, \u201chabr\u00e1 consecuencias\u201d.<\/p>\n<p>En un discurso este jueves, el l\u00edder hut\u00ed Abdul Malek Al-Houthi dijo que cualquier ataque estadounidense contra Yemen \u201cno quedar\u00e1 sin respuesta\u201d, advirtiendo cr\u00edpticamente que la respuesta ser\u00e1 \u201cmucho m\u00e1s\u201d que atacar barcos estadounidenses en el mar.<\/p>\n<p>Los ataques se realizaron con aviones de combate y misiles Tomahawk. M\u00e1s de una docena de objetivos hut\u00edes fueron impactados por misiles que se dispararon desde plataformas a\u00e9reas, de superficie y subplataformas, dijo a CNN un segundo funcionario de EE.UU. Los objetivos se eligieron por su capacidad para degradar los continuos ataques de los hut\u00edes a buques en el mar Rojo, a\u00f1adi\u00f3 la fuente.<\/p>\n<p>Incluyeron sistemas de radar, lugares de almacenamiento y lanzamiento de drones, de misiles bal\u00edsticos y de misiles de crucero.<\/p>\n<p>El USS Florida, un submarino de misiles guiados que entr\u00f3 en el mar Rojo el 23 de noviembre, particip\u00f3 en el ataque a Yemen, seg\u00fan un segundo funcionario estadounidense. Al igual que los buques de superficie que participaron en el ataque, el submarino dispar\u00f3 misiles de ataque terrestre Tomahawk, dijo el funcionario.<\/p>\n<p>Estados Unidos hab\u00eda advertido sobre &#171;consecuencias&#187;<\/p>\n<p>Este jueves, el secretario de Estado de EE.UU., Antony Blinken, advirti\u00f3 durante un viaje a la regi\u00f3n que &#171;si no se detienen, tendr\u00e1 que haber consecuencias. Y desafortunadamente, no han parado&#187;.<\/p>\n<p>El funcionario tambi\u00e9n dijo que no cree que la guerra en Gaza est\u00e9 escalando a un conflicto regional, aunque advirti\u00f3 de &#171;muchos puntos de peligro&#187;. Durante su visita a la regi\u00f3n, Blinken visit\u00f3 Bahrein, sede del Mando Central de las Fuerzas Navales de Estados Unidos y de la Quinta Flota de la Marina.<\/p>\n<p>Un aspecto importante del viaje de Blinken a Medio Oriente fue comunicar a los l\u00edderes regionales que si Estados Unidos emprende una acci\u00f3n militar contra los hut\u00edes, esta debe entenderse como defensiva, no como una escalada, seg\u00fan un alto funcionario del Departamento de Estado.<\/p>\n<p>Los hut\u00edes \u2014una organizaci\u00f3n pol\u00edtica y militar respaldada por Ir\u00e1n que libra una guerra civil en Yemen contra una coalici\u00f3n respaldada por Arabia Saudita\u2014 llevan semanas lanzando drones y misiles contra buques mercantes en el mar Rojo, muchos de los cuales fueron interceptados y derribados por buques de la Marina de Estados Unidos en la zona.<\/p>\n<p>El grupo rebelde ha dicho que act\u00faa en apoyo de la lucha de Hamas contra Israel en Gaza, tras el ataque de el grupo contra Israel el 7 de octubre.<\/p>\n<p>Este mi\u00e9rcoles, el Consejo de Seguridad de las Naciones Unidas aprob\u00f3 una resoluci\u00f3n liderada por Estados Unidos y Jap\u00f3n en la que se condenan &#171;en los t\u00e9rminos m\u00e1s en\u00e9rgicos las al menos dos docenas de ataques hut\u00edes contra buques mercantes y comerciales desde el 19 de noviembre de 2023&#187; y se exige &#171;que los hut\u00edes pongan fin inmediatamente a todos esos ataques.&#187;<\/p>\n<p>Once pa\u00edses votaron a favor de la resoluci\u00f3n. Cuatro se abstuvieron, entre ellos China y Rusia. Un diplom\u00e1tico occidental declar\u00f3 a CNN que Estados Unidos accedi\u00f3 a algunas de las peticiones de China sobre el lenguaje de la resoluci\u00f3n.<\/p>\n<p>Los ataques estadounidenses en Yemen no carecen de precedentes. Seg\u00fan el Consejo de Relaciones Exteriores, Estados Unidos ha llevado a cabo cerca de 400 ataques a\u00e9reos en Yemen desde 2002. Sin embargo, funcionarios de la Casa Blanca y del Pent\u00e1gono han manifestado desde el ataque de Hamas que no quieren que el conflicto de Gaza se extienda a la regi\u00f3n. John Kirby, portavoz del Consejo de Seguridad Nacional, dijo la semana pasada que Estados Unidos &#171;no busca un conflicto con los hut\u00edes&#187;.<\/p>\n<p>Entre las preocupaciones de Estados Unidos sobre emprender acciones directas dentro de Yemen est\u00e1 el riesgo de alterar una tregua cuidadosamente negociada en la guerra de Yemen entre los hut\u00edes y Arabia Saudita, que un funcionario estadounidense dijo previamente a CNN que el Gobierno de Biden considera uno de sus logros m\u00e1s significativos en pol\u00edtica exterior.<\/p>\n<p>Los hut\u00edes contraatacan<\/p>\n<p>Las fuerzas hut\u00edes lanzaron contraataques a buques de guerra estadounidenses y brit\u00e1nicos en el mar Rojo, en represalia por el ataque de los aliados occidentales, afirm\u00f3 un alto miembro del grupo hut\u00ed, Abdul Salam Jahaf, en un comunicado a primera hora del viernes, hora local.<\/p>\n<p>Mientras tanto, el viceministro de Asuntos Exteriores hut\u00ed advirti\u00f3 que Estados Unidos y Reino Unido afrontar\u00edan graves repercusiones por lo que calific\u00f3 como un evidente acto de agresi\u00f3n.<\/p>\n<p>Hussein al-Ezzi dijo que Yemen fue objeto de un &#171;ataque masivo agresivo&#187; por parte de buques de guerra y aviones de combate estadounidenses y brit\u00e1nicos.<\/p>\n<p>&#171;Nuestro pa\u00eds fue sometido a un ataque masivo agresivo por parte de barcos, submarinos y aviones de guerra estadounidenses y brit\u00e1nicos, y Estados Unidos y Reino Unido, sin duda, tendr\u00e1n que prepararse para pagar un alto precio y soportar todas las terribles consecuencias de esta evidente agresi\u00f3n&#187;, dijo al-Ezzi. dicho.<\/p>\n<p>El grupo rebelde hut\u00ed tom\u00f3 el control de partes de San\u00e1, la capital de Yemen, en 2014, consolidando su poder en la parte norte del pa\u00eds.<\/p>\n<p>\u00bfQu\u00e9 puede pasar ahora?<\/p>\n<p>Un alto funcionario de la administraci\u00f3n estadounidense se\u00f1al\u00f3 que podr\u00edan producirse m\u00e1s acciones contra los hut\u00edes.<\/p>\n<p>&#171;Es muy posible que esta no sea la \u00faltima palabra sobre el tema&#187;, dijo el funcionario de la administraci\u00f3n. &#171;Y cuando tengamos m\u00e1s que decir y m\u00e1s que hacer, tendr\u00e1n noticias nuestras&#187;.<\/p>\n<p>El viernes se escucharon nuevas explosiones en la ciudad portuaria de Hodeidah, en el oeste de Yemen, dijo un residente a CNN.<\/p>\n<p>El aeropuerto de Hodeidah hab\u00eda sido alcanzado en la ronda inicial de ataques a primera hora de la ma\u00f1ana del viernes. El residente facilit\u00f3 a CNN un video en el que se ve\u00eda humo saliendo de la direcci\u00f3n del aeropuerto.<\/p>\n<p>CNN se ha puesto en contacto con el Departamento de Defensa de Estados Unidos para informarse sobre las explosiones y sobre si se est\u00e1n produciendo nuevos ataques en Yemen.<\/p>\n<p>Mientras tanto, el ministro brit\u00e1nico de Fuerzas Armadas, James Heappey, dijo el viernes que no hay m\u00e1s misiones del Reino Unido &#171;previstas inmediatamente&#187; de los ataques del jueves.<\/p>\n<p>&#171;Anoche fue una respuesta limitada, proporcionada y necesaria en defensa propia de nuestros buques de guerra en la regi\u00f3n&#187;, dijo Heappey a BBC News.<\/p>\n<p>Los ataques de los hut\u00edes contra barcos en el mar Rojo<\/p>\n<p>Estados Unidos y sus aliados emitieron una advertencia a los hut\u00edes el pasado 3 de enero. En una declaraci\u00f3n conjunta se\u00f1alaron que los hut\u00edes \u201ctendr\u00e1n que asumir la responsabilidad de las consecuencias si contin\u00faan amenazando vidas, la econom\u00eda global y el libre flujo de comercio en las v\u00edas fluviales principales de la regi\u00f3n&#187;.<\/p>\n<p>A\u00fan as\u00ed, los ataques han continuado.<\/p>\n<p>Apenas unas horas despu\u00e9s de que se publicara la declaraci\u00f3n conjunta, los hut\u00edes lanzaron un dron de superficie contra las rutas mar\u00edtimas comerciales, en lo que marc\u00f3 la primera vez que utilizaron ese tipo de arma desde el comienzo de sus ataques. Y este martes, en uno de los mayores ataques por parte del grupo hasta la fecha, tres destructores de la Marina de Estados Unidos \u2014los F\/A-18 del USS Dwight D. Eisenhower\u2014 y un destructor brit\u00e1nico \u2014el HMS Diamond\u2014 derribaron 21 misiles y drones. El ataque no caus\u00f3 da\u00f1os a ning\u00fan buque ni se registraron heridos.<\/p>\n<p>Los combatientes hut\u00edes tambi\u00e9n han intentado subir a bordo de buques comerciales, incluido un caso reciente en el que helic\u00f3pteros estadounidenses hundieron tres peque\u00f1as embarcaciones hut\u00edes que estaban atacando el Maersk Hangzhou el 30 de diciembre, por lo cual murieron sus tripulantes.<\/p>\n<p>Las navieras se debaten sobre si navegar de nuevo o no en el mar Rojo mientras contin\u00faan los ataques de los hut\u00edes<\/p>\n<p>Desde el 19 de noviembre se han producido al menos 27 ataques hut\u00edes. Mientras Estados Unidos y sus aliados sortean los continuos ataques de los hut\u00edes, tambi\u00e9n se han producido al menos 131 ataques contra fuerzas estadounidenses y de la coalici\u00f3n en Iraq y Siria desde el 17 de octubre, lo que ha llevado a varios ataques contra instalaciones vinculadas a los Cuerpos de la Guardia Revolucionaria Isl\u00e1mica de Ir\u00e1n y otras fuerzas respaldadas por Ir\u00e1n. La semana pasada, Estados Unidos atac\u00f3 a un miembro del grupo Harakat al-Nujaba, respaldado por Ir\u00e1n, que, seg\u00fan un funcionario, tiene &#171;las manos manchadas de sangre estadounidense&#187; en Iraq.<\/p>\n<p>Los ataques de los hut\u00edes comenzaron poco despu\u00e9s del inicio de la guerra en Gaza, luego de que dijeron que atacar\u00edan barcos vinculados a Israel. Norman Roule, exdirector nacional de inteligencia para Ir\u00e1n en la CIA, dijo previamente a CNN que el hecho de que los comandantes hut\u00edes se jacten &#171;ante sus seguidores tribales de haber llevado a cabo ataques contra Israel y Estados Unidos realza su posici\u00f3n dentro del movimiento&#187;.<\/p>\n<p>Sin embargo, muchos de los buques comerciales no han tenido ninguna conexi\u00f3n con Israel. El vicealmirante Brad Cooper, comandante del Mando Central de la Marina de EE.UU., declar\u00f3 la semana pasada que Estados Unidos calcula que 55 naciones tienen &#171;conexiones directas&#187; con los buques que fueron objeto de ataques.<\/p>\n<p>Nota del editor: este art\u00edculo fue actualizado con detalles adicionales.<\/p>\n<p>Samantha Waldenberg, de CNN, contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los repetidos ataques con drones y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443603","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los repetidos ataques con drones y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-13T04:33:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n\",\"datePublished\":\"2024-01-13T04:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/\"},\"wordCount\":2440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/\",\"name\":\"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-13T04:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/","og_locale":"es_ES","og_type":"article","og_title":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n - Noticias","og_description":"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los repetidos ataques con drones y [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/","og_site_name":"Noticias","article_published_time":"2024-01-13T04:33:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/"},"author":{"name":"","@id":""},"headline":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n","datePublished":"2024-01-13T04:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/"},"wordCount":2440,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/","url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/","name":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-13T04:33:33+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-13T04:33:33Z","datePublished":"2024-01-13T04:33:33Z","dateModified":"2024-01-13T04:33:33Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\\u00edes respaldados por Ir\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/12\\\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/12\\\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-13T04:33:33Z\",\"datePublished\":\"2024-01-13T04:33:33Z\",\"dateModified\":\"2024-01-13T04:33:33Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443576,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/estados-unidos-y-reino-unido-lanzan-ataques-en-yemen-contra-huties-respaldados-por-iran-4\/","url_meta":{"origin":1443603,"position":0},"title":"Estados Unidos y Reino Unido lanzan ataques en Yemen contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443584,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/yemen-estados-unidos-y-reino-unido-lanzan-ataques-contra-huties-respaldados-por-iran\/","url_meta":{"origin":1443603,"position":1},"title":"Yemen: Estados Unidos y Reino Unido lanzan ataques contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443564,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/estados-unidos-y-reino-unido-lanzan-ataques-en-yemen-contra-huties-respaldados-por-iran\/","url_meta":{"origin":1443603,"position":2},"title":"Estados Unidos y Reino Unido lanzan ataques en Yemen contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Los ej\u00e9rcitos de Estados Unidos y Reino Unido lanzaron ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, dijeron a CNN un funcionario estadounidense y un funcionario brit\u00e1nicoLos ataques se realizaron con aviones de combate y misiles Tomahawk. M\u00e1s de una docena de objetivos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443569,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/estados-unidos-y-reino-unido-lanzan-ataques-en-yemen-contra-huties-respaldados-por-iran-2\/","url_meta":{"origin":1443603,"position":3},"title":"Estados Unidos y Reino Unido lanzan ataques en Yemen contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443572,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/estados-unidos-y-reino-unido-lanzan-ataques-en-yemen-contra-huties-respaldados-por-iran-3\/","url_meta":{"origin":1443603,"position":4},"title":"Estados Unidos y Reino Unido lanzan ataques en Yemen contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Estados Unidos y el Reino Unido lanzaron el jueves ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, una respuesta significativa despu\u00e9s de que el gobierno de Biden y sus aliados advirtieran que el grupo militante respaldado por Ir\u00e1n sufrir\u00eda las consecuencias de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443556,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/estados-unidos-y-reino-unido-lanzan-ataques-aereos-en-yemen-contra-huties-respaldados-por-iran\/","url_meta":{"origin":1443603,"position":5},"title":"Estados Unidos y Reino Unido lanzan ataques a\u00e9reos en Yemen contra hut\u00edes respaldados por Ir\u00e1n","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Los ej\u00e9rcitos de Estados Unidos y el Reino Unido lanzaron ataques contra m\u00faltiples objetivos hut\u00edes en \u00e1reas de Yemen controladas por este grupo, dijeron a CNN un funcionario estadounidense y un funcionario del Reino Unido.Los ataques se realizaron con aviones de combate y misiles Tomahawk. M\u00e1s de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443603"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443603\/revisions"}],"predecessor-version":[{"id":1443621,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443603\/revisions\/1443621"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}