{"id":1443610,"date":"2024-01-12T23:33:33","date_gmt":"2024-01-13T07:33:33","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443610"},"modified":"2024-01-12T23:33:33","modified_gmt":"2024-01-13T07:33:33","slug":"descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/","title":{"rendered":"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0 Los arque\u00f3logos que trabajan en las profundidades de la selva amaz\u00f3nica descubrieron una extensa red de ciudades que datan de hace 2.500 a\u00f1os.<\/p>\n<p>Los asentamientos prehisp\u00e1nicos, muy estructurados, con calles anchas y caminos largos y rectos, plazas y grupos de plataformas monumentales, fueron hallados en el valle de Upano, en la Amazon\u00eda ecuatoriana, en las faldas orientales de los Andes, seg\u00fan un estudio publicado el jueves en la revista Science.<\/p>\n<p>El descubrimiento de la red urbana de elementos construidos y excavados m\u00e1s antigua y extensa de la Amazon\u00eda hasta la fecha fue el resultado de m\u00e1s de dos d\u00e9cadas de investigaciones en la regi\u00f3n por parte del equipo de Francia, Alemania, Ecuador y Puerto Rico.<\/p>\n<p>La investigaci\u00f3n comenz\u00f3 con un trabajo de campo antes de desplegar un m\u00e9todo de teledetecci\u00f3n llamado lidar (sistema de medici\u00f3n y detecci\u00f3n de objetos mediante l\u00e1ser), que utiliza luz l\u00e1ser para detectar estructuras bajo las espesas copas de los \u00e1rboles.<\/p>\n<p>El autor principal del estudio, St\u00e9phen Rostain, arque\u00f3logo y director de Investigaci\u00f3n del Centro Nacional de Investigaci\u00f3n Cient\u00edfica (CNRS) de Francia, describi\u00f3 el descubrimiento como &#171;incre\u00edble&#187;.<\/p>\n<p>Colombia se suma a esfuerzos para proteger el 80% de la Amazonia al 2025<\/p>\n<p>Ingenier\u00eda avanzada<\/p>\n<p>&#171;El lidar nos dio una visi\u00f3n general de la regi\u00f3n y pudimos apreciar en gran medida el tama\u00f1o de los sitios&#187;, dijo a CNN el viernes, y agreg\u00f3 que les mostr\u00f3 una &#171;red completa&#187; de caminos excavados. &#171;El lidar fue la cereza del pastel&#187;.<\/p>\n<p>Rostain dijo que las primeras personas que vivieron all\u00ed, hace 3.000 a\u00f1os, ten\u00edan casas peque\u00f1as y desperdigadas.<br \/>\nSin embargo, entre aproximadamente 500 a.C. y 300 a 600 d.C., las culturas Kilamope y m\u00e1s tarde Upano empezaron a construir mont\u00edculos y a asentar sus casas sobre plataformas de tierra, seg\u00fan los autores del estudio. Estas plataformas se organizaban en torno a una plaza baja y cuadrada.<\/p>\n<p>Los datos de la tecnolog\u00eda lidar revelaron la existencia de m\u00e1s de 6.000 plataformas en la mitad sur de los 600 kil\u00f3metros cuadrados estudiados.<\/p>\n<p>Seg\u00fan el estudio, las plataformas eran en su mayor\u00eda rectangulares, aunque algunas eran circulares, y med\u00edan unos 20 por 10 metros. Normalmente se constru\u00edan alrededor de una plaza en grupos de tres o seis. Las plazas tambi\u00e9n sol\u00edan tener una plataforma central.<\/p>\n<p>El equipo tambi\u00e9n descubri\u00f3 complejos monumentales con plataformas mucho m\u00e1s grandes, que probablemente ten\u00edan una funci\u00f3n c\u00edvica o ceremonial.<\/p>\n<p>Se descubrieron al menos 15 grupos de complejos identificados como asentamientos.<\/p>\n<p>Algunos asentamientos estaban protegidos por zanjas, mientras que hab\u00eda obstrucciones de caminos cerca de algunos de los grandes complejos. Seg\u00fan los investigadores, esto sugiere que los asentamientos estaban expuestos a amenazas, ya fueran externas o derivadas de tensiones entre grupos.<\/p>\n<p>Incluso los complejos m\u00e1s aislados estaban conectados por caminos y una extensa red de carreteras rectas m\u00e1s grandes con bordillos.<\/p>\n<p>En las zonas vac\u00edas entre los complejos, el equipo hall\u00f3 rasgos de cultivo de la tierra, como campos de drenaje y terrazas. Seg\u00fan el estudio, estos elementos estaban conectados a una red de senderos.<\/p>\n<p>&#171;Por eso las llamo ciudades jard\u00edn&#187;, dijo Rostain, que a\u00f1adi\u00f3: &#171;Es una revoluci\u00f3n completa en nuestro paradigma sobre la Amazon\u00eda&#187;.<\/p>\n<p>&#171;Tenemos que pensar que todos los (pueblos) ind\u00edgenas de la selva no eran tribus semin\u00f3madas perdidas en la selva, buscando comida. Son una gran variedad, diversidad de casos y algunos ten\u00edan tambi\u00e9n (un) sistema urban\u00edstico, con (una) sociedad estratificada&#187;, dijo.<\/p>\n<p>En un rinc\u00f3n remoto de Asia, una de las ciudades m\u00e1s antiguas del mundo sigue maravillando a los visitantes<\/p>\n<p>La organizaci\u00f3n general de las ciudades sugiere &#171;la existencia de una ingenier\u00eda avanzada&#187; en la \u00e9poca, seg\u00fan los autores del estudio, que concluyeron que el urbanismo de jard\u00edn del valle del Upano &#171;proporciona una prueba m\u00e1s de que la Amazon\u00eda no es la selva pr\u00edstina que una vez se represent\u00f3&#187;.<\/p>\n<p>Rostain dijo que deber\u00edamos imaginarnos la Amazon\u00eda precolombina &#171;como un nido de hormigas&#187;, con todo el mundo ocupado en sus actividades.<\/p>\n<p>Yacimientos similares en todo el continente americano<\/p>\n<p>Seg\u00fan el arque\u00f3logo paisajista Carlos Morales-Aguilar, becario postdoctoral de la Universidad de Texas en Austin, que no particip\u00f3 en el estudio, esta red urbana reci\u00e9n descubierta coincide estrechamente con otros yacimientos hallados en los bosques tropicales de Panam\u00e1, Guatemala, Belice, Brasil y M\u00e9xico.<\/p>\n<p>Morales-Aguilar calific\u00f3 el estudio de &#171;pionero&#187; y dijo a CNN que no solo &#171;proporciona pruebas concretas de una planificaci\u00f3n urbana temprana y avanzada en la Amazon\u00eda, sino que tambi\u00e9n contribuye significativamente a nuestra comprensi\u00f3n del legado cultural y ambiental de las sociedades ind\u00edgenas en esta regi\u00f3n&#187;.<\/p>\n<p>El hallazgo de &#171;supercarreteras&#187; sugiere que la antigua civilizaci\u00f3n maya era m\u00e1s avanzada de lo que se pensaba<\/p>\n<p>En 2022, Morales-Aguilar form\u00f3 parte de un equipo de investigadores que utiliz\u00f3 la tecnolog\u00eda lidar para descubrir un vasto yacimiento en el norte de Guatemala, con cientos de antiguas ciudades, pueblos y aldeas mayas interconectados, as\u00ed como una red de 177 kil\u00f3metros de senderos de piedra elevados que conectaban las comunidades.<\/p>\n<p>El investigador afirm\u00f3 que los hallazgos de este \u00faltimo estudio reflejan las avanzadas t\u00e9cnicas de agricultura y planificaci\u00f3n urbana que observ\u00f3 en el norte de Guatemala y &#171;ofrecen nuevas perspectivas sobre las complejidades de estas sociedades primitivas&#187;.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0 Los arque\u00f3logos que trabajan en las profundidades de la selva amaz\u00f3nica descubrieron una extensa red de ciudades que datan de hace 2.500 a\u00f1os. Los asentamientos prehisp\u00e1nicos, muy estructurados, con calles anchas y caminos largos y rectos, plazas y grupos de plataformas monumentales, fueron hallados en el valle de Upano, en la Amazon\u00eda ecuatoriana, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443610","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0 Los arque\u00f3logos que trabajan en las profundidades de la selva amaz\u00f3nica descubrieron una extensa red de ciudades que datan de hace 2.500 a\u00f1os. Los asentamientos prehisp\u00e1nicos, muy estructurados, con calles anchas y caminos largos y rectos, plazas y grupos de plataformas monumentales, fueron hallados en el valle de Upano, en la Amazon\u00eda ecuatoriana, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-13T07:33:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica\",\"datePublished\":\"2024-01-13T07:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/\"},\"wordCount\":954,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/\",\"name\":\"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-13T07:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/","og_locale":"es_ES","og_type":"article","og_title":"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica - Noticias","og_description":"(CNN) &#8212;\u00a0 Los arque\u00f3logos que trabajan en las profundidades de la selva amaz\u00f3nica descubrieron una extensa red de ciudades que datan de hace 2.500 a\u00f1os. Los asentamientos prehisp\u00e1nicos, muy estructurados, con calles anchas y caminos largos y rectos, plazas y grupos de plataformas monumentales, fueron hallados en el valle de Upano, en la Amazon\u00eda ecuatoriana, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/","og_site_name":"Noticias","article_published_time":"2024-01-13T07:33:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/"},"author":{"name":"","@id":""},"headline":"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica","datePublished":"2024-01-13T07:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/"},"wordCount":954,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/","url":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/","name":"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-13T07:33:33+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Descubren una enorme red de ciudades antiguas en la selva amaz\u00f3nica","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/12\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-13T07:33:33Z","datePublished":"2024-01-13T07:33:33Z","dateModified":"2024-01-13T07:33:33Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Descubren una enorme red de ciudades antiguas en la selva amaz\\u00f3nica\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/12\\\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/12\\\/descubren-una-enorme-red-de-ciudades-antiguas-en-la-selva-amazonica\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-13T07:33:33Z\",\"datePublished\":\"2024-01-13T07:33:33Z\",\"dateModified\":\"2024-01-13T07:33:33Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445424,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/14\/la-amazonia-ha-sobrevivido-a-los-cambios-climaticos-durante-65-millones-de-anos-ahora-se-dirige-al-colapso-segun-un-estudio\/","url_meta":{"origin":1443610,"position":0},"title":"La Amazonia ha sobrevivido a los cambios clim\u00e1ticos durante 65 millones de a\u00f1os. Ahora se dirige al colapso, seg\u00fan un estudio","author":"","date":"febrero 14, 2024","format":false,"excerpt":"(CNN) -- La selva amaz\u00f3nica est\u00e1 a punto de alcanzar un punto de inflexi\u00f3n crucial en 2050, con consecuencias devastadoras para la regi\u00f3n y la capacidad del planeta para hacer frente al cambio clim\u00e1tico, seg\u00fan un estudio publicado este mi\u00e9rcoles.La Amazonia ha demostrado ser resistente a los cambios naturales del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445427,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/14\/la-amazonia-ha-sobrevivido-a-los-cambios-climaticos-durante-65-millones-de-anos-ahora-se-dirige-al-colapso-segun-un-estudio-2\/","url_meta":{"origin":1443610,"position":1},"title":"La Amazonia ha sobrevivido a los cambios clim\u00e1ticos durante 65 millones de a\u00f1os. Ahora se dirige al colapso, seg\u00fan un estudio","author":"","date":"febrero 14, 2024","format":false,"excerpt":"(CNN) -- La selva amaz\u00f3nica est\u00e1 a punto de alcanzar un punto de inflexi\u00f3n crucial en 2050, con consecuencias devastadoras para la regi\u00f3n y la capacidad del planeta para hacer frente al cambio clim\u00e1tico, seg\u00fan un estudio publicado este mi\u00e9rcoles.La Amazonia ha demostrado ser resistente a los cambios naturales del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462711,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/05\/23\/papa-leon-beatificar-misioneros-asesinados-efe\/","url_meta":{"origin":1443610,"position":2},"title":"El papa Le\u00f3n XIV firma decretos para beatificar a misioneros asesinados en la selva amaz\u00f3nica de Ecuador","author":"","date":"mayo 23, 2025","format":false,"excerpt":"Le\u00f3n XIV emiti\u00f3 sus primeros decretos de causas de santos y aprob\u00f3 el primer paso en el camino para beatificaci\u00f3n de dos misioneros: el espa\u00f1ol Alejandro Labaka Ugarte (1920-1987) y la colombiana In\u00e9s Arango Vel\u00e1squez (1937-1987), ambos asesinados violentamente en la selva amaz\u00f3nica de Ecuador, inform\u00f3 este jueves la Santa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446477,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/nueva-especie-serpiente-gigante-selva-amazonica-trax-2\/","url_meta":{"origin":1443610,"position":3},"title":"Descubren nueva especie de serpiente gigante en la selva amaz\u00f3nica: podr\u00eda ser la m\u00e1s grande del mundo","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) --\u00a0Los cient\u00edficos que trabajan en la selva amaz\u00f3nica han descubierto una nueva especie de serpiente, que se rumorea que es la m\u00e1s grande del mundo.Un equipo de la Universidad de Queensland viaj\u00f3 a la Amazon\u00eda ecuatoriana para buscar la anaconda verde del norte (Eunectes akayima), previamente no documentada, tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445950,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/23\/nueva-especie-serpiente-gigante-selva-amazonica-trax\/","url_meta":{"origin":1443610,"position":4},"title":"Descubren nueva especie de serpiente gigante en la selva amaz\u00f3nica: podr\u00eda ser la m\u00e1s grande del mundo","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) --\u00a0Los cient\u00edficos que trabajan en la selva amaz\u00f3nica han descubierto una nueva especie de serpiente, que se rumorea que es la m\u00e1s grande del mundo.Un equipo de la Universidad de Queensland viaj\u00f3 a la Amazon\u00eda ecuatoriana para buscar la anaconda verde del norte (Eunectes akayima), previamente no documentada, tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455890,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/11\/17\/biden-primera-visita-presidencial-historica-amazonia-proximo-gobierno-trump-amenaza-lucha-climatica-trax\/","url_meta":{"origin":1443610,"position":5},"title":"Biden hizo una primera visita presidencial hist\u00f3rica a la Amazonia mientras el pr\u00f3ximo gobierno de Trump representa una amenaza para la lucha clim\u00e1tica","author":"","date":"noviembre 17, 2024","format":false,"excerpt":"(CNN) \u2014 Cuando el presidente de Estados Unidos, Joe Biden, trabaj\u00f3 para mejorar su legado clim\u00e1tico en la Amazonia brasile\u00f1a este domingo, la presencia t\u00e1cita de Donald Trump ensombreci\u00f3 la visita hist\u00f3rica.Nunca antes un presidente estadounidense hab\u00eda pisado la selva amaz\u00f3nica, y Biden quiso utilizar su presencia en ese lugar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443610"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443610\/revisions"}],"predecessor-version":[{"id":1443626,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443610\/revisions\/1443626"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}