{"id":1443632,"date":"2024-01-13T09:33:28","date_gmt":"2024-01-13T17:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443632"},"modified":"2024-01-13T09:33:28","modified_gmt":"2024-01-13T17:33:28","slug":"el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/","title":{"rendered":"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni"},"content":{"rendered":"<p>(CNN) &#8212; Un video viral que muestra a m\u00e1s de 150 hombres vestidos de negro y levantando el brazo derecho para hacer un saludo fascista en el centro de Roma ha causado revuelo en todas partes menos en el despacho de la primera ministra italiana, Giorgia Meloni.<\/p>\n<p>El suceso, ahora investigado por la unidad especial antifascismo de la polic\u00eda de Roma, tuvo lugar la noche del 7 de enero para conmemorar el 46 aniversario de la masacre de Acca Larentia, cuando tres j\u00f3venes militantes neofascistas del Movimiento Social Italiano (MSI) fueron asesinados en la calle de ese nombre.<\/p>\n<p>Dos, Franco Bigonzetti y Francesco Ciavatta, fueron asesinados por presuntos activistas de izquierdas en la calle, frente a la sede del partido MSI, y el tercero, Stefano Recchioni, muri\u00f3 a manos de un agente de polic\u00eda que respond\u00eda a los disturbios tras los primeros asesinatos.<\/p>\n<p>Nunca se ha acusado a nadie de los asesinatos de 1978.<\/p>\n<p>En los videos grabados por curiosos el pasado fin de semana se oye claramente a los hombres que saludan gritar &#171;presente&#187; tres veces mientras levantan el brazo derecho.<\/p>\n<p>A continuaci\u00f3n, uno de ellos lanza un grito de guerra neofascista habitual: &#171;Por todos los camaradas ca\u00eddos&#187;.<\/p>\n<p>Cada 7 de enero se celebra una conmemoraci\u00f3n de sus muertes, en la que la polic\u00eda se encarga de la seguridad, tanto bajo gobiernos de izquierdas como de derechas. A ella asisten constantemente miembros de ambos extremos del espectro pol\u00edtico, que depositan coronas de flores en un monumento a los j\u00f3venes.<\/p>\n<p>El partido MSI surgi\u00f3 de las cenizas del Partido Nacional Fascista de Benito Mussolini tras su desmantelamiento al final de la Segunda Guerra Mundial, cuando el dictador fue depuesto y ejecutado.<\/p>\n<p>Es el partido a trav\u00e9s del cual Meloni entr\u00f3 en pol\u00edtica por primera vez. Ella dirigi\u00f3 el MSI antes de fusionarlo con su propio partido, Hermanos de Italia, m\u00e1s moderado, que gan\u00f3 las elecciones anticipadas de 2022.<\/p>\n<p>Meloni ha asistido a la conmemoraci\u00f3n en la Via Acca Larentia muchas veces en el pasado, seg\u00fan sus propias redes sociales, pero nunca como primera ministra.<\/p>\n<p>Varios miembros del partido de Meloni, entre ellos Francesco Rocca, jefe de la regi\u00f3n del Lacio, donde se encuentra Roma, y el agregado de cultura de Roma, Miguel Gotor, que forma parte del opositor Partido Democr\u00e1tico, asistieron el pasado fin de semana. Gotor y Rocca depositaron una corona de flores en un monumento a los activistas ca\u00eddos, pero se marcharon antes de que se realizara el saludo fascista, seg\u00fan informaron sus oficinas a CNN.<\/p>\n<p>La oposici\u00f3n italiana, incluida la l\u00edder del Partido Democr\u00e1tico, Elly Schlein, ha pedido a Meloni que proh\u00edba los grupos neofascistas.<\/p>\n<p>Aunque la Constituci\u00f3n italiana proh\u00edbe la ideolog\u00eda fascista, en todo el pa\u00eds sigue habiendo monumentos al pasado fascista de Italia, como un obelisco con el nombre de Mussolini frente al Estadio Ol\u00edmpico de Roma.<\/p>\n<p>Es un tema complicado y la ley \u2014como muchas en Italia\u2014 es ambigua. Hacer &#171;apolog\u00eda&#187; del fascismo antiguo es delito en Italia, pero los grupos neofascistas no son ilegales: estos grupos suelen tener cuidado de no adoptar una ideolog\u00eda abiertamente fascista en sus constituciones.<\/p>\n<p>Tampoco son ilegales los recuerdos fascistas ni gestos como el saludo fascista, algo que, seg\u00fan los cr\u00edticos, debe cambiar.<\/p>\n<p>&#171;Esto es Roma, 7 de enero de 2024. Parece 1924&#187;, escribi\u00f3 Schlein en las redes sociales con una imagen del saludo. &#171;Lo que ha pasado es inaceptable. Los grupos neofascistas deben ser disueltos&#187;.<\/p>\n<p>En un pedido al Gobierno para que condene el saludo, Noemi Di Segna, presidenta de la Uni\u00f3n de Comunidades Jud\u00edas Italianas, dijo que las leyes deber\u00edan ser m\u00e1s estrictas, calificando tales actos de &#171;nostalgia peligrosa&#187;.<\/p>\n<p>&#171;Desde hace mucho tiempo pedimos que se refuercen las normas relativas a la nostalgia del neofascismo&#187;, declar\u00f3.<\/p>\n<p>El episodio tambi\u00e9n fue condenado por el vicepresidente y ministro de Asuntos Exteriores de Meloni, Antonio Tajani \u2014actual jefe del partido Forza Italia tras la muerte de Silvio Berlusconi\u2014, quien afirm\u00f3 que su partido es antifascista y que ning\u00fan partido debe celebrar las dictaduras.<\/p>\n<p>Meloni no estuvo en la conmemoraci\u00f3n del domingo por la noche, y solo ha respondido al revuelo calificando de &#171;ataques&#187; a su Gobierno las reacciones y las peticiones de que proh\u00edba los grupos neofascistas.<\/p>\n<p>&#171;Este gobierno contin\u00faa respondiendo a los ataques gratuitos y las controversias de los \u00faltimos d\u00edas por parte de ciertos partidos de la oposici\u00f3n con hechos y resultados&#187;, escribi\u00f3 en Facebook.<\/p>\n<p>Un portavoz de Meloni dijo que la primera ministra probablemente no har\u00eda m\u00e1s comentarios.<\/p>\n<p>La primera ministra de Italia, Giorgia Meloni. (Cr\u00e9dito: Valeria Mongelli\/Bloomberg\/Getty Images)<\/p>\n<p>Un testigo que vive en la calle donde tuvo lugar la conmemoraci\u00f3n dijo a CNN que ocurre todos los a\u00f1os, incluso con el saludo fascista.<\/p>\n<p>&#171;Todos los a\u00f1os conmemoran los asesinatos y ponen flores en el monumento, y todos los a\u00f1os, despu\u00e9s de que los dignatarios se marchan, hacen el saludo&#187;, dijo Maria Calderone a CNN. &#171;Lo chocante es que, en 46 a\u00f1os, reci\u00e9n ahora se le preste atenci\u00f3n&#187;.<\/p>\n<p>&#171;El fascismo en Italia nunca muri\u00f3&#187;<\/p>\n<p>Paolo Berizzi, periodista italiano de La Repubblica que vive bajo protecci\u00f3n policial por sus reportajes sobre el neofascismo y que adquiri\u00f3 el video, dijo a CNN que la raz\u00f3n por la que el fascismo &#171;sigue de moda&#187; en Italia es porque &#171;nunca desapareci\u00f3&#187;.<\/p>\n<p>&#171;El fascismo no es un producto del gobierno de Meloni&#187;, dijo a CNN. &#171;El fascismo en Italia nunca muri\u00f3. Fue derrotado militarmente, pero no fue derrotado culturalmente (&#8230;). En cierto modo est\u00e1 en el est\u00f3mago del pa\u00eds, y resurge en momentos de debilidad&#187;.<\/p>\n<p>Esto contrasta con otros pa\u00edses como Alemania, que tienen tolerancia cero con otras formas de fascismo. Berizzi afirm\u00f3 que &#171;en este momento los grupos neofascistas se sienten protegidos por el silencio de Meloni, por su ambig\u00fcedad. Meloni no es capaz de cortar el cord\u00f3n con su pasado. En cierto modo es reh\u00e9n de su pasado&#187;.<\/p>\n<p>El fiscal principal de Roma abri\u00f3 una investigaci\u00f3n sobre el acto, para determinar si alguien infringi\u00f3 la ley de &#171;apolog\u00eda del fascismo&#187; con el saludo fascista.<\/p>\n<p>La Divisi\u00f3n General de Investigaciones y Operaciones Especiales (DIGOS) de Italia ha identificado a 150 participantes, todos ellos hombres, de los cuales nueve son conocidos militantes de derechas con cargos penales previos relacionados con el fascismo, seg\u00fan un portavoz de la agencia.<\/p>\n<p>En su primer a\u00f1o en el poder, Meloni demostr\u00f3 cumplir promesa de que se hab\u00eda distanciado de su educaci\u00f3n neofascista convirti\u00e9ndose en una de las l\u00edderes m\u00e1s moderadas de Europa, donde ha sido elogiada por su liderazgo en cuestiones que van desde Ucrania a la migraci\u00f3n. Pero su silencio sobre el problema interno que sacude ahora al pa\u00eds puede cambiar todo eso.<\/p>\n<p>El martes, el Parlamento Europeo de Estrasburgo abordar\u00e1 el caso cuando debata el resurgimiento del neofascismo en Europa. Ewan MacPhee, portavoz de los socialdem\u00f3cratas en el Parlamento Europeo, advirti\u00f3 que piensan tomarse en serio el debate.<\/p>\n<p>&#171;El silencio de la primera ministra nos parece a\u00fan m\u00e1s desconcertante, y nos preguntamos por qu\u00e9 no conden\u00f3 los acontecimientos del 7 de enero&#187;, declar\u00f3 MacPhee antes de la reuni\u00f3n del martes, seg\u00fan medios italianos. &#171;El debate se hace necesario y es importante que el Parlamento haga lo que Meloni parece incapaz de hacer: es decir, condenar lo ocurrido&#187;.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un video viral que muestra a m\u00e1s de 150 hombres vestidos de negro y levantando el brazo derecho para hacer un saludo fascista en el centro de Roma ha causado revuelo en todas partes menos en el despacho de la primera ministra italiana, Giorgia Meloni. El suceso, ahora investigado por la unidad especial [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443632","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un video viral que muestra a m\u00e1s de 150 hombres vestidos de negro y levantando el brazo derecho para hacer un saludo fascista en el centro de Roma ha causado revuelo en todas partes menos en el despacho de la primera ministra italiana, Giorgia Meloni. El suceso, ahora investigado por la unidad especial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-13T17:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni\",\"datePublished\":\"2024-01-13T17:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/\"},\"wordCount\":1303,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/\",\"name\":\"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-13T17:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/","og_locale":"es_ES","og_type":"article","og_title":"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni - Noticias","og_description":"(CNN) &#8212; Un video viral que muestra a m\u00e1s de 150 hombres vestidos de negro y levantando el brazo derecho para hacer un saludo fascista en el centro de Roma ha causado revuelo en todas partes menos en el despacho de la primera ministra italiana, Giorgia Meloni. El suceso, ahora investigado por la unidad especial [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/","og_site_name":"Noticias","article_published_time":"2024-01-13T17:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/"},"author":{"name":"","@id":""},"headline":"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni","datePublished":"2024-01-13T17:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/"},"wordCount":1303,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/","url":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/","name":"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-13T17:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El video de una multitud haciendo el saludo fascista en el coraz\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/01\/13\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-13T17:33:28Z","datePublished":"2024-01-13T17:33:28Z","dateModified":"2024-01-13T17:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El video de una multitud haciendo el saludo fascista en el coraz\\u00f3n de Roma sacude a Italia, pero no a su primera ministra, Giorgia Meloni\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/13\\\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/01\\\/13\\\/el-video-de-una-multitud-haciendo-el-saludo-fascista-en-el-corazon-de-roma-sacude-a-italia-pero-no-a-su-primera-ministra-giorgia-meloni\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-13T17:33:28Z\",\"datePublished\":\"2024-01-13T17:33:28Z\",\"dateModified\":\"2024-01-13T17:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448559,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/04\/26\/papa-francisco-sesion-inteligencia-artificial-cumbre-del-g7-trax\/","url_meta":{"origin":1443632,"position":0},"title":"Papa Francisco participar\u00e1 en sesi\u00f3n de Inteligencia Artificial en cumbre del G7","author":"","date":"abril 26, 2024","format":false,"excerpt":"(CNN) -- El papa Francisco participar\u00e1 en la sesi\u00f3n sobre Inteligencia Artificial que el G7 llevar\u00e1 a cabo en su cumbre del pr\u00f3ximo mes de junio, anunci\u00f3 este viernes la primera ministra de Italia, Giorgia Meloni.\"Tengo el honor de anunciar hoy que el papa Francisco asistir\u00e1 a la sesi\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457234,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/01\/05\/trump-se-reune-georgia-meloni-en-mar-a-lago-trax\/","url_meta":{"origin":1443632,"position":1},"title":"Trump se re\u00fane con la primera ministra de Italia, Georgia Meloni, en Mar-a-Lago","author":"","date":"enero 5, 2025","format":false,"excerpt":"El presidente electo Donald Trump se reuni\u00f3 con la primera ministra de Italia, Giorgia Meloni, en Mar-a-Lago en Palm Beach, Florida, este s\u00e1bado, y su campa\u00f1a public\u00f3 una foto de los dos en X.Meloni, miembro del partido de derecha Hermanos de Italia, asumi\u00f3 el cargo en octubre de 2022. Tambi\u00e9n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456610,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/12\/14\/como-meloni-podria-salvar-brecha-trump-europa-trax\/","url_meta":{"origin":1443632,"position":2},"title":"C\u00f3mo la primera ministra de Italia, Giorgia Meloni, podr\u00eda salvar la brecha entre Trump y Europa","author":"","date":"diciembre 14, 2024","format":false,"excerpt":"Hace unos a\u00f1os, habr\u00eda sido inimaginable que Italia fuera el hogar de uno de los Gobiernos m\u00e1s estables de Europa. Los Gobiernos de coalici\u00f3n italianos tend\u00edan a durar poco m\u00e1s de un a\u00f1o antes de desmoronarse, lo que hac\u00eda que Italia fuera previsiblemente impredecible.Pero una serie de factores, incluidas las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459241,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/02\/26\/papa-francisco-mejoria-salud-insuficiencia-renal-retrocedido-trax\/","url_meta":{"origin":1443632,"position":3},"title":"El papa Francisco presenta una leve mejor\u00eda en su salud: la insuficiencia renal leve ha &#171;retrocedido&#187;, dice el Vaticano","author":"","date":"febrero 26, 2025","format":false,"excerpt":"El papa Francisco ha mostrado una \u201cmejor\u00eda leve adicional\u201d y su insuficiencia renal leve \u2014anunciada durante el fin de semana\u2014 ha \u201cretrocedido\u201d, seg\u00fan inform\u00f3 el Vaticano este mi\u00e9rcoles.Francisco, que ha estado hospitalizado durante m\u00e1s de una semana, sigue recibiendo altos flujos de ox\u00edgeno, aunque no tuvo ning\u00fan ataque respiratorio asm\u00e1tico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459093,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/02\/23\/papa-francisco-noche-tranquila-sabado-trax\/","url_meta":{"origin":1443632,"position":4},"title":"El papa Francisco tuvo una noche tranquila y descans\u00f3, inform\u00f3 el Vaticano este domingo","author":"","date":"febrero 23, 2025","format":false,"excerpt":"El papa Francisco pas\u00f3 una noche tranquila y descans\u00f3, dijo la Oficina de Prensa del Vaticano la ma\u00f1ana de este domingo, en un comunicado. Ese informe llega un d\u00eda despu\u00e9s que el Vaticano reportara que el pont\u00edfice hab\u00eda sufrido una \u201ccrisis respiratoria asm\u00e1tica\u201d y se encontraba en estado \u201ccr\u00edtico\u201d.El s\u00e1bado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457375,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/01\/08\/biden-cancela-viaje-roma-italia-incendios-california-trax\/","url_meta":{"origin":1443632,"position":5},"title":"Biden cancela su viaje a Italia para centrarse en la respuesta federal a los incendios de Los \u00c1ngeles","author":"","date":"enero 8, 2025","format":false,"excerpt":"El presidente de EE.UU., Joe Biden, ya no viajar\u00e1 a Italia esta semana como estaba previsto, seg\u00fan anunci\u00f3 la Casa Blanca a \u00faltima hora de este mi\u00e9rcoles, cancelando el viaje en los \u00faltimos d\u00edas de su presidencia para supervisar los voraces incendios forestales en la zona de Los \u00c1ngeles.\u201cTras regresar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1443632"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443632\/revisions"}],"predecessor-version":[{"id":1443648,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1443632\/revisions\/1443648"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1443632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1443632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1443632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}