{"id":1448383,"date":"2024-04-22T18:03:46","date_gmt":"2024-04-23T01:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/"},"modified":"2024-04-22T18:03:46","modified_gmt":"2024-04-23T01:03:46","slug":"nave-voyager-1-datos-tierra-5-meses-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/","title":{"rendered":"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses"},"content":{"rendered":"<p>(CNN) &#8212; Por primera vez en cinco meses, los ingenieros de la NASA recibieron datos descifrables de la Voyager 1 tras idear una soluci\u00f3n creativa para arreglar un problema de comunicaci\u00f3n a bordo de la nave espacial m\u00e1s distante del cosmos.<\/p>\n<p>La Voyager 1 se encuentra actualmente a unos 24.000 millones de kil\u00f3metros de distancia y, a sus 46 a\u00f1os, la sonda ha mostrado m\u00faltiples peculiaridades y signos de envejecimiento en los \u00faltimos a\u00f1os.<\/p>\n<p>La vieja nave Voyager 1 env\u00eda una respuesta sorprendente despu\u00e9s de que la Tierra le diera un \u201cempuj\u00f3n\u201d<\/p>\n<p>El \u00faltimo problema experimentado por la Voyager 1 apareci\u00f3 por primera vez en noviembre de 2023, cuando la unidad de modulaci\u00f3n de telemetr\u00eda del sistema de datos de vuelo comenz\u00f3 a enviar un patr\u00f3n de c\u00f3digo repetitivo indescifrable.<\/p>\n<p>El sistema de datos de vuelo de la Voyager 1 recoge informaci\u00f3n de los instrumentos cient\u00edficos de la nave y la combina con datos de ingenier\u00eda que reflejan su estado de salud actual. El control de la misi\u00f3n en la Tierra recibe esos datos en c\u00f3digo binario, o una serie de unos y ceros.<\/p>\n<p>Pero desde noviembre, el sistema de datos de vuelo de la Voyager 1 ha estado bloqueado en un bucle. Aunque la sonda ha seguido enviando una se\u00f1al de radio constante a su equipo de control de misi\u00f3n en la Tierra durante los \u00faltimos meses, la se\u00f1al no transportaba ning\u00fan dato utilizable.<\/p>\n<p>El equipo de la misi\u00f3n recibi\u00f3 los primeros datos coherentes sobre la salud y el estado de los sistemas de ingenier\u00eda de la Voyager 1 el 20 de abril. Aunque el equipo todav\u00eda est\u00e1 revisando la informaci\u00f3n, todo lo que han visto hasta ahora sugiere que la Voyager 1 est\u00e1 sana y funciona correctamente.<\/p>\n<p>&#171;Hoy ha sido un gran d\u00eda para la Voyager 1&#187;, dijo Linda Spilker, cient\u00edfica del proyecto Voyager en el JPL, en un comunicado el s\u00e1bado. &#171;Volvemos a estar en comunicaci\u00f3n con la nave espacial. Y no podemos esperar a recuperar los datos cient\u00edficos&#187;.<\/p>\n<p>El avance fue el resultado de un ingenioso proceso de ensayo y error y del desentra\u00f1amiento de un misterio que condujo al equipo hasta un \u00fanico chip.<\/p>\n<p>As\u00ed mantiene la NASA funcionando la nave Voyager tras 46 a\u00f1os 2:36<\/p>\n<p>Solucionar problemas a miles de millones de kil\u00f3metros de distancia<\/p>\n<p>Tras descubrir el problema, el equipo de la misi\u00f3n intent\u00f3 enviar comandos para reiniciar el sistema inform\u00e1tico de la nave espacial y averiguar m\u00e1s sobre la causa subyacente del problema.<\/p>\n<p>El 1 de marzo, el equipo envi\u00f3 un comando llamado &#171;poke&#187;, un peque\u00f1o &#171;empuj\u00f3n&#187; a la Voyager 1 para que el sistema de datos de vuelo ejecutara diferentes secuencias de software con la esperanza de descubrir la causa del fallo.<\/p>\n<p>El 3 de marzo, el equipo observ\u00f3 que la actividad de una parte del sistema de datos de vuelo sobresal\u00eda del resto de los datos confusos. Aunque la se\u00f1al no ten\u00eda el formato que el equipo de la Voyager est\u00e1 acostumbrado a ver cuando el sistema de datos de vuelo funciona seg\u00fan lo esperado, un ingeniero de la Red de Espacio Profundo de la NASA fue capaz de decodificarla.<\/p>\n<p>La Red de Espacio Profundo es un sistema de antenas de radio en la Tierra que ayudan a la agencia a comunicarse con las sondas Voyager y otras naves espaciales que exploran nuestro sistema solar.<\/p>\n<p>La se\u00f1al decodificada inclu\u00eda una lectura de toda la memoria del sistema de datos de vuelo.<\/p>\n<p>Al investigar la lectura, el equipo determin\u00f3 la causa del problema: el 3% de la memoria del sistema de datos de vuelo est\u00e1 da\u00f1ada. Un \u00fanico chip responsable de almacenar parte de la memoria del sistema, incluido parte del c\u00f3digo de software de la computadora, no funciona correctamente. Si bien se desconoce la causa del fallo del chip, se cree que podr\u00eda estar desgastado o haber sido alcanzado por una part\u00edcula energ\u00e9tica procedente del espacio, seg\u00fan el equipo.<\/p>\n<p>La p\u00e9rdida del c\u00f3digo en el chip provoc\u00f3 que los datos cient\u00edficos y de ingenier\u00eda de la Voyager 1 quedaran inutilizables.<\/p>\n<p>Como no hab\u00eda forma de reparar el chip, el equipo opt\u00f3 por almacenar el c\u00f3digo afectado del chip en otro lugar de la memoria del sistema. Aunque no pudieron encontrar un lugar lo suficientemente grande como para almacenar todo el c\u00f3digo, pudieron dividirlo en secciones y almacenarlo en diferentes lugares dentro del sistema de datos de vuelo.<\/p>\n<p>&#171;Para que este plan funcionara, tambi\u00e9n tuvieron que ajustar esas secciones de c\u00f3digo para garantizar, por ejemplo, que todas siguieran funcionando como un todo&#187;, seg\u00fan una actualizaci\u00f3n de la NASA. &#171;Tambi\u00e9n era necesario actualizar cualquier referencia a la ubicaci\u00f3n de ese c\u00f3digo en otras partes de la memoria (del sistema de datos de vuelo)&#187;.<\/p>\n<p>Tras determinar el c\u00f3digo necesario para empaquetar los datos de ingenier\u00eda de la Voyager 1, los ingenieros enviaron una se\u00f1al de radio a la sonda ordenando el c\u00f3digo a una nueva ubicaci\u00f3n en la memoria del sistema el 18 de abril.<\/p>\n<p>Dada la inmensa distancia que separa la Voyager 1 de la Tierra, una se\u00f1al de radio tarda unas 22,5 horas en llegar a la sonda, y otras 22,5 horas para que una se\u00f1al de respuesta de la nave espacial llegue a la Tierra.<\/p>\n<p>El 20 de abril, el equipo recibi\u00f3 la respuesta de la Voyager 1 indicando que la modificaci\u00f3n del c\u00f3digo hab\u00eda funcionado, y que por fin pod\u00edan volver a recibir datos de ingenier\u00eda legibles de la sonda.<\/p>\n<p>Miembros del equipo de vuelo de la Voyager celebran tras recibir los primeros datos coherentes de la Voyager 1 en cinco meses en el Laboratorio de Propulsi\u00f3n a Chorro de la NASA el 20 de abril. Cr\u00e9dito: NASA\/JPL-Caltech<\/p>\n<p>Explorando el espacio interestelar<\/p>\n<p>En las pr\u00f3ximas semanas, el equipo continuar\u00e1 reubicando otras partes afectadas del software del sistema, incluidas las responsables de devolver los valiosos datos cient\u00edficos que la Voyager 1 est\u00e1 recopilando.<\/p>\n<p>Las sondas Voyager 1 y su gemela, la Voyager 2, se lanzaron en 1977, dise\u00f1adas inicialmente para durar cinco a\u00f1os, la y son las naves espaciales operativas m\u00e1s longevas de la historia. Su vida \u00fatil excepcionalmente larga significa que ambas naves espaciales han proporcionado informaci\u00f3n adicional sobre nuestro sistema solar y m\u00e1s all\u00e1 despu\u00e9s de alcanzar sus objetivos preliminares de volar por J\u00fapiter, Saturno, Urano y Neptuno hace d\u00e9cadas.<\/p>\n<p>Actualmente, las sondas se aventuran por territorios c\u00f3smicos inexplorados a lo largo de los confines del sistema solar. Ambas se encuentran en el espacio interestelar y son las \u00fanicas naves espaciales que han operado m\u00e1s all\u00e1 de la heliosfera, la burbuja de campos magn\u00e9ticos y part\u00edculas del Sol que se extiende mucho m\u00e1s all\u00e1 de la \u00f3rbita de Plut\u00f3n.<\/p>\n<p>La Voyager 2, que funciona con normalidad, se ha alejado m\u00e1s de 20.300 millones de kil\u00f3metros de nuestro planeta.<br \/>\nA lo largo del tiempo, ambas naves espaciales se han encontrado con problemas inesperados y periodos de falta de comunicaci\u00f3n, incluido un periodo de siete meses en 2020 en el que Voyager 2 no pudo comunicarse con la Tierra.<\/p>\n<p>En agosto de 2023, el equipo de la misi\u00f3n utiliz\u00f3 una t\u00e9cnica de &#171;grito&#187; de larga duraci\u00f3n para restablecer las comunicaciones con la Voyager 2 despu\u00e9s de que un comando orientara inadvertidamente la antena de la nave espacial en la direcci\u00f3n equivocada.<\/p>\n<p>El equipo calcula que faltan unas semanas para recibir los datos cient\u00edficos de la Voyager 1 y est\u00e1 ansioso por ver qu\u00e9 contienen.<\/p>\n<p>&#171;Nunca sabemos con certeza qu\u00e9 va a ocurrir con las Voyager, pero no deja de sorprenderme que sigan adelante&#187;, declar\u00f3 Suzanne Dodd, directora del proyecto Voyager. &#171;Hemos tenido muchas anomal\u00edas, y cada vez son m\u00e1s dif\u00edciles. Pero hasta ahora hemos tenido la suerte de recuperarnos de ellas. Y la misi\u00f3n sigue adelante. Y los ingenieros m\u00e1s j\u00f3venes se est\u00e1n incorporando al equipo Voyager y aportan sus conocimientos para que la misi\u00f3n siga adelante&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Por primera vez en cinco meses, los ingenieros de la NASA recibieron datos descifrables de la Voyager 1 tras idear una soluci\u00f3n creativa para arreglar un problema de comunicaci\u00f3n a bordo de la nave espacial m\u00e1s distante del cosmos. La Voyager 1 se encuentra actualmente a unos 24.000 millones de kil\u00f3metros de distancia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448383","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Por primera vez en cinco meses, los ingenieros de la NASA recibieron datos descifrables de la Voyager 1 tras idear una soluci\u00f3n creativa para arreglar un problema de comunicaci\u00f3n a bordo de la nave espacial m\u00e1s distante del cosmos. La Voyager 1 se encuentra actualmente a unos 24.000 millones de kil\u00f3metros de distancia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T01:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses\",\"datePublished\":\"2024-04-23T01:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/\"},\"wordCount\":1401,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/\",\"name\":\"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-23T01:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses - Noticias","og_description":"(CNN) &#8212; Por primera vez en cinco meses, los ingenieros de la NASA recibieron datos descifrables de la Voyager 1 tras idear una soluci\u00f3n creativa para arreglar un problema de comunicaci\u00f3n a bordo de la nave espacial m\u00e1s distante del cosmos. La Voyager 1 se encuentra actualmente a unos 24.000 millones de kil\u00f3metros de distancia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-23T01:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/"},"author":{"name":"","@id":""},"headline":"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses","datePublished":"2024-04-23T01:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/"},"wordCount":1401,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/","name":"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-23T01:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La nave Voyager 1 env\u00eda datos a la Tierra por primera vez en 5 meses","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/04\/22\/nave-voyager-1-datos-tierra-5-meses-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-23T01:03:46Z","datePublished":"2024-04-23T01:03:46Z","dateModified":"2024-04-23T01:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La nave Voyager 1 env\\u00eda datos a la Tierra por primera vez en 5 meses\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/04\\\/22\\\/nave-voyager-1-datos-tierra-5-meses-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/04\\\/22\\\/nave-voyager-1-datos-tierra-5-meses-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-23T01:03:46Z\",\"datePublished\":\"2024-04-23T01:03:46Z\",\"dateModified\":\"2024-04-23T01:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455515,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/11\/01\/voyager-logra-encender-radiotransmisor-trax\/","url_meta":{"origin":1448383,"position":0},"title":"Una envejecida nave espacial logra encender un radiotransmisor que no utilizaba desde 1981 a 24.000 millones de kil\u00f3metros de distancia","author":"","date":"noviembre 1, 2024","format":false,"excerpt":"(CNN) -- La nave espacial Voyager 1, de 47 a\u00f1os de edad, recuper\u00f3 el contacto con la NASA, aunque no est\u00e1 del todo fuera de peligro, despu\u00e9s de que un problema t\u00e9cnico provocara un corte de comunicaciones de varios d\u00edas con la hist\u00f3rica misi\u00f3n, que se encuentra a miles de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452742,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/09\/16\/sonda-espacial-voyager-enciende-propulsores-trax\/","url_meta":{"origin":1448383,"position":1},"title":"La sonda espacial Voyager 1, de 47 a\u00f1os de antig\u00fcedad, enciende propulsores que no hab\u00eda utilizado en d\u00e9cadas","author":"","date":"septiembre 16, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Los ingenieros de la NASA encendieron con \u00e9xito un conjunto de propulsores que la Voyager 1 no ha utilizado en d\u00e9cadas para resolver un problema que podr\u00eda impedir que la nave espacial de 47 a\u00f1os se comunique con la Tierra a miles de millones de kil\u00f3metros de distancia.Cuando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466780,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/09\/24\/heliosfera-nueva-mision-misterios-entorno-cosmico-trax\/","url_meta":{"origin":1448383,"position":2},"title":"\u00bfQu\u00e9 es la heliosfera? Una nueva misi\u00f3n podr\u00eda desentra\u00f1ar los misterios de este complejo entorno c\u00f3smico","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"Alrededor de nuestro sistema solar existe un escudo c\u00f3smico natural y enigm\u00e1tico llamado heliosfera, y una nueva misi\u00f3n se ha lanzado para ayudar a los astr\u00f3nomos a comprenderla mejor.Creada por el viento solar, un flujo constante de part\u00edculas cargadas que emanan del Sol, la heliosfera act\u00faa como una enorme burbuja\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443330,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/08\/investigadores-revelan-imagenes-con-los-verdaderos-colores-de-urano-y-neptuno\/","url_meta":{"origin":1448383,"position":3},"title":"Investigadores revelan im\u00e1genes con los verdaderos colores de Urano y Neptuno","author":"","date":"enero 8, 2024","format":false,"excerpt":"(CNN) -- Una nueva investigaci\u00f3n descubri\u00f3 que los verdaderos colores de Neptuno y Urano, que a menudo aparecen en las im\u00e1genes con tonos marcadamente diferentes, pueden ser m\u00e1s similares de lo que se pensaba anteriormente.Las primeras vistas detalladas de los dos gigantes de hielo en el borde exterior de nuestro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451035,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/07\/11\/astronauta-starliner-boeing-nave-asombrosa-fallas-trax\/","url_meta":{"origin":1448383,"position":4},"title":"Astronauta del Starliner dice que la nave espacial es &#171;realmente asombrosa&#187; a pesar de las fallas y los retrasos","author":"","date":"julio 11, 2024","format":false,"excerpt":"(CNN) -- La nave espacial Starliner de Boeing y su tripulaci\u00f3n han estado en el espacio durante m\u00e1s de un mes, mucho m\u00e1s que la estad\u00eda de una semana inicialmente prevista.El veh\u00edculo sufri\u00f3 problemas t\u00e9cnicos que retrasaron su regreso indefinidamente, y todav\u00eda no hay una fecha de retorno definida.Pero los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451985,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/08\/19\/nave-espacial-tierra-luna-jupiter-trax\/","url_meta":{"origin":1448383,"position":5},"title":"Una nave espacial se desplazar\u00e1 alrededor de la Tierra y la Luna en su camino hacia J\u00fapiter","author":"","date":"agosto 19, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 La misi\u00f3n Juice, de la Agencia Espacial Europea, est\u00e1 a punto de alcanzar dos hitos hist\u00f3ricos en su largo viaje para estudiar la posible habitabilidad de las lunas heladas de J\u00fapiter.La nave Juice, o Jupiter Icy Moons Explorer, que se lanz\u00f3 en abril de 2023, realizar\u00e1 este lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1448383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1448383"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1448383\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1448383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1448383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1448383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}