{"id":1449411,"date":"2024-05-12T02:03:50","date_gmt":"2024-05-12T09:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/"},"modified":"2024-05-12T02:03:50","modified_gmt":"2024-05-12T09:03:50","slug":"muere-el-cineasta-roger-corman-a-los-98-anos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/","title":{"rendered":"Muere el cineasta Roger Corman a los 98 a\u00f1os"},"content":{"rendered":"<p>(CNN) &#8212; El prol\u00edfico cineasta de Hollywood Roger Corman, cuyas pel\u00edculas su familia describi\u00f3 como \u201crevolucionarias e iconoclastas\u201d, muri\u00f3 a los 98 a\u00f1os el jueves, seg\u00fan su familia.<\/p>\n<p>&#171;Con profunda tristeza y gratitud ilimitada por su extraordinaria vida, recordamos a nuestro amado esposo y padre, Roger Corman&#187;, dijeron su esposa e hijas en un comunicado.<\/p>\n<p>Corman ha producido m\u00e1s de 300 pel\u00edculas y tiene cr\u00e9ditos de direcci\u00f3n en 50 t\u00edtulos, seg\u00fan el sitio web de la Academia de Artes y Ciencias Cinematogr\u00e1ficas.<\/p>\n<p>Fue director y productor de varios proyectos, entre ellos \u201cLa peque\u00f1a tienda de los horrores\u201d.<\/p>\n<p>Corman muri\u00f3 en su casa en Santa M\u00f3nica, California, y estaba \u201crodeado de su familia\u201d, seg\u00fan el comunicado.<\/p>\n<p>&#171;Era generoso, de coraz\u00f3n abierto y amable con todos aquellos que lo conocieron&#187;, contin\u00faa el comunicado. \u201cUn padre devoto y desinteresado, sus hijas lo amaban profundamente. Sus pel\u00edculas fueron revolucionarias e iconoclastas y capturaron el esp\u00edritu de una \u00e9poca\u201d.<\/p>\n<p>En un correo electr\u00f3nico a CNN, Julie, la esposa de Corman, describi\u00f3 a su marido como &#171;apasionado por impulsar las carreras de los dem\u00e1s como lo era por su propia carrera&#187;.<\/p>\n<p>\u201cPens\u00f3 en disparar en la calle cuando nadie lo hac\u00eda. Pens\u00f3 en poner Gritos y susurros de Ingmar Bergman en autocines cuando nadie m\u00e1s lo habr\u00eda hecho\u201d, escribi\u00f3. &#171;Cuando le pregunt\u00e9 c\u00f3mo quer\u00eda que lo recordaran, dijo: &#8216;Yo era cineasta, so\u00f3lo eso&#8217;. Estaba dedicado a sus hijas Catherine y Mary y ellas a \u00e9l&#187;.<\/p>\n<p>A mi marido le apasionaba tanto impulsar las carreras de los dem\u00e1s como la suya propia. Pens\u00f3 en disparar en la calle cuando nadie lo hac\u00eda. Pens\u00f3 en poner Gritos y susurros de Ingmar Bergman en autocines cuando nadie m\u00e1s lo habr\u00eda hecho. Cuando le pregunt\u00e9 c\u00f3mo quer\u00eda que lo recordaran, dijo: &#171;Yo era cineasta, s\u00f3lo eso&#187;. Era devoto de sus hijas Catalina y Mar\u00eda y ellas de \u00e9l.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El prol\u00edfico cineasta de Hollywood Roger Corman, cuyas pel\u00edculas su familia describi\u00f3 como \u201crevolucionarias e iconoclastas\u201d, muri\u00f3 a los 98 a\u00f1os el jueves, seg\u00fan su familia. &#171;Con profunda tristeza y gratitud ilimitada por su extraordinaria vida, recordamos a nuestro amado esposo y padre, Roger Corman&#187;, dijeron su esposa e hijas en un comunicado. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1449411","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere el cineasta Roger Corman a los 98 a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere el cineasta Roger Corman a los 98 a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El prol\u00edfico cineasta de Hollywood Roger Corman, cuyas pel\u00edculas su familia describi\u00f3 como \u201crevolucionarias e iconoclastas\u201d, muri\u00f3 a los 98 a\u00f1os el jueves, seg\u00fan su familia. &#171;Con profunda tristeza y gratitud ilimitada por su extraordinaria vida, recordamos a nuestro amado esposo y padre, Roger Corman&#187;, dijeron su esposa e hijas en un comunicado. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-12T09:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere el cineasta Roger Corman a los 98 a\u00f1os\",\"datePublished\":\"2024-05-12T09:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/\"},\"wordCount\":364,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/\",\"name\":\"Muere el cineasta Roger Corman a los 98 a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-12T09:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere el cineasta Roger Corman a los 98 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere el cineasta Roger Corman a los 98 a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere el cineasta Roger Corman a los 98 a\u00f1os - Noticias","og_description":"(CNN) &#8212; El prol\u00edfico cineasta de Hollywood Roger Corman, cuyas pel\u00edculas su familia describi\u00f3 como \u201crevolucionarias e iconoclastas\u201d, muri\u00f3 a los 98 a\u00f1os el jueves, seg\u00fan su familia. &#171;Con profunda tristeza y gratitud ilimitada por su extraordinaria vida, recordamos a nuestro amado esposo y padre, Roger Corman&#187;, dijeron su esposa e hijas en un comunicado. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-12T09:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/"},"author":{"name":"","@id":""},"headline":"Muere el cineasta Roger Corman a los 98 a\u00f1os","datePublished":"2024-05-12T09:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/"},"wordCount":364,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/","name":"Muere el cineasta Roger Corman a los 98 a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-12T09:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere el cineasta Roger Corman a los 98 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere el cineasta Roger Corman a los 98 a\u00f1os","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/05\/12\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-12T09:03:50Z","datePublished":"2024-05-12T09:03:50Z","dateModified":"2024-05-12T09:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere el cineasta Roger Corman a los 98 a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/05\\\/12\\\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/05\\\/12\\\/muere-el-cineasta-roger-corman-a-los-98-anos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-12T09:03:50Z\",\"datePublished\":\"2024-05-12T09:03:50Z\",\"dateModified\":\"2024-05-12T09:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471284,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/02\/16\/muere-actor-robert-duvall-95-anos-trax\/","url_meta":{"origin":1449411,"position":0},"title":"Muere el actor ganador del Oscar Robert Duvall a los 95 a\u00f1os","author":"","date":"febrero 16, 2026","format":false,"excerpt":"Robert Duvall, el actor ganador del Oscar m\u00e1s conocido por \u201cThe Godfather\u201d, \u201cApocalypse Now\u201d y muchos otros papeles de hombre duro a lo largo de una aclamada carrera en pantalla que se extendi\u00f3 por seis d\u00e9cadas, muri\u00f3. Ten\u00eda 95 a\u00f1os.Duvall muri\u00f3 \u201cen paz\u201d en su casa en Middleburg, Virginia, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449743,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/05\/24\/muere-cineasta-documental-mcdonalds-super-size-me-morgan-spurlock-trax\/","url_meta":{"origin":1449411,"position":1},"title":"Muere a los 53 a\u00f1os el cineasta detr\u00e1s del documental de McDonald&#8217;s &#171;Super Size Me&#187;","author":"","date":"mayo 24, 2024","format":false,"excerpt":"(CNN) -- Morgan Spurlock, el cineasta y expresentador de CNN cuyo documental de McDonald's \"Super Size Me\" fue nominado a un Premio de la Academia, muri\u00f3 el jueves por complicaciones de c\u00e1ncer, inform\u00f3 su familia.Spurlock, que ten\u00eda 53 a\u00f1os, muri\u00f3 en Nueva York, rodeado de familiares y amigos, dijo su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452641,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/09\/13\/chad-mcqueen-karate-muere-trax\/","url_meta":{"origin":1449411,"position":2},"title":"Chad McQueen, protagonista de &#171;Karate Kid&#187; e hijo de Steve McQueen, muere a los 63 a\u00f1os","author":"","date":"septiembre 13, 2024","format":false,"excerpt":"(CNN) -- El actor Chad McQueen, hijo de la leyenda de Hollywood Steve McQueen, muri\u00f3 a los 63 a\u00f1os.McQueen tuvo su gran oportunidad en 1984, cuando fue elegido para el reparto de la exitosa pel\u00edcula \"Karate Kid\", en la que interpretaba a Dutch, el adversario del protagonista Ralph Macchio.Su abogado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455541,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/11\/04\/muere-quincy-jones-a-los-91-anos-trax\/","url_meta":{"origin":1449411,"position":3},"title":"Muere Quincy Jones a los 91 a\u00f1os","author":"","date":"noviembre 4, 2024","format":false,"excerpt":"(CNN) -- El m\u00fasico Quincy Jones muri\u00f3 a los 91 a\u00f1os en su casa de Bel Air, California, \u201crodeado de sus hijos, sus hermanos y familiares cercanos en el momento de su muerte\u201d, seg\u00fan un comunicado de sus representantes.\u201cEsta noche, con el coraz\u00f3n lleno pero roto, debemos compartir la noticia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457055,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/12\/29\/muere-charles-dolan-fundador-hbo-cablevision-trax\/","url_meta":{"origin":1449411,"position":4},"title":"Muere Charles Dolan, fundador de HBO y Cablevision, a los 98 a\u00f1os","author":"","date":"diciembre 29, 2024","format":false,"excerpt":"Charles F. Dolan, quien fund\u00f3 algunas de las empresas de medios m\u00e1s prominentes de Estados Unidos, incluyendo Home Box Office Inc. y Cablevision Systems Corp., muri\u00f3 a los 98 a\u00f1os, seg\u00fan un reporte de noticias.Un comunicado emitido el s\u00e1bado por su familia dijo que Dolan muri\u00f3 de causas naturales, inform\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469899,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/01\/08\/quien-mujer-murio-disparos-ice-minneapolis-trax\/","url_meta":{"origin":1449411,"position":5},"title":"\u00bfQui\u00e9n era Renee Nicole Good, la mujer que muri\u00f3 baleada por un agente de ICE en Minneapolis?","author":"","date":"enero 8, 2026","format":false,"excerpt":"La mujer que muri\u00f3 baleada por un agente de Inmigraci\u00f3n y Control de Aduanas en Minneapolis era una madre amorosa, una poeta y una compa\u00f1era cuya familia \u2014junto con los vecinos de su at\u00f3nita ciudad y extra\u00f1os mucho m\u00e1s all\u00e1\u2014 est\u00e1 conmocionada por las circunstancias que rodearon su muerte.Renee Nicole\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1449411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1449411"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1449411\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1449411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1449411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1449411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}