{"id":1450564,"date":"2024-06-20T17:03:38","date_gmt":"2024-06-21T00:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/"},"modified":"2024-06-20T17:03:38","modified_gmt":"2024-06-21T00:03:38","slug":"cientificos-gen-obesidad-nuevo-estudio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/","title":{"rendered":"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio"},"content":{"rendered":"<p>(CNN) &#8212; La obesidad no es simplemente una cuesti\u00f3n de comida y ejercicio: puede estar en tu c\u00f3digo gen\u00e9tico, seg\u00fan una nueva investigaci\u00f3n.<\/p>\n<p>&#171;Las causas de la obesidad son muy complejas y, en la mayor\u00eda de los casos, la combinaci\u00f3n de muchos factores. En este estudio, sin embargo, hemos hallado un claro desencadenante gen\u00e9tico de la obesidad&#187;, afirma en un correo electr\u00f3nico el Dr. Mattia Frontini, autor principal del estudio, investigador principal de la Fundaci\u00f3n Brit\u00e1nica del Coraz\u00f3n y profesor asociado de Biolog\u00eda Celular en la Universidad de Exeter, en el Reino Unido.<\/p>\n<p>La obesidad se relaciona con el desarrollo de ciertos tipos de c\u00e1ncer, seg\u00fan especialista<\/p>\n<p>Los investigadores utilizaron datos del Biobanco del Reino Unido, una gran base de datos biom\u00e9dica y recurso de investigaci\u00f3n que realiza un seguimiento a largo plazo de las personas, seg\u00fan el estudio publicado el jueves en la revista acad\u00e9mica Med. Los investigadores compararon los datos de personas con dos copias defectuosas de un gen concreto (SMIM1) con los de aquellas que no ten\u00edan las dos copias defectuosas.<\/p>\n<p>Seg\u00fan el estudio, las mujeres con la mutaci\u00f3n gen\u00e9tica pesaban 4,6 kilos m\u00e1s y los hombres con la variante 2,4 kilos m\u00e1s.<br \/>\nLas copias defectuosas del gen SMIM1 provocan una disminuci\u00f3n de la funci\u00f3n tiroidea y un menor gasto energ\u00e9tico, seg\u00fan Frontini, &#171;lo que significa que, dada la misma ingesta de alimentos, se utiliza menos energ\u00eda y este exceso se almacena en forma de grasa&#187;.<\/p>\n<p>La correlaci\u00f3n no s\u00f3lo es significativa, sino que adem\u00e1s este estudio identifica una mutaci\u00f3n gen\u00e9tica espec\u00edfica, lo que no siempre ocurre en la investigaci\u00f3n, se\u00f1al\u00f3 el Dr. Philipp Scherer, director del Centro de Diabetes Touchstone del Centro M\u00e9dico Southwestern de la Universidad de Texas, que no particip\u00f3 en el estudio.<\/p>\n<p>&#171;Se trata de un estudio emocionante, porque pone un nuevo gen en el mapa&#187;, dijo Scherer. &#171;Se trata de un gen real, y no s\u00f3lo de un locus gen\u00f3mico con una mutaci\u00f3n en alg\u00fan lugar que no comprendemos&#8230; Creemos que estamos ante un gen que podemos seguir estudiando&#187;.<\/p>\n<p>Este hallazgo gen\u00e9tico es &#171;bastante raro&#187;<\/p>\n<p>Este hallazgo gen\u00e9tico en particular no se aplica a una gran poblaci\u00f3n de personas con obesidad &#8211; s\u00f3lo alrededor de 1 de cada 5.000 personas tienen esta composici\u00f3n gen\u00e9tica, dijo Frontini.<\/p>\n<p>&#171;Es bastante raro, pero si lo multiplicamos por una poblaci\u00f3n de 10 o 15 millones, hay bastantes personas que podr\u00edan andar por ah\u00ed con esa mutaci\u00f3n y tal vez no fueran plenamente conscientes de que existe una explicaci\u00f3n gen\u00e9tica para su lucha contra la obesidad&#187;, dijo Scherer.<\/p>\n<p>Seg\u00fan Frontini, la disfunci\u00f3n tiroidea es frecuente y afecta a casi el 2% de la poblaci\u00f3n del Reino Unido. Y la disfunci\u00f3n tiroidea se trata regularmente con un medicamento relativamente asequible, dijo Frontini.<\/p>\n<p>El siguiente paso de la investigaci\u00f3n es averiguar si las personas con la mutaci\u00f3n SMIM1 cumplen los requisitos para tratar su tiroides con medicaci\u00f3n, a\u00f1adi\u00f3.<\/p>\n<p>&#171;En caso afirmativo, tenemos previsto realizar un ensayo cl\u00ednico aleatorizado para determinar si se beneficiar\u00edan del tratamiento&#187;, explic\u00f3 Frontini. &#171;La esperanza es que lo hagan y podamos mejorar su calidad de vida utilizando un tratamiento barato y seguro&#187;.<\/p>\n<p>Lo que muestran los resultados del ensayo cl\u00ednico m\u00e1s largo de Wegovy sobre la p\u00e9rdida de peso, los efectos secundarios y la protecci\u00f3n del coraz\u00f3n<\/p>\n<p>El mejor enfoque mientras tanto<\/p>\n<p>El peso no es s\u00f3lo cuesti\u00f3n de fuerza de voluntad o pereza. Seg\u00fan el Instituto Nacional de Diabetes y Enfermedades Digestivas y Renales, el tama\u00f1o y la forma del cuerpo vienen determinados por muchos factores, sobre algunos de los cuales se tiene control y sobre otros no.<\/p>\n<p>Entre estos factores est\u00e1n los h\u00e1bitos de vida, la cantidad de horas de sue\u00f1o, los medicamentos, los problemas de salud, el lugar de residencia y de trabajo, y la gen\u00e9tica, seg\u00fan el Instituto.<\/p>\n<p>Todav\u00eda se est\u00e1n investigando los factores gen\u00e9ticos y los posibles tratamientos, pero Scherer afirma que la mejor estrategia actual para el tratamiento m\u00e9dico de la obesidad es la medicaci\u00f3n con GLP-1.<\/p>\n<p>Las dietas restrictivas severas no son la soluci\u00f3n, afirma Brooke Alpert, dietista titulada y autora de &#171;The Diet Detox: Why Your Diet Is Making You Fat and What to Do About It&#187;, en un art\u00edculo anterior de CNN.<\/p>\n<p>Demonizar demasiado los alimentos puede hacer que se te antojen m\u00e1s, y luego la culpa que sientes cuando cedes puede llevar a un ciclo de fluctuar entre restringirte y darte atracones, a\u00f1adi\u00f3.<\/p>\n<p>Si quieres hacer cambios en tu estilo de vida, lo mejor es intentar un enfoque gradual y sostenible mientras mantienes una relaci\u00f3n sana con la comida, afirm\u00f3 Emily Feig, becaria posdoctoral del Hospital General de Massachusetts, en el mismo reportaje de CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La obesidad no es simplemente una cuesti\u00f3n de comida y ejercicio: puede estar en tu c\u00f3digo gen\u00e9tico, seg\u00fan una nueva investigaci\u00f3n. &#171;Las causas de la obesidad son muy complejas y, en la mayor\u00eda de los casos, la combinaci\u00f3n de muchos factores. En este estudio, sin embargo, hemos hallado un claro desencadenante gen\u00e9tico de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450564","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La obesidad no es simplemente una cuesti\u00f3n de comida y ejercicio: puede estar en tu c\u00f3digo gen\u00e9tico, seg\u00fan una nueva investigaci\u00f3n. &#171;Las causas de la obesidad son muy complejas y, en la mayor\u00eda de los casos, la combinaci\u00f3n de muchos factores. En este estudio, sin embargo, hemos hallado un claro desencadenante gen\u00e9tico de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-21T00:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio\",\"datePublished\":\"2024-06-21T00:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/\"},\"wordCount\":881,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/\",\"name\":\"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-21T00:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio - Noticias","og_description":"(CNN) &#8212; La obesidad no es simplemente una cuesti\u00f3n de comida y ejercicio: puede estar en tu c\u00f3digo gen\u00e9tico, seg\u00fan una nueva investigaci\u00f3n. &#171;Las causas de la obesidad son muy complejas y, en la mayor\u00eda de los casos, la combinaci\u00f3n de muchos factores. En este estudio, sin embargo, hemos hallado un claro desencadenante gen\u00e9tico de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-21T00:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/"},"author":{"name":"","@id":""},"headline":"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio","datePublished":"2024-06-21T00:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/"},"wordCount":881,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/","name":"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-21T00:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-21T00:03:38Z","datePublished":"2024-06-21T00:03:38Z","dateModified":"2024-06-21T00:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cient\\u00edficos identifican un gen relacionado con la obesidad, seg\\u00fan un nuevo estudio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/20\\\/cientificos-gen-obesidad-nuevo-estudio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/20\\\/cientificos-gen-obesidad-nuevo-estudio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-21T00:03:38Z\",\"datePublished\":\"2024-06-21T00:03:38Z\",\"dateModified\":\"2024-06-21T00:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455881,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/11\/17\/reino-unido-medicamentos-adelgazar-desempleo-expertos-fantasia-trax\/","url_meta":{"origin":1450564,"position":0},"title":"Reino Unido cree que los medicamentos para adelgazar podr\u00edan aliviar el desempleo. Los expertos dicen que eso es una fantas\u00eda","author":"","date":"noviembre 17, 2024","format":false,"excerpt":"(CNN) -- Los medicamentos para adelgazar como Wegovy y Ozempic fueron aclamados en todo el mundo como revolucionarios para la medicina. En Reino Unido, el gobierno espera que tambi\u00e9n puedan mejorar las finanzas p\u00fablicas, considerando su uso para ayudar a los desempleados a reincorporarse a la fuerza laboral y, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457840,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/01\/24\/nueva-definicion-obesidad-trax\/","url_meta":{"origin":1450564,"position":1},"title":"Podr\u00eda haber una nueva definici\u00f3n de obesidad. Una m\u00e9dica nos explica por qu\u00e9 es importante","author":"","date":"enero 24, 2025","format":false,"excerpt":"Durante a\u00f1os, los expertos m\u00e9dicos han definido la obesidad bas\u00e1ndose principalmente en el \u00edndice de masa corporal, que mide la grasa acumulada calculando la altura y el peso, para determinar los riesgos para la salud de una persona.Las principales organizaciones de salud p\u00fablica, como la Organizaci\u00f3n Mundial de la Salud\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465112,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/08\/04\/alimentos-ultraprocesados-perdida-peso-trax\/","url_meta":{"origin":1450564,"position":2},"title":"Comer alimentos m\u00ednimamente procesados duplica p\u00e9rdida de peso incluso con  ultraprocesados que son saludables, dice estudio","author":"","date":"agosto 4, 2025","format":false,"excerpt":"Las personas en el Reino Unido perdieron el doble de peso comiendo comidas t\u00edpicamente hechas en casa que cuando com\u00edan alimentos ultraprocesados comprados en tiendas considerados saludables, seg\u00fan ha descubierto la investigaci\u00f3n m\u00e1s reciente.\u201cEste nuevo estudio muestra que incluso cuando una dieta ultraprocesada cumple con las pautas nutricionales, las personas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447032,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/16\/predisposicion-genetica-peso-consejos-trax\/","url_meta":{"origin":1450564,"position":3},"title":"Algunas personas tienen una predisposici\u00f3n gen\u00e9tica a subir de peso. Aqu\u00ed hay algunos consejos que pueden ayudar","author":"","date":"marzo 16, 2024","format":false,"excerpt":"(CNN) --\u00a0 Cuando la Asociaci\u00f3n M\u00e9dica Estadounidense vot\u00f3 a favor de reconocer la obesidad como una enfermedad en el a\u00f1o 2013, el grupo profesional m\u00e1s grande de m\u00e9dicos allan\u00f3 el camino para que finalmente la problem\u00e1tica sea tomada en serio.En ese momento, e incluso ahora, hubo mucha controversia en torno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459699,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/03\/09\/pilar-quevedo-el-62-63-de-las-personas-que-viven-en-argentina-tienen-sobrepeso-u-obesidad\/","url_meta":{"origin":1450564,"position":4},"title":"Pilar Quevedo:  &#171;El 62, 63% de las personas que viven en Argentina tienen sobrepeso u obesidad&#187;","author":"","date":"marzo 9, 2025","format":false,"excerpt":"Pilar Quevedo, jefa de la Divisi\u00f3n Nutrici\u00f3n del Hospital de Cl\u00ednicas habl\u00f3 este domingo con CNN Radio sobre la obesidad.En Mundo UBA con Ricardo Braginski indic\u00f3: \u201cNosotros tenemos como dos datos. Uno, lo que es la Encuesta Nacional de Factores de Riesgo, que es salud p\u00fablica que se va actualizando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473141,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/14\/ultraprocesados-aumentan-grasa-musculos-trax\/","url_meta":{"origin":1450564,"position":5},"title":"Los alimentos ultraprocesados aumentan la grasa en los m\u00fasculos, advierte estudio","author":"","date":"abril 14, 2026","format":false,"excerpt":"La imagen parece una rebanada de carne con abundante marmoleo, similar a un corte de alta calidad con finas vetas de grasa. Pero no es comida. Es una resonancia magn\u00e9tica del muslo de una mujer de 62 a\u00f1os que obten\u00eda el 87 % de sus calor\u00edas anuales de alimentos ultraprocesados.\u201cLa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1450564"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450564\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1450564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1450564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1450564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}