{"id":1450600,"date":"2024-06-21T18:03:39","date_gmt":"2024-06-22T01:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/"},"modified":"2024-06-21T18:03:39","modified_gmt":"2024-06-22T01:03:39","slug":"cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/","title":{"rendered":"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca"},"content":{"rendered":"<p>(CNN) &#8212; El n\u00famero oficial de muertos en la peregrinaci\u00f3n Hajj de este a\u00f1o se ha disparado a casi 500 y el n\u00famero real podr\u00eda ser m\u00e1s del doble, ya que surgieron informes de que hasta 600 fieles egipcios murieron en la ruta a La Meca en medio de un calor extremo.<\/p>\n<p>Al menos 14 malasios, 165 indonesios, 75 jordanos, 35 paquistan\u00edes, 49 tunecinos, 11 iran\u00edes y 98 indios han muerto, seg\u00fan las autoridades de cada pa\u00eds. Otros 27 jordanos est\u00e1n hospitalizados y alrededor de 14 siguen desaparecidos, afirm\u00f3 el Ministerio de Asuntos Exteriores de Jordania.<\/p>\n<p>El Departamento de Estado de Estados Unidos dijo que varios ciudadanos estadounidenses murieron durante la peregrinaci\u00f3n Hajj, pero no proporcion\u00f3 una cifra. \u201cPodemos confirmar la muerte de varios ciudadanos estadounidenses en Arabia Saudita. Ofrecemos nuestras m\u00e1s sinceras condolencias a las familias por su p\u00e9rdida\u201d, dijo el portavoz del Departamento de Estado, y agreg\u00f3 que la agencia est\u00e1 lista para brindar asistencia consular.<\/p>\n<p>Decenas de peregrinos del Hajj mueren mientras las temperaturas en La Meca alcanzan los 49 \u00baC<\/p>\n<p>Decenas de iran\u00edes tambi\u00e9n han sido hospitalizados debido a insolaci\u00f3n y otras afecciones, dijo el mi\u00e9rcoles la Media Luna Roja iran\u00ed, seg\u00fan la agencia de noticias semioficial iran\u00ed Tasnim.<\/p>\n<p>Seg\u00fan un recuento de CNN, esto eleva el \u00faltimo n\u00famero oficial de muertos durante la peregrinaci\u00f3n de este a\u00f1o a al menos 480.<\/p>\n<p>Se espera que el n\u00famero de muertos aumente mucho m\u00e1s, ya que Arabia Saudita y Egipto a\u00fan no han publicado cifras oficiales. Adem\u00e1s, los gobiernos solo conocen a los peregrinos que se han registrado y han viajado a La Meca como parte de la cuota de su pa\u00eds; se teme que haya m\u00e1s muertes entre los peregrinos no registrados.<\/p>\n<p>Los peregrinos hicieron el viaje de este a\u00f1o en temperaturas peligrosamente altas, de hasta 49 grados cent\u00edgrados (120 grados Fahrenheit).<\/p>\n<p>Una peregrina musulmana turca se vierte agua fr\u00eda de una botella en la cabeza para refrescarse mientras espera en la ciudad santa de La Meca, en Arabia Saudita, el 20 de junio de 2024. (Foto de ABDEL GHANI BASHIR \/AFP v\u00eda Getty Images)<\/p>\n<p>De acuerdo la Presidencia de Egipto, la unidad de crisis estar\u00e1 encabezada por el primer ministro Mostafa Madbouly y \u201cbrindar\u00e1 apoyo a las familias de los fallecidos\u201d.<\/p>\n<p>El presidente de Egipto, Abdel Fattah el-Sisi, tambi\u00e9n ha dado instrucciones a la unidad sobre la &#171;pronta coordinaci\u00f3n con las autoridades de Arabia Saudita para facilitar la devoluci\u00f3n de los cuerpos&#187; de los que murieron, a\u00f1ade el comunicado.<\/p>\n<p>El n\u00famero oficial de egipcios muertos es de 28, seg\u00fan un comunicado del gabinete egipcio del jueves. Sin embargo, la agencia de noticias Reuters y otros medios informan ampliamente que entre 500 y 600 egipcios murieron en la ruta.<\/p>\n<p>Los funcionarios egipcios dijeron que estaban trabajando para reunir un recuento preciso de v\u00edctimas y personas desaparecidas. La discrepancia se debe a un gran n\u00famero de peregrinos no registrados que no se cuentan entre los que se contabilizaron y viajaron a La Meca como parte de la cuota de su pa\u00eds.<\/p>\n<p>Miles m\u00e1s han sido tratados por insolaci\u00f3n despu\u00e9s de que una multitud estimada en 1,8 millones de musulmanes se enfrentara a las altas temperaturas.<\/p>\n<p>El Ministerio de Salud saudita implement\u00f3 medidas de seguridad, incluidas estaciones de enfriamiento a lo largo de la ruta oficial, e inst\u00f3 a los peregrinos a usar paraguas y mantenerse hidratados, inform\u00f3 The Associated Press. A pesar de esto, el evento de este a\u00f1o se vio ensombrecido por la tragedia, lo que gener\u00f3 dudas sobre si se podr\u00eda haber hecho m\u00e1s para garantizar la seguridad de las personas.<\/p>\n<p>Tambi\u00e9n pone de relieve los peligros que representan para los numerosos fieles no registrados que quieren cumplir con su deber religioso a pesar de no obtener un permiso para el Hajj y que no tienen acceso a las instalaciones oficiales.<\/p>\n<p>Un peregrino recibe un chorro de agua fr\u00eda en Mina, cerca de la ciudad santa de La Meca. (Rafiq Maqbool\/AP)<\/p>\n<p>De las decenas de jordanos que murieron de insolaci\u00f3n mientras realizaban los rituales del Hajj, al menos 68 peregrinos obtuvieron permisos para ser enterrados en La Meca por deseo de sus familias, afirm\u00f3 el jefe de la Direcci\u00f3n de Operaciones y Asuntos Consulares de Jordania, Sufian Qudah.<\/p>\n<p>El ministro de Asuntos Religiosos de Malasia, Dr. Mohd Na&#8217;im Mokhtar, dijo que la mayor\u00eda de los peregrinos de su pa\u00eds murieron de &#171;enfermedades card\u00edacas, neumon\u00eda e infecciones de la sangre&#187;, seg\u00fan la agencia estatal de noticias Bernama. El informe Bernama no especific\u00f3 si los muertos eran miembros de la delegaci\u00f3n oficial del Hajj del pa\u00eds.<\/p>\n<p>Un portavoz del Ministerio de Asuntos Exteriores de la India anunci\u00f3 la muerte de los 98 ciudadanos indios el viernes y dijo: &#171;Estas muertes se han producido por enfermedades naturales, causas naturales, enfermedades cr\u00f3nicas y tambi\u00e9n por vejez&#187;.<\/p>\n<p>El s\u00e1bado, d\u00eda en que los musulmanes se re\u00fanen en el monte Arafat y donde se cree que el profeta Mahoma pronunci\u00f3 su \u00faltimo serm\u00f3n, seis ciudadanos indios murieron en medio de un calor extremo y otros cuatro murieron debido a &#171;accidentes&#187;, afirm\u00f3 el portavoz, sin dar m\u00e1s detalles.<\/p>\n<p>Las consecuencias de las muertes provocaron que el presidente de T\u00fanez, Kais Saied, despidiera al ministro de Asuntos Religiosos del pa\u00eds. Antes de su despido, Ibrahim Chaibi hab\u00eda reconocido la posibilidad de negligencia en el cuidado de los peregrinos. \u201cEs posible que haya habido negligencia. Estar\u00e1 presente y lo evaluaremos a nivel ministerial, y quien no lo haga ser\u00e1 castigado\u201d, dijo Chaibi el viernes.<\/p>\n<p>El Gobierno saudita dijo el lunes que m\u00e1s de 2.700 personas hab\u00edan sido tratadas por insolaci\u00f3n. Mientras tanto, cientos de personas han recurrido a las redes sociales para publicar sobre la desaparici\u00f3n de sus seres queridos.<\/p>\n<p>M\u00e1s de 1,8 millones de personas participan en el Hajj de este a\u00f1o, una de las reuniones religiosas m\u00e1s grandes del mundo, seg\u00fan la Autoridad General de Estad\u00edsticas de Arabia Saudita.<\/p>\n<p>Si bien las muertes entre los peregrinos no son inusuales (hubo m\u00e1s de 200 el a\u00f1o pasado), la reuni\u00f3n de este a\u00f1o se lleva a cabo en medio de temperaturas particularmente altas.<\/p>\n<p>Seis peregrinos del Hajj mueren por insolaci\u00f3n en La Meca tras advertencia de temperaturas cercanas a los 48 grados Celsius<\/p>\n<p>La temporada del Hajj cambia cada a\u00f1o seg\u00fan el calendario isl\u00e1mico y este a\u00f1o cay\u00f3 en junio, uno de los meses m\u00e1s calurosos del reino.<\/p>\n<p>Arabia Saudita aconsej\u00f3 a los peregrinos que no realizaran el ritual de \u201clapidaci\u00f3n del diablo\u201d entre ciertas horas despu\u00e9s de que las temperaturas alcanzaran los extremos 49 grados Celsius (120 grados Fahrenheit).<\/p>\n<p>Los funcionarios del Hajj pidieron a los peregrinos que llevaran paraguas y se mantuvieran hidratados en medio de las duras condiciones, mientras que el ej\u00e9rcito saud\u00ed despleg\u00f3 m\u00e1s de 1.600 elementos con unidades m\u00e9dicas espec\u00edficas para golpes de calor y 30 equipos de respuesta r\u00e1pida. Participaron otros 5.000 voluntarios de salud y primeros auxilios.<\/p>\n<p>Realizar el Hajj es uno de los cinco pilares del Islam, que requiere que todo musulm\u00e1n que sea f\u00edsica y financieramente capaz de hacer el viaje a la ciudad santa de La Meca al menos una vez en su vida.<\/p>\n<p>La peregrinaci\u00f3n incluye numerosos rituales detallados, incluido el uso de una prenda especial que simboliza la igualdad humana y la unidad ante Dios, una procesi\u00f3n circular en sentido anti contrario a las manecillas del reloj alrededor del edificio de la Kaaba en forma de cubo y la lapidaci\u00f3n simb\u00f3lica del mal.<\/p>\n<p>Peregrinos musulmanes usan paraguas para protegerse del sol mientras llegan para arrojar piedras a los pilares en la lapidaci\u00f3n simb\u00f3lica del diablo en Mina, cerca de la ciudad santa de La Meca, el 18 de junio de 2024. (Cr\u00e9dito: Rafiq Maqbool\/AP)<\/p>\n<p>Una fuente de prestigio e ingresos<\/p>\n<p>El Hajj es una fuente de prestigio para el rey de Arabia Saudita, que ostenta el t\u00edtulo de Custodio de las Dos Mezquitas Sagradas como guardi\u00e1n de los lugares m\u00e1s sagrados del Islam. Pero la peregrinaci\u00f3n es tambi\u00e9n una importante fuente de ingresos para la econom\u00eda saudita.<\/p>\n<p>Poco despu\u00e9s de que el rey Salman bin Abdulaziz asumiera el poder en 2015, Arabia Saudita lanz\u00f3 un proyecto de US$ 21.000 millones para ampliar la Gran Mezquita de La Meca para dar cabida a 300.000 fieles adicionales. Un a\u00f1o despu\u00e9s, el entonces pr\u00edncipe heredero adjunto Mohammed bin Salman identific\u00f3 la peregrinaci\u00f3n como un componente clave de un plan para diversificar la econom\u00eda saudita para 2030.<\/p>\n<p>Los expertos dicen que, dado que las ventas de petr\u00f3leo generan cerca de US$ 1.000 millones diarios para el reino, el beneficio econ\u00f3mico de la peregrinaci\u00f3n es marginal en comparaci\u00f3n. Pero su gran potencial sin explotar podr\u00eda aportar importantes riquezas al reino en el largo plazo.<\/p>\n<p>Se pronosticaba que los ingresos por peregrinaci\u00f3n alcanzar\u00edan un promedio de unos US$ 30.000 millones al a\u00f1o y crear\u00edan 100.000 puestos de trabajo para los sauditas cuando el reino atra\u00eda a alrededor de 21 millones de fieles anualmente durante el Hajj de 10 d\u00edas, as\u00ed como la peregrinaci\u00f3n de un a\u00f1o de duraci\u00f3n de la Umrah, seg\u00fan datos oficiales citados por Reuters. El objetivo del gobierno es llegar a 30 millones de peregrinos para 2030.<\/p>\n<p>Edward Szekeres, Handi Alkhshali y Aishwarya S Iyer contribuyeron con el reportaje de esta publicaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El n\u00famero oficial de muertos en la peregrinaci\u00f3n Hajj de este a\u00f1o se ha disparado a casi 500 y el n\u00famero real podr\u00eda ser m\u00e1s del doble, ya que surgieron informes de que hasta 600 fieles egipcios murieron en la ruta a La Meca en medio de un calor extremo. Al menos 14 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450600","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El n\u00famero oficial de muertos en la peregrinaci\u00f3n Hajj de este a\u00f1o se ha disparado a casi 500 y el n\u00famero real podr\u00eda ser m\u00e1s del doble, ya que surgieron informes de que hasta 600 fieles egipcios murieron en la ruta a La Meca en medio de un calor extremo. Al menos 14 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-22T01:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca\",\"datePublished\":\"2024-06-22T01:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/\"},\"wordCount\":1648,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/\",\"name\":\"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-22T01:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca - Noticias","og_description":"(CNN) &#8212; El n\u00famero oficial de muertos en la peregrinaci\u00f3n Hajj de este a\u00f1o se ha disparado a casi 500 y el n\u00famero real podr\u00eda ser m\u00e1s del doble, ya que surgieron informes de que hasta 600 fieles egipcios murieron en la ruta a La Meca en medio de un calor extremo. Al menos 14 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-22T01:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/"},"author":{"name":"","@id":""},"headline":"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca","datePublished":"2024-06-22T01:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/"},"wordCount":1648,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/","name":"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-22T01:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cientos de personas murieron por ola de calor en peregrinaci\u00f3n del Hajj a La Meca","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/21\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-22T01:03:39Z","datePublished":"2024-06-22T01:03:39Z","dateModified":"2024-06-22T01:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cientos de personas murieron por ola de calor en peregrinaci\\u00f3n del Hajj a La Meca\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/21\\\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/21\\\/cientos-murieron-ola-calor-peregrinacion-hajj-la-meca-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-22T01:03:39Z\",\"datePublished\":\"2024-06-22T01:03:39Z\",\"dateModified\":\"2024-06-22T01:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450524,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/19\/peregrinos-mueren-temperaturas-meca-49-trax\/","url_meta":{"origin":1450600,"position":0},"title":"Decenas de peregrinos del Hajj mueren mientras las temperaturas en La Meca alcanzan los 49 \u00baC","author":"","date":"junio 19, 2024","format":false,"excerpt":"(CNN) -- Decenas de personas murieron y miles fueron asistidas por insolaci\u00f3n mientras realizaban la peregrinaci\u00f3n anual musulmana Hajj a La Meca en medio de temperaturas extremas de hasta 49 \u00baC (120 \u00baF).Al menos 41 jordanos, 35 tunecinos y 11 iran\u00edes se encuentran entre los muertos, seg\u00fan las autoridades de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450633,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/egipto-revocara-licencias-empresas-turisticas-hajj-ilegales-muertes-calor-trax\/","url_meta":{"origin":1450600,"position":1},"title":"Arabia Saudita informa que este a\u00f1o han muerto m\u00e1s de 1.300 personas en peregrinaci\u00f3n del Hajj","author":"","date":"junio 23, 2024","format":false,"excerpt":"(CNN) -- Arabia Saudita inform\u00f3 este domingo que m\u00e1s de 1.300 personas murieron en la peregrinaci\u00f3n del Hajj de este a\u00f1o, y que m\u00e1s de cuatro de cada cinco v\u00edctimas mortales fue por \"numerosos casos\" de estr\u00e9s por calor y a viajes \"no autorizados\".\"El sistema sanitario ha tratado numerosos casos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450645,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/24\/la-meca-peregrinacion-hach-arabia-saudita-ola-calor-trax\/","url_meta":{"origin":1450600,"position":2},"title":"Hija de un hombre que muri\u00f3 por la ola de calor en peregrinaci\u00f3n: &#171;Estamos contentos de que est\u00e9 enterrado en La Meca&#187;","author":"","date":"junio 24, 2024","format":false,"excerpt":"(CNN) -- La familia de un anciano indonesio fallecido durante el Hajj de este a\u00f1o se alegra de que fuera enterrado en la ciudad santa de La Meca, seg\u00fan declar\u00f3\u00a0su hija, mientras la naci\u00f3n del sudeste asi\u00e1tico llora a cientos de sus ciudadanos que perecieron bajo un calor extremo durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451586,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/08\/03\/jordania-insta-ciudadanos-abandonar-libano-lo-antes-posible-trax\/","url_meta":{"origin":1450600,"position":3},"title":"Jordania insta a sus ciudadanos a abandonar L\u00edbano &#171;lo antes posible&#187;","author":"","date":"agosto 3, 2024","format":false,"excerpt":"(CNN) --Jordania inst\u00f3 a sus ciudadanos a abandonar L\u00edbano \"lo antes posible\", seg\u00fan un comunicado del Ministerio de Asuntos Exteriores difundido este s\u00e1bado.\"A la luz de los acontecimientos en la regi\u00f3n, y con el fin de garantizar la seguridad de los ciudadanos, el Ministerio de Asuntos Exteriores y Expatriados insta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450570,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/20\/emisiones-combustibles-fosiles-niveles-record-trax\/","url_meta":{"origin":1450600,"position":4},"title":"El uso y las emisiones de combustibles f\u00f3siles alcanzan niveles r\u00e9cord mientras el mundo lucha contra el calor extremo, las tormentas y los incendios","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN) -- El mundo consumi\u00f3 cantidades r\u00e9cord de petr\u00f3leo, carb\u00f3n y gas\u00a0 en 2023, lo que llev\u00f3 a la contaminaci\u00f3n por carbono que calienta el planeta a un nuevo m\u00e1ximo, seg\u00fan un informe publicado este jueves. Esto destroza las ilusiones de los cient\u00edficos del clima, quienes esperaban que las emisiones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466671,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/09\/21\/cinco-estadounidenses-tres-ninos-murieron-ataque-israeli-libano-trax\/","url_meta":{"origin":1450600,"position":5},"title":"Cinco ciudadanos estadounidenses, incluidos tres ni\u00f1os, murieron en un ataque israel\u00ed en L\u00edbano, seg\u00fan el Gobierno liban\u00e9s","author":"","date":"septiembre 21, 2025","format":false,"excerpt":"Cinco personas murieron, incluidos tres ni\u00f1os, en un ataque a\u00e9reo israel\u00ed en el sur de L\u00edbano este domingo, seg\u00fan el Gobierno liban\u00e9s.Las v\u00edctimas eran una familia con ciudadan\u00eda estadounidense, seg\u00fan el presidente del Parlamento, Nabih Berri, en un comunicado en el que lament\u00f3 la muerte de la madre, el padre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1450600"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450600\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1450600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1450600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1450600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}