{"id":1450635,"date":"2024-06-23T14:03:42","date_gmt":"2024-06-23T21:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/"},"modified":"2024-06-23T14:03:42","modified_gmt":"2024-06-23T21:03:42","slug":"excursionista-desaparecido-california-beber-agua-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/","title":{"rendered":"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda"},"content":{"rendered":"<p>(CNN) &#8212; Un hombre de California pas\u00f3 diez d\u00edas varado en las monta\u00f1as despu\u00e9s de perderse en una caminata, y tuvo que depender en parte de grandes vol\u00famenes de agua para sobrevivir.<\/p>\n<p>Lukas McClish, de 34 a\u00f1os, emprendi\u00f3 lo que pens\u00f3 que ser\u00eda una caminata de tres horas en las monta\u00f1as de Santa Cruz el 11 de junio, seg\u00fan KABC, afiliada de CNN. Sin embargo, se perdi\u00f3 en las monta\u00f1as debido a la destrucci\u00f3n de puntos de referencia locales en los recientes incendios forestales.<\/p>\n<p>Su familia denunci\u00f3 oficialmente su desaparici\u00f3n cuando no se present\u00f3 a la cena del D\u00eda del Padre el 16 de junio, lo que desencaden\u00f3 esfuerzos de b\u00fasqueda y rescate, inform\u00f3 KABC.<\/p>\n<p>McClish finalmente fue encontrado este jueves gracias a un dron de la Oficina del Sheriff de Santa Cruz, seg\u00fan una publicaci\u00f3n en X de Cal Fire San Mateo, que dec\u00eda que McClish fue encontrado en el Parque Estatal Big Basin Redwoods, el parque estatal m\u00e1s antiguo de California y hogar de una imponente costa antigua de \u00e1rboles secuoya.<\/p>\n<p>Encuentran muerto a un turista estadounidense en una peque\u00f1a isla griega; hay otros tres viajeros desaparecidos<\/p>\n<p>\u201cHubo m\u00faltiples informes de testigos que escucharon a alguien gritar en pedido de ayuda, pero fue dif\u00edcil establecer la ubicaci\u00f3n de esa persona\u201d, dijo Cal Fire.<\/p>\n<p>McClish fue encontrado &#171;sin heridas graves y se reuni\u00f3 con su familia&#187;, seg\u00fan la oficina del sheriff.<\/p>\n<p>En di\u00e1logo con KABC, McClish dijo que estaba &#171;cansado y un poco dolorido&#187; despu\u00e9s de su terrible experiencia. \u201cPerd\u00ed la voz\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Lo \u00fanico que ten\u00eda para sobrevivir en el bosque era la ropa que llevaba cuando se fue: \u201cSal\u00ed con s\u00f3lo un par de pantalones, mi par de zapatos para caminar y un sombrero\u201d, le dijo a KABC. \u201cTen\u00eda una linterna y unas tijeras plegables, una especie de herramienta Leatherman. Y eso fue todo\u201d.<\/p>\n<p>Atribuy\u00f3 su supervivencia a beber mucha agua de arroyos y cascadas que encontr\u00f3 mientras caminaba por el parque todos los d\u00edas, mientras ped\u00eda ayuda, seg\u00fan KSBW, afiliada de CNN.<\/p>\n<p>\u201cS\u00f3lo me asegur\u00e9 de beber un gal\u00f3n de agua todos los d\u00edas, pero luego, cuando me acercaba al final, mi cuerpo necesitaba comida y alg\u00fan tipo de sustento\u201d, dijo McClish a KABC.<\/p>\n<p>Ver la cantidad de trabajadores de b\u00fasqueda y rescate que trabajaron para encontrarlo lo hizo sentir \u201crealmente humilde\u201d, dijo. &#171;Fue una experiencia inrec\u00edble&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un hombre de California pas\u00f3 diez d\u00edas varado en las monta\u00f1as despu\u00e9s de perderse en una caminata, y tuvo que depender en parte de grandes vol\u00famenes de agua para sobrevivir. Lukas McClish, de 34 a\u00f1os, emprendi\u00f3 lo que pens\u00f3 que ser\u00eda una caminata de tres horas en las monta\u00f1as de Santa Cruz el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450635","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un hombre de California pas\u00f3 diez d\u00edas varado en las monta\u00f1as despu\u00e9s de perderse en una caminata, y tuvo que depender en parte de grandes vol\u00famenes de agua para sobrevivir. Lukas McClish, de 34 a\u00f1os, emprendi\u00f3 lo que pens\u00f3 que ser\u00eda una caminata de tres horas en las monta\u00f1as de Santa Cruz el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-23T21:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda\",\"datePublished\":\"2024-06-23T21:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/\",\"name\":\"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-23T21:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda - Noticias","og_description":"(CNN) &#8212; Un hombre de California pas\u00f3 diez d\u00edas varado en las monta\u00f1as despu\u00e9s de perderse en una caminata, y tuvo que depender en parte de grandes vol\u00famenes de agua para sobrevivir. Lukas McClish, de 34 a\u00f1os, emprendi\u00f3 lo que pens\u00f3 que ser\u00eda una caminata de tres horas en las monta\u00f1as de Santa Cruz el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-23T21:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/"},"author":{"name":"","@id":""},"headline":"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda","datePublished":"2024-06-23T21:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/","name":"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-23T21:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un excursionista desaparecido durante 10 d\u00edas en las monta\u00f1as de California sobrevivi\u00f3 bebiendo un gal\u00f3n de agua cada d\u00eda","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/excursionista-desaparecido-california-beber-agua-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-23T21:03:42Z","datePublished":"2024-06-23T21:03:42Z","dateModified":"2024-06-23T21:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un excursionista desaparecido durante 10 d\\u00edas en las monta\\u00f1as de California sobrevivi\\u00f3 bebiendo un gal\\u00f3n de agua cada d\\u00eda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/23\\\/excursionista-desaparecido-california-beber-agua-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/23\\\/excursionista-desaparecido-california-beber-agua-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-23T21:03:42Z\",\"datePublished\":\"2024-06-23T21:03:42Z\",\"dateModified\":\"2024-06-23T21:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469563,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/25\/tormenta-california-navidad-lluvias-vientos-nieve-trax\/","url_meta":{"origin":1450635,"position":0},"title":"Otra tormenta azota California el d\u00eda de Navidad con lluvias torrenciales, fuertes vientos y nieve en las monta\u00f1as","author":"","date":"diciembre 25, 2025","format":false,"excerpt":"Tras una v\u00edspera angustiante y mortal en California, con rescates y evacuaciones en medio de inundaciones generalizadas y amenazas de flujos de escombros, otra tormenta golpea al estado este d\u00eda de Navidad, y se espera que las condiciones adversas contin\u00faen hasta el viernes.Ya en la madrugada del d\u00eda de Navidad,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446161,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/01\/tormenta-invernal-nevada-california-pronostico-trax\/","url_meta":{"origin":1450635,"position":1},"title":"Potente tormenta invernal desatar\u00e1 la mayor nevada en lo que va del a\u00f1o en California","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN) -- Una tormenta invernal muy peligrosa lleg\u00f3 a California y descargar\u00e1 metros de nieve, vientos potentes y raras condiciones de ventisca en las monta\u00f1as durante el fin de semana.La tormenta implica la mayor nevada del a\u00f1o en California, lo que representa un peligro significativo para los viajeros, pero proporcionar\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446478,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/tormenta-invernal-nevada-california-pronostico-trax-2\/","url_meta":{"origin":1450635,"position":2},"title":"Potente tormenta invernal desatar\u00e1 la mayor nevada en lo que va del a\u00f1o en California","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- Una tormenta invernal muy peligrosa lleg\u00f3 a California y descargar\u00e1 metros de nieve, vientos potentes y raras condiciones de ventisca en las monta\u00f1as durante el fin de semana.La tormenta implica la mayor nevada del a\u00f1o en California, lo que representa un peligro significativo para los viajeros, pero proporcionar\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446185,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/01\/condiciones-ventisca-azotan-montanas-california-fuertes-nevadas-fuertes-vientos-trax\/","url_meta":{"origin":1450635,"position":3},"title":"Raras condiciones de ventisca azotan las monta\u00f1as de California con fuertes nevadas y fuertes vientos, lo que hace que viajar sea peligroso","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN) -- Una peligrosa tormenta invernal est\u00e1 azotando el norte de California con raras condiciones de ventisca y vientos feroces, mientras amenaza con descargar hasta 3 metros de nieve en las monta\u00f1as y entorpecer los viajes.En Sierra Nevada, la tormenta est\u00e1 causando fuertes nevadas, visibilidad reducida, cables el\u00e9ctricos derribados y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469516,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/23\/tormentas-inundaciones-california-navidad-trax\/","url_meta":{"origin":1450635,"position":4},"title":"El sur de California se prepara para una gran tormenta y se prev\u00e9n evacuaciones por un inusual &#171;alto riesgo&#187; de inundaciones","author":"","date":"diciembre 23, 2025","format":false,"excerpt":"Una importante tormenta se est\u00e1 gestando y se espera que genere lluvias equivalentes a las de varios meses y fuertes vientos en el sur de California, la m\u00e1s potente de una serie de tormentas impulsadas por r\u00edos atmosf\u00e9ricos que se dirigen a la regi\u00f3n esta semana.Llega inmediatamente despu\u00e9s de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444986,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/06\/mas-de-35-millones-de-personas-estan-bajo-amenaza-de-inundaciones-en-el-sur-de-california-y-se-esperan-mas-lluvias-este-martes\/","url_meta":{"origin":1450635,"position":5},"title":"M\u00e1s de 35 millones de personas est\u00e1n bajo amenaza de inundaciones en el sur de California y se esperan m\u00e1s lluvias este martes","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN) -- Un r\u00edo atmosf\u00e9rico intenso y de larga duraci\u00f3n avanza por California, causando cortes de energ\u00eda generalizados, deslizamientos de tierra e inundaciones potencialmente mortales, mientras tambi\u00e9n produce fuertes lluvias y nieve. Este es el recuento de lo que est\u00e1 pasando:\u2013\u2013 Persisten las amenazas de lluvia y nieve: fuertes lluvias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1450635"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450635\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1450635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1450635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1450635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}