{"id":1450641,"date":"2024-06-23T23:03:40","date_gmt":"2024-06-24T06:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/"},"modified":"2024-06-23T23:03:40","modified_gmt":"2024-06-24T06:03:40","slug":"manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/","title":{"rendered":"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Hoy en d\u00eda, Aubrey Sauvie, una estudiante de secundaria de Tennessee de 12 a\u00f1os que naci\u00f3 sin manos, dice que puede tocar su bater\u00eda tan fuerte o tan r\u00e1pido como quiera.<\/p>\n<p>Todo gracias al generoso regalo de un grupo de estudiantes universitarios de ingenier\u00eda que crearon un par de manos impresas en 3D para la joven m\u00fasico en potencia.<\/p>\n<p>Diez alumnos de la Universidad Tecnol\u00f3gica de Tennessee fabricaron las pr\u00f3tesis especiales para Aubrey \u2013quien naci\u00f3 con una triple amputaci\u00f3n cong\u00e9nita\u2013 como parte de una clase de din\u00e1mica de maquinaria durante el semestre de primavera.<\/p>\n<p>Pr\u00f3tesis impresas en 3D est\u00e1n cambiando la vida de m\u00e1s de 100 amputados en Uruguay<\/p>\n<p>No tiene brazos por debajo de los codos y tiene el pie izquierdo parcialmente amputado, explic\u00f3 su madre, Jennifer Sauvie, a CNN.<\/p>\n<p>Las nuevas pr\u00f3tesis han supuesto una gran diferencia para Aubrey, que empez\u00f3 a tocar la bater\u00eda el curso pasado por influencia de su hermana mayor, que toca la percusi\u00f3n.<\/p>\n<p>&#171;Antes de tenerlas, ten\u00eda que meterme las baquetas y dem\u00e1s en las mangas y sujetarlas en el pliegue del codo, de modo que se me sal\u00edan con el tiempo dependiendo de lo fuerte que tocara o lo r\u00e1pido que fuera&#187;, explica Aubrey, que vive en Murfreesboro, Tennessee. &#171;Pero con estas&#8230; se mantienen estables e intactas&#187;.<\/p>\n<p>Su director de banda conoc\u00eda un programa de Tennessee Tech llamado Tech Engineering for Kids y se puso en contacto con Stephen Canfield, profesor de ingenier\u00eda mec\u00e1nica que supervisa el programa.<\/p>\n<p>Este podr\u00eda ser el futuro de la tecnolog\u00eda rob\u00f3tica<\/p>\n<p>Tech Engineering for Kids, que se lleva a cabo a trav\u00e9s del curso de ingenier\u00eda de nivel junior de Canfield, implica que los estudiantes trabajen en equipos para dise\u00f1ar una forma de tecnolog\u00eda de asistencia personalizada para un ni\u00f1o con necesidades particulares en la regi\u00f3n de Middle Tennessee.<\/p>\n<p>&#171;Tengo una red de profesionales m\u00e9dicos, coordinadores de cuidados, terapeutas y similares que trabajan con ni\u00f1os con necesidades especiales en nuestra regi\u00f3n, y me ayudan a identificar a un ni\u00f1o y una familia con necesidades&#187;, explica Canfield a la CNN.<\/p>\n<p>A continuaci\u00f3n, empareja al ni\u00f1o con un grupo de estudiantes que dise\u00f1an el tipo de tecnolog\u00eda que el ni\u00f1o necesita, la fabrican, la prueban y la entregan a la familia a lo largo de un semestre, explica.<\/p>\n<p>Sus alumnos han creado juguetes y dispositivos para ni\u00f1os con necesidades sensoriales, seg\u00fan Canfield.<\/p>\n<p>Aubrey utiliz\u00f3 anteriormente un brazo mioel\u00e9ctrico Hero impreso en 3D, dijo su madre.<\/p>\n<p>Ucranianos que sufrieron amputaciones viajan a Alemania para recibir pr\u00f3tesis a medida<\/p>\n<p>&#171;Solo tiene uno, as\u00ed que no le serv\u00eda para sujetar las baquetas&#187;, explic\u00f3 Jennifer Sauvie.<\/p>\n<p>La diferencia de longitud cuando Aubrey utilizaba el brazo \u00fanico para intentar tocar la bater\u00eda tambi\u00e9n supon\u00eda un reto.<\/p>\n<p>&#171;No pod\u00eda usar el brazo de Hero para tocar la bater\u00eda o la percusi\u00f3n&#187;, dijo Jennifer Sauvie.<\/p>\n<p>Aubrey Sauvie aparece como un beb\u00e9 con su primera pr\u00f3tesis de brazo. (Cortes\u00eda: Jennifer Sauvie).<\/p>\n<p>Las nuevas pr\u00f3tesis de Aubrey son m\u00e1s vers\u00e1tiles, a\u00f1ade su madre.<\/p>\n<p>&#171;Las que tiene impresas ahora son para la bater\u00eda y para sujetar baquetas, pero en realidad, si quisieras (que) sujetaran palos de kayak o lo que fuera, en teor\u00eda podr\u00edas simplemente imprimir diferentes puntas para ponerlas en esta misma base (de) pr\u00f3tesis&#187;, dijo Jennifer Sauvie. &#171;Es genial&#187;.<\/p>\n<p>Los estudiantes de Tennessee Tech trabajaron con Aubrey durante todo el semestre para asegurarse de que los brazos prot\u00e9sicos impresos en 3D le quedaran bien.<\/p>\n<p>&#171;Le envi\u00e1bamos un dise\u00f1o determinado a Aubrey y ella nos dec\u00eda: &#8216;Vale, creo que est\u00e1 bien, pero es un poco largo, \u00bfpodr\u00eda acortarse?&#8217; o&#8230; &#8216;me da un poco de calor en el brazo, \u00bfpodr\u00edas, por ejemplo, hacerlo un poco m\u00e1s transpirable?'&#187;, declar\u00f3 a CNN Zak Henson, estudiante de \u00faltimo curso de ingenier\u00eda mec\u00e1nica en la Universidad Tecnol\u00f3gica de Tennessee, que codirigi\u00f3 el proyecto.<\/p>\n<p>\u00bfConoces la diferencia entre una pr\u00f3tesis y un exoesqueleto?, un ingeniero boliviano experto en rob\u00f3tica lo explica<\/p>\n<p>&#171;As\u00ed que ahora estamos tratando de pensar, &#8216;OK, \u00bfc\u00f3mo podemos mantener el dise\u00f1o de lo que estamos buscando y ajustarlo para satisfacer estas nuevas necesidades?'&#187;, dijo Henson sobre el proceso.<\/p>\n<p>El equipo cre\u00f3 unas seis iteraciones de la pr\u00f3tesis hasta que quedaron satisfechos con el producto final, explica Branson Blaylock, estudiante de \u00faltimo curso de ingenier\u00eda mec\u00e1nica y director del proyecto.<\/p>\n<p>Aubrey dice que no estaba segura de si las manos impresas en 3D le funcionar\u00edan, pero acabaron siendo un \u00e9xito.<\/p>\n<p>&#171;Estaba muy emocionada porque iba a poder usarlas y probarlas&#187;, dice Aubrey, quien quiere ser ecografista cuando sea mayor.<\/p>\n<p>Y a\u00f1adi\u00f3: &#171;Se est\u00e1n convirtiendo en una herramienta muy \u00fatil y llena de recursos para ayudarme con mi bater\u00eda&#187;.<\/p>\n<p>Aubrey Sauvie, que naci\u00f3 sin manos y con el pie izquierdo parcialmente amputado, rompe tablas para obtener su cinta negra de segundo grado en taekwondo. (Cortes\u00eda: Jennifer Sauvie)<\/p>\n<p>&#171;Ella lo hace parecer f\u00e1cil&#187;<\/p>\n<p>Jennifer Sauvie dice que era consciente de que Aubrey nacer\u00eda con un miembro diferente cuando estaba embarazada.<\/p>\n<p>&#171;Me daba mucho miedo, por supuesto, pero si hubiera sabido entonces lo que s\u00e9 ahora, habr\u00eda sido un embarazo mucho m\u00e1s feliz y alegre, porque ella no deja que nada la detenga ni se interponga en su camino&#187;, afirma Jennifer Sauvie.<\/p>\n<p>Su hija ha participado en actividades como danza, taekwondo, arte y m\u00fasica.<\/p>\n<p>El grupo de estudiantes que trabaja estrechamente con la ni\u00f1a de 12 a\u00f1os en la toma de medidas y el ajuste de pr\u00f3tesis la considera una inspiraci\u00f3n.<\/p>\n<p>&#171;Vi\u00e9ndola hacer cosas que yo pensaba que era imposible que pudiera hacer, es tan decidida&#187;, dijo Micah Page, estudiante de ingenier\u00eda mec\u00e1nica. &#171;Hace que parezca f\u00e1cil vivir sin manos&#187;.<\/p>\n<p>Las pr\u00f3tesis a medida deber\u00edan durarle a Aubrey los pr\u00f3ximos a\u00f1os, antes de que se le queden peque\u00f1as, dice Canfield&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Hoy en d\u00eda, Aubrey Sauvie, una estudiante de secundaria de Tennessee de 12 a\u00f1os que naci\u00f3 sin manos, dice que puede tocar su bater\u00eda tan fuerte o tan r\u00e1pido como quiera. Todo gracias al generoso regalo de un grupo de estudiantes universitarios de ingenier\u00eda que crearon un par de manos impresas en 3D para [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450641","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Hoy en d\u00eda, Aubrey Sauvie, una estudiante de secundaria de Tennessee de 12 a\u00f1os que naci\u00f3 sin manos, dice que puede tocar su bater\u00eda tan fuerte o tan r\u00e1pido como quiera. Todo gracias al generoso regalo de un grupo de estudiantes universitarios de ingenier\u00eda que crearon un par de manos impresas en 3D para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-24T06:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os\",\"datePublished\":\"2024-06-24T06:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/\"},\"wordCount\":1084,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/\",\"name\":\"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-24T06:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os - Noticias","og_description":"(CNN) &#8212;\u00a0Hoy en d\u00eda, Aubrey Sauvie, una estudiante de secundaria de Tennessee de 12 a\u00f1os que naci\u00f3 sin manos, dice que puede tocar su bater\u00eda tan fuerte o tan r\u00e1pido como quiera. Todo gracias al generoso regalo de un grupo de estudiantes universitarios de ingenier\u00eda que crearon un par de manos impresas en 3D para [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-24T06:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/"},"author":{"name":"","@id":""},"headline":"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os","datePublished":"2024-06-24T06:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/"},"wordCount":1084,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/","name":"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-24T06:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\u00e1 la vida de una baterista de 12 a\u00f1os","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/23\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-24T06:03:40Z","datePublished":"2024-06-24T06:03:40Z","dateModified":"2024-06-24T06:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Manos impresas en 3D, el regalo de universitarios de Tennessee que cambiar\\u00e1 la vida de una baterista de 12 a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/23\\\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/23\\\/manos-impresas-3d-universitarios-tennessee-baterista-12-anos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-24T06:03:40Z\",\"datePublished\":\"2024-06-24T06:03:40Z\",\"dateModified\":\"2024-06-24T06:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456467,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/12\/11\/lo-que-debes-saber-sobre-las-armas-fantasma-trax\/","url_meta":{"origin":1450641,"position":0},"title":"Lo que debes saber sobre las &#171;armas fantasmas&#187;","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"El hombre sospechoso del tiroteo fatal del CEO de UnitedHealthcare, Brian Thompson, portaba una \u201carma fantasma\u201d \u2014un tipo de arma de fuego casera y no rastreable\u2014 cuando fue detenido el lunes, dijo la Polic\u00eda.Luigi Mangione ten\u00eda el arma cuando fue revisado por la polic\u00eda local en un McDonald\u2019s de Pennsylvania,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467818,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/10\/28\/detenido-ice-liberado-regalo-paletas-celebrar-orix\/","url_meta":{"origin":1450641,"position":1},"title":"Un vendedor de helado estuvo detenido 114 d\u00edas por ICE. Fue liberado y regal\u00f3 paletas para celebrar","author":"","date":"octubre 28, 2025","format":false,"excerpt":"La enorme sonrisa de Ambrocio Lozano parece decirlo todo. Despu\u00e9s de m\u00e1s de cien d\u00edas en un centro de detenci\u00f3n de Los \u00c1ngeles, fue liberado y un juez aprob\u00f3 su petici\u00f3n para obtener la residencia legal permanente en Estados Unidos. La suya podr\u00eda decirse que es una historia con un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449692,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/05\/22\/mansion-graceland-elvis-embargada-trax\/","url_meta":{"origin":1450641,"position":2},"title":"Tribunal dictamina que la mansi\u00f3n Graceland de Elvis no puede ser embargada por el momento","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN) -- Graceland puede permanecer en manos de la familia de Elvis Presley por el momento, despu\u00e9s de que un canciller de la corte de Tennessee dictaminara este mi\u00e9rcoles que una misteriosa compa\u00f1\u00eda que intentaba venderla probablemente cometi\u00f3 fraude.El canciller JoeDae Jenkins dijo que una venta por ejecuci\u00f3n hipotecaria planificada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448731,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/05\/01\/analisis-disturbios-estudiantiles-agravan-ano-electoral-tenso-trax\/","url_meta":{"origin":1450641,"position":3},"title":"AN\u00c1LISIS | Los disturbios estudiantiles agravan un a\u00f1o electoral ya de por s\u00ed tenso","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN) -- Las dram\u00e1ticas protestas en los campus universitarios est\u00e1n inyectando un nuevo elemento incendiario en un a\u00f1o electoral que ya amenaza con llevar la unidad nacional a un punto de ruptura.Las tensiones se dispararon a \u00faltima hora de este martes tras una operaci\u00f3n de los equipos de refuerzo del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442647,"url":"https:\/\/noticiasya.com\/las-vegas\/2023\/12\/25\/que-hacer-si-recibes-un-regalo-que-no-te-gusta\/","url_meta":{"origin":1450641,"position":4},"title":"\u00bfQu\u00e9 hacer si recibes un regalo que no te gusta?","author":"","date":"diciembre 25, 2023","format":false,"excerpt":"(CNN) -- Cuando Abby Eckel vio la peque\u00f1a bolsa de regalo de joyer\u00eda que su esposo le regal\u00f3 por su cumplea\u00f1os, pens\u00f3 que sab\u00eda exactamente lo que hab\u00eda dentro: un anillo con una piedra preciosa de morganita que ella hab\u00eda pedido. Pero cuando Eckel abri\u00f3 el paquete y vio en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468896,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/02\/huevo-faberge-record-millonario-subasta-christies-trax\/","url_meta":{"origin":1450641,"position":5},"title":"Huevo Faberg\u00e9 alcanza r\u00e9cord de US$ 30,2 millones en rara subasta","author":"","date":"diciembre 2, 2025","format":false,"excerpt":"Uno de los \u00faltimos huevos Faberg\u00e9 en manos privadas se vendi\u00f3 por \u00a322,9 millones (US$ 30,2 millones), incluyendo comisiones, el martes, superando su propio r\u00e9cord como la obra m\u00e1s cara del joyero ruso jam\u00e1s subastada.Encargado por el zar Nicol\u00e1s II como regalo para su madre en 1913, el Huevo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1450641"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450641\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1450641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1450641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1450641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}