{"id":1450720,"date":"2024-06-26T14:03:41","date_gmt":"2024-06-26T21:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/"},"modified":"2024-06-26T14:03:41","modified_gmt":"2024-06-26T21:03:41","slug":"bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/","title":{"rendered":"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un &#171;intento de golpe de Estado&#187;"},"content":{"rendered":"<p>(CNN) &#8212; El presidente de Bolivia, Luis Arce, asegur\u00f3 este mi\u00e9rcoles que &#171;el pa\u00eds hoy est\u00e1 enfrentando un intento de golpe de Estado&#187;, en un video publicado en su cuenta de Facebook.<\/p>\n<p>Anteriormente, Arce hab\u00eda denunciado \u201cmovilizaciones irregulares\u201d de \u201calgunas\u201d unidades del Ej\u00e9rcito en La Paz.<\/p>\n<p>\u201cDenunciamos movilizaciones irregulares de algunas unidades del Ej\u00e9rcito de Bolivia\u201d, escribi\u00f3 Arce en X.<\/p>\n<p>&#171;La democracia debe ser respetada&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Efectivos militares son vistos en la Plaza de Armas en La Paz, Bolivia, el 26 de junio de 2024. (Cr\u00e9dito: AIZAR RALDES\/AFP v\u00eda Getty Images)<\/p>\n<p>La agencia estatal de medios ABI inform\u00f3 que se est\u00e1n posicionando tanques militares en y alrededor de la Plaza Murillo, una plaza principal de La Paz donde se encuentran las oficinas ejecutiva y legislativa nacional.<\/p>\n<p>Se desconoce por qu\u00e9 hay unidades militares en la Plaza Murillo y cu\u00e1ntas son.<\/p>\n<p>Efectivos militares disparan gases lacrim\u00f3genos a la gente fuera del Palacio Quemado en la Plaza Murillo en La Paz, Bolivia, el 26 de junio de 2024. (Cr\u00e9dito: AIZAR RALDES\/AFP v\u00eda Getty Images)<\/p>\n<p>CNN est\u00e1 intentando contactar al Gobierno de Bolivia para hacer comentarios.<\/p>\n<p>El expresidente Evo Morales hab\u00eda dicho en X que \u201cse gesta el golpe de Estado\u201d.<\/p>\n<p>Morales tambi\u00e9n llam\u00f3 a \u201clos movimientos sociales del campo y de la ciudad a defender la democracia\u201d.<\/p>\n<p>Efectivos militares son vistos en la Plaza de Armas en La Paz, Bolivia, el 26 de junio de 2024. (Cr\u00e9dito: AIZAR RALDES\/AFP v\u00eda Getty Images)<\/p>\n<p>Seg\u00fan ABI, la movilizaci\u00f3n militar comenz\u00f3 alrededor de las 2:30 p.m. hora local.<\/p>\n<p>El secretario general de la OEA, Luis Almagro, conden\u00f3 las movilizaciones de la \u201cmanera m\u00e1s en\u00e9rgica\u201d. \u201cEl Ej\u00e9rcito debe someterse al poder civil leg\u00edtimamente elegido\u201d, escribi\u00f3 Almagro en X.<\/p>\n<p>La Uni\u00f3n Europea conden\u00f3 &#171;cualquier intento de alterar el orden constitucional en #Bolivia y derrocar a los gobiernos elegidos democr\u00e1ticamente&#187;, y agrega que se solidariza con el Gobierno boliviano y su pueblo, en una publicaci\u00f3n del jefe de pol\u00edtica europea, Josep Borrell, en X.<\/p>\n<p>El presidente de Chile, Gabriel Boric, manifest\u00f3 este mi\u00e9rcoles su preocupaci\u00f3n por la situaci\u00f3n en Bolivia, pa\u00eds con el que Chile comparte frontera.<\/p>\n<p>&#171;Desde Chile manifiesto mi preocupaci\u00f3n por la situaci\u00f3n en Bolivia. Expresamos nuestro apoyo a la democracia en el hermano pa\u00eds y al Gobierno leg\u00edtimo de Luis Arce. Condenamos en\u00e9rgicamente la inaceptable acci\u00f3n de fuerza de un sector del ej\u00e9rcito de ese pa\u00eds. No podemos tolerar ning\u00fan quebrantamiento del orden constitucional leg\u00edtimo en Bolivia o en cualquier otro lugar&#187;, escribi\u00f3 en su cuenta de X.<\/p>\n<p>El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, extendi\u00f3 este mi\u00e9rcoles su m\u00e1s en\u00e9rgica condena a lo ocurrido en Bolivia. &#171;Manifestamos la m\u00e1s en\u00e9rgica condena al intento de golpe de Estado en Bolivia. Nuestro total apoyo y respaldo al presidente Luis Alberto Arce Catacora, aut\u00e9ntica autoridad democr\u00e1tica de ese pueblo y pa\u00eds hermano&#187;, dijo en X.<\/p>\n<p>Por su parte, el canciller cubano, Bruno Rodr\u00edguez, manifest\u00f3 su preocupaci\u00f3n por las movilizaciones irregulares del Ej\u00e9rcito en Bolivia.\u00a0\u201cMovilizaciones irregulares de algunas unidades del Ej\u00e9rcito boliviano son muy preocupantes. Rechazamos contundentemente esos actos y expresamos nuestra solidaridad al Presidente Luis Arce\u201d,asegur\u00f3.<\/p>\n<p>Noticia en desarrollo&#8230;<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El presidente de Bolivia, Luis Arce, asegur\u00f3 este mi\u00e9rcoles que &#171;el pa\u00eds hoy est\u00e1 enfrentando un intento de golpe de Estado&#187;, en un video publicado en su cuenta de Facebook. Anteriormente, Arce hab\u00eda denunciado \u201cmovilizaciones irregulares\u201d de \u201calgunas\u201d unidades del Ej\u00e9rcito en La Paz. \u201cDenunciamos movilizaciones irregulares de algunas unidades del Ej\u00e9rcito de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450720","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un &quot;intento de golpe de Estado&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un &quot;intento de golpe de Estado&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El presidente de Bolivia, Luis Arce, asegur\u00f3 este mi\u00e9rcoles que &#171;el pa\u00eds hoy est\u00e1 enfrentando un intento de golpe de Estado&#187;, en un video publicado en su cuenta de Facebook. Anteriormente, Arce hab\u00eda denunciado \u201cmovilizaciones irregulares\u201d de \u201calgunas\u201d unidades del Ej\u00e9rcito en La Paz. \u201cDenunciamos movilizaciones irregulares de algunas unidades del Ej\u00e9rcito de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-26T21:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un &#171;intento de golpe de Estado&#187;\",\"datePublished\":\"2024-06-26T21:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/\"},\"wordCount\":602,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/\",\"name\":\"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un \\\"intento de golpe de Estado\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-26T21:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un &#171;intento de golpe de Estado&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un \"intento de golpe de Estado\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un \"intento de golpe de Estado\" - Noticias","og_description":"(CNN) &#8212; El presidente de Bolivia, Luis Arce, asegur\u00f3 este mi\u00e9rcoles que &#171;el pa\u00eds hoy est\u00e1 enfrentando un intento de golpe de Estado&#187;, en un video publicado en su cuenta de Facebook. Anteriormente, Arce hab\u00eda denunciado \u201cmovilizaciones irregulares\u201d de \u201calgunas\u201d unidades del Ej\u00e9rcito en La Paz. \u201cDenunciamos movilizaciones irregulares de algunas unidades del Ej\u00e9rcito de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-26T21:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/"},"author":{"name":"","@id":""},"headline":"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un &#171;intento de golpe de Estado&#187;","datePublished":"2024-06-26T21:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/"},"wordCount":602,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/","name":"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un \"intento de golpe de Estado\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-26T21:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un &#171;intento de golpe de Estado&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El presidente de Bolivia, Luis Arce, asegura que el pa\u00eds enfrenta un &#171;intento de golpe de Estado&#187;","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/26\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-26T21:03:41Z","datePublished":"2024-06-26T21:03:41Z","dateModified":"2024-06-26T21:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El presidente de Bolivia, Luis Arce, asegura que el pa\\u00eds enfrenta un &#171;intento de golpe de Estado&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/26\\\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/26\\\/bolivia-luis-arce-movilizaciones-irregulares-ejercito-en-la-paz-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-26T21:03:41Z\",\"datePublished\":\"2024-06-26T21:03:41Z\",\"dateModified\":\"2024-06-26T21:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450732,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/26\/bolivia-fallido-golpe-estado-soldados-armados-tension-defensa-democracia-trax\/","url_meta":{"origin":1450720,"position":0},"title":"Soldados armados, tensi\u00f3n en las calles y el llamado a la defensa de la democracia: as\u00ed se vivi\u00f3 el fracasado intento de golpe de Estado en Bolivia","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN) -- El presidente de Bolivia, Luis Arce, hizo frente este mi\u00e9rcoles a un intento de golpe de Estado de corta duraci\u00f3n, tras llamar a la ciudadan\u00eda a \"organizarse y movilizarse\" en defensa de la democracia, mientras soldados y veh\u00edculos militares blindados rodeaban edificios gubernamentales en La Paz.\"No podemos permitir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451024,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/07\/10\/evo-morales-aristegui-entrevista-orix\/","url_meta":{"origin":1450720,"position":1},"title":"Evo Morales: Intento de golpe de Estado fue un &#171;show bien montado&#187; entre Arce y Z\u00fa\u00f1iga","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Evo Morales, expresidente de Bolivia y l\u00edder del oficialista Movimiento al Socialismo (MAS), dijo que el levantamiento de militares en Bolivia el 26 de junio fue un \"show bien montado entre el presidente Lucho Arce con el comandante de entonces Juan Z\u00fa\u00f1iga\". En entrevista con Carmen Aristegui\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450759,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/27\/arche-rechaza-acusaciones-supuesto-autogolpe-estado-bolivia-orix\/","url_meta":{"origin":1450720,"position":2},"title":"Arce rechaza acusaciones sobre supuesto autogolpe de Estado en Bolivia","author":"","date":"junio 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un d\u00eda despu\u00e9s del intento de golpe de Estado en Bolivia, el presidente Luis Arce rechaz\u00f3 las acusaciones del general detenido por encabezar estos hechos, Juan Jos\u00e9 Z\u00fa\u00f1iga, quien la noche del mi\u00e9rcoles dijo que fue el mandatario quien le orden\u00f3 ejecutar un autogolpe que le ayudara\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450832,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/07\/01\/gobierno-bolivia-convoca-embajador-argentina-declaraciones-milei-intento-golpe-estado-orix\/","url_meta":{"origin":1450720,"position":3},"title":"El Gobierno de Bolivia convoca a su embajador en Argentina tras declaraciones de Milei sobre intento de golpe de Estado","author":"","date":"julio 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Gobierno de Bolivia convoc\u00f3 este lunes a consulta a su embajador en Argentina, Ramiro Tapia, ante las declaraciones de la Oficina del presidente Javier Milei que se\u00f1al\u00f3 como \u201cfalsa\u201d la denuncia de golpe de Estado del 26 de junio.La ministra de la Presidencia de Bolivia, Maria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450801,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/29\/prision-preventiva-juan-jose-zuniga-intento-golpe-de-estado-bolivia-orix\/","url_meta":{"origin":1450720,"position":4},"title":"Dictan prisi\u00f3n preventiva al general Juan Jos\u00e9 Z\u00fa\u00f1iga por intento de golpe de Estado en Bolivia","author":"","date":"junio 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un tribunal de Bolivia orden\u00f3 la prisi\u00f3n preventiva durante seis meses para el exjefe del Ej\u00e9rcito, Juan Jos\u00e9 Z\u00fa\u00f1iga, tras presuntamente haber liderarado el intento de golpe de Estado del mi\u00e9rcoles, inform\u00f3 este viernes la Fiscal\u00eda General de Bolivia.Z\u00fa\u00f1iga tambi\u00e9n fue acusado por la Fiscal\u00eda boliviana de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450780,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/28\/imputan-general-zuniga-terrorirsmo-alzamiento-bolivia-orix\/","url_meta":{"origin":1450720,"position":5},"title":"Imputan al general Z\u00fa\u00f1iga por terrorismo y alzamiento armado tras intento de golpe de Estado en Bolivia","author":"","date":"junio 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El general Juan Jos\u00e9 Z\u00fa\u00f1iga, exjefe del Ej\u00e9rcito de Bolivia, fue imputado por la Fiscal\u00eda del pa\u00eds por los delitos de terrorismo y alzamiento armado y este viernes tendr\u00e1 una audiencia judicial en la que se discutir\u00e1 qu\u00e9 medida cautelar imponerle, inform\u00f3 su abogado, Steven Orellana.Durante un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1450720"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450720\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1450720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1450720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1450720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}