{"id":1450735,"date":"2024-06-27T02:03:43","date_gmt":"2024-06-27T09:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/"},"modified":"2024-06-27T02:03:43","modified_gmt":"2024-06-27T09:03:43","slug":"militar-estadounidense-acusado-agresion-sexua-japon-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/","title":{"rendered":"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n"},"content":{"rendered":"<p>(CNN) &#8212; La fiscal\u00eda japonesa acus\u00f3 a un militar estadounidense de secuestrar y agredir sexualmente a una menor de edad el pasado mes de diciembre en Okinawa, seg\u00fan confirm\u00f3 este mi\u00e9rcoles a CNN la Jefatura de Polic\u00eda de la Prefectura.<\/p>\n<p>Brennon R. E. Washington, aviador de 25 a\u00f1os de la Fuerza A\u00e9rea estadounidense, fue acusado el 27 de marzo de &#171;relaciones sexuales no consentidas&#187; y &#171;secuestro indecente&#187;, seg\u00fan declar\u00f3 a CNN un portavoz del Tribunal del Distrito de Naha, quien a\u00f1adi\u00f3 que las Fuerzas Armadas de EE.UU. entregaron al militar a las autoridades japonesas ese mismo d\u00eda.<\/p>\n<p>El portavoz del tribunal dijo a CNN que no tienen detalles sobre la representaci\u00f3n legal del aviador.<\/p>\n<p>Washington fue puesto en libertad bajo fianza y trasladado a la base a\u00e9rea estadounidense de Kadena, en Okinawa, para su custodia, seg\u00fan un portavoz de la prefectura de Okinawa.<\/p>\n<p>Pent\u00e1gono presentar\u00e1 plan para abordar agresiones sexuales y la violencia dom\u00e9stica en el Ej\u00e9rcito<\/p>\n<p>No estaba claro cu\u00e1ndo fue trasladado.<\/p>\n<p>Se fij\u00f3 la fecha del juicio para el 12 de julio, seg\u00fan el portavoz del tribunal.<\/p>\n<p>El gobernador de Okinawa, Denny Tamaki, declar\u00f3 este martes a la prensa que el incidente era &#171;extremadamente lamentable&#187; y que las autoridades &#171;adoptar\u00e1n una postura firme para hacer frente a la situaci\u00f3n&#187;.<\/p>\n<p>Masataka Okano, viceministro de Asuntos Exteriores de Jap\u00f3n, pidi\u00f3 una disciplina m\u00e1s estricta por parte de los funcionarios estadounidenses y present\u00f3 una protesta ante el embajador de Estados Unidos en Jap\u00f3n, Rahm Emanuel, este 27 de marzo, el d\u00eda en que Washington fue acusado, seg\u00fan el Ministerio de Asuntos Exteriores japon\u00e9s.<\/p>\n<p>CNN se puso en contacto con la Embajada de EE.UU. en Jap\u00f3n, que dijo estar al corriente del caso pero no hizo comentarios. La embajada dijo a CNN en una llamada telef\u00f3nica que se pusiera en contacto con la Base A\u00e9rea de Kadena en Okinawa, donde Washington estaba destacado, para obtener informaci\u00f3n sobre el caso.<\/p>\n<p>CNN se puso en contacto con la Base A\u00e9rea de Kadena para obtener comentarios.<\/p>\n<p>Aumentan agresiones sexuales en fuerzas armadas de EE.UU., seg\u00fan informe del Pent\u00e1gono (2019)<\/p>\n<p>Washington estaba destinado en el 18\u00ba Escuadr\u00f3n de Preparaci\u00f3n Log\u00edstica de la base a\u00e9rea, seg\u00fan la Fuerza A\u00e9rea estadounidense, que confirm\u00f3 a CNN el rango y la hoja de servicios del miembro del servicio acusado, sin hacer comentarios sobre la acusaci\u00f3n.<\/p>\n<p>Un portavoz del Ala 18 confirm\u00f3 que el escuadr\u00f3n estaba al tanto del caso.<\/p>\n<p>&#171;El Ala 18 est\u00e1 al tanto de una acusaci\u00f3n de agresi\u00f3n sexual contra un aviador de Kadena que involucra a una ciudadana japonesa&#187;, dijo el primer teniente Alvin G. Nelson III, a CNN el mi\u00e9rcoles.<\/p>\n<p>&#171;Entendemos y compartimos las preocupaciones de la comunidad local con respecto a este caso&#187;, dijo Nelson, a\u00f1adiendo que el l\u00edder del Ala 18 estaba &#171;profundamente preocupado por la gravedad de este presunto delito&#187; y estuvo trabajando con las autoridades locales para investigar las acusaciones.<\/p>\n<p>&#171;Se espera que todos los miembros de las Fuerzas Armadas de EE.UU. respeten las normas m\u00e1s estrictas. Las Fuerzas Armadas de EE.UU. se compromete a exigir responsabilidades a quienes sean declarados culpables de actos delictivos&#187;, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La fiscal\u00eda japonesa acus\u00f3 a un militar estadounidense de secuestrar y agredir sexualmente a una menor de edad el pasado mes de diciembre en Okinawa, seg\u00fan confirm\u00f3 este mi\u00e9rcoles a CNN la Jefatura de Polic\u00eda de la Prefectura. Brennon R. E. Washington, aviador de 25 a\u00f1os de la Fuerza A\u00e9rea estadounidense, fue acusado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450735","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La fiscal\u00eda japonesa acus\u00f3 a un militar estadounidense de secuestrar y agredir sexualmente a una menor de edad el pasado mes de diciembre en Okinawa, seg\u00fan confirm\u00f3 este mi\u00e9rcoles a CNN la Jefatura de Polic\u00eda de la Prefectura. Brennon R. E. Washington, aviador de 25 a\u00f1os de la Fuerza A\u00e9rea estadounidense, fue acusado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-27T09:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n\",\"datePublished\":\"2024-06-27T09:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/\"},\"wordCount\":587,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/\",\"name\":\"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-27T09:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n - Noticias","og_description":"(CNN) &#8212; La fiscal\u00eda japonesa acus\u00f3 a un militar estadounidense de secuestrar y agredir sexualmente a una menor de edad el pasado mes de diciembre en Okinawa, seg\u00fan confirm\u00f3 este mi\u00e9rcoles a CNN la Jefatura de Polic\u00eda de la Prefectura. Brennon R. E. Washington, aviador de 25 a\u00f1os de la Fuerza A\u00e9rea estadounidense, fue acusado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-27T09:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/"},"author":{"name":"","@id":""},"headline":"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n","datePublished":"2024-06-27T09:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/"},"wordCount":587,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/","name":"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-27T09:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Acusan a un militar estadounidense de agresi\u00f3n sexual a una menor en Jap\u00f3n","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/27\/militar-estadounidense-acusado-agresion-sexua-japon-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-27T09:03:43Z","datePublished":"2024-06-27T09:03:43Z","dateModified":"2024-06-27T09:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Acusan a un militar estadounidense de agresi\\u00f3n sexual a una menor en Jap\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/27\\\/militar-estadounidense-acusado-agresion-sexua-japon-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/27\\\/militar-estadounidense-acusado-agresion-sexua-japon-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-27T09:03:43Z\",\"datePublished\":\"2024-06-27T09:03:43Z\",\"dateModified\":\"2024-06-27T09:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1443745,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/15\/las-ultimas-cartas-de-jovenes-pilotos-kamikazes-muestran-como-fue-la-temida-unidad-de-ataque-especial-de-japon\/","url_meta":{"origin":1450735,"position":0},"title":"Las \u00faltimas cartas de j\u00f3venes pilotos kamikazes muestran c\u00f3mo fue la temida unidad de ataque especial de Jap\u00f3n","author":"","date":"enero 15, 2024","format":false,"excerpt":"(CNN) -- Piensen en un piloto kamikaze y la imagen que se le viene a uno a la mente probablemente sea una cara gritando oscurecida por gafas lanz\u00e1ndose a una zambullida mortal.O tal vez sin rostro alguno y solo un avi\u00f3n de combate chocando contra un buque de guerra.Probablemente no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451874,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/08\/15\/tribunal-ruso-condena-ciudadano-estadounidense-15-dias-prision-atacar-a-policia-trax\/","url_meta":{"origin":1450735,"position":1},"title":"Un tribunal ruso condena a un ciudadano estadounidense a 15 d\u00edas de prisi\u00f3n por atacar a un Polic\u00eda","author":"","date":"agosto 15, 2024","format":false,"excerpt":"(CNN) -- Un ciudadano estadounidense fue sentenciado a 15 d\u00edas de prisi\u00f3n en una prisi\u00f3n rusa acusado de \u201cvandalismo menor\u201d por atacar a un oficial de Polic\u00eda, seg\u00fan funcionarios del tribunal de Mosc\u00fa.El ciudadano estadounidense, identificado como Joseph Tater, recibi\u00f3 este mi\u00e9rcoles una \u201csanci\u00f3n administrativa en forma de arresto administrativo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471702,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/02\/26\/expiloto-fuerza-aerea-ee-uu-entrenar-china-trax\/","url_meta":{"origin":1450735,"position":2},"title":"Acusan a expiloto de combate de la Fuerza A\u00e9rea de EE.UU. de conspirar para entrenar a militares de China","author":"","date":"febrero 26, 2026","format":false,"excerpt":"Un expiloto de combate de la Fuerza A\u00e9rea de Estados Unidos con m\u00e1s de dos d\u00e9cadas de experiencia en sistemas de entrega nuclear y aeronaves, incluidos los avanzados aviones furtivos F-35, fue arrestado y acusado de conspirar para ayudar a las fuerzas militares de China.Gerald Eddie Brown Jr., de 65\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472874,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/04\/rescatan-tripulante-desaparecido-f-15-iran-trax\/","url_meta":{"origin":1450735,"position":3},"title":"Fuerzas de EE.UU. rescatan al tripulante desaparecido del F-15 derribado en Ir\u00e1n, anunci\u00f3 Trump","author":"","date":"abril 4, 2026","format":false,"excerpt":"Un miembro del servicio estadounidense desaparecido cuyo avi\u00f3n de combate fue derribado sobre Ir\u00e1n fue rescatado por fuerzas estadounidenses, dijo el presidente de EE.UU., Donald Trump, en una publicaci\u00f3n en Truth Social a primera hora de este domingo.\u201c\u00a1LO TENEMOS! Mis compatriotas estadounidenses, durante las \u00faltimas horas, las Fuerzas Armadas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463871,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/06\/23\/iran-lanza-misiles-base-militar-eeuu-qatar-trax\/","url_meta":{"origin":1450735,"position":4},"title":"Ir\u00e1n atac\u00f3 base militar estadounidense en Qatar; los misiles fueron interceptados","author":"","date":"junio 23, 2025","format":false,"excerpt":"Ir\u00e1n lanz\u00f3 este lunes misiles bal\u00edsticos de corto y mediano alcance contra la base a\u00e9rea estadounidense de Al Udeid, en Qatar, en aparente respuesta al ataque de Estados Unidos contra instalaciones nucleares iran\u00edes.As\u00ed lo confirm\u00f3 un funcionario del Departamento de Defensa estadounidense, quien precis\u00f3 que los misiles se originaron en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464308,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/07\/08\/soldado-estadounidense-base-militar-alemania-deportado-a-jamaica-trax\/","url_meta":{"origin":1450735,"position":5},"title":"Hijo de un soldado de EE. UU., naci\u00f3 en una base militar en Alemania y fue deportado a Jamaica, donde nunca hab\u00eda estado","author":"","date":"julio 8, 2025","format":false,"excerpt":"Nacido en una base militar de Estados Unidos, hijo de un padre ciudadano estadounidense que sirvi\u00f3 en el Ej\u00e9rcito, Jermaine Thomas nunca consider\u00f3 que pudiera no ser estadounidense.Hace un mes, se encontr\u00f3 encadenado por las mu\u00f1ecas y los tobillos y obligado a abordar un vuelo hacia Jamaica, el lugar de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1450735"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450735\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1450735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1450735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1450735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}