{"id":1450776,"date":"2024-06-28T14:03:44","date_gmt":"2024-06-28T21:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/"},"modified":"2024-06-28T14:03:44","modified_gmt":"2024-06-28T21:03:44","slug":"479-millones-vieron-debate-cnn-biden-y-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/","title":{"rendered":"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump"},"content":{"rendered":"<p>(CNN) &#8212; El debate de la noche del jueves en CNN entre el presidente Joe Biden y el expresidente Donald Trump fue visto por 47,9 millones de espectadores por televisi\u00f3n, seg\u00fan cifras preliminares de Nielsen.<\/p>\n<p>El debate de 90 minutos, que conmocion\u00f3 al mundo pol\u00edtico, se transmiti\u00f3 simult\u00e1neamente a trav\u00e9s de 22 cadenas. CNN, que organiz\u00f3 el debate desde sus estudios de Atlanta, ofreci\u00f3 una transmisi\u00f3n en vivo de la transmisi\u00f3n a cualquier cadena de forma gratuita, pero con condiciones estrictas sobre su presentaci\u00f3n y marca.<\/p>\n<p>En televisi\u00f3n, CNN atrajo a 8,7 millones de espectadores en su canal insignia, incluidos tres millones en el codiciado grupo demogr\u00e1fico de 25 a 54 a\u00f1os, dijo la cadena este viernes. El canal de entrevistas de derecha Fox News atrajo a 8,8 millones de espectadores, ABC News a 8,7 millones de espectadores y MSNBC atrajo a 3,968 millones de espectadores.<\/p>\n<p>La transmisi\u00f3n tambi\u00e9n atrajo la mayor audiencia registrada para CNN en el servicio de transmisi\u00f3n Max, aunque la cadena no revel\u00f3 cifras de audiencia.<\/p>\n<p>Los casi 48 millones de personas que vieron el debate del jueves por la noche por televisi\u00f3n representan una ca\u00edda del 35% en audiencia con respecto a 2020, cuando m\u00e1s de 73 millones de personas vieron el primer debate entre Trump y Biden en todas las cadenas de televisi\u00f3n. En 2016, una cifra r\u00e9cord de 84 millones sintonizaron el primer debate entre Hillary Clinton y Trump.<\/p>\n<p>Si bien menos estadounidenses vieron el debate por televisi\u00f3n que en a\u00f1os electorales anteriores, millones m\u00e1s lo vieron en plataformas digitales.<\/p>\n<p>CNN dijo que el evento gener\u00f3 m\u00e1s de 30 millones de visitas en sus productos digitales y en YouTube. &#171;En todas las plataformas digitales de CNN el debate fue el m\u00e1s grande jam\u00e1s realizado por CNN y empat\u00f3 con nuestro evento de transmisi\u00f3n en vivo m\u00e1s grande hasta la fecha con 2,3 millones de vistas en vivo simult\u00e1neas a las 9:47 p.m.&#187;, dijo la cadena.<\/p>\n<p>Para CNN, el debate del jueves por la noche fue un golpe de marketing, que se produjo en un momento crucial para la cadena mientras trabaja para revertir la ca\u00edda del ratings y se embarca en una estrategia para revolucionar el funcionamiento de cuatro d\u00e9cadas de existencia en la era digital.<\/p>\n<p>El anterior programa m\u00e1s visto en la historia de CNN hab\u00eda ocurrido en 2015, cuando un debate republicano en el que participaron Trump y una serie de rivales republicanos tuvo un promedio de 23,1 millones de espectadores.<\/p>\n<p>El enfrentamiento del jueves en horario estelar supuso una ruptura con la tradici\u00f3n del debate sobre las elecciones generales, que durante mucho tiempo ha sido organizado por la Comisi\u00f3n no partidista de Debates Presidenciales y compartido con las cadenas de televisi\u00f3n. Si bien los debates primarios tradicionalmente s\u00ed son organizados por cadenas individuales, los candidatos y CNN rompieron la tradici\u00f3n al correr por completo a la comisi\u00f3n de la ecuaci\u00f3n, celebrando el debate antes de que los candidatos fueran siquiera oficialmente los nominados de sus partidos.<\/p>\n<p>El debate representa un est\u00edmulo muy necesario para CNN, que ha visto caer sus \u00edndices de audiencia despu\u00e9s de cambios en su programaci\u00f3n al aire y a medida que los espectadores de televisi\u00f3n tradicionales cortan cada vez m\u00e1s el cable en favor de los servicios de streaming.<\/p>\n<p>Los ciclos de elecciones presidenciales suelen dar lugar a una bonanza de rating para las redes de noticias, ya que las audiencias sintonizan para ver el desarrollo de la campa\u00f1a, pero hasta ahora 2024 ha demostrado ser la excepci\u00f3n, ya que pr\u00e1cticamente todos los medios de noticias han experimentado una disminuci\u00f3n en la audiencia con respecto a 2020.<\/p>\n<p>Si bien gran parte de la atenci\u00f3n despu\u00e9s del debate se centr\u00f3 en el desempe\u00f1o de Biden, el enfoque de no intervenci\u00f3n de CNN en la verificaci\u00f3n de hechos durante el debate provoc\u00f3 algunas cr\u00edticas.<\/p>\n<p>&#171;Me gustar\u00eda que los moderadores de CNN verificaran m\u00e1s los hechos, permitiendo que la audiencia sepa cuando se dicen cosas que son rotundamente falsas&#187;, escribi\u00f3 el columnista del New York Times Nicholas Kristof. &#171;No estoy seguro de c\u00f3mo ayuda que una plataforma transmita falsedades disfrazadas de hechos&#187;.<\/p>\n<p>Antes del evento, el director pol\u00edtico de CNN, David Chalian, dijo que la cadena limitar\u00eda la verificaci\u00f3n de hechos desde el escenario, con el objetivo de que los candidatos lidien con los problemas y que los moderadores &#171;no se conviertan en participantes de ese debate&#187;.<\/p>\n<p>Los moderadores Jake Tapper y Dana Bash adoptaron un enfoque deliberado durante las preguntas, haciendo un seguimiento cuando los candidatos no respond\u00edan las preguntas y controlando el tiempo de palabra asignado. En un momento, Bash presion\u00f3 a Trump tres veces sobre si aceptar\u00eda el resultado de las elecciones de 2024.<\/p>\n<p>&#171;Estamos muy orgullosos de Jake y Dana&#187;, dijo un portavoz de CNN. &#171;Nuestro trabajo era asegurarnos de que los candidatos fueran escuchados para que los votantes pudieran tomar decisiones informadas y estamos contentos de haber podido hacerlo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El debate de la noche del jueves en CNN entre el presidente Joe Biden y el expresidente Donald Trump fue visto por 47,9 millones de espectadores por televisi\u00f3n, seg\u00fan cifras preliminares de Nielsen. El debate de 90 minutos, que conmocion\u00f3 al mundo pol\u00edtico, se transmiti\u00f3 simult\u00e1neamente a trav\u00e9s de 22 cadenas. CNN, que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1450776","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El debate de la noche del jueves en CNN entre el presidente Joe Biden y el expresidente Donald Trump fue visto por 47,9 millones de espectadores por televisi\u00f3n, seg\u00fan cifras preliminares de Nielsen. El debate de 90 minutos, que conmocion\u00f3 al mundo pol\u00edtico, se transmiti\u00f3 simult\u00e1neamente a trav\u00e9s de 22 cadenas. CNN, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-28T21:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump\",\"datePublished\":\"2024-06-28T21:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/\"},\"wordCount\":883,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/\",\"name\":\"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-28T21:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump - Noticias","og_description":"(CNN) &#8212; El debate de la noche del jueves en CNN entre el presidente Joe Biden y el expresidente Donald Trump fue visto por 47,9 millones de espectadores por televisi\u00f3n, seg\u00fan cifras preliminares de Nielsen. El debate de 90 minutos, que conmocion\u00f3 al mundo pol\u00edtico, se transmiti\u00f3 simult\u00e1neamente a trav\u00e9s de 22 cadenas. CNN, que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-28T21:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/"},"author":{"name":"","@id":""},"headline":"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump","datePublished":"2024-06-28T21:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/"},"wordCount":883,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/","name":"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-28T21:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump","url":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2024\/06\/28\/479-millones-vieron-debate-cnn-biden-y-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-28T21:03:44Z","datePublished":"2024-06-28T21:03:44Z","dateModified":"2024-06-28T21:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"47,9 millones de personas vieron el debate presidencial de CNN entre Biden y Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/28\\\/479-millones-vieron-debate-cnn-biden-y-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2024\\\/06\\\/28\\\/479-millones-vieron-debate-cnn-biden-y-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-28T21:03:44Z\",\"datePublished\":\"2024-06-28T21:03:44Z\",\"dateModified\":\"2024-06-28T21:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466798,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/09\/25\/abc-jimmy-kimmel-live-acumulo-6-3-millones-espectadores-trax\/","url_meta":{"origin":1450776,"position":0},"title":"ABC afirma que &#171;Jimmy Kimmel Live!&#187; acumul\u00f3 6,3 millones de espectadores en su transmisi\u00f3n de regreso a la noche","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"El primer episodio nuevo de \u201cJimmy Kimmel Live!\u201d desde su suspensi\u00f3n tuvo un promedio de 6,3 millones de espectadores a trav\u00e9s de la televisi\u00f3n tradicional, m\u00e1s de tres veces la audiencia televisiva t\u00edpica del programa, a pesar de que fue suspendido en docenas de mercados.En el grupo demogr\u00e1fico clave para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445350,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/13\/el-super-bowl-lviii-establece-un-record-de-audiencia-con-la-asombrosa-cifra-de-1234-millones-de-espectadores-la-mayor-audiencia-televisiva-desde-el-alunizaje\/","url_meta":{"origin":1450776,"position":1},"title":"El Super Bowl LVIII establece un r\u00e9cord de audiencia con la asombrosa cifra de 123,4 millones de espectadores, la mayor audiencia televisiva desde el alunizaje","author":"","date":"febrero 13, 2024","format":false,"excerpt":"(CNN) --\u00a0 El Super Bowl LVIII fue la transmisi\u00f3n televisiva m\u00e1s vista en una generaci\u00f3n.El thriller de tiempo extra de este domingo, en el que los Kansas City Chiefs se enfrentaron a los San Francisco 49ers, tuvo un promedio de 123,4 millones de espectadores, dijo CBS este lunes, rompiendo r\u00e9cords\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445352,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/13\/el-super-bowl-lviii-establece-un-record-de-audiencia-con-la-asombrosa-cifra-de-1234-millones-de-espectadores-la-mayor-audiencia-televisiva-desde-el-alunizaje-2\/","url_meta":{"origin":1450776,"position":2},"title":"El Super Bowl LVIII establece un r\u00e9cord de audiencia con la asombrosa cifra de 123,4 millones de espectadores, la mayor audiencia televisiva desde el alunizaje","author":"","date":"febrero 13, 2024","format":false,"excerpt":"(CNN) --\u00a0 El Super Bowl LVIII fue la transmisi\u00f3n televisiva m\u00e1s vista en una generaci\u00f3n.El thriller de tiempo extra de este domingo, en el que los Kansas City Chiefs se enfrentaron a los San Francisco 49ers, tuvo un promedio de 123,4 millones de espectadores, dijo CBS este lunes, rompiendo r\u00e9cords\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445370,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/13\/el-super-bowl-lviii-establece-un-record-de-audiencia-con-la-asombrosa-cifra-de-1234-millones-de-espectadores-la-mayor-audiencia-televisiva-desde-el-alunizaje-3\/","url_meta":{"origin":1450776,"position":3},"title":"El Super Bowl LVIII establece un r\u00e9cord de audiencia con la asombrosa cifra de 123,4 millones de espectadores, la mayor audiencia televisiva desde el alunizaje","author":"","date":"febrero 13, 2024","format":false,"excerpt":"(CNN) --\u00a0 El Super Bowl LVIII fue la transmisi\u00f3n televisiva m\u00e1s vista en una generaci\u00f3n.El thriller de tiempo extra de este domingo, en el que los Kansas City Chiefs se enfrentaron a los San Francisco 49ers, tuvo un promedio de 123,4 millones de espectadores, dijo CBS este lunes, rompiendo r\u00e9cords\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457728,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/01\/21\/netflix-subira-precios-mayor-aumento-suscriptores-trax\/","url_meta":{"origin":1450776,"position":4},"title":"Netflix aumentar\u00e1 sus precios despu\u00e9s de reportar su mayor aumento de suscriptores hasta la fecha","author":"","date":"enero 21, 2025","format":false,"excerpt":"Netflix anunci\u00f3 este martes que aumentar\u00e1 los precios en la mayor\u00eda de sus niveles de suscripci\u00f3n en EE.UU. y Canad\u00e1 despu\u00e9s de que el gigante del streaming reportara 19 millones de nuevos suscriptores en el \u00faltimo trimestre de 2024.El aumento de suscriptores, el mayor de Netflix hasta la fecha, sit\u00faa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450763,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/06\/27\/quien-gano-debate-biden-trump-encuesta-mayoria-trax\/","url_meta":{"origin":1450776,"position":5},"title":"\u00bfQui\u00e9n gan\u00f3 el debate entre Biden y Trump? Esto muestra una encuesta de CNN","author":"","date":"junio 27, 2024","format":false,"excerpt":"(CNN) -- \u00bfQui\u00e9n gan\u00f3 el debate? Los votantes registrados que vieron el debate del jueves entre el presidente Joe Biden y el expresidente Donald Trump dicen que Trump tuvo un mejor desempe\u00f1o, en proporci\u00f3n del 67% frente al 33%. Antes del debate, los mismos votantes dec\u00edan que esperaban que Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1450776"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1450776\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1450776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1450776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1450776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}