{"id":1469430,"date":"2025-12-19T15:03:47","date_gmt":"2025-12-19T23:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/"},"modified":"2025-12-19T15:03:47","modified_gmt":"2025-12-19T23:03:47","slug":"eeuu-ataques-siria-muerte-dos-soldados-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/","title":{"rendered":"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses"},"content":{"rendered":"<p>Estados Unidos atac\u00f3 varios objetivos en Siria este viernes, los cuales las Fuerzas Armadas estadounidenses vincularon con ISIS, como represalia por el reciente ataque contra militares estadounidenses en ese pa\u00eds, que <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/13\/eeuu\/siria-mueren-soldados-ee-uu-trax\">dej\u00f3 dos efectivos muertos,<\/a> seg\u00fan dos funcionarios de Estados Unidos.<\/p>\n<p>La operaci\u00f3n, denominada \u201cHawkeye\u201d en referencia a que los dos soldados fallecidos eran originarios de Iowa, conocido como el \u201cestado Hawkeye\u201d, alcanz\u00f3 decenas de objetivos relacionados con ISIS, incluyendo infraestructura y dep\u00f3sitos de armas en distintas zonas de Siria, seg\u00fan uno de los funcionarios.<\/p>\n<p>Tras el ataque del 13 de diciembre, en el que murieron los dos soldados y un int\u00e9rprete civil, fuerzas de Estados Unidos y sus aliados realizaron 10 operaciones que resultaron en la muerte o detenci\u00f3n de unas 23 personas, a\u00f1adi\u00f3 el funcionario. Adem\u00e1s, se obtuvo informaci\u00f3n de dispositivos electr\u00f3nicos incautados durante esas operaciones, lo que ayud\u00f3 a identificar los objetivos de los ataques.<\/p>\n<p>Cientos de militares estadounidenses siguen desplegados en Siria como parte de la misi\u00f3n de largo plazo para combatir a ISIS, que comenz\u00f3 cuando el grupo tom\u00f3 r\u00e1pidamente el control de amplias zonas de Siria e Iraq a mediados de la d\u00e9cada de 2010. Posteriormente, las operaciones conjuntas y los cambios en el Gobierno sirio eliminaron en gran medida ese control territorial.<\/p>\n<p>El objetivo de la Operaci\u00f3n Hawkeye es asestar un golpe importante a los remanentes de ISIS en Siria y reducir su capacidad de amenazar a las fuerzas estadounidenses en la regi\u00f3n, dijo el funcionario a CNN.<\/p>\n<p>Pa\u00edses aliados, como Jordania, participaron junto a Estados Unidos en los ataques, seg\u00fan la misma fuente.<\/p>\n<p>Aunque el gobierno de Trump prometi\u00f3 represalias contra ISIS tras el ataque del 13 de diciembre, CNN inform\u00f3 que el Ministerio del Interior de Siria se\u00f1al\u00f3 que el atacante era miembro del servicio de Seguridad Interna sirio. Funcionarios de Estados Unidos y Siria reconocieron a CNN que los v\u00ednculos del atacante con ISIS no est\u00e1n del todo claros; el grupo no se ha atribuido el ataque.<\/p>\n<p>Los dos militares estadounidenses fallecidos en Siria fueron identificados esta semana como el sargento Edgar Brian Torres Tovar, de 25 a\u00f1os, de Des Moines, Iowa, y el sargento William Nathaniel Howard, de 29 a\u00f1os, de Marshalltown, Iowa. Murieron mientras enfrentaban a fuerzas hostiles en Palmira, Siria, seg\u00fan el Ej\u00e9rcito de Estados Unidos. Ambos pertenec\u00edan al 1\u00b0 Escuadr\u00f3n, 113\u00ba Regimiento de Caballer\u00eda, 2\u00aa Brigada de Infanter\u00eda, 34\u00aa Divisi\u00f3n de Infanter\u00eda de la Guardia Nacional de Iowa.<\/p>\n<p>Otros tres miembros de la Guardia Nacional de Iowa resultaron heridos en el ataque y fueron evacuados para recibir atenci\u00f3n m\u00e9dica.<\/p>\n<p>\u201cNuestra prioridad en este momento es apoyar a las familias de nuestros soldados ca\u00eddos y heridos\u201d, declar\u00f3 el general de divisi\u00f3n Stephen Osborne, jefe de la Guardia Nacional de Iowa. \u201cToda la Guardia Nacional de Iowa lamenta esta terrible p\u00e9rdida y estamos unidos para apoyar a los soldados y sus familias\u201d.<\/p>\n<p>Aproximadamente 1.800 soldados de la Guardia Nacional de Iowa comenzaron a desplegarse en Medio Oriente a principios de este a\u00f1o como parte de la Operaci\u00f3n Inherent Resolve, de acuerdo con un comunicado de la oficina de la gobernadora Kim Reynolds.<\/p>\n<p><em>Noticia en desarrollo\u2026<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos atac\u00f3 varios objetivos en Siria este viernes, los cuales las Fuerzas Armadas estadounidenses vincularon con ISIS, como represalia por el reciente ataque contra militares estadounidenses en ese pa\u00eds, que dej\u00f3 dos efectivos muertos, seg\u00fan dos funcionarios de Estados Unidos. La operaci\u00f3n, denominada \u201cHawkeye\u201d en referencia a que los dos soldados fallecidos eran originarios [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469430","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses - Noticias\" \/>\n<meta property=\"og:description\" content=\"Estados Unidos atac\u00f3 varios objetivos en Siria este viernes, los cuales las Fuerzas Armadas estadounidenses vincularon con ISIS, como represalia por el reciente ataque contra militares estadounidenses en ese pa\u00eds, que dej\u00f3 dos efectivos muertos, seg\u00fan dos funcionarios de Estados Unidos. La operaci\u00f3n, denominada \u201cHawkeye\u201d en referencia a que los dos soldados fallecidos eran originarios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-19T23:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses\",\"datePublished\":\"2025-12-19T23:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/\"},\"wordCount\":575,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/\",\"name\":\"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-19T23:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses - Noticias","og_description":"Estados Unidos atac\u00f3 varios objetivos en Siria este viernes, los cuales las Fuerzas Armadas estadounidenses vincularon con ISIS, como represalia por el reciente ataque contra militares estadounidenses en ese pa\u00eds, que dej\u00f3 dos efectivos muertos, seg\u00fan dos funcionarios de Estados Unidos. La operaci\u00f3n, denominada \u201cHawkeye\u201d en referencia a que los dos soldados fallecidos eran originarios [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-19T23:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses","datePublished":"2025-12-19T23:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/"},"wordCount":575,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/","name":"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-19T23:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\u00f3 a dos soldados estadounidenses","url":"http:\/\/noticiasya.com\/las-vegas\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2025\/12\/19\/eeuu-ataques-siria-muerte-dos-soldados-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-19T23:03:47Z","datePublished":"2025-12-19T23:03:47Z","dateModified":"2025-12-19T23:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. realiza ataques en Siria en respuesta al ataque que mat\\u00f3 a dos soldados estadounidenses\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2025\\\/12\\\/19\\\/eeuu-ataques-siria-muerte-dos-soldados-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2025\\\/12\\\/19\\\/eeuu-ataques-siria-muerte-dos-soldados-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-19T23:03:47Z\",\"datePublished\":\"2025-12-19T23:03:47Z\",\"dateModified\":\"2025-12-19T23:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469966,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/01\/10\/ee-uu-ataques-siria-represalias-isis-trax\/","url_meta":{"origin":1469430,"position":0},"title":"EE. UU. realiza ataques en Siria como parte de las represalias contra ISIS","author":"","date":"enero 10, 2026","format":false,"excerpt":"Estados Unidos llev\u00f3 a cabo ataques a gran escala contra objetivos de ISIS en Siria este s\u00e1bado, como parte de una campa\u00f1a de represalia denominada operaci\u00f3n \u201cHawkeye Strike\u201d.\u201cHoy, aproximadamente a las 12:30 p. m., hora de Miami, las fuerzas del Comando Central de EE.UU. (CENTCOM), junto a fuerzas aliadas, realizaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470197,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/01\/17\/ataque-letal-lider-al-qaeda-siria-trax\/","url_meta":{"origin":1469430,"position":1},"title":"EE.UU. lleva a cabo ataque letal contra l\u00edder afiliado a al Qaeda en Siria","author":"","date":"enero 17, 2026","format":false,"excerpt":"Estados Unidos anunci\u00f3 este s\u00e1bado que realiz\u00f3 un ataque letal en Siria contra un l\u00edder afiliado a al Qaeda que, seg\u00fan afirma, ten\u00eda v\u00ednculos directos con un atacante de ISIS que mat\u00f3 a tres estadounidenses a principios de diciembre.\u201cLa muerte de un operador terrorista vinculado a la muerte de tres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469328,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/16\/ataque-siria-soldados-eeuu-trump-trax\/","url_meta":{"origin":1469430,"position":2},"title":"Tras ataque en Siria en el que murieron dos soldados de EE.UU., Trump lidia con un aliado complicado y los ecos de Afganist\u00e1n","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Cuando un atacante mat\u00f3 a dos militares estadounidenses y a un int\u00e9rprete civil en Siria durante el fin de semana, el presidente Donald Trump prometi\u00f3 represalias \u201cmuy serias\u201d contra los responsables.Funcionarios de la administraci\u00f3n Trump tambi\u00e9n se apresuraron a describir al agresor como un \u201catacante solitario\u201d que era miembro de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469241,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/13\/siria-mueren-soldados-ee-uu-trax\/","url_meta":{"origin":1469430,"position":3},"title":"Dos soldados del Ej\u00e9rcito de EE.UU. y un int\u00e9rprete civil murieron en Siria","author":"","date":"diciembre 13, 2025","format":false,"excerpt":"Dos soldados del Ej\u00e9rcito de EE.UU. y un int\u00e9rprete civil murieron en un ataque en Siria este s\u00e1bado, seg\u00fan el Departamento de Defensa.Otros tres resultaron heridos en el ataque, dijo Sean Parnell, portavoz principal del Pent\u00e1gono, en un comunicado en X.\u201cEl ataque ocurri\u00f3 mientras los soldados realizaban un encuentro con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455457,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/10\/30\/hasta-35-operativos-isis-murieron-siria-ejercito-eeuu-trax\/","url_meta":{"origin":1469430,"position":4},"title":"Hasta 35 agentes de ISIS murieron en ataques estadounidenses en Siria, seg\u00fan el ej\u00e9rcito de EE.UU.","author":"","date":"octubre 30, 2024","format":false,"excerpt":"(CNN) -- Hasta 35 agentes de ISIS murieron en ataques estadounidenses contra m\u00faltiples campamentos de ISIS en Siria el lunes por la noche, anunci\u00f3 el mi\u00e9rcoles el ej\u00e9rcito de Estados Unidos.\"Las fuerzas del Comando Central de EE.UU. llevaron a cabo una serie de ataques contra varios campamentos conocidos de ISIS\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456787,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/12\/20\/soldados-estados-unidos-siria-damasco-trax\/","url_meta":{"origin":1469430,"position":5},"title":"EE.UU. admite que tiene el doble de soldados en Siria mientras Biden env\u00eda funcionarios a Damasco","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"El Pent\u00e1gono anunci\u00f3 que EE.UU. tiene actualmente \u201caproximadamente 2.000\u201d soldados en Siria, m\u00e1s del doble del n\u00famero previamente revelado de 900, dijo un portavoz del Departamento de Defensa en una rueda de prensa de este jueves.\u201cHay consideraciones de seguridad diplom\u00e1ticas y operativas a menudo con nuestros despliegues y algunos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1469430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1469430"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1469430\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1469430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1469430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1469430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}