{"id":1469488,"date":"2025-12-22T06:03:44","date_gmt":"2025-12-22T14:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/"},"modified":"2025-12-22T06:03:44","modified_gmt":"2025-12-22T14:03:44","slug":"trump-fusion-nuclear-preocupaciones-eticas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/","title":{"rendered":"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas"},"content":{"rendered":"<p>La expansi\u00f3n del imperio empresarial de Trump hacia la fusi\u00f3n nuclear ha encendido las alarmas de los expertos en \u00e9tica, quienes advierten que la misma plantea graves conflictos de intereses y podr\u00eda implicar que el Gobierno federal haga favoritismos en lo que podr\u00eda ser el santo grial de la energ\u00eda limpia.<\/p>\n<p>Trump Media &#038; Technology Group (DJT) sorprendi\u00f3 a Wall Street la semana pasada al concertar una fusi\u00f3n de US$ 6 mil millones con TAE Technologies, una empresa respaldada por Google y l\u00edder en energ\u00eda de fusi\u00f3n.<\/p>\n<p>La compra implica que muy pronto el presidente Donald Trump tendr\u00e1 un importante inter\u00e9s financiero en una empresa cuyo futuro se ver\u00e1 influenciado por las acciones de un Gobierno que \u00e9l mismo preside.<\/p>\n<p>Las empresas de fusi\u00f3n nuclear est\u00e1n reguladas por el Gobierno federal y probablemente necesiten una profunda investigaci\u00f3n de su parte y a\u00fan m\u00e1s recursos para ser comercialmente viables. La fusi\u00f3n debe ser aprobada por los reguladores federales, algunos de los cuales fueron nominados por Trump.<\/p>\n<p>\u201cExiste un claro conflicto de intereses\u201d, declar\u00f3 a CNN Richard Painter, el principal funcionario de \u00e9tica del expresidente George W. Bush. \u201cTodos los dem\u00e1s presidentes desde la Guerra Civil se han desprendido de sus intereses comerciales en conflicto con sus funciones oficiales. El presidente Trump ha hecho lo contrario\u201d.<\/p>\n<p>Painter, quien ahora es profesor en la Facultad de Derecho de la Universidad de Minnesota, afirm\u00f3 que cualquier persona que no sea el presidente o el vicepresidente podr\u00eda estar cometiendo un delito si participara en un asunto del Gobierno estadounidense en el que supiera que tiene un inter\u00e9s financiero.<\/p>\n<p>Por ejemplo, indic\u00f3 que el secretario de energ\u00eda tendr\u00eda que recusarse de cualquier asunto relacionado con la fusi\u00f3n si simult\u00e1neamente tuviera una participaci\u00f3n significativa en una empresa de fusi\u00f3n.<\/p>\n<p>\u201cEs legal solo porque la ley de conflicto de intereses penal no se aplica al presidente\u201d, afirm\u00f3 Painter, y a\u00f1adi\u00f3 que, si bien es \u201ct\u00e9cnicamente legal\u201d, no cree que los presidentes deban estar exceptuados.<\/p>\n<p>El acuerdo de fusi\u00f3n provoc\u00f3 un aumento inmediato en el patrimonio neto de Trump.<\/p>\n<p>El precio de las acciones de Trump Media se dispar\u00f3 un 42 % tras el anuncio de la fusi\u00f3n del jueves. Esto increment\u00f3 el valor de la participaci\u00f3n que Trump posee a trav\u00e9s de un fideicomiso en US$ 500 millones, hasta los US$ 1.700 millones. El precio de las acciones de Trump Media continu\u00f3 subiendo el viernes, lo que elev\u00f3 el valor de dicha participaci\u00f3n a m\u00e1s de US$ 1.800 millones.<\/p>\n<p>Algunos en Wall Street apuestan a que el acuerdo crear\u00e1 un efecto halo para TAE.<\/p>\n<p>En nuestra opini\u00f3n, TAE \u201ccuenta claramente con un importante apoyo pol\u00edtico del presidente Trump, lo que, de manera importante, crear\u00e1 una importante apuesta nacional por la energ\u00eda de fusi\u00f3n nuclear en Estados Unidos en los pr\u00f3ximos a\u00f1os\u201d, declar\u00f3 Dan Ives, veterano analista tecnol\u00f3gico de Wedbush Securities, a sus clientes en una nota la semana pasada.<\/p>\n<p>La fusi\u00f3n es una forma futurista de energ\u00eda que pretende replicar el mismo proceso que alimenta al sol y a otras estrellas. Desde hace tiempo se ha considerado un potencial punto de inflexi\u00f3n, ya que podr\u00eda proporcionar energ\u00eda limpia casi ilimitada.<\/p>\n<p>Sin embargo, la fusi\u00f3n a\u00fan no es comercialmente viable, y para que despegue podr\u00eda necesitar apoyo del Gobierno federal en forma de pr\u00e9stamos, subsidios, contratos e investigaci\u00f3n.<\/p>\n<p>Por eso, el inter\u00e9s p\u00fablico podr\u00eda verse perjudicado si la fusi\u00f3n crea una ventaja injusta para TAE, respaldada por Trump, preocupa a Kathleen Clark, profesora de derecho en la Universidad de Washington en St. Louis, quien estudia \u00e9tica gubernamental.<\/p>\n<p>\u201cEl riesgo es que una empresa termine siendo la favorita del Gobierno, no por una evaluaci\u00f3n cient\u00edfica objetiva, sino porque soborn\u00f3 al presidente\u201d, dijo Clark. \u201cMe recuerda a la Uni\u00f3n Sovi\u00e9tica, que nombraba cient\u00edficos en base a su supuesta ideolog\u00eda, no en sus logros reales\u201d.<\/p>\n<p>El representante Don Beyer, dem\u00f3crata de Virginia y copresidente del Caucus de Energ\u00eda de Fusi\u00f3n de la C\u00e1mara de Representantes, declar\u00f3 a CNN en una entrevista telef\u00f3nica que estaba \u201cat\u00f3nito\u201d por el acuerdo con Trump Media. \u201cDetesto la idea de que un presidente que inscribe su nombre en el Kennedy Center est\u00e9 poniendo un pie en la balanza de los ganadores y perdedores de la energ\u00eda de fusi\u00f3n\u201d, declar\u00f3 Beyer.<\/p>\n<p>Beyer afirm\u00f3 que se ha sentido \u201calentado\u201d por el apoyo del Departamento de Energ\u00eda a la energ\u00eda de fusi\u00f3n y que le complace tener un presidente que apoye a la industria.<\/p>\n<p>En octubre, la administraci\u00f3n Trump public\u00f3 una Hoja de Ruta para la Ciencia y la Tecnolog\u00eda de la Fusi\u00f3n que \u201cpretende impulsar la floreciente industria privada de fusi\u00f3n en Estados Unidos hacia su madurez lo m\u00e1s r\u00e1pidamente posible\u201d.<\/p>\n<p>Sin embargo, Beyer se\u00f1al\u00f3 que hay m\u00e1s de dos docenas de empresas de fusi\u00f3n operando en Estados Unidos, algunas de las cuales est\u00e1n m\u00e1s avanzadas que TAE.<\/p>\n<p>\u201cSi la colaboraci\u00f3n de Trump significa que toda la industria avanza m\u00e1s r\u00e1pido, es una victoria para la humanidad\u201d, declar\u00f3 Beyer. \u201cPero si significa que todos los dem\u00e1s se ver\u00e1n perjudicados y la generosidad del obierno se centrar\u00e1 en una sola empresa, eso es malo para la humanidad y malo para Estados Unidos\u201d.<\/p>\n<p>La Casa Blanca rechaz\u00f3 las preocupaciones sobre un conflicto de inter\u00e9s.<\/p>\n<p>\u201cLos continuos intentos de los medios de comunicaci\u00f3n de inventar conflictos de inter\u00e9s son irresponsables y refuerzan la desconfianza del p\u00fablico en lo que lee. Ni el presidente ni su familia han tenido, ni tendr\u00e1n, conflictos de intereses\u201d, declar\u00f3 Karoline Leavitt, secretaria de prensa de la Casa Blanca, en un comunicado a CNN.<\/p>\n<p>Ni el Departamento de Energ\u00eda ni la Organizaci\u00f3n Trump respondieron a las solicitudes de comentarios.<\/p>\n<p>Michl Binderbauer, director ejecutivo de TAE, declar\u00f3 a CNN que decidi\u00f3 fusionarse con Trump Media porque ofrec\u00eda la \u201c\u00faltima pieza del rompecabezas\u201d en su b\u00fasqueda para construir una central el\u00e9ctrica: capital.<\/p>\n<p>\u201cA veces tienes suerte y conoces a las personas adecuadas\u201d, afirm\u00f3.<\/p>\n<p>Binderbauer afirm\u00f3 que no le preocupa que el apoyo gubernamental que su empresa necesita o recibe se vuelva pol\u00edticamente controvertido por haber unido fuerzas con Trump.<\/p>\n<p>\u201cNo busco nada especial\u201d, afirm\u00f3.<\/p>\n<p>Tras ganar las elecciones el oto\u00f1o pasado, Trump transfiri\u00f3 su participaci\u00f3n mayoritaria en Trump Media al Fideicomiso Revocable Donald J. Trump.<\/p>\n<p>Trump es el \u00fanico beneficiario de dicho fideicomiso, controlado por su hijo mayor, Donald Trump Jr., quien tambi\u00e9n planea formar parte de la junta directiva de la empresa fusionada.<\/p>\n<p>Clark afirm\u00f3 que la transferencia a un fideicomiso es irrelevante cuando se trata de un conflicto de intereses.<\/p>\n<p>\u201cCarece completamente de sentido. Desde el punto de vista \u00e9tico, es una tonter\u00eda\u201d, afirm\u00f3.<\/p>\n<p>Painter, exfuncionaria de \u00e9tica de Bush, coincide en que la transferencia a un fideicomiso no importa porque Trump sigue teniendo un inter\u00e9s financiero.<\/p>\n<p>\u201cEs como decir: \u2018No soy due\u00f1o de una propiedad solo porque contrat\u00e9 a un administrador de propiedades para que la cuidara\u2019\u201d, afirm\u00f3 Painter.<\/p>\n<p>Painter afirm\u00f3 que existe una manera sencilla para que Trump evite la apariencia de un conflicto de intereses.<\/p>\n<p>\u201cDeber\u00eda desinvertir. Desinvertir en la fusi\u00f3n nuclear, las redes sociales y las criptomonedas\u201d, dijo Painter.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La expansi\u00f3n del imperio empresarial de Trump hacia la fusi\u00f3n nuclear ha encendido las alarmas de los expertos en \u00e9tica, quienes advierten que la misma plantea graves conflictos de intereses y podr\u00eda implicar que el Gobierno federal haga favoritismos en lo que podr\u00eda ser el santo grial de la energ\u00eda limpia. Trump Media &#038; Technology [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469488","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas - Noticias\" \/>\n<meta property=\"og:description\" content=\"La expansi\u00f3n del imperio empresarial de Trump hacia la fusi\u00f3n nuclear ha encendido las alarmas de los expertos en \u00e9tica, quienes advierten que la misma plantea graves conflictos de intereses y podr\u00eda implicar que el Gobierno federal haga favoritismos en lo que podr\u00eda ser el santo grial de la energ\u00eda limpia. Trump Media &#038; Technology [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-22T14:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas\",\"datePublished\":\"2025-12-22T14:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/\"},\"wordCount\":1298,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/\",\"name\":\"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-22T14:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas - Noticias","og_description":"La expansi\u00f3n del imperio empresarial de Trump hacia la fusi\u00f3n nuclear ha encendido las alarmas de los expertos en \u00e9tica, quienes advierten que la misma plantea graves conflictos de intereses y podr\u00eda implicar que el Gobierno federal haga favoritismos en lo que podr\u00eda ser el santo grial de la energ\u00eda limpia. Trump Media &#038; Technology [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-22T14:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/"},"author":{"name":"","@id":""},"headline":"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas","datePublished":"2025-12-22T14:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/"},"wordCount":1298,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/","name":"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-22T14:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Empresa de Trump invierte en fusi\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \u00e9ticas","url":"http:\/\/noticiasya.com\/las-vegas\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2025\/12\/22\/trump-fusion-nuclear-preocupaciones-eticas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-22T14:03:44Z","datePublished":"2025-12-22T14:03:44Z","dateModified":"2025-12-22T14:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Empresa de Trump invierte en fusi\\u00f3n nuclear por US$ 6 mil millones. El acuerdo plantea serias preocupaciones \\u00e9ticas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2025\\\/12\\\/22\\\/trump-fusion-nuclear-preocupaciones-eticas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2025\\\/12\\\/22\\\/trump-fusion-nuclear-preocupaciones-eticas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-22T14:03:44Z\",\"datePublished\":\"2025-12-22T14:03:44Z\",\"dateModified\":\"2025-12-22T14:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473676,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/30\/fusion-nuclear-electricidad-empresa-trax\/","url_meta":{"origin":1469488,"position":0},"title":"Esta empresa afirma que la fusi\u00f3n nuclear podr\u00eda finalmente alimentar la red el\u00e9ctrica, y que podr\u00eda hacerlo pronto","author":"","date":"abril 30, 2026","format":false,"excerpt":"Una empresa de fusi\u00f3n con sede en Massachusetts dio esta semana un paso m\u00e1s en su carrera por convertirse en la primera en suministrar a la red el\u00e9ctrica estadounidense la misma energ\u00eda que alimenta al sol y a las estrellas.Commonwealth Fusion Systems est\u00e1 construyendo un tokamak, una m\u00e1quina con forma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456731,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/12\/18\/primera-central-fusion-nuclear-red-electrica-trax\/","url_meta":{"origin":1469488,"position":1},"title":"Anuncian construcci\u00f3n en Estados Unidos de la &#171;primera&#187; central de fusi\u00f3n nuclear del mundo a nivel de la red el\u00e9ctrica","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"Virginia se convertir\u00e1, si todo sale seg\u00fan lo previsto, en el primer centro mundial de energ\u00eda de fusi\u00f3n nuclear a escala de red, capaz de aprovechar esta energ\u00eda limpia futurista y generar electricidad a partir de ella a principios de la d\u00e9cada de 2030, seg\u00fan anunci\u00f3 este martes la empresa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469384,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/18\/redes-trump-unificacion-fusion-nuclear-trax\/","url_meta":{"origin":1469488,"position":2},"title":"El negocio de redes sociales de Trump se une a una compa\u00f1\u00eda de fusi\u00f3n nuclear","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"Trump Media & Technology Group, empresa matriz de Truth Social, anunci\u00f3 este jueves un acuerdo para integrarse a la empresa de fusi\u00f3n nuclear TAE Technologies.Esta sorpresiva unificaci\u00f3n impuls\u00f3 las acciones de Trump Media un 17 % en las operaciones previas a la apertura del mercado.Las empresas afirmaron que la transacci\u00f3n,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456930,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/12\/24\/energia-nuclear-empresas-nucleares-ia-trax\/","url_meta":{"origin":1469488,"position":3},"title":"Los grandes nombres de la IA quieren apostar por la energ\u00eda nuclear. Tambi\u00e9n est\u00e1n detr\u00e1s de empresas nucleares.","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"Sam Altman es el presidente de una empresa que promete un futuro m\u00e1s brillante para la humanidad.No, no es OpenAI, la empresa de inteligencia artificial que cofund\u00f3 y ahora dirige como CEO.Es una empresa llamada Oklo, y est\u00e1 desarrollando el tipo de tecnolog\u00eda de energ\u00eda nuclear que muchos l\u00edderes tecnol\u00f3gicos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460854,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/04\/04\/nuevo-concepto-cohete-propulsion-nuclear-viajes-espaciales-trax\/","url_meta":{"origin":1469488,"position":4},"title":"Un nuevo concepto de cohete de propulsi\u00f3n nuclear podr\u00eda reducir a la mitad el tiempo de viaje a Marte","author":"","date":"abril 4, 2025","format":false,"excerpt":"Algunas de las mentes m\u00e1s brillantes del mundo han so\u00f1ado conlograr la fusi\u00f3n nuclear durante d\u00e9cadas. Es sencillo ver por qu\u00e9: replicar el funcionamiento interno de las estrellas aqu\u00ed en la Tierra significar\u00eda obtener energ\u00eda limpia pr\u00e1cticamente ilimitada.A pesar de una larga historia de intentos y varios avances, el sue\u00f1o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458305,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/02\/05\/china-instalacion-laser-fusion-nuclear-imagenes-satelite-trax\/","url_meta":{"origin":1469488,"position":5},"title":"China habr\u00eda construido una enorme planta de &#171;fusi\u00f3n l\u00e1ser&#187; nuclear, seg\u00fan im\u00e1genes satelitales","author":"","date":"febrero 5, 2025","format":false,"excerpt":"Im\u00e1genes desde el espacio revelan un enorme edificio en forma de X que se eleva desde un terreno rocoso en el suroeste de China. Este es un enorme centro de investigaci\u00f3n sobre fusi\u00f3n nuclear, dicen los analistas, y podr\u00eda ser una se\u00f1al de que China est\u00e1 avanzando en la b\u00fasqueda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1469488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1469488"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1469488\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1469488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1469488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1469488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}