{"id":1469546,"date":"2025-12-24T13:03:40","date_gmt":"2025-12-24T21:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/"},"modified":"2025-12-24T13:03:40","modified_gmt":"2025-12-24T21:03:40","slug":"madre-melodee-buzzard-urtah-california-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/","title":{"rendered":"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah"},"content":{"rendered":"<p>La b\u00fasqueda multiestatal de Melodee Buzzard, una ni\u00f1a californiana desaparecida de 9 a\u00f1os, concluy\u00f3 con el descubrimiento de sus restos en una zona rural del sur de Utah, anunciaron las autoridades el martes.<\/p>\n<p>Miembros de la oficina del sheriff y del FBI arrestaron a Ashlee Buzzard, la madre de Melodee, el martes por la ma\u00f1ana, acusada de homicidio premeditado, seg\u00fan inform\u00f3 el sheriff forense del condado de Santa B\u00e1rbara, Bill Brown.<\/p>\n<p>Las autoridades afirman que intent\u00f3 ocultar deliberadamente sus pasos, por ejemplo, al entrar en gasolineras con un coche de alquiler marcha atr\u00e1s, para evitar ser detectada por las c\u00e1maras de vigilancia.<\/p>\n<p>El cuerpo fue descubierto por una pareja que tomaba fotos en una zona remota del condado de Wayne, Utah, seg\u00fan Brown. Las autoridades del condado de Wayne indican que el cuerpo se encontraba cerca de una carretera con objetos que sirven como evidencia cerca.<\/p>\n<p>Los restos no pudieron ser identificados de inmediato, a\u00f1adi\u00f3, pero \u201cera evidente que la fallecida era una hembra que hab\u00eda fallecido por heridas de bala en la cabeza\u201d.<\/p>\n<p>Pero el an\u00e1lisis de ADN revel\u00f3 una coincidencia de ADN familiar con la madre de Melodee, a\u00f1adi\u00f3.<\/p>\n<p>Un laboratorio forense de Utah tard\u00f3 menos de 24 horas en relacionar el cuerpo con la desaparici\u00f3n de Melodee, declar\u00f3 el sheriff del condado de Wayne, Micah Gulley.<\/p>\n<p>\u201cHemos recuperado una cantidad significativa de pruebas que indican claramente que este atroz crimen fue cometido por Ashlee Buzzard, la madre de Melodee, y la persona en quien m\u00e1s confiaba en este mundo\u201d, declar\u00f3 Brown en una conferencia de prensa.<\/p>\n<p>CNN est\u00e1 intentando determinar si Buzzard cuenta con un abogado.<\/p>\n<p>Los investigadores no tienen el arma homicida ni han establecido un motivo, y a\u00f1aden que Buzzard se muestra \u201cpoco cooperativa\u201d, seg\u00fan informaron las autoridades el martes.<\/p>\n<p>La abuela paterna de Melodee, Lilly Denes, declar\u00f3 el martes por la ma\u00f1ana a KEYT y KSBY, afiliadas de CNN, que la oficina del sheriff le inform\u00f3 que se hab\u00eda descubierto el cuerpo de Melodee.<\/p>\n<p>\u201cEs muy triste para nosotros, especialmente porque ma\u00f1ana es Nochebuena y, ya saben, el resto de mis nietos vuelven a casa\u201d, <a href=\"https:\/\/keyt.com\/news\/santa-maria-north-county\/2025\/12\/23\/missing-nine-year-old-melodee-buzzard-is-dead-and-her-mother-is-now-in-custody\/\">declar\u00f3 Denes a KEYT el martes.<\/a><\/p>\n<p>Dijo que fue la primera persona a la que la polic\u00eda notific\u00f3 que la menor hab\u00eda fallecido.<\/p>\n<p>\u201cAhora est\u00e1 all\u00e1 con su pap\u00e1\u201d, dijo Denes. El padre de Melodee, hijo de Denes, muri\u00f3 en un accidente de motocicleta cuando Melodee era una beb\u00e9.<\/p>\n<p>CNN contact\u00f3 a Denes para obtener comentarios.<\/p>\n<p>Brown repas\u00f3 el martes una cronolog\u00eda que explicaba lo que llev\u00f3 a los investigadores al cuerpo de Melodee.<\/p>\n<p>Buzzard sali\u00f3 de viaje por carretera con su hija de 9 a\u00f1os el 7 de octubre, cuando las im\u00e1genes de vigilancia captaron a la ni\u00f1a en una agencia local de alquiler de coches vestida con lo que parec\u00eda ser un disfraz, informaron las autoridades.<\/p>\n<p>Melodee llevaba una sudadera con capucha sobre la cabeza y \u201clo que parece ser una peluca m\u00e1s oscura y lisa que su cabello natural\u201d, seg\u00fan inform\u00f3 previamente la Oficina del Sheriff del Condado de Santa B\u00e1rbara. \u201cLos investigadores creen que la peluca podr\u00eda haber sido utilizada para alterar su apariencia\u201d.<\/p>\n<p>El auto de alquiler recorri\u00f3 Nebraska, Utah, Arizona, Nevada y Kansas antes de regresar a su casa en Lompoc, a unos 88 kil\u00f3metros al noroeste de Santa B\u00e1rbara, informaron las autoridades.<\/p>\n<p>En alg\u00fan momento del viaje, Buzzard cambi\u00f3 la matr\u00edcula del veh\u00edculo que hab\u00eda alquilado por una de Nueva York, declar\u00f3 Brown el martes.<\/p>\n<p>\u201cLos investigadores han confirmado que Ashlee fue vista regresando a su residencia en Lompoc el 10 de octubre, conduciendo el mismo veh\u00edculo de alquiler con el que sali\u00f3 el 7 de octubre, pero Melodee no estaba en el auto\u201d, indic\u00f3 previamente la oficina del sheriff.<\/p>\n<p>La ni\u00f1a fue vista por \u00faltima vez en un video de vigilancia con su madre en el lado de Colorado de la frontera entre Colorado y Utah el 9 de octubre, seg\u00fan Brown.<\/p>\n<p>Los detectives, seg\u00fan Brown, ahora creen que Melodee fue asesinada poco despu\u00e9s de esa parada.<\/p>\n<p>Melodee fue reportada como desaparecida d\u00edas despu\u00e9s, el 14 de octubre, no por un familiar, sino por un administrador escolar preocupado por su prolongada ausencia.<\/p>\n<p>Al d\u00eda siguiente, 15 de octubre, los detectives cumplieron una orden de registro en la casa de Buzzard, <a href=\"https:\/\/www.sbsheriff.org\/ashlee-buzzard-arrested-for-murder-of-daughter-melodee-following-discovery-of-remains-in-utah\/\">seg\u00fan un comunicado de la Oficina del Sheriff del Condado de Santa B\u00e1rbara.<\/a><\/p>\n<p>El 30 de octubre, los detectives del sheriff, junto con el Equipo de Respuesta a Evidencias del FBI, cumplieron \u00f3rdenes de registro posteriores en la casa de Buzzard, as\u00ed como en un almac\u00e9n y un auto que hab\u00eda alquilado recientemente, seg\u00fan los investigadores.<\/p>\n<p>Se recuper\u00f3 un casquillo de bala durante el registro de la casa, dijo Brown, y durante el registro del auto alquilado se localiz\u00f3 una munici\u00f3n real similar, a\u00f1adi\u00f3 Brown.<\/p>\n<p>El 17 de diciembre, la ATF encontr\u00f3 casquillos de bala de la escena del crimen en Utah vinculados a un casquillo de bala encontrado en la residencia de Buzzard, seg\u00fan las autoridades.<\/p>\n<p>\u201cLa premeditaci\u00f3n y la crueldad, a sangre fr\u00eda y con una sofisticaci\u00f3n criminal\u2026 se usaron para planear el crimen\u201d, dijo Brown.<\/p>\n<p>La crueldad con la que se cometi\u00f3, a\u00f1adi\u00f3, fue impactante.<\/p>\n<p>\u201cEs incre\u00edble simplemente pensar que una madre pudiera hacerle esto a su hija\u201d, declar\u00f3 Lizabeth Meza, t\u00eda de Melodee, a KSBY, afiliada de CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La b\u00fasqueda multiestatal de Melodee Buzzard, una ni\u00f1a californiana desaparecida de 9 a\u00f1os, concluy\u00f3 con el descubrimiento de sus restos en una zona rural del sur de Utah, anunciaron las autoridades el martes. Miembros de la oficina del sheriff y del FBI arrestaron a Ashlee Buzzard, la madre de Melodee, el martes por la ma\u00f1ana, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469546","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah - Noticias\" \/>\n<meta property=\"og:description\" content=\"La b\u00fasqueda multiestatal de Melodee Buzzard, una ni\u00f1a californiana desaparecida de 9 a\u00f1os, concluy\u00f3 con el descubrimiento de sus restos en una zona rural del sur de Utah, anunciaron las autoridades el martes. Miembros de la oficina del sheriff y del FBI arrestaron a Ashlee Buzzard, la madre de Melodee, el martes por la ma\u00f1ana, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-24T21:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah\",\"datePublished\":\"2025-12-24T21:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/\"},\"wordCount\":964,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/\",\"name\":\"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-24T21:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah - Noticias","og_description":"La b\u00fasqueda multiestatal de Melodee Buzzard, una ni\u00f1a californiana desaparecida de 9 a\u00f1os, concluy\u00f3 con el descubrimiento de sus restos en una zona rural del sur de Utah, anunciaron las autoridades el martes. Miembros de la oficina del sheriff y del FBI arrestaron a Ashlee Buzzard, la madre de Melodee, el martes por la ma\u00f1ana, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-24T21:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/"},"author":{"name":"","@id":""},"headline":"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah","datePublished":"2025-12-24T21:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/"},"wordCount":964,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/","name":"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-24T21:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Arrestan a la madre de Melodee Buzzard, la ni\u00f1a de 9 a\u00f1os asesinada cuyo cuerpo fue hallado en Utah","url":"http:\/\/noticiasya.com\/las-vegas\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2025\/12\/24\/madre-melodee-buzzard-urtah-california-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-24T21:03:40Z","datePublished":"2025-12-24T21:03:40Z","dateModified":"2025-12-24T21:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Arrestan a la madre de Melodee Buzzard, la ni\\u00f1a de 9 a\\u00f1os asesinada cuyo cuerpo fue hallado en Utah\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2025\\\/12\\\/24\\\/madre-melodee-buzzard-urtah-california-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2025\\\/12\\\/24\\\/madre-melodee-buzzard-urtah-california-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-24T21:03:40Z\",\"datePublished\":\"2025-12-24T21:03:40Z\",\"dateModified\":\"2025-12-24T21:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469582,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/26\/melodee-buzzard-arresto-madre-trax\/","url_meta":{"origin":1469546,"position":0},"title":"Un hallazgo en un camino secundario llev\u00f3 al arresto de la madre de Melodee Buzzard por el asesinato &#171;calculado&#187; de la ni\u00f1a","author":"","date":"diciembre 26, 2025","format":false,"excerpt":"Mientras el sol de diciembre se pon\u00eda sobre los picos de arenisca del centro de Utah, una pareja se aventur\u00f3 por un anodino camino de tierra para tomarse fotos con el paisaje de rocas rojas como tel\u00f3n de fondo. Pero se toparon con un descubrimiento espeluznante entre arbustos dispersos y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468139,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/11\/08\/arrestan-madre-nina-desaparecida-trax\/","url_meta":{"origin":1469546,"position":1},"title":"Arrestan a la madre de la ni\u00f1a de 9 a\u00f1os desaparecida. Las autoridades afirman que no est\u00e1 relacionado con el caso de su hija","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"La madre de una ni\u00f1a californiana de 9 a\u00f1os que desapareci\u00f3 durante un viaje por carretera el mes pasado fue arrestada el viernes por un delito grave de privaci\u00f3n ilegal de la libertad, pero no est\u00e1 directamente relacionado con la b\u00fasqueda de su hija, informaron las autoridades.Los investigadores estaban indagando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468516,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/11\/19\/nina-california-desaparecida-madre-sospechosa-trax\/","url_meta":{"origin":1469546,"position":2},"title":"Una ni\u00f1a de California est\u00e1 desaparecida y su madre parece sospechosa. \u00bfQu\u00e9 puede suceder a continuaci\u00f3n?","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"Melodee Buzzard, de nueve a\u00f1os, lleva desaparecida m\u00e1s de un mes. Fue vista por \u00faltima vez con su madre, que llevaba pelucas, en un viaje por carretera a trav\u00e9s del pa\u00eds.La madre, Ashlee Buzzard, regres\u00f3 a su casa en California sin Melodee, no denunci\u00f3 la desaparici\u00f3n de su hija y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450955,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/07\/08\/bebe-murio-abandonada-texas-acusaron-madre-trax\/","url_meta":{"origin":1469546,"position":3},"title":"El caso de una reci\u00e9n nacida que muri\u00f3 abandonada estuvo sin resolverse por 23 a\u00f1os. Las autoridades de Texas acaban de acusar a su madre de homicidio accidental","author":"","date":"julio 8, 2024","format":false,"excerpt":"(CNN) -- Una beb\u00e9 reci\u00e9n nacida que muri\u00f3 abandonada en una zanja de Texas estuvo sin identificar durante 23 a\u00f1os hasta que las autoridades dijeron que recientemente reconocieron y acusaron a la madre.La Oficina del Sheriff del Condado de Johnson se ha referido a la beb\u00e9 como \"Angel Baby Doe\"\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471902,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/03\/05\/mujeres-muertas-utah-busqueda-trax\/","url_meta":{"origin":1469546,"position":4},"title":"Tres mujeres son halladas muertas en una zona rural de Utah: la b\u00fasqueda del responsable causa cierre de escuelas y negocios","author":"","date":"marzo 5, 2026","format":false,"excerpt":"El macabro hallazgo de tres cad\u00e1veres en el centro-sur de Utah ha desatado una b\u00fasqueda en varios condados, lo que ha provocado el cierre de escuelas y negocios.Las autoridades recibieron una llamada el mi\u00e9rcoles por la tarde sobre \u201cdos mujeres fallecidas localizadas en una ruta de senderismo\u201d en el condado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445855,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/02\/21\/persona-interes-desaparicion-audrii-cunningham-trax\/","url_meta":{"origin":1469546,"position":5},"title":"Encuentran el cuerpo de Audrii Cunningham, la ni\u00f1a desaparecida en Texas, en el r\u00edo Trinity, informan autoridades","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- El cuerpo de Audrii Cunningham, una ni\u00f1a de 11 a\u00f1os que desapareci\u00f3 en Texas luego de salir de su casa camino a la escuela, fue encontrado este martes en el r\u00edo Trinity, seg\u00fan el sheriff del condado de Polk, Byron Lyons.En rueda de prensa, Lyons se\u00f1al\u00f3: \"Lamentablemente anuncio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1469546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1469546"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1469546\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1469546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1469546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1469546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}