{"id":1469561,"date":"2025-12-25T09:03:46","date_gmt":"2025-12-25T17:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/"},"modified":"2025-12-25T09:03:46","modified_gmt":"2025-12-25T17:03:46","slug":"paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/","title":{"rendered":"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras"},"content":{"rendered":"<p>En medio de la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/24\/latinoamerica\/incertidumbre-honduras-consejo-electoral-fuertes-acusaciones-orix\">controversia electoral<\/a> y de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/25\/latinoamerica\/presidente-honduras-asfura-reconciliacion-nasralla-no-acepta-resultado-orix\">advertencias de impugnaciones<\/a> a los resultados de votaci\u00f3n de Honduras, Nasry \u201cTito\u201d Asfura ya suma varios apoyos internacionales luego de que el Consejo Nacional Electoral (CNE) lo declarara el mi\u00e9rcoles como ganador de los comicios presidenciales.<\/p>\n<p>Varios pa\u00edses han felicitado ya a Asfura \u2014candidato del conservador Partido Nacional\u2014 tras la declaratoria del CNE, a pesar de que su competidor m\u00e1s cercano, Salvador Nasralla \u2014candidato del tambi\u00e9n conservador Partido Liberal\u2014, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/25\/latinoamerica\/presidente-honduras-asfura-reconciliacion-nasralla-no-acepta-resultado-orix\">dice<\/a> que no acepta los resultados de las elecciones.<\/p>\n<p>Nasralla dice que apelar\u00e1 a los resultados por la \u201cv\u00eda legal\u201d. Tanto el Partido Liberal como el oficialismo de la presidenta Xiomara Castro advierten que el CNE aprob\u00f3 la declaratoria pese a que faltaba contar a\u00fan actas con irregularidades, algo m\u00e1s de 300.<\/p>\n<p>Asfura, seg\u00fan los resultados aprobados por el CNE, derrot\u00f3 a Nasralla por poco m\u00e1s de 27.000 votos, un margen menor al 1% de los sufragios emitidos el 30 de noviembre pasado. El CNE, por su lado, argument\u00f3 que no estaban dadas las condiciones para continuar con el escrutinio especial.<\/p>\n<p>Adem\u00e1s de gobiernos de otros pa\u00edses, organismos internacionales tambi\u00e9n han expresado su apoyo al resultado que da el triunfo electoral a Asfura.<\/p>\n<p>El secretario de Estado de EE.UU., Marco Rubio, felicit\u00f3 el mi\u00e9rcoles a Asfura y dijo que espera colaborar con su gobierno.<\/p>\n<p>\u201cEl pueblo de Honduras se ha pronunciado: Nasry Asfura es el pr\u00f3ximo presidente de Honduras\u201d, <a href=\"https:\/\/x.com\/SecRubio\/status\/2003943258351964628\">dijo Rubio en X<\/a>. \u201cEstados Unidos felicita al presidente electo y espera colaborar con su administraci\u00f3n para impulsar la prosperidad y la seguridad en nuestro hemisferio\u201d.<\/p>\n<p>Asfura fue el candidato que el presidente de Estados Unidos, Donald Trump, respald\u00f3 previo a las elecciones en Honduras, una intervenci\u00f3n que el gobernante Partido Libertad y Refundaci\u00f3n <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/22\/latinoamerica\/eeuu-proceso-electoral-honduras-consecuencias-orix\">calific\u00f3<\/a> de \u201cinjerencia imperialista\u201d.<\/p>\n<p>El Gobierno de China dijo este jueves que \u201crespeta la decisi\u00f3n del pueblo hondure\u00f1o\u201d luego de darse a conocer la declaratoria que da el triunfo de las elecciones a Asfura.<\/p>\n<p>China \u201cest\u00e1 dispuesto a colaborar con Honduras para impulsar conjuntamente el desarrollo continuo\u201d de las relaciones bilaterales, asegur\u00f3 Lin Jian, portavoz de la Canciller\u00eda del pa\u00eds asi\u00e1tico, en rueda de prensa.<\/p>\n<p>Asfura plante\u00f3 en su campa\u00f1a presidencial la posibilidad de romper los lazos entre Honduras y China para restablecerlos con Taiw\u00e1n. Honduras y Taiw\u00e1n rompieron relaciones en marzo de 2023 durante el Gobierno de Xiomara Castro.<\/p>\n<p>El Partido Comunista de China reivindica a <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/18\/mundo\/estados-unidos-taiwan-acuerdos-armas-trax\">Taiw\u00e1n<\/a>, un pa\u00eds aut\u00f3nomo y democr\u00e1tico, como parte de su territorio soberano, a pesar de nunca haberlo controlado.<\/p>\n<p>El Ministerio de Asuntos Exteriores de Taiw\u00e1n asegur\u00f3 este jueves que mantendr\u00e1 una actitud \u201cabierta y pragm\u00e1tica\u201d respecto a sus relaciones con el pr\u00f3ximo Gobierno de Honduras.<\/p>\n<p>La Canciller\u00eda de Taiw\u00e1n inst\u00f3 a Asfura a implementar pol\u00edticas favorables al \u201cbienestar\u201d del pueblo de Honduras, aunque no habl\u00f3 sobre un posible restablecimiento de las relaciones bilaterales.<\/p>\n<p>Argentina, Bolivia, Costa Rica, Ecuador, Panam\u00e1, Paraguay, Per\u00fa y Rep\u00fablica Dominicana felicitaron el mi\u00e9rcoles a Asfura tras ser declarado como el ganador de las elecciones presidenciales.<\/p>\n<p>\u201cFelicitamos al se\u00f1or Nasry \u2018Tito\u2019 Asfura, presidente electo de la Rep\u00fablica de Honduras tras los comicios celebrados el 30 de noviembre. Con su gobierno, a ser inaugurado el pr\u00f3ximo 27 de enero, esperamos trabajar conjuntamente en los temas que nos unen como pa\u00edses hermanos, en particular el comercio, la seguridad, la migraci\u00f3n y el fortalecimiento de la democracia en la regi\u00f3n\u201d, dijeron los ocho pa\u00edses en un <a href=\"https:\/\/www.facebook.com\/MIREXRDO\/posts\/pfbid0bSGVPQNM435rRoGVkRmVvGeeXrNvddSKduiGHgvuoDxFGzBkcPCzzrHquiNCbuf7l?locale=es_LA\">comunicado conjunto<\/a>.<\/p>\n<p>Por separado de esta declaraci\u00f3n conjunta, el presidente de Argentina, Javier Milei, celebr\u00f3 el mi\u00e9rcoles la declaratoria de triunfo para Asfura y afirm\u00f3 que se trata de \u201cuna derrota contundente del narcosocialismo y una se\u00f1al clara de que la libertad vuelve a imponerse en Honduras\u201d.<\/p>\n<p>\u201cEl pueblo hondure\u00f1o se expres\u00f3 con valent\u00eda en las urnas y eligi\u00f3 terminar con a\u00f1os de autoritarismo y decadencia\u201d, <a href=\"https:\/\/x.com\/JMilei\/status\/2003938349648695309\">escribi\u00f3<\/a> Milei en X.<\/p>\n<p>Tambi\u00e9n por separado, el Gobierno de Bolivia felicit\u00f3 el mi\u00e9rcoles a Asfura y manifest\u00f3 se reconocimiento a los resultados emitidos por la autoridad electoral hondure\u00f1a.<\/p>\n<p>\u201cBolivia reconoce los resultados proclamados por el Consejo Nacional Electoral y felicita al se\u00f1or Nasry Asfura por haber sido electo presidente de la Rep\u00fablica, destacando que la consolidaci\u00f3n de resultados claros constituye un factor esencial para la estabilidad democr\u00e1tica, la gobernabilidad y la confianza ciudadana\u201d, dijo la Canciller\u00eda boliviana en un comunicado.<\/p>\n<p>En tanto, el presidente de Paraguay, Santiago Pe\u00f1a, <a href=\"https:\/\/x.com\/SantiPenap\/status\/2003990670663352411\">habl\u00f3<\/a> con Asfura el mi\u00e9rcoles y le expres\u00f3 su deseo de trabajar juntos \u201cen la construcci\u00f3n de un hemisferio m\u00e1s seguro y pr\u00f3spero\u201d.<\/p>\n<p>Por su parte, el presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, felicit\u00f3 este jueves a Asfura y comparti\u00f3 deseos similares a los de sus hom\u00f3logos latinoamericanos.<\/p>\n<p>\u201cFelicito al presidente electo de Honduras Tito Asfura y deseo que trabajemos juntos en beneficio de nuestros pa\u00edses y de la regi\u00f3n\u201d, <a href=\"https:\/\/x.com\/JoseRaulMulino\/status\/2004182984530776228\">dijo<\/a> Mulino en su cuenta de X.<\/p>\n<p>El bloque de 27 pa\u00edses que conforma la Uni\u00f3n Europea (UE) se sum\u00f3 a las felicitaciones a Asfura y dijo que busca \u201cprofundizar\u201d los lazos con Honduras.<\/p>\n<p>\u201cTras un proceso largo y prolongado y la proclamaci\u00f3n de los resultados por parte del Consejo Nacional Electoral (CNE), la Uni\u00f3n Europea felicita a Nasry Asfura por su elecci\u00f3n como presidente de Honduras\u201d, indic\u00f3 una misiva oficial difundida por la delegaci\u00f3n de la UE en el pa\u00eds centroamericano.<\/p>\n<p>Seg\u00fan la declaraci\u00f3n, la UE espera \u201ccon inter\u00e9s trabajar con el presidente Asfura y su administraci\u00f3n y seguimos comprometidos a trabajar en prioridades comunes para profundizar\u201d la relaci\u00f3n bilateral \u201cen todos los \u00e1mbitos de inter\u00e9s mutuo\u201d.<\/p>\n<p>El mi\u00e9rcoles, el Gobierno del Reino Unido tambi\u00e9n se sum\u00f3 a las felicitaciones.<\/p>\n<p>\u201cEl pueblo hondure\u00f1o decidi\u00f3 y el CNE lo confirm\u00f3. Felicitaciones al presidente electo Nasry Asfura\u201d, indic\u00f3 el Reino Unido a trav\u00e9s de su Embajada concurrente para Honduras en Guatemala.<\/p>\n<p>A\u00f1adi\u00f3 que \u201cespera continuar su trabajo con Honduras para promover la prosperidad, el desarrollo humano, el medio ambiente y profundizar a\u00fan m\u00e1s nuestra relaci\u00f3n\u201d.<\/p>\n<p>La Misi\u00f3n de Observaci\u00f3n Electoral de la Organizaci\u00f3n de los Estados Americanos (MOE\/OEA) en Honduras dijo el mi\u00e9rcoles que respaldaba los resultados del CNE.<\/p>\n<p>Los datos declarados por el CNE, asegur\u00f3 la MOE\/OEA en un comunicado, \u201creflejan la voluntad\u201d ciudadana y no se identificaron \u201celementos fraudulentos determinantes\u201d.<\/p>\n<p>Sobre la espera prolongada para conocer la declaratoria del CNE, la MOE\/OEA se\u00f1al\u00f3 que la \u201cextrema polarizaci\u00f3n y complejidad\u201d del proceso poselectoral impidi\u00f3 que las autoridades electorales trabajaran \u201ccon la tranquilidad y autonom\u00eda que es propia de una democracia, afectando incluso su integridad personal y la de sus familias\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de la controversia electoral y de advertencias de impugnaciones a los resultados de votaci\u00f3n de Honduras, Nasry \u201cTito\u201d Asfura ya suma varios apoyos internacionales luego de que el Consejo Nacional Electoral (CNE) lo declarara el mi\u00e9rcoles como ganador de los comicios presidenciales. Varios pa\u00edses han felicitado ya a Asfura \u2014candidato del conservador Partido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469561","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras - Noticias\" \/>\n<meta property=\"og:description\" content=\"En medio de la controversia electoral y de advertencias de impugnaciones a los resultados de votaci\u00f3n de Honduras, Nasry \u201cTito\u201d Asfura ya suma varios apoyos internacionales luego de que el Consejo Nacional Electoral (CNE) lo declarara el mi\u00e9rcoles como ganador de los comicios presidenciales. Varios pa\u00edses han felicitado ya a Asfura \u2014candidato del conservador Partido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-25T17:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras\",\"datePublished\":\"2025-12-25T17:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/\"},\"wordCount\":1190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/\",\"name\":\"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-25T17:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras - Noticias","og_description":"En medio de la controversia electoral y de advertencias de impugnaciones a los resultados de votaci\u00f3n de Honduras, Nasry \u201cTito\u201d Asfura ya suma varios apoyos internacionales luego de que el Consejo Nacional Electoral (CNE) lo declarara el mi\u00e9rcoles como ganador de los comicios presidenciales. Varios pa\u00edses han felicitado ya a Asfura \u2014candidato del conservador Partido [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-25T17:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/"},"author":{"name":"","@id":""},"headline":"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras","datePublished":"2025-12-25T17:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/"},"wordCount":1190,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/","name":"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-25T17:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras","url":"http:\/\/noticiasya.com\/las-vegas\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-25T17:03:46Z","datePublished":"2025-12-25T17:03:46Z","dateModified":"2025-12-25T17:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qu\\u00e9 pa\\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2025\\\/12\\\/25\\\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2025\\\/12\\\/25\\\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-25T17:03:46Z\",\"datePublished\":\"2025-12-25T17:03:46Z\",\"dateModified\":\"2025-12-25T17:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469557,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/25\/presidente-honduras-asfura-reconciliacion-nasralla-no-acepta-resultado-orix\/","url_meta":{"origin":1469561,"position":0},"title":"Tras ser declarado presidente de Honduras, Asfura llama a la reconciliaci\u00f3n, pero Nasralla dice que no acepta el resultado","author":"","date":"diciembre 25, 2025","format":false,"excerpt":"Nasry \u201cTito\u201d Asfura, declarado como ganador de las elecciones presidenciales de Honduras por la autoridad electoral, llam\u00f3 a la reconciliaci\u00f3n en un mensaje de Nochebuena el mi\u00e9rcoles, al tiempo que su competidor m\u00e1s cercano, Salvador Nasralla, asegur\u00f3 que no acepta el resultado.\u201cEs tiempo de reconciliaci\u00f3n, de unidad y de paz.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470024,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/01\/12\/fuerzas-armadas-respaldo-resultados-elecciones-honduras-efe\/","url_meta":{"origin":1469561,"position":1},"title":"Fuerzas Armadas de Honduras respaldan los resultados ya anunciados de las elecciones presidenciales","author":"","date":"enero 12, 2026","format":false,"excerpt":"Las Fuerzas Armadas de Honduras anunciaron este lunes que contin\u00faan \u201crespaldando la declaratoria del Consejo Nacional Electoral (CNE)\u201d sobre los resultados de las elecciones presidenciales del pasado 30 de noviembre, que dieron como vencedor al conservador Nasry \u201cTito\u201d Asfura, apoyado p\u00fablicamente por el mandatario estadounidense, Donald Trump, ante peticiones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468994,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/05\/asfura-nasralla-honduras-elecciones-conteo-orix\/","url_meta":{"origin":1469561,"position":2},"title":"Asfura sigue con ventaja sobre Nasralla en medio de un conteo con muchos cuestionamientos en Honduras","author":"","date":"diciembre 5, 2025","format":false,"excerpt":"Nasry \u2018Tito\u2019 Asfura, candidato presidencial de Honduras por el opositor y conservador Partido Nacional, continuaba este viernes manteniendo una ventaja sobre Salvador Nasralla, del tambi\u00e9n conservador Partido Liberal, seg\u00fan la p\u00e1gina web del Consejo Nacional Electoral (CNE).Con el 87,35 % de las actas escrutadas, Asfura, el candidato apoyado por Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469586,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/26\/marco-rubio-asfura-felicitarlo-clara-victoria-electoral-honduras-orix\/","url_meta":{"origin":1469561,"position":3},"title":"Marco Rubio habla con Asfura &#171;para felicitarlo por una clara victoria electoral&#187; en Honduras","author":"","date":"diciembre 26, 2025","format":false,"excerpt":"El secretario de Estado de Estados Unidos, Marco Rubio, habl\u00f3 este viernes con Nasry \u201cTito\u201d Asfura, declarado como ganador de las elecciones presidenciales de Honduras, \u201cpara felicitarlo por una clara victoria electoral\u201d.En la conversaci\u00f3n, Rubio elogi\u00f3 a Asfura por defender \u201clos objetivos estrat\u00e9gicos\u201d de EE.UU., se\u00f1al\u00f3 el Departamento de Estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469547,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/24\/cne-honduras-declara-nasry-asfura-ganador-presidencial-orix\/","url_meta":{"origin":1469561,"position":4},"title":"El Consejo Electoral de Honduras declara a Nasry Asfura ganador de la elecci\u00f3n presidencial; sus rivales dicen que impugnar\u00e1n","author":"","date":"diciembre 24, 2025","format":false,"excerpt":"El Consejo Nacional Electoral de Honduras (CNE) declar\u00f3 este mi\u00e9rcoles a Nasy \u201cTito\u201d Asfura, candidato del conservador Partido Nacional, ganador de la elecci\u00f3n presidencial del 30 de noviembre.D\u00edas antes de las elecciones, Asfura fue respaldado por el presidente de Estados Unidos, Donald Trump.En un mensaje en video, las consejeras Ana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469603,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/12\/27\/cne-declaro-asfura-ganador-elecciones-honduras-escrutinio-especial-trabado-efe\/","url_meta":{"origin":1469561,"position":5},"title":"El CNE ya declar\u00f3 a Asfura ganador de las elecciones presidenciales de Honduras. Pero el escrutinio especial sigue trabado","author":"","date":"diciembre 27, 2025","format":false,"excerpt":"La presidenta del Consejo Nacional Electoral (CNE) de Honduras, Ana Paola Hall, dijo el viernes que, pese las m\u00faltiples dificultades que ha tenido el proceso de las elecciones generales del pasado 30 de noviembre, \u201chabr\u00e1 declaraci\u00f3n en tiempo y forma, tal como la Constituci\u00f3n y la ley indican\u201d.Hasta ahora el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1469561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1469561"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1469561\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1469561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1469561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1469561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}