{"id":1473280,"date":"2026-04-17T11:03:39","date_gmt":"2026-04-17T18:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/"},"modified":"2026-04-17T11:03:39","modified_gmt":"2026-04-17T18:03:39","slug":"buscador-alemania-nazis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/17\/buscador-alemania-nazis-trax\/","title":{"rendered":"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis"},"content":{"rendered":"<p>Un nuevo buscador que permite a los usuarios consultar los registros del partido nazi para averiguar si sus antepasados \u200b\u200bfueron miembros ha recibido millones de visitas desde su lanzamiento a principios de este mes.<\/p>\n<p>Esta enorme base de datos ha sido puesta a disposici\u00f3n por el peri\u00f3dico alem\u00e1n <a href=\"https:\/\/www.zeit.de\/wissen\/2026-04\/nsdap-mitgliederkartei-karteikarten-familienmitglieder-suche\">Die Zeit <\/a>con el objetivo de \u201cromper el silencio nacido de una verg\u00fcenza injustificada\u201d, seg\u00fan un editorial de la publicaci\u00f3n. Funciona en colaboraci\u00f3n con archivos de Alemania y Estados Unidos.<\/p>\n<p>Fundado tras la Primera Guerra Mundial, el partido de Hitler no alcanz\u00f3 gran popularidad sino hasta el colapso econ\u00f3mico de la Gran Depresi\u00f3n. Experiment\u00f3 un fuerte aumento de apoyo durante las elecciones de 1930, y cuando Hitler fue elegido tres a\u00f1os despu\u00e9s, aboli\u00f3 todos los dem\u00e1s partidos, creando un movimiento de masas que controlaba todos los aspectos de la vida alemana.<\/p>\n<p>Una portavoz de Die Zeit declar\u00f3 a CNN que el nuevo sitio web hab\u00eda sido visitado millones de veces y compartido miles de veces.<\/p>\n<p>A finales de la d\u00e9cada de 1930, \u201cla gran mayor\u00eda de los alemanes apoyaba a Hitler y al Estado nazi\u201d, seg\u00fan el Museo Conmemorativo del Holocausto de Estados Unidos. Seg\u00fan Die Zeit, 10,2 millones de alemanes se afiliaron al partido en los 20 a\u00f1os posteriores a 1925, y en su apogeo, al final de la Segunda Guerra Mundial, contaba con aproximadamente 9 millones de miembros.<\/p>\n<p>En los \u00faltimos d\u00edas de la guerra, los nazis intentaron destruir la vasta colecci\u00f3n de carn\u00e9s de afiliaci\u00f3n del partido, pero estos se salvaron en el \u00faltimo momento y posteriormente fueron entregados a los estadounidenses. Estos documentos se almacenaron en el Centro de Documentaci\u00f3n de Berl\u00edn, pero m\u00e1s tarde fueron transferidos al Archivo Federal Alem\u00e1n, con copias tambi\u00e9n en el Archivo Nacional de Estados Unidos, seg\u00fan inform\u00f3 el peri\u00f3dico.<\/p>\n<p>Christian Staas, jefe del departamento de historia de Die Zeit, declar\u00f3 a CNN que la respuesta al motor de b\u00fasqueda hab\u00eda sido abrumadora. Explic\u00f3 que un promedio de 75.000 personas consultan anualmente esta informaci\u00f3n en el Archivo Federal Alem\u00e1n, y cuando el Archivo Nacional de Estados Unidos puso los registros a disposici\u00f3n en l\u00ednea, la demanda fue tan alta que el sitio web se cay\u00f3 temporalmente.<\/p>\n<p>Die Zeit obtuvo acceso a esos registros y, con la ayuda de la IA, desarroll\u00f3 una \u201copci\u00f3n de b\u00fasqueda pr\u00e1ctica\u201d, afirm\u00f3 Staas. \u201cEste nivel de inter\u00e9s parece relativamente reciente, y estoy seguro de que el hecho de que la mayor\u00eda de los antiguos miembros del NSDAP (partido nazi), o las personas involucradas en cr\u00edmenes nazis o cr\u00edmenes de guerra, ya no vivan, facilita que muchas personas se planteen preguntas sobre su propia historia familiar\u201d.<\/p>\n<p>\u201cEn las encuestas de opini\u00f3n, muy pocos alemanes afirman que sus antepasados \u200b\u200bapoyaron el r\u00e9gimen nazi, y muchos creen que sus familias se opusieron a Hitler. Obviamente, eso no puede ser cierto. Quiz\u00e1s nuestro buscador ayude a la gente a obtener una visi\u00f3n m\u00e1s realista del pasado\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Algunos de los que consultaron los registros compartieron sus reacciones con Die Zeit tras comprobar que sus sospechas se hab\u00edan confirmado.<\/p>\n<p>\u201cTengo sentimientos encontrados ahora mismo\u201d, escribi\u00f3 una persona, identificada solo como Katha1927, que sospechaba que sus dos abuelos se hab\u00edan unido al partido. \u201cMe pregunto qu\u00e9 fecha de ingreso me parece peor: \u00bf1931, tan pronto, ya tan convencidos? \u00bfO 1941, a pesar de que ya sab\u00edan tanto?\u201d.<\/p>\n<p>Otra persona, identificada como \u201cchica\u201d, coment\u00f3: \u201cDurante m\u00e1s de 40 a\u00f1os me pregunt\u00e9 si mi bisabuelo hab\u00eda sido miembro. Era ingeniero ferroviario durante la \u00e9poca nazi y siempre se enfurec\u00eda cuando se hablaba de la guerra. \u00a1Misi\u00f3n resuelta! Gracias, ZEIT. Aunque duela much\u00edsimo\u201d.<\/p>\n<p>Una persona identificada como \u201cT\u00eda Horst\u201d dijo que su investigaci\u00f3n familiar siempre se hab\u00eda centrado en una rama jud\u00eda, la cual, seg\u00fan ella, fue \u201cexterminada por el Holocausto\u201d.<\/p>\n<p>La persona que respondi\u00f3 afirm\u00f3 haber descubierto al \u201cesposo \u2018ario\u2019 de una t\u00eda abuela jud\u00eda\u201d, quien se uni\u00f3 al partido nazi en 1933. \u201cSu esposa, de quien probablemente se divorci\u00f3, fue asesinada en mayo de 1942 por los gases de escape de un cami\u00f3n en Kulmhof (campo de exterminio)\u201d, escribi\u00f3.<\/p>\n<p>Christine Schmidt, codirectora de la Biblioteca Wiener del Holocausto en Londres, describi\u00f3 el buscador como una \u201cgran ayuda para la investigaci\u00f3n sobre el per\u00edodo nazi\u201d.<\/p>\n<p>\u201cEn su apogeo, el partido nazi lleg\u00f3 a tener unos 8 millones de miembros\u201d, afirm\u00f3, \u201cy la gente se un\u00eda por diversas razones: desesperaci\u00f3n econ\u00f3mica, el atractivo del nacionalismo y el liderazgo carism\u00e1tico, o por su propio antisemitismo\u201d.<\/p>\n<p>A\u00f1adi\u00f3 que la accesibilidad a los datos del archivo \u201crepresenta un avance significativo en la comprensi\u00f3n nacional e internacional de este periodo y del horror que de \u00e9l se deriv\u00f3\u201d, y que \u201cen una \u00e9poca de creciente desinformaci\u00f3n sobre la historia del Holocausto, esto tambi\u00e9n nos recuerda el poder de la documentaci\u00f3n original y su capacidad probatoria frente a la negaci\u00f3n o la distorsi\u00f3n de los hechos de la \u00e9poca\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo buscador que permite a los usuarios consultar los registros del partido nazi para averiguar si sus antepasados \u200b\u200bfueron miembros ha recibido millones de visitas desde su lanzamiento a principios de este mes. Esta enorme base de datos ha sido puesta a disposici\u00f3n por el peri\u00f3dico alem\u00e1n Die Zeit con el objetivo de \u201cromper [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473280","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un nuevo buscador que permite a los usuarios consultar los registros del partido nazi para averiguar si sus antepasados \u200b\u200bfueron miembros ha recibido millones de visitas desde su lanzamiento a principios de este mes. Esta enorme base de datos ha sido puesta a disposici\u00f3n por el peri\u00f3dico alem\u00e1n Die Zeit con el objetivo de \u201cromper [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T18:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis\",\"datePublished\":\"2026-04-17T18:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/\"},\"wordCount\":901,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/\",\"name\":\"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-17T18:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis - Noticias","og_description":"Un nuevo buscador que permite a los usuarios consultar los registros del partido nazi para averiguar si sus antepasados \u200b\u200bfueron miembros ha recibido millones de visitas desde su lanzamiento a principios de este mes. Esta enorme base de datos ha sido puesta a disposici\u00f3n por el peri\u00f3dico alem\u00e1n Die Zeit con el objetivo de \u201cromper [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-17T18:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/"},"author":{"name":"","@id":""},"headline":"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis","datePublished":"2026-04-17T18:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/"},"wordCount":901,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/","name":"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-17T18:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/17\/buscador-alemania-nazis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/17\/buscador-alemania-nazis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis","url":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/17\/buscador-alemania-nazis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/17\/buscador-alemania-nazis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-17T18:03:39Z","datePublished":"2026-04-17T18:03:39Z","dateModified":"2026-04-17T18:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una nueva base de datos en Alemania permite comprobar si tienes antepasados nazis\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/17\\\/buscador-alemania-nazis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/17\\\/buscador-alemania-nazis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-17T18:03:39Z\",\"datePublished\":\"2026-04-17T18:03:39Z\",\"dateModified\":\"2026-04-17T18:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464274,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/07\/06\/aumentan-llamados-prohibir-partido-ultraderechista-afd-creciente-popularidad-trax\/","url_meta":{"origin":1473280,"position":0},"title":"Aumentan los llamados para prohibir al partido ultraderechista AfD en Alemania, pese a su creciente popularidad","author":"","date":"julio 6, 2025","format":false,"excerpt":"El partido ultraderechista Alternativa para Alemania (AfD) se ha convertido en el principal grupo de oposici\u00f3n del pa\u00eds e incluso encabez\u00f3 varias encuestas de opini\u00f3n, superando brevemente en las semanas posteriores a las elecciones federales de febrero al partido de centroderecha del actual canciller Friedrich Merz.Al mismo tiempo, crecen los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459108,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/02\/23\/resultados-elecciones-alemania-friedrich-merz-conservadores-ultraderecha-trax\/","url_meta":{"origin":1473280,"position":1},"title":"Friedrich Merz reivindica la victoria de los conservadores alemanes y ser\u00eda el pr\u00f3ximo canciller","author":"","date":"febrero 23, 2025","format":false,"excerpt":"La Uni\u00f3n Dem\u00f3crata Cristiana (CDU) de centroderecha de Alemania est\u00e1 lista para volver al poder con la ultraderechista Alternativa para Alemania como segundo partido m\u00e1s grande, seg\u00fan muestran las encuestas de salida, despu\u00e9s de unas elecciones anticipadas dominadas por las preocupaciones sobre la inmigraci\u00f3n, la econom\u00eda y el regreso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468337,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/11\/14\/adn-hitler-documental-revelacion-polemica-trax\/","url_meta":{"origin":1473280,"position":2},"title":"Investigadores dicen que verificaron y secuenciaron el ADN de Hitler. La revelaci\u00f3n es pol\u00e9mica","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Investigadores han analizado una muestra de ADN que se cree perteneci\u00f3 a Adolf Hitler, la cual, seg\u00fan un nuevo documental, revela que el dictador de la Alemania nazi ten\u00eda un marcador gen\u00e9tico para un trastorno raro que puede retrasar la pubertad.La investigaci\u00f3n, que tard\u00f3 m\u00e1s de cuatro a\u00f1os en completarse,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447639,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/04\/02\/alemania-camisetas-futbol-asociacion-nazi-trax\/","url_meta":{"origin":1473280,"position":3},"title":"Alemania redise\u00f1ar\u00e1 los n\u00fameros de las camisetas de la selecci\u00f3n de f\u00fatbol en medio de la pol\u00e9mica por su asociaci\u00f3n con un s\u00edmbolo nazi","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN) -- Las autoridades del f\u00fatbol alem\u00e1n redise\u00f1ar\u00e1n el n\u00famero \"4\" de las camisetas de la selecci\u00f3n del pa\u00eds ante las denuncias de que se asemeja a un logotipo utilizado por unidades paramilitares nazis.La Federaci\u00f3n Alemana de F\u00fatbol (DFB) hizo el anuncio el lunes despu\u00e9s de que usuarios de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459124,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/02\/24\/afd-extrema-derecha-alemania-fuerza-poderosa-trax\/","url_meta":{"origin":1473280,"position":4},"title":"AN\u00c1LISIS | La ultraderecha alemana puede haber quedado fuera del poder, pero la AfD es una fuerza poderosa","author":"","date":"febrero 24, 2025","format":false,"excerpt":"El sistema pol\u00edtico alem\u00e1n est\u00e1 dise\u00f1ado para excluir a los extremistas. Sin embargo, el pa\u00eds est\u00e1 despertando a una nueva realidad pol\u00edtica que se ha inclinado hacia la derecha con el otrora marginado partido Alternativa para Alemania (AfD), ahora firmemente establecido en la pol\u00edtica alemana.Los principales conservadores del pa\u00eds, como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450899,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/07\/05\/espana-alemania-mejores-eurocopa-orix\/","url_meta":{"origin":1473280,"position":5},"title":"\u00bfSon Espa\u00f1a y Alemania los mejores equipos de la Eurocopa? Esto dicen los n\u00fameros","author":"","date":"julio 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Espa\u00f1a hizo el puntaje perfecto en la fase de grupos de la Eurocopa y es hasta ahora el \u00fanico equipo que ha ganado todos los partidos. En cuartos elimin\u00f3 de manera rotunda a Georgia y es la favorita. Alemania, que se ha mostrado como el otro gran\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1473280"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473280\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1473280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1473280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1473280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}