{"id":1473309,"date":"2026-04-18T20:03:50","date_gmt":"2026-04-19T03:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/"},"modified":"2026-04-18T20:03:50","modified_gmt":"2026-04-19T03:03:50","slug":"cuando-guerra-puede-considerarse-justa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/","title":{"rendered":"\u00bfCu\u00e1ndo una guerra puede considerarse &#171;justa&#187;?"},"content":{"rendered":"<p>Un resultado interesante de la extra\u00f1a y, en gran medida, unilateral disputa del presidente Donald Trump con el papa es que existe cierto debate \u2014visto a trav\u00e9s del prisma de la teolog\u00eda cat\u00f3lica\u2014 sobre si la guerra de Estados Unidos e Israel contra Ir\u00e1n constituye una \u201cguerra justa\u201d.<\/p>\n<p>Sin volver a exponer los pormenores de los ataques directos de Trump al papa Le\u00f3n XIV y de la reflexi\u00f3n de Le\u00f3n XIV sobre si Dios escucha las oraciones de quienes hacen la guerra, baste decir que ambos est\u00e1n en desacuerdo.<\/p>\n<p>\u201cMe gusta que el papa sea un defensor de la paz; creo que ese es, sin duda, uno de sus roles\u201d, dijo el vicepresidente J. D. Vance durante una intervenci\u00f3n en un evento de Turning Point USA, en la Universidad de Georgia esta semana.<\/p>\n<p>En lugar de atacar al papa, Vance dijo que le gusta que el papa hable de \u201casuntos relativos a la guerra y la paz\u201d porque \u201ccomo m\u00ednimo, invita a entablar un di\u00e1logo\u201d.<\/p>\n<p>Es una conversaci\u00f3n posterior porque, en lugar de presentar p\u00fablicamente un argumento a favor de la guerra y buscar respaldo internacional, Estados Unidos lanz\u00f3 ataques contra Ir\u00e1n mientras las conversaciones nucleares estaban en curso.<\/p>\n<p>Vance, converso al catolicismo, tiene previsto publicar pr\u00f3ximamente un libro sobre su propio viaje espiritual. Tambi\u00e9n se reuni\u00f3 el a\u00f1o pasado con el papa Le\u00f3n y coment\u00f3 que este le agrada.<\/p>\n<p>Pero \u201c\u00bfc\u00f3mo es posible afirmar que Dios nunca est\u00e1 del lado de quienes empu\u00f1an la espada?\u201d, plante\u00f3 Vance en el evento de la Universidad de Georgia. \u201c\u00bfEstaba Dios del lado de los estadounidenses que liberaron Francia de los nazis? \u00bfEstaba Dios del lado de los estadounidenses que liberaron los campos de exterminio del Holocausto\u2026?\u201d<\/p>\n<p>Vance, interrumpido entre abucheos de un asistente, a\u00f1adi\u00f3 esto:<\/p>\n<p>\u201cCuando el papa dice que Dios nunca est\u00e1 del lado de quienes empu\u00f1an la espada, hay una tradici\u00f3n de m\u00e1s de 1.000 a\u00f1os de la teor\u00eda de la guerra justa, \u00bfde acuerdo? Ahora, por supuesto, podemos discrepar sobre si este o aquel conflicto es justo, pero creo que es importante, de la misma manera que es importante que el vicepresidente de Estados Unidos sea cuidadoso cuando hablo de asuntos de pol\u00edtica p\u00fablica, resulta sumamente importante que el papa sea cuidadoso cuando habla de asuntos de teolog\u00eda\u201d.<\/p>\n<p>Vance ha sido criticado por la \u00faltima parte de esa cita \u2014al pretender decirle a un papa que tenga cuidado con la teolog\u00eda\u2014, pero el comentario requiere su contexto completo.<\/p>\n<p>Tambi\u00e9n vale la pena se\u00f1alar aqu\u00ed que el concepto de la teor\u00eda de la guerra justa ha sufrido muchos cambios en los \u00faltimos 1.000 a\u00f1os, pero se remonta a San Agust\u00edn. El papa Le\u00f3n proviene de la orden agustiniana y probablemente sabe algo al respecto.<\/p>\n<p>Otros republicanos han hecho eco de lo que dijo Vance sobre la teor\u00eda de la guerra justa.<\/p>\n<p>El presidente de la C\u00e1mara de Representantes, Mike Johnson, un cristiano evang\u00e9lico, insinu\u00f3 que la guerra contra Ir\u00e1n es una \u201cguerra justa\u201d.<\/p>\n<p>\u201cEs una cuesti\u00f3n muy bien establecida dentro de la teolog\u00eda cristiana. Existe algo llamado doctrina de la guerra justa\u201d, afirm\u00f3 Johnson. \u201cHay un tiempo para todo prop\u00f3sito bajo el cielo. Creo que lo que reflejan los comentarios del presidente \u2014y los del vicepresidente\u2014 es su comprensi\u00f3n \u2014adquirida en la profundidad de las salas de informaci\u00f3n segura (SCIF) y las sesiones informativas clasificadas\u2014 de lo que est\u00e1 en juego en la situaci\u00f3n que enfrentamos\u201d, asegur\u00f3 Johnson.<\/p>\n<p>La Conferencia de Obispos Cat\u00f3licos de Estados Unidos tiene una visi\u00f3n diferente sobre si la guerra es justa, y emiti\u00f3 una aclaraci\u00f3n de los comentarios del papa Le\u00f3n el mi\u00e9rcoles.<\/p>\n<p>\u201cDurante m\u00e1s de 1.000 a\u00f1os, la Iglesia cat\u00f3lica ha ense\u00f1ado la teor\u00eda de la guerra justa, y es esa larga tradici\u00f3n a la que el Santo Padre hace referencia cuidadosamente en sus comentarios sobre la guerra\u201d, seg\u00fan la declaraci\u00f3n de los obispos.<\/p>\n<p>Los obispos a\u00f1adieron:<\/p>\n<p>\u201cUn principio constante de esa tradici\u00f3n de 1.000 a\u00f1os es que una naci\u00f3n solo puede leg\u00edtimamente tomar la espada \u2018en defensa propia, una vez que todos los esfuerzos de paz han fracasado\u2019\u2026 Es decir, para ser una guerra justa, debe ser una defensa contra otro que activamente libra la guerra, que es lo que el Santo Padre realmente dijo: \u2018\u00c9l no escucha las oraciones de quienes libran la guerra\u2019\u201d.<\/p>\n<p>El Gobierno de Trump se ha empe\u00f1ado en distanciar a las Fuerzas Armadas de Estados Unidos del concepto de \u201cdefensa\u201d. Ha a\u00f1adido \u201cDepartamento de Guerra\u201d como nombre secundario del Pent\u00e1gono, cambiando letreros y tarjetas de presentaci\u00f3n para reforzar el concepto de \u201chacer la guerra\u201d.<\/p>\n<p>Trump y el secretario de Defensa, Pete Hegseth, quien usa el t\u00edtulo secundario de secretario de Guerra, dijeron que hicieron el cambio para evocar una \u00e9poca en la que Estados Unidos ganaba guerras.<\/p>\n<p>As\u00ed que hay algo definitivamente ofensivo \u2014en el sentido opuesto a defensivo\u2014 en la forma en que han utilizado a las Fuerzas Armadas de EE.UU.<\/p>\n<p>El corresponsal de CNN en el Vaticano, Christopher Lamb, escribi\u00f3 sobre c\u00f3mo Le\u00f3n XIV, el primer papa estadounidense, se ha vuelto cada vez m\u00e1s expl\u00edcito sobre los peligros de la guerra.<\/p>\n<p>Se\u00f1al\u00f3 que el Vaticano ha indicado que un principio clave de la teor\u00eda de la guerra justa es la idea de \u201cproporcionalidad\u201d: que la destrucci\u00f3n causada por la acci\u00f3n militar no supere el bien que se pretende lograr.<\/p>\n<p>El cardenal Blase Cupich, arzobispo de Chicago, <a href=\"https:\/\/www.cnn.com\/audio\/podcasts\/amanpour\/episodes\/98b890d8-b53e-11f0-9a89-2361cd8dc524\">dijo a Christiane Amanpour,<\/a> de CNN, que fue un poco impactante o\u00edr a Vance equiparar la participaci\u00f3n de Estados Unidos en la Segunda Guerra Mundial con la guerra de Estados Unidos e Israel con Ir\u00e1n, que, seg\u00fan dijo, es una \u201cguerra elegida\u201d.<\/p>\n<p>Cuando Amanpour pregunt\u00f3 si la guerra contra Ir\u00e1n es una \u201cguerra justa\u201d, Cupich dijo: \u201cNo, no es justa\u201d.<\/p>\n<p>La Conferencia de Obispos Cat\u00f3licos de Estados Unidos incluy\u00f3 extractos del catecismo de la iglesia Cat\u00f3lica sobre \u201csalvaguardar la paz\u201d en su comunicado. Los extractos establecen cuatro condiciones para la \u201cdefensa leg\u00edtima mediante la fuerza militar\u201d bajo la \u201cdoctrina de la guerra justa\u201d.<\/p>\n<p>Incluyen:<\/p>\n<ul>\n<li>El da\u00f1o infligido por el agresor a la naci\u00f3n o a la comunidad de naciones sea duradero, grave y cierto;<\/li>\n<li>Todos los dem\u00e1s medios para poner fin a dicho da\u00f1o hayan resultado impracticables o ineficaces;<\/li>\n<li>Debe haber perspectivas serias de \u00e9xito;<\/li>\n<li>El uso de las armas no debe producir males y des\u00f3rdenes m\u00e1s graves que el mal que se pretende eliminar. El poder de los medios modernos de destrucci\u00f3n pesa muy fuertemente al evaluar esta condici\u00f3n.<\/li>\n<\/ul>\n<p>Cupich hizo referencia a esas condiciones cuando dijo que las armas modernas afectan a las sociedades y ponen en peligro a los civiles de formas horribles. Y sostuvo que el Gobierno de Trump no ha sido claro sobre su objetivo final.<\/p>\n<p>\u201cHemos escuchado tantos comentarios sobre esta guerra en particular en los que el objetivo no est\u00e1 claramente definido, porque salta de un tema a otro\u201d, dijo Cupich.<\/p>\n<p>La raz\u00f3n m\u00e1s mencionada para la guerra por parte del Gobierno de Trump es que era para impedir que Ir\u00e1n obtuviera armas nucleares. Ir\u00e1n afirm\u00f3 que su programa nuclear era pac\u00edfico y estaba destinado a la generaci\u00f3n de energ\u00eda nuclear.<\/p>\n<p>Para otra visi\u00f3n reflexiva de lo que constituye una \u201cguerra justa\u201d, echa un vistazo al discurso que el entonces presidente Barack Obama dio en Oslo, Noruega, al recibir el premio Nobel de la Paz en el primer a\u00f1o de su presidencia.<\/p>\n<p>Obama expuso la importancia del orden mundial y las leyes de la guerra, conceptos que Trump y Hegseth han rechazado en general. Hegseth, por ejemplo, se jacta de tirar por la borda las reglas de enfrentamiento para combatir guerras de manera m\u00e1s eficaz. Trump se ha quejado repetidamente de las Naciones Unidas y ha amenazado con retirar a Estados Unidos de la OTAN.<\/p>\n<p>Obama tambi\u00e9n dijo que la religi\u00f3n deber\u00eda quedar fuera de la guerra, adoptando un tono muy distinto del Hegseth, que cita la Biblia, que tiene tatuado en su cuerpo un s\u00edmbolo vinculado a las Cruzadas.<\/p>\n<p>Obama tambi\u00e9n se\u00f1al\u00f3 lo parad\u00f3jico que resultaba recibir ese premio como comandante en jefe de las Fuerzas Armadas de EE.UU. en un momento en que el pa\u00eds estaba sumido en guerras en Iraq y Afganist\u00e1n. La incongruencia solo se volver\u00eda m\u00e1s inc\u00f3moda a medida que Obama utiliz\u00f3 con frecuencia a las Fuerzas Armadas de Estados Unidos mientras estuvo en el cargo y utiliz\u00f3 drones para matar a personas, sin, seg\u00fan los cr\u00edticos, el debido proceso. Al mismo tiempo, en lugar de librar una guerra contra Ir\u00e1n, alcanz\u00f3 un acuerdo para contener su programa nuclear.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un resultado interesante de la extra\u00f1a y, en gran medida, unilateral disputa del presidente Donald Trump con el papa es que existe cierto debate \u2014visto a trav\u00e9s del prisma de la teolog\u00eda cat\u00f3lica\u2014 sobre si la guerra de Estados Unidos e Israel contra Ir\u00e1n constituye una \u201cguerra justa\u201d. Sin volver a exponer los pormenores de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473309","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1ndo una guerra puede considerarse &quot;justa&quot;? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1ndo una guerra puede considerarse &quot;justa&quot;? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un resultado interesante de la extra\u00f1a y, en gran medida, unilateral disputa del presidente Donald Trump con el papa es que existe cierto debate \u2014visto a trav\u00e9s del prisma de la teolog\u00eda cat\u00f3lica\u2014 sobre si la guerra de Estados Unidos e Israel contra Ir\u00e1n constituye una \u201cguerra justa\u201d. Sin volver a exponer los pormenores de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-19T03:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfCu\u00e1ndo una guerra puede considerarse &#171;justa&#187;?\",\"datePublished\":\"2026-04-19T03:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/\"},\"wordCount\":1551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/\",\"name\":\"\u00bfCu\u00e1ndo una guerra puede considerarse \\\"justa\\\"? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-19T03:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1ndo una guerra puede considerarse &#171;justa&#187;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1ndo una guerra puede considerarse \"justa\"? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1ndo una guerra puede considerarse \"justa\"? - Noticias","og_description":"Un resultado interesante de la extra\u00f1a y, en gran medida, unilateral disputa del presidente Donald Trump con el papa es que existe cierto debate \u2014visto a trav\u00e9s del prisma de la teolog\u00eda cat\u00f3lica\u2014 sobre si la guerra de Estados Unidos e Israel contra Ir\u00e1n constituye una \u201cguerra justa\u201d. Sin volver a exponer los pormenores de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-19T03:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfCu\u00e1ndo una guerra puede considerarse &#171;justa&#187;?","datePublished":"2026-04-19T03:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/"},"wordCount":1551,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/","name":"\u00bfCu\u00e1ndo una guerra puede considerarse \"justa\"? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-19T03:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1ndo una guerra puede considerarse &#171;justa&#187;?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfCu\u00e1ndo una guerra puede considerarse &#171;justa&#187;?","url":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/18\/cuando-guerra-puede-considerarse-justa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-19T03:03:50Z","datePublished":"2026-04-19T03:03:50Z","dateModified":"2026-04-19T03:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfCu\\u00e1ndo una guerra puede considerarse &#171;justa&#187;?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/18\\\/cuando-guerra-puede-considerarse-justa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/18\\\/cuando-guerra-puede-considerarse-justa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-19T03:03:50Z\",\"datePublished\":\"2026-04-19T03:03:50Z\",\"dateModified\":\"2026-04-19T03:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473267,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/17\/primer-papa-estadounidense-administracion-trump-trax\/","url_meta":{"origin":1473309,"position":0},"title":"C\u00f3mo el primer papa estadounidense est\u00e1 recuperando los valores cristianos frente a las cr\u00edticas de la administraci\u00f3n Trump","author":"","date":"abril 17, 2026","format":false,"excerpt":"Al volar a Argelia el lunes para dar inicio a su hist\u00f3rica gira por \u00c1frica, el papa Le\u00f3n XIV ten\u00eda que tomar una decisi\u00f3n. Pod\u00eda ignorar la extraordinaria diatriba que Donald Trump le lanz\u00f3 en las redes sociales durante la noche, o pod\u00eda enfrentarla directamente.Finalmente, opt\u00f3 por la segunda opci\u00f3n,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473093,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/13\/papa-leon-xiv-miedo-trump-guerra-trax\/","url_meta":{"origin":1473309,"position":1},"title":"El papa dice que &#171;no tiene miedo de la administraci\u00f3n Trump&#187; tras las cr\u00edticas del presidente a su posici\u00f3n sobre la guerra","author":"","date":"abril 13, 2026","format":false,"excerpt":"El papa Le\u00f3n XIV rechaz\u00f3 con firmeza este lunes las cr\u00edticas del presidente de Estados Unidos, Donald Trump, y defendi\u00f3 su postura de buscar la paz y rechazar la violencia en medio de la guerra con Ir\u00e1n.\u201cNo tengo miedo de la administraci\u00f3n Trump ni de hablar en voz alta del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472867,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/04\/nombre-dios-papa-leon-xiv-opone-justificacion-guerra-trax\/","url_meta":{"origin":1473309,"position":2},"title":"No en nombre de Dios: c\u00f3mo el papa Le\u00f3n XIV se opone a la justificaci\u00f3n divina de la guerra","author":"","date":"abril 4, 2026","format":false,"excerpt":"El martes por la noche, en un ventoso Castel Gandolfo, le hice una pregunta al papa Le\u00f3n XIV. Con la guerra potencialmente escalando en Medio Oriente, quer\u00eda saber si ten\u00eda un mensaje para el presidente Donald Trump y otros l\u00edderes de Estados Unidos e Israel.Su respuesta fue reveladora. El primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473240,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/16\/papa-leon-xiv-advierte-tiranos-tras-criticas-trump-trax\/","url_meta":{"origin":1473309,"position":3},"title":"El papa Le\u00f3n XIV advierte sobre un mundo devastado por &#171;tiranos&#187; tras las cr\u00edticas de Trump","author":"","date":"abril 16, 2026","format":false,"excerpt":"El papa Le\u00f3n XIV advirti\u00f3 que el mundo est\u00e1 siendo asolado por \u201ctiranos\u201d en unas contundentes declaraciones realizadas despu\u00e9s de que el presidente Donald Trump atacara al pont\u00edfice por su postura sobre la guerra con Ir\u00e1n.Le\u00f3n XIV se ha convertido en un firme cr\u00edtico del conflicto y, en su discurso,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466583,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/09\/18\/papa-leon-xiv-entrevista-preocupado-ee-uu-trax\/","url_meta":{"origin":1473309,"position":4},"title":"En su primera gran entrevista, el papa Le\u00f3n XIV dice que est\u00e1 preocupado por &#171;algunas de las cosas&#187; que suceden en EE.UU.","author":"","date":"septiembre 18, 2025","format":false,"excerpt":"El papa Le\u00f3n XIV expres\u00f3 su preocupaci\u00f3n por \u201calgunas cosas\u201d que est\u00e1n sucediendo en Estados Unidos y revel\u00f3 que rechaz\u00f3 el plan para hacer una versi\u00f3n de s\u00ed mismo basada en IA, en su primera gran entrevista desde su elecci\u00f3n.El primer papa estadounidense destac\u00f3 la importancia de una carta que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472876,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/05\/papa-leon-xiv-misa-pascua-domingo-trax\/","url_meta":{"origin":1473309,"position":5},"title":"El papa Le\u00f3n XIV se centra en mantener la esperanza en medio de la guerra y el sufrimiento en su primera Misa de Pascua","author":"","date":"abril 5, 2026","format":false,"excerpt":"El papa Le\u00f3n XIV se centr\u00f3 en mantener la esperanza en medio de la violencia de la guerra, el cambio clim\u00e1tico y otros sufrimientos, en su primera homil\u00eda de Pascua desde que se convirti\u00f3 el a\u00f1o pasado en el l\u00edder de la Iglesia cat\u00f3lica.El papa Le\u00f3n, al hablar durante la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1473309"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473309\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1473309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1473309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1473309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}