{"id":1473325,"date":"2026-04-20T02:03:50","date_gmt":"2026-04-20T09:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/"},"modified":"2026-04-20T02:03:50","modified_gmt":"2026-04-20T09:03:50","slug":"sismo-costa-japon-alerta-tsunami-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/","title":{"rendered":"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami"},"content":{"rendered":"<p>Se emiti\u00f3 una alerta de tsunami de tres metros para Jap\u00f3n despu\u00e9s de que un fuerte sismo de magnitud 7,5 sacudiera la costa nororiental, seg\u00fan la Agencia Meteorol\u00f3gica de Jap\u00f3n.<\/p>\n<p>La agencia meteorol\u00f3gica nacional emiti\u00f3 una alerta de tsunami de tres metros para la prefectura de Iwate y partes de Hokkaido y Aomori. En otras zonas del noreste de Jap\u00f3n, emiti\u00f3 un aviso, estimando un tsunami de 1 metro.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se emiti\u00f3 una alerta de tsunami de tres metros para Jap\u00f3n despu\u00e9s de que un fuerte sismo de magnitud 7,5 sacudiera la costa nororiental, seg\u00fan la Agencia Meteorol\u00f3gica de Jap\u00f3n. La agencia meteorol\u00f3gica nacional emiti\u00f3 una alerta de tsunami de tres metros para la prefectura de Iwate y partes de Hokkaido y Aomori. En otras [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473325","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se emiti\u00f3 una alerta de tsunami de tres metros para Jap\u00f3n despu\u00e9s de que un fuerte sismo de magnitud 7,5 sacudiera la costa nororiental, seg\u00fan la Agencia Meteorol\u00f3gica de Jap\u00f3n. La agencia meteorol\u00f3gica nacional emiti\u00f3 una alerta de tsunami de tres metros para la prefectura de Iwate y partes de Hokkaido y Aomori. En otras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T09:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami\",\"datePublished\":\"2026-04-20T09:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/\"},\"wordCount\":105,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/\",\"name\":\"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-20T09:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami - Noticias","og_description":"Se emiti\u00f3 una alerta de tsunami de tres metros para Jap\u00f3n despu\u00e9s de que un fuerte sismo de magnitud 7,5 sacudiera la costa nororiental, seg\u00fan la Agencia Meteorol\u00f3gica de Jap\u00f3n. La agencia meteorol\u00f3gica nacional emiti\u00f3 una alerta de tsunami de tres metros para la prefectura de Iwate y partes de Hokkaido y Aomori. En otras [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-20T09:03:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/"},"author":{"name":"","@id":""},"headline":"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami","datePublished":"2026-04-20T09:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/"},"wordCount":105,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/","name":"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-20T09:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un fuerte sismo sacude la costa de Jap\u00f3n; se emite una alerta de tsunami","url":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/20\/sismo-costa-japon-alerta-tsunami-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-20T09:03:50Z","datePublished":"2026-04-20T09:03:50Z","dateModified":"2026-04-20T09:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un fuerte sismo sacude la costa de Jap\\u00f3n; se emite una alerta de tsunami\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/20\\\/sismo-costa-japon-alerta-tsunami-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/20\\\/sismo-costa-japon-alerta-tsunami-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-20T09:03:50Z\",\"datePublished\":\"2026-04-20T09:03:50Z\",\"dateModified\":\"2026-04-20T09:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457476,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/01\/13\/alerta-tsunami-sismo-japon-trax\/","url_meta":{"origin":1473325,"position":0},"title":"Emiten alerta de tsunami en Jap\u00f3n tras un sismo de magnitud 6,9 que sacudi\u00f3 el suroeste","author":"","date":"enero 13, 2025","format":false,"excerpt":"La Agencia Meteorol\u00f3gica de Jap\u00f3n emiti\u00f3 una alerta de tsunami tras un sismo de magnitud 6,9 frente a las costas del suroeste del pa\u00eds.El sismo se produjo poco despu\u00e9s de las 09:19 p.m. hora local (7:19 a.m. hora de Miami), seg\u00fan la agencia, que emiti\u00f3 una alerta para la provincia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447665,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/04\/02\/sismo-de-magnitud-75-sacude-taiwan-cerca-de-la-ciudad-de-hualien-reporta-usgs\/","url_meta":{"origin":1473325,"position":1},"title":"Sismo de magnitud 7,4 sacude la costa este de Taiw\u00e1n, reporta USGS: hay alerta de tsunami","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN) \u2013\u2013\u00a0 Un fuerte sismo de magnitud 7,4 sacudi\u00f3 la costa este de Taiw\u00e1n en la ma\u00f1ana de este mi\u00e9rcoles, hora local, report\u00f3 el Servicio Geol\u00f3gico de Estados Unidos (USGS, por sus siglas en ingl\u00e9s).El sismo tuvo una profundidad de 34,8 kil\u00f3metros, seg\u00fan la entidad. Su epicentro se ubic\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464960,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/07\/29\/alertas-tsunami-terremoto-costa-oriental-rusia-trax\/","url_meta":{"origin":1473325,"position":2},"title":"Activan alertas de tsunami para partes de Rusia y Jap\u00f3n tras un fuerte sismo","author":"","date":"julio 29, 2025","format":false,"excerpt":"Se emitieron alertas de tsunami para partes de Rusia y Jap\u00f3n tras un enorme terremoto de magnitud 8,7 que sacudi\u00f3 el mi\u00e9rcoles la remota y escasamente poblada costa oriental de Rusia.El sismo ocurri\u00f3 a unos 136 kil\u00f3metros de Petropavlovsk-Kamchatsky, Rusia, a una profundidad de 19 kil\u00f3metros, de acuerdo con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442995,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/01\/un-terremoto-de-magnitud-75-sacude-el-oeste-de-japon-y-genera-alerta-de-tsunami\/","url_meta":{"origin":1473325,"position":3},"title":"Un terremoto de magnitud 7,5 sacude el oeste de Jap\u00f3n y genera alerta de tsunami","author":"","date":"enero 1, 2024","format":false,"excerpt":"(CNN) --\u00a0 Un terremoto de magnitud 7,5 sacudi\u00f3 el oeste de Jap\u00f3n este lunes por la tarde, lo que provoc\u00f3 una alerta de tsunami, seg\u00fan el Servicio Geol\u00f3gico de Estados Unidos y la Agencia Meteorol\u00f3gica de Jap\u00f3n.El terremoto, que tuvo una profundidad de 10 kil\u00f3metros, se produjo a las 4:10\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443001,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/01\/sismo-en-japon-en-vivo-noticias-replicas-alerta-de-tsunami-y-mas-2\/","url_meta":{"origin":1473325,"position":4},"title":"Sismo en Jap\u00f3n en vivo: noticias, r\u00e9plicas, alerta de tsunami y m\u00e1s","author":"","date":"enero 1, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edTV screens in Osaka show news of a large earthquake hitting a wide area on the Sea of Japan coast in central Japan and subsequent tsunami warnings in the affected regions on Jan. 1, 2024. (Photo by Kyodo News via Getty\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443006,"url":"https:\/\/noticiasya.com\/las-vegas\/2024\/01\/01\/sismo-en-japon-en-vivo-noticias-replicas-alerta-de-tsunami-y-mas-3\/","url_meta":{"origin":1473325,"position":5},"title":"Sismo en Jap\u00f3n en vivo: noticias, r\u00e9plicas, alerta de tsunami y m\u00e1s","author":"","date":"enero 1, 2024","format":false,"excerpt":"\ud83d\udd04 Para ver las actualizaciones m\u00e1s recientes haz clic aqu\u00edTV screens in Osaka show news of a large earthquake hitting a wide area on the Sea of Japan coast in central Japan and subsequent tsunami warnings in the affected regions on Jan. 1, 2024. (Photo by Kyodo News via Getty\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1473325"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473325\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1473325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1473325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1473325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}