{"id":1473340,"date":"2026-04-20T13:03:44","date_gmt":"2026-04-20T20:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/"},"modified":"2026-04-20T13:03:44","modified_gmt":"2026-04-20T20:03:44","slug":"teotihuacan-balacera-muertos-heridos-mexico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/","title":{"rendered":"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n"},"content":{"rendered":"<p>Una balacera en las pir\u00e1mides de Teotihuac\u00e1n dej\u00f3 al menos una persona muerta y varias m\u00e1s heridas, inform\u00f3 este lunes el gabinete de seguridad de M\u00e9xico.<\/p>\n<p>Un hombre abri\u00f3 fuego en el popular sitio arqueol\u00f3gico, matando a una mujer canadiense, antes de quitarse la vida, <a href=\"https:\/\/x.com\/GabSeguridadMX\">se\u00f1al\u00f3 el gabinete en su cuenta de X<\/a>. Un n\u00famero a\u00fan no especificado de personas result\u00f3 herido y est\u00e1 recibiendo atenci\u00f3n m\u00e9dica.<\/p>\n<p>CNN se puso en contacto con el Ministerio de Relaciones Exteriores de Canad\u00e1 para solicitar comentarios.<\/p>\n<p>Las autoridades informaron que aseguraron un arma de fuego, un arma blanca y cartuchos \u00fatiles en el lugar.<\/p>\n<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo que autoridades federales, estatales y locales est\u00e1n atendiendo el caso.<\/p>\n<p>\u201cLo ocurrido hoy en Teotihuac\u00e1n nos duele profundamente. Expreso mi m\u00e1s sincera solidaridad con las personas afectadas y sus familias. Estamos en contacto con la embajada de Canad\u00e1\u201d, se\u00f1al\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una balacera en las pir\u00e1mides de Teotihuac\u00e1n dej\u00f3 al menos una persona muerta y varias m\u00e1s heridas, inform\u00f3 este lunes el gabinete de seguridad de M\u00e9xico. Un hombre abri\u00f3 fuego en el popular sitio arqueol\u00f3gico, matando a una mujer canadiense, antes de quitarse la vida, se\u00f1al\u00f3 el gabinete en su cuenta de X. Un n\u00famero [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473340","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una balacera en las pir\u00e1mides de Teotihuac\u00e1n dej\u00f3 al menos una persona muerta y varias m\u00e1s heridas, inform\u00f3 este lunes el gabinete de seguridad de M\u00e9xico. Un hombre abri\u00f3 fuego en el popular sitio arqueol\u00f3gico, matando a una mujer canadiense, antes de quitarse la vida, se\u00f1al\u00f3 el gabinete en su cuenta de X. Un n\u00famero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-20T20:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n\",\"datePublished\":\"2026-04-20T20:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/\"},\"wordCount\":197,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/\",\"name\":\"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-20T20:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n - Noticias","og_description":"Una balacera en las pir\u00e1mides de Teotihuac\u00e1n dej\u00f3 al menos una persona muerta y varias m\u00e1s heridas, inform\u00f3 este lunes el gabinete de seguridad de M\u00e9xico. Un hombre abri\u00f3 fuego en el popular sitio arqueol\u00f3gico, matando a una mujer canadiense, antes de quitarse la vida, se\u00f1al\u00f3 el gabinete en su cuenta de X. Un n\u00famero [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-20T20:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/"},"author":{"name":"","@id":""},"headline":"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n","datePublished":"2026-04-20T20:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/"},"wordCount":197,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/","name":"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-20T20:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n","url":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-20T20:03:44Z","datePublished":"2026-04-20T20:03:44Z","dateModified":"2026-04-20T20:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\\u00e1mides de Teotihuac\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/20\\\/teotihuacan-balacera-muertos-heridos-mexico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/20\\\/teotihuacan-balacera-muertos-heridos-mexico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-20T20:03:44Z\",\"datePublished\":\"2026-04-20T20:03:44Z\",\"dateModified\":\"2026-04-20T20:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473361,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/21\/teotihuacan-tiroteo-que-paso-ataque-trax\/","url_meta":{"origin":1473340,"position":0},"title":"Tiroteo en Teotihuac\u00e1n: qu\u00e9 pas\u00f3 en el ataque que dej\u00f3 una turista muerta y varios heridos","author":"","date":"abril 21, 2026","format":false,"excerpt":"Una mujer canadiense muri\u00f3 y seis turistas estadounidenses est\u00e1n entre m\u00e1s de una docena de personas heridas despu\u00e9s de que un hombre armado abri\u00f3 fuego este lunes cerca de las pir\u00e1mides de Teotihuac\u00e1n, en M\u00e9xico, dijeron autoridades.Seg\u00fan informaci\u00f3n preliminar, un hombre dispar\u00f3 en el popular sitio arqueol\u00f3gico, mat\u00f3 a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462730,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/05\/23\/heridos-accidente-globo-aerostatico-teotihuacan-mexico-orix\/","url_meta":{"origin":1473340,"position":1},"title":"Al menos 12 heridos en accidente de globo aerost\u00e1tico cerca Teotihuac\u00e1n, un popular sitio tur\u00edstico en M\u00e9xico","author":"","date":"mayo 23, 2025","format":false,"excerpt":"Al menos doce personas resultaron heridas en un accidente de globo aerost\u00e1tico cerca de un sitio arqueol\u00f3gico pr\u00f3ximo en la Ciudad de M\u00e9xico el viernes, informaron las autoridades locales.El globo realiz\u00f3 un \u201caterrizaje forzado\u201d en San Mart\u00edn de las Pir\u00e1mides tras chocar con una burbuja de aire, seg\u00fan un comunicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473376,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/21\/victimas-tiroteo-teotihuacan-esto-sabemos-orix\/","url_meta":{"origin":1473340,"position":2},"title":"Una mujer fallecida y 13 personas heridas: lo que sabemos de las v\u00edctimas del tiroteo en Teotihuac\u00e1n","author":"","date":"abril 21, 2026","format":false,"excerpt":"Trece son las personas extranjeras que resultaron heridas en diversos grados durante el ataque con arma de fuego ocurrido en la ma\u00f1ana del lunes en la concurrida zona arqueol\u00f3gica de Teotihuac\u00e1n, en el Estado de M\u00e9xico. Se trata de tres ciudadanos colombianos \u2014entre ellos, un menor\u2014, seis estadounidenses, un hombre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473395,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/","url_meta":{"origin":1473340,"position":3},"title":"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad","author":"","date":"abril 22, 2026","format":false,"excerpt":"\u201c\u00bfC\u00f3mo es que entra con un arma? Es la pregunta que se hacen todos\u201d, reconoci\u00f3 este martes la presidenta de M\u00e9xico, Claudia Sheinbaum, al hablar del agresor del tiroteo ocurrido el lunes en la zona arqueol\u00f3gica de Teotihuac\u00e1n, Estado de M\u00e9xico, donde murieron una turista canadiense y el propio atacante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473380,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/21\/julio-cesar-jasso-ramirez-atacante-teotihuacan-orix\/","url_meta":{"origin":1473340,"position":4},"title":"Plane\u00f3 con tiempo el ataque en Teotihuac\u00e1n, se arm\u00f3 y actu\u00f3 &#171;de manera solitaria&#187;: esto sabemos de Julio C\u00e9sar Jasso Ram\u00edrez","author":"","date":"abril 21, 2026","format":false,"excerpt":"Un tiroteo el lunes en la zona arqueol\u00f3gica de Teotihuac\u00e1n, ubicada en el Estado de M\u00e9xico, en el centro del pa\u00eds, dej\u00f3 como saldo una turista canadiense fallecida y 13 extranjeros m\u00e1s lesionados, seg\u00fan informaron las autoridades mexicanas.La Fiscal\u00eda del Estado de M\u00e9xico identific\u00f3 al atacante como Julio C\u00e9sar Jasso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461122,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/04\/12\/altar-cuerpos-antigua-ciudad-maya-teotihuacan-trax\/","url_meta":{"origin":1473340,"position":5},"title":"Un misterioso altar con cuerpos hallado en una antigua ciudad maya revelar\u00eda fuerte influencia de la cultura teotihuacana","author":"","date":"abril 12, 2025","format":false,"excerpt":"Arque\u00f3logos que trabajan en una antigua ciudad maya desenterraron un misterioso altar de 1.700 a\u00f1os de antig\u00fcedad cuyas brillantes decoraciones y siniestros contenidos pueden contener la clave para desentra\u00f1ar la compleja geopol\u00edtica de la \u00e9poca.A pesar de encontrar el altar en Tikal, una ciudad maya en ruinas situada en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1473340"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473340\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1473340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1473340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1473340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}