{"id":1473357,"date":"2026-04-21T05:03:40","date_gmt":"2026-04-21T12:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/"},"modified":"2026-04-21T05:03:40","modified_gmt":"2026-04-21T12:03:40","slug":"dentro-audicion-blanche-secretario-justicia-ee-uu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","title":{"rendered":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU."},"content":{"rendered":"<p>El secretario interino de Justicia de EE.UU. Todd Blanche viaj\u00f3 a Florida el lunes, donde se reuni\u00f3 con el nuevo fiscal designado para encargarse de uno de los casos m\u00e1s importantes para el presidente Donald Trump: la investigaci\u00f3n sobre el exdirector de la CIA y cr\u00edtico de Trump, <a href=\"https:\/\/www.cnn.com\/2026\/04\/17\/politics\/prosecutor-running-john-brennan-investigation-removed\">John Brennan.<\/a><\/p>\n<p>La reuni\u00f3n se produce en un momento en que Blanche lucha por demostrar que es el hombre id\u00f3neo para cumplir con la mayor prioridad de Trump: enjuiciar a los adversarios pol\u00edticos del presidente.<\/p>\n<p>A menos de dos semanas de haber asumido el cargo, Blanche ha tomado medidas p\u00fablicas para cumplir con la agenda de Trump.<\/p>\n<p>Ha realizado cambios en el equipo que investiga a Brennan, public\u00f3 un informe muy esperado sobre las protestas antiaborto y supervis\u00f3 un esfuerzo para anular las condenas de miembros de los Proud Boys y los Oath Keepers involucrados en el ataque del 6 de enero de 2021 contra el Capitolio de Estados Unidos.<\/p>\n<p>Hasta el momento, Trump ha elogiado el trabajo de Blanche como secretario de Justicia interino y, seg\u00fan funcionarios actuales y anteriores de la administraci\u00f3n que hablaron con CNN, el puesto parece estar en sus manos.<\/p>\n<p>Sin embargo, de acuerdo con las fuentes, Blanche a\u00fan debe lidiar con muchos de los obst\u00e1culos que aquejaron el mandato de la exsecretaria Pam Bondi antes de su reciente destituci\u00f3n.<\/p>\n<p>Al igual que Bondi, debe hacer frente a la baja moral entre los fiscales y a la persistente controversia en torno a la publicaci\u00f3n de los archivos de Jeffrey Epstein.<\/p>\n<p>Los sonados procesos judiciales contra los adversarios pol\u00edticos de Trump deben sobrevivir a los jueces y jurados investigadores que hasta ahora han rechazado muchos de los intentos.<\/p>\n<p>Y no est\u00e1 garantizada la colaboraci\u00f3n de los fiscales de carrera encargados de las investigaciones.<\/p>\n<p>\u201cHay muchos fiscales que se oponen a la agenda del presidente y no est\u00e1n interesados \u200b\u200ben llevar los casos que son importantes para la Casa Blanca\u201d, declar\u00f3 recientemente a CNN Harmeet Dhillon, jefa de la Divisi\u00f3n de Derechos Civiles.<\/p>\n<p>Blanche tendr\u00e1 que afrontar estos desaf\u00edos mientras otros altos funcionarios del Departamento de Justicia intentan demostrar su capacidad para llevar a cabo la agenda de Trump si \u00e9l no puede.<\/p>\n<p>Mientras se encontraba en Florida para participar en un evento legal el lunes, Blanche se reuni\u00f3 con Jason Reding Qui\u00f1ones, fiscal federal del distrito sur de Florida; el funcionario de justicia Christopher-James DeLorenz; y el reci\u00e9n nombrado asesor del secretario de Justicia, Joseph diGenova, seg\u00fan un funcionario del Departamento de Justicia.<\/p>\n<p>A\u00fan no se ha informado sobre la reuni\u00f3n.<\/p>\n<p>DiGenova trabajar\u00e1 ahora en la investigaci\u00f3n sobre Brennan, que se centra en una de las quejas pol\u00edticas m\u00e1s antiguas del presidente: la evaluaci\u00f3n de inteligencia de 2017 que concluy\u00f3 que Rusia interfiri\u00f3 en las elecciones presidenciales de 2016 para ayudarlo.<\/p>\n<p>Para Trump, los procesos judiciales como el de Brennan \u2014y la insistencia en las acusaciones desacreditadas de un supuesto fraude electoral en 2020\u2014 son su m\u00e1xima prioridad.<\/p>\n<p>Anteriormente, se quej\u00f3 directamente ante funcionarios del Departamento de Justicia de que no estaba satisfecho con la lentitud del proceso.<\/p>\n<p>Algunos procesos judiciales que avanzaron r\u00e1pidamente se desmoronaron. En noviembre, un juez federal desestim\u00f3 los cargos contra la fiscal general de Nueva York, Letitia James, y el exdirector del FBI, James Comey.<\/p>\n<p>El Departamento de Justicia intent\u00f3 en repetidas ocasiones volver a acusar a James, pero no logr\u00f3 convencer a un jurado investigador para que presentara cargos.<\/p>\n<p>En febrero, <a href=\"https:\/\/www.cnn.com\/2026\/02\/10\/politics\/jury-declines-to-indict-lawmakers-illegal-orders-video\">otro jurado investigador desestim\u00f3<\/a> los cargos penales contra seis legisladores dem\u00f3cratas que publicaron un video instando a los miembros de las fuerzas armadas a desafiar las \u00f3rdenes ilegales de la administraci\u00f3n Trump.<\/p>\n<p>La tarea de llevar a cabo la agenda de Trump pas\u00f3 factura a Bondi, <a href=\"https:\/\/www.cnn.com\/2026\/04\/04\/politics\/how-pam-bondi-lost-her-job\">quien, seg\u00fan fuentes,<\/a> cre\u00eda que en ocasiones se le ped\u00eda que hiciera lo imposible.<\/p>\n<p>Bondi declin\u00f3 hacer comentarios para este art\u00edculo.<\/p>\n<p>Cuando Bondi asumi\u00f3 el cargo form\u00f3 el \u201cGrupo de Trabajo sobre la Instrumentalizaci\u00f3n\u201d, encargado de investigar las acciones de los fiscales durante las administraciones anteriores que, seg\u00fan funcionarios de Trump, ten\u00edan motivaciones pol\u00edticas.<\/p>\n<p>Entre sus objetivos se encuentran los casos presentados por James, as\u00ed como el del exfiscal especial Jack Smith, y el extenso proceso judicial contra los implicados en los disturbios del Capitolio de Estados Unidos.<\/p>\n<p>El grupo ten\u00eda la tarea de publicar informes que pudieran sustentar cargos penales.<\/p>\n<p>Sin embargo, cuando Bondi fue sustituida a principios de abril, el grupo no hab\u00eda elaborado ni un solo informe.<\/p>\n<p>El vicesecreatrio de Justicia adjunto Stan Woodward, el segundo funcionario de mayor rango en el Departamento, defendi\u00f3 ante CNN el ritmo de trabajo del \u201cGrupo de Trabajo sobre la Instrumentalizaci\u00f3n\u201d.<\/p>\n<p>\u201cNos corresponde simplemente calificar esas atrocidades como instrumetalizaci\u00f3n, sino probarlo y buscar las pruebas de su utilizaci\u00f3n como tal\u201d, afirm\u00f3. \u201cY eso lleva tiempo\u201d.<\/p>\n<p>En su primera semana en el cargo, Blanche supervis\u00f3 la publicaci\u00f3n del <a href=\"https:\/\/www.cnn.com\/2026\/04\/14\/politics\/justice-department-weaponization-face-act-report\">primer informe del grupo<\/a>, en el que se alegaba que el Departamento de Justicia de Biden hab\u00eda actuado con parcialidad contra las manifestantes proaborto.<\/p>\n<p>El departamento despidi\u00f3 a cuatro fiscales que trabajaron en los casos.<\/p>\n<p>El informe fue significativo para algunos republicanos, pero el grupo a\u00fan no ha presentado nada relacionado con las personas cuyas investigaciones derivaron en cargos penales contra el presidente.<\/p>\n<p>\u201cParte de la dificultad para convertir esto en un arma es que se necesitan personas que sean partidarias de MAGA y que sean realmente competentes\u201d, declar\u00f3 Chad Mizelle, exjefe de gabinete de Bondi. \u201cMuchos fiscales de carrera no est\u00e1n interesados \u200b\u200ben este tipo de trabajo. Es un grupo muy reducido de personas\u201d.<\/p>\n<p>Mizelle trabaj\u00f3 junto a Blanche y se\u00f1ala que, incluso si el Departamento de Justicia logra presentar un caso contra uno de los adversarios pol\u00edticos de Trump, se enfrentar\u00e1n a los mejores abogados defensores.<\/p>\n<p>Sin embargo, al final, Mizelle afirm\u00f3 estar \u201cseguro\u201d de que Blanche tendr\u00e1 \u00e9xito en estos procesos judiciales.<\/p>\n<p>En cuanto a los fiscales de carrera que puedan oponerse a este tipo de investigaciones, puede que tenga que ver con la solidez de esos casos, coment\u00f3 Elie Honig, analista legal s\u00e9nior de CNN.<\/p>\n<p>\u201cLos fiscales del Departamento de Justicia generalmente no reh\u00fayen los casos complejos y de gran repercusi\u00f3n. De hecho, suelen sentirse atra\u00eddos por asuntos de alto riesgo\u201d, afirm\u00f3 Honig, exfiscal estatal y federal.<\/p>\n<p>\u201cPor lo tanto, cuando vemos a fiscales profesionales, apol\u00edticos, expresar dudas sobre ciertos casos con connotaciones pol\u00edticas, suele ser porque simplemente no ven pruebas suficientes para sustentar una acusaci\u00f3n penal. Los fiscales del Departamento de Justicia son en\u00e9rgicos, pero no imprudentes, y no presentar\u00e1n cargos que no crean que prosperar\u00e1n\u201d, opin\u00f3.<\/p>\n<p>Pero en una administraci\u00f3n que ha visto una divisi\u00f3n entre los dedicados al conservadurismo tradicional y los incondicionales seguidores de Trump, conocidos <a href=\"https:\/\/www.cnn.com\/2026\/02\/07\/politics\/todd-blanche-ed-martin-schism-broader-maga-divide-administration\">como \u201cMAGA\u201d,<\/a> algunos todav\u00eda se preguntan si Blanche est\u00e1 dispuesta a hacer lo que sea necesario para cumplir con los deseos del presidente.<\/p>\n<p>Un alto funcionario de la administraci\u00f3n cuestion\u00f3 si Blanche ha hecho lo suficiente para apoyar el movimiento MAGA.<\/p>\n<p>\u201cTodd est\u00e1 al mando en el Departamento de Justicia, pero no ha hecho lo suficiente para apoyar a MAGA\u201d, declar\u00f3 el funcionario.<\/p>\n<p>Otros no est\u00e1n de acuerdo.<\/p>\n<p>\u201cTodd Blanche lo arriesg\u00f3 todo para defender al presidente Trump durante muchos a\u00f1os, incluso represent\u00e1ndolo diariamente en los tribunales\u201d, se\u00f1al\u00f3 Mike Davis, asesor legal de Trump desde hace mucho tiempo. \u201cNo necesita demostrarle a nadie sus credenciales de MAGA\u201d.<\/p>\n<p>La base de seguidores de MAGA ha criticado repetidamente la gesti\u00f3n del departamento en relaci\u00f3n con los archivos de Epstein.<\/p>\n<p>En febrero de 2025, Bondi declar\u00f3 a Fox News que la lista de clientes de Epstein \u2014de cuya existencia el departamento afirm\u00f3 posteriormente que no exist\u00eda ninguna prueba\u2014 se <a href=\"https:\/\/www.cnn.com\/2025\/07\/08\/politics\/epstein-files-handling-bondi-frustrations\">encontraba sobre su escritorio.<\/a><\/p>\n<p>Su departamento tambi\u00e9n promocion\u00f3 los supuestos \u201carchivos de Epstein\u201d y los distribuy\u00f3 entre figuras influyentes del movimiento MAGA, pero, en \u00faltima instancia, esa publicaci\u00f3n inicial conten\u00eda informaci\u00f3n que ya era de dominio p\u00fablico.<\/p>\n<p>Ante los repetidos tropiezos de Bondi, Blanche se convirti\u00f3 en la principal portavoz del departamento en la investigaci\u00f3n y, finalmente, supervis\u00f3 la publicaci\u00f3n de millones de documentos.<\/p>\n<p>Su <a href=\"https:\/\/www.cnn.com\/2025\/07\/24\/politics\/todd-blanche-ghislaine-maxwell-meeting\">pol\u00e9mica visita<\/a> a Ghislaine Maxwell en julio de 2025 y su declaraci\u00f3n de que no se esperaban cargos en el caso Epstein a menos que surgiera nueva informaci\u00f3n tambi\u00e9n fueron objeto de escrutinio.<\/p>\n<p>\u201cEn primer lugar, el caso Epstein fue el pecado original de este Departamento de Justicia y Todd no nos libra de eso\u201d, declar\u00f3 un alto funcionario de la administraci\u00f3n.<\/p>\n<p>Sin embargo, el Departamento de Justicia ha defendido sus gestiones en el caso Epstein.<\/p>\n<p>\u201cEl secretraio de Justicia interino se reuni\u00f3 el a\u00f1o pasado con Ghislaine Maxwell y su abogado porque ella nunca se hab\u00eda reunido con las fuerzas del orden, y era de inter\u00e9s p\u00fablico determinar si ten\u00eda informaci\u00f3n que no se hab\u00eda compartido anteriormente. La entrevista completa est\u00e1 disponible p\u00fablicamente\u201d, indic\u00f3 recientemente un funcionario del Departamento de Justicia.<\/p>\n<p>\u201cEn cuanto a la presentaci\u00f3n de los expedientes, todos los que cumpl\u00edan con la ley fueron publicados tras revisar millones de documentos en un plazo muy breve para dar cumplimiento a la misma\u201d, declar\u00f3 el funcionario. \u201cA pesar de ser un tema recurrente en las redes sociales, cualquier secretario de Justicia podr\u00e1 constatar lo mismo: que todos los expedientes han sido publicados\u201d.<\/p>\n<p>Si Blanche no logra convencer al presidente, hay varios funcionarios de alto rango del Departamento de Justicia que parecen dispuestos a tomar el relevo.<\/p>\n<p>En los \u00faltimos meses, <a href=\"https:\/\/www.cnn.com\/2026\/04\/06\/politics\/jeanine-pirro-trials-dc-juries\">la fiscal estadounidense Jeanine Pirro<\/a>, una conocida personalidad televisiva con l\u00ednea directa con el presidente, ha buscado ser el centro de atenci\u00f3n.<\/p>\n<p>Pirro habilit\u00f3 una l\u00ednea telef\u00f3nica para recibir cualquier informaci\u00f3n sobre el exdiputado Eric Swalwell en medio de acusaciones de abuso sexual, y ofreci\u00f3 una rueda de prensa criticando duramente a un juez federal por bloquear las citaciones del Departamento de Justicia contra el presidente de la Reserva Federal, Jerome Powell.<\/p>\n<p>La capacidad de Pirro para operar con mayor autonom\u00eda que otros fiscales estadounidenses \u2014llegando incluso a <a href=\"https:\/\/www.cnn.com\/2026\/01\/13\/politics\/jeanine-pirro-powell-investigation-frustration\">sorprender a la Casa Blanca<\/a> con su trabajo\u2014 ha suscitado dudas sobre si est\u00e1 haciendo una prueba para el puesto de secretaria de Justicia.<\/p>\n<p>En respuesta a las sugerencias de que podr\u00eda querer asumir el cargo, Pirro emiti\u00f3 un comunicado a CNN en el que afirmaba: \u201cComo fiscal federal del Distrito de Columbia, he sido testigo directo de la competencia, la experiencia y la capacidad de liderazgo de Todd Blanche. Con m\u00e1s de 15 a\u00f1os en el Departamento de Justicia y una relaci\u00f3n excepcional con el presidente, es la persona id\u00f3nea para dirigir dicho departamento\u201d.<\/p>\n<p>Dhillon, la en\u00e9rgica jefa de derechos civiles, tambi\u00e9n ha sido mencionada como posible candidata para el puesto. Ha trabajado para reestructurar la divisi\u00f3n con el fin de centrarse en revertir <a href=\"https:\/\/www.cnn.com\/2024\/12\/11\/politics\/justice-department-civil-rights-division-dei-trump\">las iniciativas de diversidad, equidad e<\/a> inclusi\u00f3n y combatir el antisemitismo.<\/p>\n<p>Seg\u00fan declar\u00f3 a CNN, \u201cTodd es la elecci\u00f3n del presidente y la apoyo plenamente. Tengo una excelente relaci\u00f3n laboral con \u00e9l. Brinda un gran apoyo tanto a los abogados de base como a los de carrera en el edificio principal de la Corte Suprema\u201d.<\/p>\n<p>Seg\u00fan la Ley de Reforma de Vacantes Federales, Blanche puede desempe\u00f1ar el cargo de manera interina por un m\u00e1ximo de 210 d\u00edas, por lo que no es necesario cubrir el puesto de forma permanente hasta noviembre.<\/p>\n<p>Aunque Blanche consiga el puesto, todos los anteriores secretarios de Justicia de Trump han acabado siendo despedidos, sustituidos o dimitiendo.<\/p>\n<p>Sin embargo, si no consigue el puesto, Blanche <a href=\"https:\/\/www.cnn.com\/2026\/04\/07\/politics\/todd-blanche-nobody-knows-why-bondi-was-fired\">declar\u00f3 recientemente a los periodistas<\/a> que no se lo tendr\u00e1 en cuenta al presidente.<\/p>\n<p>\u201cSi decide nominar a otra persona y me pide que haga otra cosa, le dir\u00e9: \u2018Muchas gracias, lo aprecio mucho, se\u00f1or\u2019\u201d, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario interino de Justicia de EE.UU. Todd Blanche viaj\u00f3 a Florida el lunes, donde se reuni\u00f3 con el nuevo fiscal designado para encargarse de uno de los casos m\u00e1s importantes para el presidente Donald Trump: la investigaci\u00f3n sobre el exdirector de la CIA y cr\u00edtico de Trump, John Brennan. La reuni\u00f3n se produce en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473357","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"El secretario interino de Justicia de EE.UU. Todd Blanche viaj\u00f3 a Florida el lunes, donde se reuni\u00f3 con el nuevo fiscal designado para encargarse de uno de los casos m\u00e1s importantes para el presidente Donald Trump: la investigaci\u00f3n sobre el exdirector de la CIA y cr\u00edtico de Trump, John Brennan. La reuni\u00f3n se produce en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T12:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU.\",\"datePublished\":\"2026-04-21T12:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/\"},\"wordCount\":2061,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/\",\"name\":\"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-21T12:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU. - Noticias","og_description":"El secretario interino de Justicia de EE.UU. Todd Blanche viaj\u00f3 a Florida el lunes, donde se reuni\u00f3 con el nuevo fiscal designado para encargarse de uno de los casos m\u00e1s importantes para el presidente Donald Trump: la investigaci\u00f3n sobre el exdirector de la CIA y cr\u00edtico de Trump, John Brennan. La reuni\u00f3n se produce en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-21T12:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/"},"author":{"name":"","@id":""},"headline":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU.","datePublished":"2026-04-21T12:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/"},"wordCount":2061,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","name":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-21T12:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU.","url":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/las-vegas\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-21T12:03:40Z","datePublished":"2026-04-21T12:03:40Z","dateModified":"2026-04-21T12:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Esto es lo que est\\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/21\\\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/las-vegas\\\/2026\\\/04\\\/21\\\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-21T12:03:40Z\",\"datePublished\":\"2026-04-21T12:03:40Z\",\"dateModified\":\"2026-04-21T12:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473015,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/09\/primer-dia-vicesecretario-justicia-interino-todd-blanche-trax\/","url_meta":{"origin":1473357,"position":0},"title":"El secretario de Justicia interino Todd Blanche marca su primer d\u00eda en el cargo con una serie de memorandos al personal","author":"","date":"abril 9, 2026","format":false,"excerpt":"El secretario de Justicia interino Todd Blanche envi\u00f3 el jueves una serie de memorandos a empleados del Departamento de Justicia, marcando su primer d\u00eda oficial al frente de la agencia.En un memorando al personal, obtenido por CNN, escribi\u00f3: \u201cNuestra misi\u00f3n aqu\u00ed en el Departamento sigue siendo la misma hoy que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472826,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/03\/blanche-departamento-justicia-ee-uu-archivos-epstein-trax\/","url_meta":{"origin":1473357,"position":1},"title":"Blanche asume el cargo del Departamento de Justicia de EE.UU., donde sigue omnipresente la sombra de los archivos de Epstein","author":"","date":"abril 3, 2026","format":false,"excerpt":"El vicesecretario de Justicia de EE.UU., Todd Blanche, a quien el presidente Donald Trump design\u00f3 el jueves para dirigir interinamente el Departamento de Justicia, gestion\u00f3 las operaciones diarias de esta agencia federal durante el \u00faltimo a\u00f1o, asumiendo a menudo un papel m\u00e1s visible para el p\u00fablico cuando Pam Bondi se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470974,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/02\/07\/todd-blanche-ed-martin-division-maga-trax\/","url_meta":{"origin":1473357,"position":2},"title":"Una disputa entre los abogados favoritos de Trump expone una amplia divisi\u00f3n de MAGA dentro del Gobierno","author":"","date":"febrero 7, 2026","format":false,"excerpt":"La disputa entre dos de los fiscales favoritos del presidente Donald Trump lleg\u00f3 a su punto \u00e1lgido a principios de a\u00f1o, cuando el fiscal general adjunto Todd Blanche, exabogado personal del presidente, destituy\u00f3 al activista de MAGA, Ed Martin, de un puesto clave que investigaba a los enemigos pol\u00edticos del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473059,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/11\/kilmar-abrego-garcia-comentarios-todd-blanche-trax\/","url_meta":{"origin":1473357,"position":3},"title":"El caso de Kilmar \u00c1brego Garc\u00eda podr\u00eda ser desestimado por los comentarios del secretario de Justicia interino Todd Blanche","author":"","date":"abril 11, 2026","format":false,"excerpt":"Mientras Todd Blanche toma las riendas del Departamento de Justicia, un juez federal est\u00e1 a punto de decidir si los comentarios controvertidos hechos el a\u00f1o pasado por el ahora secretario de Justicia interino deber\u00edan llevar al desmoronamiento de uno de los casos penales emblem\u00e1ticos del Gobierno de Trump.Las declaraciones p\u00fablicas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464759,"url":"https:\/\/noticiasya.com\/las-vegas\/2025\/07\/22\/reunion-departamento-justicia-ghislaine-maxwell-caso-epstein-trax\/","url_meta":{"origin":1473357,"position":4},"title":"El Departamento de Justicia contact\u00f3 a Ghislaine Maxwell para una reuni\u00f3n en relaci\u00f3n con el caso Epstein","author":"","date":"julio 22, 2025","format":false,"excerpt":"El Departamento de Justicia dijo el martes que se comunic\u00f3 con la ex asociada de Jeffrey Epstein, Ghislaine Maxwell, para una reuni\u00f3n en medio de las cr\u00edticas por el manejo por parte de la administraci\u00f3n de los archivos relacionados con el acusado de tr\u00e1fico sexual.\u201cLa justicia exige valent\u00eda. Por primera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473434,"url":"https:\/\/noticiasya.com\/las-vegas\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/","url_meta":{"origin":1473357,"position":5},"title":"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa","author":"","date":"abril 23, 2026","format":false,"excerpt":"El secretario de Justicia interino de EE.UU., Todd Blanche, firm\u00f3 este jueves una orden que reclasifica la marihuana medicinal autorizada por el estado como una droga menos peligrosa. Esta decisi\u00f3n cambia una pol\u00edtica que durante d\u00e9cadas ha dificultado la investigaci\u00f3n de los posibles beneficios medicinales de la droga.La orden de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/las-vegas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=1473357"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/posts\/1473357\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=1473357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=1473357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=1473357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}