{"id":1450828,"date":"2024-07-01T13:03:46","date_gmt":"2024-07-01T20:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/"},"modified":"2024-07-01T13:03:46","modified_gmt":"2024-07-01T20:03:46","slug":"rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/","title":{"rendered":"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza"},"content":{"rendered":"<p>(CNN) &#8212; Molly Parren estaba rastreando una tortuga de bosque en Vermont cuando sinti\u00f3 un olor sorprendente, pero familiar. La cient\u00edfica especializada en anfibios de la Agencia Estatal de Fauna y Flora Silvestres rastre\u00f3 el olor hasta un raro ajo silvestre e hizo una foto.<\/p>\n<p>Lo que no sab\u00eda en ese momento era que hab\u00eda encontrado no una, sino dos plantas raras, una de las cuales no se ve\u00eda en el estado desde 1916.<\/p>\n<p>Parren envi\u00f3 la foto a su colega Grace Glynn, bot\u00e1nica del estado de Vermont.<\/p>\n<p>Un subastador de Florida estaba a punto de vender un reloj de bolsillo del siglo XIX. Se enter\u00f3 que era una pieza robada que perteneci\u00f3 a Roosevelt<\/p>\n<p>&#171;Vi esta otra planta en primer plano, esta diminuta, peque\u00f1a planta que ten\u00eda un color muy diferente&#187;, dijo Glynn a CNN. &#171;Inmediatamente supe que era floerkea. Falsa sirena&#187;.<\/p>\n<p>Glynn buscaba esta planta &#171;un poco obsesivamente&#187;, dijo. Por su naturaleza ef\u00edmera, era f\u00e1cil no verla. Su breve periodo de floraci\u00f3n comienza en abril. Decir que sus flores blancas son peque\u00f1as es quedarse corto: tienen el tama\u00f1o de la cabeza de un alfiler. En junio, la planta se marchita.<\/p>\n<p>Seg\u00fan Glynn, s\u00f3lo hay tres lugares hist\u00f3ricos de floerkea en el estado. &#171;He so\u00f1ado con encontrarla porque es una plantita muy discreta con una visibilidad limitada y sab\u00eda que pod\u00eda estar al acecho a plena vista. Nunca la hab\u00eda visto en persona, pero hab\u00eda mirado muchas veces las fotos&#187;, explica.<\/p>\n<p>Cuando vio lo que Parren fotografi\u00f3, Glynn &#171;salt\u00f3 y grit\u00f3&#187;.<\/p>\n<p>Para germinar, la falsa sirena necesita un suelo abierto en las llanuras aluviales, lo que significa que este tipo de plantas son vulnerables a especies invasoras como la mostaza del ajo, la hierba canaria y el knotweed japon\u00e9s, entre otras, explic\u00f3 Glynn. Las especies invasoras &#171;ahogan&#187; los h\u00e1bitats de las llanuras aluviales y dificultan la competencia de las plantas aut\u00f3ctonas.<\/p>\n<p>La mayor\u00eda de las especies invasoras proceden de jardines, dijo Glynn. Pero no son la \u00fanica amenaza para las plantas aut\u00f3ctonas.<\/p>\n<p>El aumento de las inundaciones en Nueva Inglaterra es muy &#171;preocupante porque puede estar alterando estos h\u00e1bitats de un modo al que la floerkea y otras especies ribere\u00f1as no est\u00e1n adaptadas&#187;, dijo Glynn. La mayor\u00eda de las plantas de ribera han evolucionado para beneficiarse de las inundaciones invernales y primaverales, no de las estivales.<\/p>\n<p>En verano, las plantas empiezan a reproducirse y florecer. Las inundaciones pueden da\u00f1ar la planta durante ese proceso cr\u00edtico, oblig\u00e1ndola a empezar de nuevo. Glynn dice que esto es &#171;realmente estresante&#187;, y aunque algunas plantas pueden ser capaces de rebrotar r\u00e1pidamente y enviar nuevas flores, &#171;despu\u00e9s de varias temporadas sucediendo esto, se puede imaginar que puede ser demasiado estresante para las plantas y podr\u00edan morir o ser equipadas por invasoras&#187;.<\/p>\n<p>Grace Glynn, bot\u00e1nica del estado de Vermont, estudia la falsa sirena. Cr\u00e9dito: Departamento de Pesca y Vida Silvestre de Vermont<\/p>\n<p>El reto para las plantas es que no pueden huir de las malas condiciones, afirma Tim Johnson, director general de Native Plant Trust, una organizaci\u00f3n que \u2014haciendo honor a su nombre\u2014 trabaja para restaurar las plantas aut\u00f3ctonas, educar a los propietarios e implantar especies aut\u00f3ctonas en el dise\u00f1o paisaj\u00edstico.<\/p>\n<p>&#171;Las especies y comunidades vegetales han evolucionado a lo largo de millones de a\u00f1os y han sido capaces de adaptarse a condiciones clim\u00e1ticas desfavorables o migrar lejos de ellas&#187;, explica Johnson a CNN. &#171;Las especies que tenemos hoy son las supervivientes. Son las que han sido capaces de navegar en este proceso a lo largo del tiempo&#187;.<\/p>\n<p>Johnson explic\u00f3 que ciertas especies de plantas tienen una distribuci\u00f3n m\u00e1s amplia que otras y que Vermont se encuentra en el l\u00edmite del \u00e1rea de distribuci\u00f3n de la falsa hierba sirena, por lo que el tama\u00f1o de la poblaci\u00f3n no es tan grande como en otros estados, lo que la hace m\u00e1s rara.<\/p>\n<p>&#171;Las especies y comunidades vegetales han evolucionado a lo largo de millones de a\u00f1os y han sido capaces de adaptarse a condiciones clim\u00e1ticas desfavorables o migrar lejos de ellas&#187;, explica Johnson. &#171;Las especies que tenemos hoy son las supervivientes. Son las que han sido capaces de navegar por este proceso a lo largo del tiempo. El reto, o uno de los mayores retos, con las plantas, es que no pueden huir&#187;.<\/p>\n<p>Los corales del mundo registran uno de los peores eventos de blanqueamiento registrado<\/p>\n<p>Las plantas aut\u00f3ctonas han evolucionado en equilibrio con el resto del ecosistema. Los polinizadores y la fauna locales dependen de las especies aut\u00f3ctonas, y est\u00e1n tan amenazados por las plantas invasoras no aut\u00f3ctonas como los propios nativos.<\/p>\n<p>&#171;Algunos insectos aut\u00f3ctonos dependen de plantas hospedadoras o especies hospedadoras muy espec\u00edficas para completar sus ciclos vitales&#187;, explica Glynn. &#171;Y luego los p\u00e1jaros dependen de (los insectos), y as\u00ed sucesivamente, a lo largo de la cadena alimentaria&#187;.<\/p>\n<p>Glynn explic\u00f3 que gran parte del trabajo depende de los entusiastas, voluntarios y otros bot\u00e1nicos profesionales que le env\u00edan fotos y videos de sus observaciones. Todas las especies &#171;tienen derecho a persistir en el paisaje, y por eso hacemos lo que hacemos&#187;, afirma Glynn.<\/p>\n<p>El descubrimiento de la falsa alga sirena demuestra que hay motivos para esperar que el mundo pueda deshacer los efectos nocivos del cambio clim\u00e1tico, dijo Johnson.<\/p>\n<p>&#171;Podemos pensar que lo hemos superado porque tenemos superordenadores en el bolsillo y aviones que nos transportan por todo el mundo, pero todo en nuestras vidas se ve facilitado por las plantas&#187;, dijo Johnson. &#171;Son los principales productores de nuestro mundo. Las comemos. Las utilizamos como materiales de construcci\u00f3n. Producen el ox\u00edgeno que respiramos. Literalmente, no podr\u00edamos vivir sin ellas&#187;.<\/p>\n<p>Vermont Fish &#038; Wildlife rastrea cientos de especies de plantas en todo el estado y publica los resultados en su sitio web. Puedes informarte del avistamiento de una especie rara en Vermont respondiendo este formulario.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Molly Parren estaba rastreando una tortuga de bosque en Vermont cuando sinti\u00f3 un olor sorprendente, pero familiar. La cient\u00edfica especializada en anfibios de la Agencia Estatal de Fauna y Flora Silvestres rastre\u00f3 el olor hasta un raro ajo silvestre e hizo una foto. Lo que no sab\u00eda en ese momento era que hab\u00eda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450828","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Molly Parren estaba rastreando una tortuga de bosque en Vermont cuando sinti\u00f3 un olor sorprendente, pero familiar. La cient\u00edfica especializada en anfibios de la Agencia Estatal de Fauna y Flora Silvestres rastre\u00f3 el olor hasta un raro ajo silvestre e hizo una foto. Lo que no sab\u00eda en ese momento era que hab\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-01T20:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza\",\"datePublished\":\"2024-07-01T20:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/\"},\"wordCount\":1062,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/\",\"name\":\"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-01T20:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza - Noticias","og_description":"(CNN) &#8212; Molly Parren estaba rastreando una tortuga de bosque en Vermont cuando sinti\u00f3 un olor sorprendente, pero familiar. La cient\u00edfica especializada en anfibios de la Agencia Estatal de Fauna y Flora Silvestres rastre\u00f3 el olor hasta un raro ajo silvestre e hizo una foto. Lo que no sab\u00eda en ese momento era que hab\u00eda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-01T20:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/"},"author":{"name":"","@id":""},"headline":"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza","datePublished":"2024-07-01T20:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/"},"wordCount":1062,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/","name":"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-01T20:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Pensaban que esta rara y diminuta flor se hab\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\u00edmbolo de esperanza","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/01\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-01T20:03:46Z","datePublished":"2024-07-01T20:03:46Z","dateModified":"2024-07-01T20:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Pensaban que esta rara y diminuta flor se hab\\u00eda extinguido desde la Primera Guerra Mundial; ahora es un s\\u00edmbolo de esperanza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/01\\\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/01\\\/rara-diminuta-flor-extinguido-primera-guerra-mundial-vermont-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-01T20:03:46Z\",\"datePublished\":\"2024-07-01T20:03:46Z\",\"dateModified\":\"2024-07-01T20:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458788,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/02\/15\/incendio-hotel-londres-san-valentin-trax\/","url_meta":{"origin":1450828,"position":0},"title":"Un incendio arras\u00f3 con un hotel de lujo en Londres el D\u00eda de San Valent\u00edn; no se reportaron heridos","author":"","date":"febrero 15, 2025","format":false,"excerpt":"M\u00e1s de 100 personas fueron evacuadas cuando las llamas arrasaron un popular hotel y restaurante de lujo en el centro de Londres el viernes.\u201cVeinte camiones de bomberos y alrededor de 125 bomberos combatieron un incendio en un hotel en Chiltern Street en Marylebone\u201d, dijo la Brigada de Bomberos de Londres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452651,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/09\/13\/boars-head-cerrara-planta-virginia-brote-listeria-orix\/","url_meta":{"origin":1450828,"position":1},"title":"Boar&#8217;s Head cerrar\u00e1 planta en Virginia vinculada a un brote mortal de listeria","author":"","date":"septiembre 13, 2024","format":false,"excerpt":"(CNN) -- Boar\u2019s Head cerrar\u00e1 la planta en Virginia que produjo carne para deli vinculada a un mortal brote de listeria, dijo la compa\u00f1\u00eda este viernes.La medida es parte de varios cambios realizados tras lo que llam\u00f3 un \"momento oscuro en la historia de nuestra compa\u00f1\u00eda\". Boar's Head dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446521,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/03\/05\/tesla-berlin-electriciad-piromanos-trax\/","url_meta":{"origin":1450828,"position":2},"title":"La gigantesca f\u00e1brica de Tesla en Berl\u00edn se queda sin electricidad despu\u00e9s de que pir\u00f3manos atacaran el suministro el\u00e9ctrico","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN) -- El suministro de energ\u00eda a la f\u00e1brica de Tesla cerca de Berl\u00edn se cort\u00f3 luego de un ataque incendiario a una torre de alta tensi\u00f3n cercana, dijo este martes un funcionario alem\u00e1n.\u201cSi se confirman las conclusiones iniciales, se trata de un ataque p\u00e9rfido a nuestra infraestructura el\u00e9ctrica. Esto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468151,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/11\/08\/desastre-aereo-ups-conmociona-bar-local-trax\/","url_meta":{"origin":1450828,"position":3},"title":"La aleatoriedad del desastre a\u00e9reo de UPS conmociona a los clientes del &#171;happy hour&#187; de un popular bar local","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"Los clientes habituales del \u201chappy hour\u201d ya se estaban reuniendo en Stooges Bar & Grill menos de dos horas antes del inicio del partido inaugural de la temporada de baloncesto masculino de la Universidad de Kentucky el martes por la noche.Unos 30 clientes ocupaban los taburetes de madera del local\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463655,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/06\/17\/redada-ice-omaha-nebraska-planta-alimentos-trax\/","url_meta":{"origin":1450828,"position":4},"title":"La redada de ICE en Nebraska que conmocion\u00f3 a las autoridades y dividi\u00f3 a familias","author":"","date":"junio 17, 2025","format":false,"excerpt":"Los compa\u00f1eros de trabajo de Rina Salado acababan de estallar confeti.La sorprendieron con la noticia de que la hab\u00edan ascendido a supervisora \u200b\u200ben la planta de fabricaci\u00f3n de tarjetas de cr\u00e9dito donde hab\u00eda trabajado durante casi tres a\u00f1os. Su equipo le pidi\u00f3 una foto para ampliarla y colgarla en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468085,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/11\/06\/desaparecidos-accidente-avion-ups-louisville-trax\/","url_meta":{"origin":1450828,"position":5},"title":"Tres empleados de una planta de Louisville est\u00e1n desaparecidos tras accidente a\u00e9reo de UPS que, seg\u00fan el due\u00f1o, fue aterrador","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"Acababa de irse la luz y el suelo temblaba en Grade A Auto Parts cuando el propietario recibi\u00f3 una videollamada de p\u00e1nico de su directora financiera.En su pantalla, el CEO Sean Garber vio una enorme bola de fuego que envolv\u00eda la planta de reciclaje y fabricaci\u00f3n de autopartes de Louisville,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1450828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1450828"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1450828\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1450828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1450828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1450828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}