{"id":1450871,"date":"2024-07-04T01:03:50","date_gmt":"2024-07-04T08:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/"},"modified":"2024-07-04T01:03:50","modified_gmt":"2024-07-04T08:03:50","slug":"por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/","title":{"rendered":"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776?"},"content":{"rendered":"<p>(CNN) &#8212; En todo Estados Unidos el 4 de julio es un d\u00eda de fiesta en que los colores rojo, azul y blanco adornan las ciudades, el cielo se ilumina con fuegos pirot\u00e9cnicos y las parrillas se encienden en los jardines, mientras que en algunas ciudades los amantes de los perros calientes tienen su propio concurso.<\/p>\n<p>Esta es la historia y las tradiciones del 4 de julio en Estados Unidos.<\/p>\n<p>Conoce curiosidades sobre la fiesta del 4 de julio 1:18<\/p>\n<p>La historia del 4 de julio<\/p>\n<p>El 4 de julio se celebra el D\u00eda de la Independencia en Estados Unidos.<\/p>\n<p>Ese d\u00eda de 1776, el Congreso Continental adopt\u00f3 la Declaraci\u00f3n de Independencia dos d\u00edas despu\u00e9s de una votaci\u00f3n sobre la separaci\u00f3n del Reino Unido. La Declaraci\u00f3n, redactada por Thomas Jefferson (quien finalmente se convirti\u00f3 en presidente y muri\u00f3 el d\u00eda 4), es b\u00e1sicamente el certificado de nacimiento de Estados Unidos: ese d\u00eda se declar\u00f3 a Estados Unidos una naci\u00f3n independiente del poder brit\u00e1nico.<\/p>\n<p>Benjamin Franklin, John Adams, Thomas Jefferson, Roger Sherman y Robert R. Livingston formaron el comit\u00e9 que redact\u00f3 la Declaraci\u00f3n. Jefferson, considerado el escritor m\u00e1s fuerte y elocuente, escribi\u00f3 la mayor parte del documento. El comit\u00e9 y el Congreso en su conjunto hicieron un total de 86 cambios al borrador de Jefferson.<\/p>\n<p>Aunque estos Padres Fundadores firmaron el documento en la d\u00e9cada de 1700, el D\u00eda de la Independencia no se convirti\u00f3 oficialmente en feriado sino hasta 1870, y se convirti\u00f3 en feriado pagado por el gobierno federal en 1941.<\/p>\n<p>Algunos datos de la Declaraci\u00f3n de Independencia de Estados Unidos<\/p>\n<p>Es posible que sepas acerca de la famosa firma grande de John Hancock o que Thomas Jefferson fue el autor del documento, pero aqu\u00ed hay algunos datos que quiz\u00e1s no conozcas sobre la Declaraci\u00f3n.<\/p>\n<p>La Declaraci\u00f3n de Independencia no se firm\u00f3 el 4 de julio<\/p>\n<p>Aunque el 4 de julio es el d\u00eda en que Estados Unidos celebra la independencia, ese no fue el d\u00eda en que se firm\u00f3 el documento. El Congreso Continental adopt\u00f3 la Declaraci\u00f3n ese d\u00eda, pero la mayor\u00eda de los delegados no firmaron el documento hasta el 2 de agosto de 1776, seg\u00fan los Archivos Nacionales. Los delegados de Nueva York no pudieron dar oficialmente su apoyo hasta el 9 de julio, y el Congreso no orden\u00f3 que el documento oficial fuera escrito en pergamino hasta el 19. Adem\u00e1s, el 4 de julio no era el d\u00eda que los fundadores esperaban que fuera recordado como el D\u00eda de la Independencia. Se pens\u00f3 que el 2 de julio, el d\u00eda en que el Congreso Continental vot\u00f3 por la independencia, era el d\u00eda de la celebraci\u00f3n, lo que incluso John Adams se\u00f1al\u00f3 en sus escritos, seg\u00fan los Archivos Nacionales.<\/p>\n<p>Hay m\u00e1s de una copia de la Declaraci\u00f3n de Independencia<\/p>\n<p>Aunque la mayor\u00eda de las personas que ven el documento ven el original en exhibici\u00f3n en los Archivos Nacionales en Washington, se imprimieron cientos m\u00e1s. Estas copias se conocen como las &#171;panfletos de Dunlop&#187;, en honor al propietario de la tienda que las imprimi\u00f3, John Dunlop.<\/p>\n<p>De los cientos de impresos, solo se sabe que sobrevivieron 26, incluidos dos que se encontraron en los \u00faltimos 26 a\u00f1os. Uno fue encontrado en 1989 por un hombre de Filadelfia escondido en un marco de fotos que compr\u00f3 en un mercado de pulgas por $4 y el otro fue encontrado en una caja de papeles en los Archivos Nacionales Brit\u00e1nicos en 2009.<\/p>\n<p>Jefferson y Adams murieron el mismo d\u00eda, el 4 de julio<\/p>\n<p>Thomas Jefferson y John Adams murieron el mismo d\u00eda, el 4 de julio de 1826, 50 a\u00f1os despu\u00e9s de la adopci\u00f3n de la Declaraci\u00f3n, seg\u00fan los Archivos Nacionales. Adams ayud\u00f3 a Jefferson a escribir la declaraci\u00f3n y tambi\u00e9n particip\u00f3 en persuadir al Congreso para que declarara la independencia.<\/p>\n<p>Una marca en el documento sigue siendo un misterio sin resolver<\/p>\n<p>Un misterio sobre el documento que a\u00fan no se ha resuelto es que aparece una huella de mano en la esquina inferior izquierda. Aunque los or\u00edgenes de la marca a\u00fan no est\u00e1n claros, su presencia no parece sorprender a los historiadores, ya que el documento se enrollaba, se met\u00eda en bolsas y se transportaba en vagones y barcos.<\/p>\n<p>Algunas ciudades de EE.UU. sustituyen los fuegos artificiales del 4 de julio por drones ecol\u00f3gicos<\/p>\n<p>\u201cFue terrible\u201d, dijo David Ward, historiador principal de la Galer\u00eda Nacional de Retratos, a Chris Moody de CNN. &#171;Lo pusieron en una bolsa de arpillera. Lo enrollaron todo el tiempo, lo que se supone que no debes hacer. Estuvo expuesto a la luz, estuvo expuesto al humo&#187;.<\/p>\n<p>Por supuesto, la protecci\u00f3n del documento se ha incrementado significativamente, ahora sellado en un marco de titanio y aluminio con humedad controlada. Durante la Segunda Guerra Mundial, seg\u00fan los Archivos Nacionales, fue transportado en 150 libras de equipo de protecci\u00f3n a Fort Knox, donde pas\u00f3 el resto de la guerra.<\/p>\n<p>\u00bfPor qu\u00e9 es famosa la frase &#171;tierra de libres, hogar de valientes&#187; en el pa\u00eds?<\/p>\n<p>Esta l\u00ednea proviene del himno nacional, &#171;The Star-Spangled Banner&#187;, que fue escrito por Francis Scott Key. Si escuchas la letra con atenci\u00f3n, notar\u00e1s que la canci\u00f3n relata los eventos del bombardeo de Fort McHenry en 1814.<\/p>\n<p>En 1931, fue nombrado himno nacional. No te preocupes, no tienes que memorizarlo todo; tararear funciona bien para muchos estadounidenses.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; En todo Estados Unidos el 4 de julio es un d\u00eda de fiesta en que los colores rojo, azul y blanco adornan las ciudades, el cielo se ilumina con fuegos pirot\u00e9cnicos y las parrillas se encienden en los jardines, mientras que en algunas ciudades los amantes de los perros calientes tienen su propio [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450871","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; En todo Estados Unidos el 4 de julio es un d\u00eda de fiesta en que los colores rojo, azul y blanco adornan las ciudades, el cielo se ilumina con fuegos pirot\u00e9cnicos y las parrillas se encienden en los jardines, mientras que en algunas ciudades los amantes de los perros calientes tienen su propio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-04T08:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776?\",\"datePublished\":\"2024-07-04T08:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/\"},\"wordCount\":956,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/\",\"name\":\"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-04T08:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776? - Noticias","og_description":"(CNN) &#8212; En todo Estados Unidos el 4 de julio es un d\u00eda de fiesta en que los colores rojo, azul y blanco adornan las ciudades, el cielo se ilumina con fuegos pirot\u00e9cnicos y las parrillas se encienden en los jardines, mientras que en algunas ciudades los amantes de los perros calientes tienen su propio [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-04T08:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776?","datePublished":"2024-07-04T08:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/"},"wordCount":956,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/","name":"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-04T08:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta al 1776?","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/04\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-04T08:03:50Z","datePublished":"2024-07-04T08:03:50Z","dateModified":"2024-07-04T08:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 se celebra en EE.UU. el 4 de julio? \\u00bfCu\\u00e1l es su origen e historia que se remonta al 1776?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/04\\\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/04\\\/por-que-celebra-eeuu-4th-july-historia-siglo-xviii-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-04T08:03:50Z\",\"datePublished\":\"2024-07-04T08:03:50Z\",\"dateModified\":\"2024-07-04T08:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464202,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/07\/03\/por-que-celebra-eeuu-4-de-julio-historia-orix\/","url_meta":{"origin":1450871,"position":0},"title":"\u00bfPor qu\u00e9 se celebra en EE.UU. el 4 de julio? \u00bfCu\u00e1l es su origen e historia que se remonta a 1776?","author":"","date":"julio 3, 2025","format":false,"excerpt":"En Estados Unidos, el 4 de julio se celebra con un despliegue de colores patrios: el rojo, el azul y el blanco ti\u00f1en calles y decoraciones, los fuegos artificiales iluminan el cielo y las parrillas se encienden en jardines y patios. En algunas ciudades, incluso hay concursos dedicados a quienes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450867,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/03\/que-tiendas-bancos-y-comercios-abren-eeuu-4-de-julio-horarios-y-mas-trax\/","url_meta":{"origin":1450871,"position":1},"title":"\u00bfQu\u00e9 tiendas, bancos y comercios abren y cierran en EE.UU. durante el 4 de julio? Horarios y m\u00e1s","author":"","date":"julio 3, 2024","format":false,"excerpt":"(CNN) -- Los estadounidenses celebrar\u00e1n el D\u00eda de la Independencia con barbacoas, fuegos artificiales y un d\u00eda libre de trabajo para muchos empleados.\u00a0El 4 de julio marca el nacimiento de la independencia estadounidense, el d\u00eda en que el Congreso Continental adopt\u00f3 la Declaraci\u00f3n de Independencia en 1776.Este a\u00f1o, el 4\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450895,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/05\/independencia-venezuela-origen-por-que-se-celebra-5-de-julio-orix\/","url_meta":{"origin":1450871,"position":2},"title":"Independencia de Venezuela: \u00bfcu\u00e1l es su origen y por qu\u00e9 se celebra el 5 de julio?","author":"","date":"julio 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Venezuela celebra este viernes el aniversario 213 de la declaraci\u00f3n de su Independencia. A continuaci\u00f3n, te explicamos el origen de este acontecimiento y por qu\u00e9 se celebra en esta fecha.La Independencia de Venezuela fue un proceso militar y pol\u00edtico que inici\u00f3 el 19 de abril de 1810\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464210,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/07\/04\/que-estara-abierto-cerrado-4-de-julio-2025-trax\/","url_meta":{"origin":1450871,"position":3},"title":"\u00bfQu\u00e9 estar\u00e1 abierto y cerrado el 4 de julio de 2025?","author":"","date":"julio 4, 2025","format":false,"excerpt":"Mientras los estadounidenses celebran 249 a\u00f1os de independencia con fuegos artificiales y barbacoas, muchos negocios permanecer\u00e1n cerrados durante el d\u00eda.El 4 de Julio se conmemora la independencia de Estados Unidos, la fecha en la que se adopt\u00f3 la Declaraci\u00f3n de Independencia en 1776. Como es un feriado federal, muchas oficinas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451279,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/20\/por-que-independencia-colombia-20-julio-1810-origen-historia-orix\/","url_meta":{"origin":1450871,"position":4},"title":"\u00bfPor qu\u00e9 se celebra el 20 de julio la Independencia de Colombia? Esto fue lo que ocurri\u00f3 en 1810","author":"","date":"julio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El 20 de julio en Colombia se conmemora el D\u00eda de la Independencia debido a una serie de eventos que dar\u00edan inicio a la Independencia de la Nueva Granada \u2014como se llamaba el conjunto de provincias que hoy forman la actual Colombia\u2014 del poder de Espa\u00f1a.Si bien\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1410538,"url":"https:\/\/noticiasya.com\/los-angeles\/2022\/07\/04\/mira-aqui-los-lugares-y-actividades-del-dia-de-la-independencia-en-colorado\/","url_meta":{"origin":1450871,"position":5},"title":"Mira aqu\u00ed los lugares y actividades del D\u00eda de la Independencia en Colorado","author":"agomez","date":"julio 4, 2022","format":false,"excerpt":"Hoy te presentamos una lista en la que podr\u00e1s ver que festejo te queda m\u00e1s cerca y \u00a1Feliz cuatro de julio!","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1450871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1450871"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1450871\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1450871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1450871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1450871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}