{"id":1450920,"date":"2024-07-06T07:03:38","date_gmt":"2024-07-06T14:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/"},"modified":"2024-07-06T07:03:38","modified_gmt":"2024-07-06T14:03:38","slug":"pezeshkian-elecciones-presidenciales-iran-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/","title":{"rendered":"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n"},"content":{"rendered":"<p>(CNN) &#8212; El candidato reformista Masoud Pezeshkian gan\u00f3 las elecciones presidenciales de Ir\u00e1n derrotando a su rival de l\u00ednea dura en una votaci\u00f3n crucial en medio de crecientes tensiones tanto a nivel nacional como internacional. Lo inform\u00f3 este s\u00e1bado la autoridad electoral del pa\u00eds.<\/p>\n<p>De los 30,5 millones de votos escrutados en la segunda vuelta del viernes, Pezeshkian obtuvo m\u00e1s de 16,3 millones, superando a su rival ultraconservador Saeed Jalili, que obtuvo m\u00e1s de 13,5 millones, seg\u00fan Press TV.\u00a0La participaci\u00f3n electoral fue del 49,8%, inform\u00f3 Press TV, citando la sede electoral auspiciada por el Ministerio del Interior.<\/p>\n<p>Pezeshkian fue elegido en la segunda vuelta, tras haber obtenido el mayor n\u00famero de papeletas en la primera, por delante del conservador de l\u00ednea dura Saeed Jalili. En la primera vuelta se registr\u00f3 la menor participaci\u00f3n en unas elecciones presidenciales desde la creaci\u00f3n de la Rep\u00fablica Isl\u00e1mica en 1979.<\/p>\n<p>Tribunal Supremo de Ir\u00e1n anula condena a muerte del rapero disidente Toomaj Salehi; abogada pide su liberaci\u00f3n incondicional<\/p>\n<p>&#171;Extenderemos la mano de la amistad a todos. Somos gente de este pa\u00eds y debemos utilizar los esfuerzos de todos para el progreso de la naci\u00f3n&#187;, dijo en sus primeras declaraciones tras la victoria electoral, seg\u00fan Press TV. Tambi\u00e9n agradeci\u00f3 a quienes votaron en las elecciones del viernes &#171;con amor y para ayudar&#187; al pa\u00eds.<\/p>\n<p>El l\u00edder supremo del pa\u00eds, el ayatol\u00e1 Seyyed Ali Jamenei, agradeci\u00f3 a los candidatos y felicit\u00f3 al presidente electo.<\/p>\n<p>Jamenei elogi\u00f3 al pa\u00eds por celebrar r\u00e1pidamente &#171;elecciones libres y transparentes&#187; tras la muerte del presidente Ebrahim Raisi. Las elecciones fueron convocadas despu\u00e9s de que Raisi muriera en un accidente de helic\u00f3ptero en mayo en el remoto noroeste de Ir\u00e1n, junto con el ministro de Relaciones Exteriores Hossein Amir-Abdollahian y otros funcionarios.<\/p>\n<p>Jamenei aconsej\u00f3 a Pezeshkian actuar &#171;en continuidad con el camino&#187; de Raisi.<\/p>\n<p>El Consejo de Guardianes, un poderoso organismo de 12 miembros encargado de supervisar las elecciones y la legislaci\u00f3n, debe certificar la votaci\u00f3n antes de que Pezeshkian pueda asumir el cargo.<\/p>\n<p>En esta fotograf\u00eda de archivo de 2002, el entonces ministro de Salud Masoud Pezeshkian, izquierda, y el entonces presidente iran\u00ed Mohammad Khatami, derecha, escuchan a Abbas-Ali Karimi, centro, jefe del Centro de Cardiolog\u00eda de Teher\u00e1n, mientras visitan un quir\u00f3fano durante la inauguraci\u00f3n del centro. (Behrouz Mehri\/AFP\/Getty Images\/Archivo)<\/p>\n<p>Cuando lo haga, Pezeshkian tomar\u00e1 el tim\u00f3n de un pa\u00eds que se enfrenta a un creciente aislamiento internacional, descontento interno, una econom\u00eda en espiral y la perspectiva de un conflicto directo con su archienemigo Israel.<\/p>\n<p>El legislador era el \u00fanico candidato reformista que compet\u00eda por el esca\u00f1o electo m\u00e1s alto del pa\u00eds despu\u00e9s de que a decenas de otros candidatos se les prohibiera postularse.<\/p>\n<p>Tras la victoria, Pezeshkian hizo un llamamiento a la unidad y pidi\u00f3 el apoyo de sus compatriotas iran\u00edes en un comunicado publicado en X. &#171;Querido pueblo de Ir\u00e1n, las elecciones terminaron y esto es s\u00f3lo el comienzo de nuestro trabajo. El dif\u00edcil camino que tenemos por delante no estar\u00e1 pavimentado excepto con su apoyo, empat\u00eda y confianza. Les extiendo mi mano y juro por mi dignidad que no los dejar\u00e9 solos en este camino. No me dejen solo&#187;, escribi\u00f3.<\/p>\n<p>El presidente electo se ha mostrado favorable al di\u00e1logo con los enemigos de Ir\u00e1n, particularmente al respecto de su programa nuclear, y ve a ese di\u00e1logo como un medio para abordar los problemas internos del pa\u00eds.<\/p>\n<p>&#171;La cuesti\u00f3n principal es la perspectiva: \u00bfqueremos resolver nuestros problemas con el mundo o no? Creo que debemos salir del estancamiento para resolver los problemas del pa\u00eds&#187;, dijo en un debate presidencial antes de la segunda ronda de votaci\u00f3n.<\/p>\n<p>Suecia e Ir\u00e1n intercambian prisioneros en un acuerdo decisivo, dicen funcionarios<\/p>\n<p>Los l\u00edderes de Rusia, Arabia Saudita, Pakist\u00e1n y Siria estuvieron entre los primeros en felicitar a Pezeshkian.<\/p>\n<p>El pr\u00edncipe heredero saudita, Mohammed Bin Salman, dijo que estaba &#171;interesado en desarrollar y profundizar las relaciones que unan a nuestros dos pa\u00edses y pueblos, y sirvan a nuestros intereses comunes&#187;, seg\u00fan la estatal Agencia de Prensa Saudita.<\/p>\n<p>El presidente de Rusia, Vladimir Putin, dijo que esperaba que la elecci\u00f3n de Pezeshkian ampliara la cooperaci\u00f3n bilateral &#171;en todas las \u00e1reas&#187; con el fin de &#171;simplificar la seguridad y la estabilidad regionales&#187;, seg\u00fan un comunicado del Kremlin.<\/p>\n<p>Si bien el presidente iran\u00ed disfruta de algunos poderes, la autoridad \u00faltima recae en el L\u00edder Supremo, quien tiene la \u00faltima palabra en todos los asuntos de Estado.<\/p>\n<p>\u00bfQui\u00e9n es Masoud Pezeshkian?<\/p>\n<p>Pezeshkian, ministro de Sanidad con el presidente reformista Mohammad Jatam\u00ed, es cardiocirujano de formaci\u00f3n y legislador. Gan\u00f3 notoriedad por su postura contra la represi\u00f3n de las protestas prodemocr\u00e1ticas de 2009 y la violencia perpetrada por la tristemente c\u00e9lebre polic\u00eda de la moralidad en 2022 a ra\u00edz de la muerte de Mahsa Amini. Amini muri\u00f3 bajo custodia de la polic\u00eda de la moralidad tras ser detenida por no respetar el estricto c\u00f3digo de vestimenta de las mujeres de la Rep\u00fablica Isl\u00e1mica. Cientos de personas murieron y miles fueron detenidas cuando las autoridades intentaron aplastar las protestas, seg\u00fan las Naciones Unidas.<\/p>\n<p>Durante las protestas de 2022, Pezeshkian declar\u00f3 en una entrevista a la televisi\u00f3n iran\u00ed IRINN: &#171;Es culpa nuestra. Queremos implantar la fe religiosa mediante el uso de la fuerza. Esto es cient\u00edficamente imposible&#187;.<\/p>\n<p>&#171;Yo tengo parte de culpa, los distinguidos eruditos religiosos y las mezquitas tienen parte de culpa, y la autoridad (iran\u00ed) de radiodifusi\u00f3n tiene parte de culpa&#187;, dijo.<\/p>\n<p>&#171;Todos deber\u00edan dar un paso al frente y rendir cuentas, en lugar de capturar a esa chica, darle una paliza y, finalmente, entregar su cuerpo (a su familia)&#187;.<\/p>\n<p>Se present\u00f3 como candidato de todos los iran\u00edes. &#171;Entre mis partidarios hay tanto de izquierdas como de derechas, incluso los que no rezan&#187;, dijo en un reciente debate presidencial. Tras perder a su mujer y a uno de sus hijos en un accidente de coche en 1994, dedic\u00f3 gran parte de su tiempo a la pol\u00edtica. Pezeshkian se present\u00f3 a las elecciones presidenciales de 2013 y 2021, pero no logr\u00f3 avanzar.<\/p>\n<p>Este hombre de 69 a\u00f1os procede de una familia \u00e9tnicamente mixta: su padre es azer\u00ed y su madre kurda. El persa no es su lengua materna. Eso ha contribuido a mejorar su imagen ante las minor\u00edas iran\u00edes, pero lo deja expuesto a los ataques xen\u00f3fobos de algunos opositores.<\/p>\n<p>Seguidores sostienen carteles del candidato presidencial iran\u00ed Masoud Pezeshkian durante un acto de campa\u00f1a en Teher\u00e1n, Ir\u00e1n, el 3 de julio. (Majid Asgaripour\/WANA\/Reuters)<\/p>\n<p>\u00bfPuede traer el cambio a Ir\u00e1n?<\/p>\n<p>Seg\u00fan los expertos, un rostro m\u00e1s moderado en la presidencia podr\u00eda facilitar el di\u00e1logo entre Ir\u00e1n y los pa\u00edses occidentales. En el \u00e1mbito nacional, Pezeshkian tambi\u00e9n podr\u00eda introducir algunos cambios sociales, en los que hizo hincapi\u00e9 durante su campa\u00f1a electoral, aunque los expertos advierten de que tales medidas distan mucho de estar garantizadas.<\/p>\n<p>Sanam Vakil, directora del Programa para Oriente Medio y el Norte de \u00c1frica del grupo de expertos Chatham House de Londres, afirm\u00f3 que es poco probable que la elecci\u00f3n de Pezeshkian se traduzca inmediatamente en cambios pol\u00edticos.<\/p>\n<p>&#171;Pero Pezeshkian dej\u00f3 claro que intentar\u00e1 trabajar a trav\u00e9s y dentro del sistema para quiz\u00e1s acomodarse a un entorno menos represivo&#187;.<\/p>\n<p>El reformista no garantiz\u00f3 que pudiera hacer esos cambios, dijo Vakil, a\u00f1adiendo que esto muestra los l\u00edmites de los poderes presidenciales en Ir\u00e1n. &#171;Pero (puede a\u00f1adir) un poco m\u00e1s de margen de maniobra en materia de libertades sociales&#187;, dijo.<\/p>\n<p>Otros factores pueden ser m\u00e1s dif\u00edciles de cambiar, en particular la pol\u00edtica exterior de Ir\u00e1n.<\/p>\n<p>Pezeshkian asume la presidencia en un momento en que su pa\u00eds est\u00e1 inmerso en una escalada de tensiones con Israel y sus aliados occidentales, desencadenada por la guerra de Gaza y el avance del programa nuclear iran\u00ed. Hace solo tres meses, Ir\u00e1n e Israel intercambiaron disparos por primera vez al agravarse el conflicto de Gaza. Israel se prepara ahora para un posible segundo frente contra Hezbollah, el principal apoderado regional de Ir\u00e1n, en L\u00edbano. La ret\u00f3rica entre Ir\u00e1n e Israel se intensific\u00f3 la semana pasada, cuando la misi\u00f3n iran\u00ed ante las Naciones Unidas afirm\u00f3 que si Israel &#171;se embarca en una agresi\u00f3n militar a gran escala&#187; contra L\u00edbano, se producir\u00e1 &#171;una guerra obliteradora&#187;.<\/p>\n<p>&#171;Todas las opciones, incluida la plena participaci\u00f3n de todos los Frentes de Resistencia, est\u00e1n sobre la mesa&#187;, dijo en X.<\/p>\n<p>El ministro israel\u00ed de Asuntos Exteriores, Israel Katz, respondi\u00f3 que &#171;un r\u00e9gimen que amenaza con la destrucci\u00f3n merece ser destruido&#187;.<\/p>\n<p>No se espera que Pezeshkian cambie la trayectoria actual sobre Israel, seg\u00fan los expertos.<\/p>\n<p>Tambi\u00e9n elogi\u00f3 al general Qasem Soleimani, el controvertido jefe de la Fuerza Quds del IRCG que fue asesinado en un ataque estadounidense en 2020.<\/p>\n<p>&#171;Lo considero una fuente de orgullo nacional y una espina en los ojos de nuestros enemigos&#187;, dijo en un reciente debate presidencial.<\/p>\n<p>Masoud Pezeshkian visita la C\u00e1mara de Comercio, Industrias, Minas y Agricultura de Ir\u00e1n en Teher\u00e1n, Ir\u00e1n, el 23 de junio. (Sepehr\/Middle East Images\/AFP\/Getty Images)<\/p>\n<p>Una cara m\u00e1s amable para Occidente<\/p>\n<p>Pero aunque los Estados occidentales no esperan que estas elecciones cambien su relaci\u00f3n con Ir\u00e1n, Pezeshkian es sin duda su candidato preferido, ya que su oponente no habr\u00eda hecho sino intensificar las tensiones existentes, seg\u00fan los expertos.<\/p>\n<p>El exministro de Asuntos Exteriores Javad Zarif, aliado clave de Pezeshkian y reformista que supervis\u00f3 un periodo comparativamente m\u00e1s c\u00e1lido de las relaciones internacionales hace casi una d\u00e9cada, fue propuesto como posible candidato a ocupar su antiguo puesto bajo el nuevo presidente.<\/p>\n<p>Zarif era el principal diplom\u00e1tico iran\u00ed cuando el r\u00e9gimen lleg\u00f3 a un acuerdo con Estados Unidos y las potencias mundiales para limitar las actividades nucleares de Teher\u00e1n a cambio de un alivio de las sanciones (un acuerdo que desde entonces pr\u00e1cticamente ha fracasado). Aunque es popular entre la juventud iran\u00ed, tambi\u00e9n ha recibido cr\u00edticas de los partidarios de la l\u00ednea dura en su pa\u00eds por ser demasiado amistoso con Occidente.<\/p>\n<p>Sin embargo, antes de las elecciones, Jamenei conden\u00f3 a quienes pretend\u00edan mejorar las relaciones con Occidente. Y Pezeshkian declar\u00f3 p\u00fablicamente que se someter\u00eda a Jamenei en cuestiones de pol\u00edtica exterior, por lo que el nombramiento de Zarif no est\u00e1 nada asegurado.<\/p>\n<p>Joseph Ataman, Isaac Yee, Lucas Lilieholm, Benjamin Brown y Abbas Al Lawati de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El candidato reformista Masoud Pezeshkian gan\u00f3 las elecciones presidenciales de Ir\u00e1n derrotando a su rival de l\u00ednea dura en una votaci\u00f3n crucial en medio de crecientes tensiones tanto a nivel nacional como internacional. Lo inform\u00f3 este s\u00e1bado la autoridad electoral del pa\u00eds. De los 30,5 millones de votos escrutados en la segunda vuelta [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450920","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El candidato reformista Masoud Pezeshkian gan\u00f3 las elecciones presidenciales de Ir\u00e1n derrotando a su rival de l\u00ednea dura en una votaci\u00f3n crucial en medio de crecientes tensiones tanto a nivel nacional como internacional. Lo inform\u00f3 este s\u00e1bado la autoridad electoral del pa\u00eds. De los 30,5 millones de votos escrutados en la segunda vuelta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-06T14:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n\",\"datePublished\":\"2024-07-06T14:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/\"},\"wordCount\":1857,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/\",\"name\":\"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-06T14:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n - Noticias","og_description":"(CNN) &#8212; El candidato reformista Masoud Pezeshkian gan\u00f3 las elecciones presidenciales de Ir\u00e1n derrotando a su rival de l\u00ednea dura en una votaci\u00f3n crucial en medio de crecientes tensiones tanto a nivel nacional como internacional. Lo inform\u00f3 este s\u00e1bado la autoridad electoral del pa\u00eds. De los 30,5 millones de votos escrutados en la segunda vuelta [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-06T14:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/"},"author":{"name":"","@id":""},"headline":"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n","datePublished":"2024-07-06T14:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/"},"wordCount":1857,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/","name":"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-06T14:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\u00e1n","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/06\/pezeshkian-elecciones-presidenciales-iran-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-06T14:03:38Z","datePublished":"2024-07-06T14:03:38Z","dateModified":"2024-07-06T14:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El legislador reformista Masoud Pezeshkian gana las elecciones presidenciales en Ir\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/06\\\/pezeshkian-elecciones-presidenciales-iran-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/06\\\/pezeshkian-elecciones-presidenciales-iran-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-06T14:03:38Z\",\"datePublished\":\"2024-07-06T14:03:38Z\",\"dateModified\":\"2024-07-06T14:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451087,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/13\/presidente-electo-iran-dispuesto-encarrilar-relaciones-europa-trax\/","url_meta":{"origin":1450920,"position":0},"title":"El presidente electo de Ir\u00e1n, dispuesto a &#171;encarrilar las relaciones&#187; con Europa","author":"","date":"julio 13, 2024","format":false,"excerpt":"(CNN) -- El presidente electo de Ir\u00e1n, Masoud Pezeshkian, declar\u00f3 este viernes que espera mejorar los lazos con Europa a pesar del retroceso del continente en sus compromisos para aliviar el impacto de las sanciones estadounidenses.\"A pesar de estos pasos en falso, espero entablar un di\u00e1logo constructivo con los pa\u00edses\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450992,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/09\/paises-tienen-elecciones-2024-giuia-mapas-graficos-trax\/","url_meta":{"origin":1450920,"position":1},"title":"Al menos 70 pa\u00edses tienen elecciones en 2024. Una gu\u00eda en mapas y gr\u00e1ficos","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN) -- Mientras la carrera presidencial en Estados Unidos se intensifica, muchos otros pa\u00edses alrededor del mundo tambi\u00e9n est\u00e1n llevando a cabo elecciones cruciales en 2024. M\u00e1s de 70 naciones, hogar de casi la mitad de la poblaci\u00f3n mundial, ya han seleccionado o pronto seleccionar\u00e1n a sus propios l\u00edderes en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471985,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/03\/07\/iran-desescalada-salvedad-trax\/","url_meta":{"origin":1450920,"position":2},"title":"Ir\u00e1n env\u00eda el primer mensaje importante de desescalada, pero hace una importante salvedad","author":"","date":"marzo 7, 2026","format":false,"excerpt":"Momentos despu\u00e9s de que el presidente de Ir\u00e1n, Masoud Pezeshkian, afirmara en una declaraci\u00f3n aparentemente pregrabada que Teher\u00e1n detendr\u00eda los ataques contra sus vecinos del Golfo bajo ciertas condiciones, varios de esos pa\u00edses reportaron nuevos ataques.Estos lanzamientos fueron de los m\u00e1s grandes desde el inicio de la guerra y coincidieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461150,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/04\/13\/daniel-noboa-gana-presidencia-ecuador-segundo-mandato-orix\/","url_meta":{"origin":1450920,"position":3},"title":"Daniel Noboa gana la presidencia de Ecuador para un segundo mandato, anuncia el Consejo Nacional Electoral","author":"","date":"abril 13, 2025","format":false,"excerpt":"El presidente de Ecuador, Daniel Noboa, candidato del movimiento Acci\u00f3n Democr\u00e1tica Nacional (ADN), gan\u00f3 este domingo la segunda vuelta de las elecciones presidenciales, seg\u00fan los datos preliminares del Consejo Nacional Electoral (CNE).La presidenta del CNE, Diana Atamaint, dijo en rueda de prensa que, con el 90% de las actas computadas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456330,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/06\/rumania-anula-primera-vuelta-elecciones-trax\/","url_meta":{"origin":1450920,"position":4},"title":"El Tribunal Constitucional de Rumania anula el resultado de la primera vuelta de las elecciones presidenciales","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"El Tribunal Constitucional de Rumania anul\u00f3 la primera vuelta de las elecciones presidenciales de 2024, ganadas por un estrecho margen por el candidato de ultraderecha Calin Georgescu, en medio de acusaciones de interferencia rusa.La hist\u00f3rica decisi\u00f3n significa que la segunda vuelta, prevista para el domingo, en la que Georgescu se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463945,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/06\/25\/mito-invencibilidad-iran-roto-consecuencias-gran-alcance-trax\/","url_meta":{"origin":1450920,"position":5},"title":"El mito de la invencibilidad de Ir\u00e1n se ha roto, y las consecuencias podr\u00edan ser de gran alcance","author":"","date":"junio 25, 2025","format":false,"excerpt":"Durante m\u00e1s de tres d\u00e9cadas, Ir\u00e1n construy\u00f3 una red de grupos aliados para librar sus batallas lejos de sus fronteras, manteniendo a raya a sus enemigos mientras el l\u00edder supremo, el ayatol\u00e1 Al\u00ed Jamenei, consolidaba su poder. Los ataques directos contra Ir\u00e1n eran impensables.Esa imagen de invencibilidad se desmoron\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1450920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1450920"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1450920\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1450920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1450920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1450920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}