{"id":1450966,"date":"2024-07-08T19:03:48","date_gmt":"2024-07-09T02:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/"},"modified":"2024-07-08T19:03:48","modified_gmt":"2024-07-09T02:03:48","slug":"exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/","title":{"rendered":"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar"},"content":{"rendered":"<p>(CNN) &#8212; Un exoplaneta del tama\u00f1o de J\u00fapiter ha intrigado durante mucho tiempo a los astr\u00f3nomos debido a sus temperaturas abrasadoras, vientos fuertes y lluvia lateral hecha de vidrio. Ahora, datos del Telescopio Espacial James Webb revelaron otra caracter\u00edstica intrigante del planeta conocido como HD 189733b: huele a huevos podridos.<\/p>\n<p>Los investigadores que estudian la atm\u00f3sfera de HD 189733b utilizaron la observaci\u00f3n del Webb para detectar trazas de sulfuro de hidr\u00f3geno, un gas incoloro que libera un fuerte hedor sulf\u00farico y que nunca ha sido detectado m\u00e1s all\u00e1 de nuestro sistema solar. El descubrimiento adelanta lo que se sabe sobre la composici\u00f3n potencial de los exoplanetas.<\/p>\n<p>Los hallazgos, compilados por un equipo de varias instituciones, se publicaron el lunes en la revista Nature.<\/p>\n<p>Un planeta extra\u00f1o con un clima mortal<\/p>\n<p>Los cient\u00edficos descubrieron por primera vez HD 189733b en 2005 y luego identificaron al gigante gaseoso como un &#171;J\u00fapiter caliente&#187;, un planeta que tiene una composici\u00f3n qu\u00edmica similar a J\u00fapiter, el planeta m\u00e1s grande de nuestro sistema solar, pero con temperaturas abrasadoras. Ubicado a s\u00f3lo 64 a\u00f1os luz de la Tierra, HD 189733b es el J\u00fapiter caliente m\u00e1s cercano que los astr\u00f3nomos pueden estudiar cuando el planeta pasa frente a su estrella. Por ese motivo, es uno de los exoplanetas mejor estudiados.<\/p>\n<p>&#171;HD 189733 b no es s\u00f3lo un planeta gigante gaseoso, sino tambi\u00e9n un &#8216;gigante&#8217; en el campo de los exoplanetas porque es uno de los primeros exoplanetas en tr\u00e1nsito jam\u00e1s descubiertos&#187;, dijo el autor principal del estudio, Guangwei Fu, astrof\u00edsico de la Universidad Johns Hopkins en un correo electr\u00f3nico. &#171;Es el punto de anclaje de gran parte de nuestra comprensi\u00f3n de la qu\u00edmica y f\u00edsica atmosf\u00e9rica de los exoplanetas&#187;.<\/p>\n<p>El exoplaneta orbita muy cerca de su estrella, lo que hace que el planeta tenga una temperatura superficial abrasadora. Cr\u00e9dito: Roberto Molar Candanosa\/Universidad Johns Hopkins<\/p>\n<p>El planeta es aproximadamente un 10% m\u00e1s grande que J\u00fapiter, pero mucho m\u00e1s caliente porque est\u00e1 13 veces m\u00e1s cerca de su estrella que Mercurio de nuestro Sol. HD 189733b s\u00f3lo tarda unos dos d\u00edas terrestres en completar una \u00fanica \u00f3rbita alrededor de su estrella, explic\u00f3 Fu.<\/p>\n<p>Esa proximidad a la estrella le da al planeta una temperatura promedio abrasadora de 1.700 \u00b0F (926 \u00b0C) y fuertes vientos que env\u00edan part\u00edculas de silicato similares al vidrio que llueven lateralmente desde nubes altas alrededor del planeta a 5.000 mph (8.046 km\/h).<\/p>\n<p>Un hedor sorprendente<\/p>\n<p>Cuando los astr\u00f3nomos decidieron utilizar el telescopio Webb para estudiar el planeta y ver qu\u00e9 pod\u00eda revelar la luz infrarroja, que es invisible al ojo humano, en la atm\u00f3sfera de HD 189733b, se llevaron una sorpresa.<\/p>\n<p>El sulfuro de hidr\u00f3geno est\u00e1 presente en J\u00fapiter y se predijo que existir\u00eda en exoplanetas gigantes gaseosos, pero la evidencia de la mol\u00e9cula hab\u00eda sido esquiva fuera de nuestro sistema solar, dijo Fu.<\/p>\n<p>&#171;El sulfuro de hidr\u00f3geno es uno de los principales reservorios de azufre en las atm\u00f3sferas planetarias&#187;, dijo Fu. \u201cLa alta precisi\u00f3n y la capacidad infrarroja (del telescopio Webb) nos permiten detectar sulfuro de hidr\u00f3geno por primera vez en exoplanetas, lo que abre una nueva ventana espectral para estudiar la qu\u00edmica del azufre atmosf\u00e9rico de exoplanetas. Esto nos ayuda a comprender de qu\u00e9 est\u00e1n hechos los exoplanetas y c\u00f3mo surgieron\u201d.<\/p>\n<p>Adem\u00e1s, el equipo detect\u00f3 agua, di\u00f3xido de carbono y mon\u00f3xido de carbono en la atm\u00f3sfera del planeta, dijo Fu, lo que significa que estas mol\u00e9culas podr\u00edan ser comunes en otros exoplanetas gigantes gaseosos.<\/p>\n<p>El telescopio Webb descubre por qu\u00e9 un exoplaneta se asemeja a un &#171;malvavisco&#187;<\/p>\n<p>Si bien los astr\u00f3nomos no esperan que exista vida en HD 189733b debido a sus temperaturas abrasadoras, la detecci\u00f3n de un componente b\u00e1sico como el azufre en un exoplaneta arroja luz sobre la formaci\u00f3n del planeta, dijo Fu.<\/p>\n<p>&#171;El azufre es un elemento vital para construir mol\u00e9culas m\u00e1s complejas y, al igual que el carbono, el nitr\u00f3geno, el ox\u00edgeno y el fosfato, los cient\u00edficos necesitan estudiarlo m\u00e1s para comprender completamente c\u00f3mo se forman los planetas y de qu\u00e9 est\u00e1n hechos&#187;, afirm\u00f3 Fu.<\/p>\n<p>Anteriormente se ha detectado mol\u00e9culas con olores distintos, como el amon\u00edaco, en atm\u00f3sferas de otros exoplanetas.<\/p>\n<p>Pero las capacidades del Webb permiten a los cient\u00edficos identificar sustancias qu\u00edmicas espec\u00edficas dentro de las atm\u00f3sferas alrededor de exoplanetas con mayor detalle que antes.<\/p>\n<p>Metales pesados \u200b\u200bplanetarios<\/p>\n<p>En nuestro sistema solar, los gigantes de hielo como Neptuno y Urano, aunque menos masivos en general, contienen m\u00e1s metales que los gigantes gaseosos J\u00fapiter y Saturno, que son los planetas m\u00e1s grandes, lo que sugiere que podr\u00eda haber una correlaci\u00f3n entre el contenido de metales y la masa.<\/p>\n<p>Los astr\u00f3nomos creen que en la formaci\u00f3n de Neptuno y Urano intervinieron m\u00e1s hielo, rocas y metales, en lugar de gases como el hidr\u00f3geno y el helio.<\/p>\n<p>Los datos del Webb tambi\u00e9n mostraron niveles de metales pesados \u200b\u200ben HD 189733b similares a los encontrados en J\u00fapiter.<\/p>\n<p>El telescopio Webb revela datos de un exoplaneta de gas caliente a 280 a\u00f1os luz de la Tierra<\/p>\n<p>&#171;Ahora tenemos esta nueva medici\u00f3n para mostrar que, de hecho, las concentraciones de metales (el planeta) han proporcionado un punto de anclaje muy importante para este estudio de c\u00f3mo la composici\u00f3n de un planeta var\u00eda con su masa y radio&#187;, dijo Fu. &#171;Los hallazgos respaldan nuestra comprensi\u00f3n de c\u00f3mo se forman los planetas mediante la creaci\u00f3n de m\u00e1s material s\u00f3lido despu\u00e9s de la formaci\u00f3n inicial del n\u00facleo y luego se mejoran naturalmente con metales pesados&#187;.<\/p>\n<p>Ahora, el equipo buscar\u00e1 firmas de azufre en otros exoplanetas y determinar\u00e1 si las altas concentraciones del compuesto influyen en la cercan\u00eda con la que se forman algunos planetas en relaci\u00f3n con sus estrellas anfitrionas.<\/p>\n<p>&#171;HD 189733b es un planeta de referencia, pero representa s\u00f3lo un punto de datos&#187;, dijo Fu. \u201cAs\u00ed como los seres humanos exhiben caracter\u00edsticas \u00fanicas, nuestros comportamientos colectivos siguen tendencias y patrones claros. Con m\u00e1s conjuntos de datos del Webb por venir, nuestro objetivo es comprender c\u00f3mo se forman los planetas y si nuestro sistema solar es \u00fanico en la galaxia\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un exoplaneta del tama\u00f1o de J\u00fapiter ha intrigado durante mucho tiempo a los astr\u00f3nomos debido a sus temperaturas abrasadoras, vientos fuertes y lluvia lateral hecha de vidrio. Ahora, datos del Telescopio Espacial James Webb revelaron otra caracter\u00edstica intrigante del planeta conocido como HD 189733b: huele a huevos podridos. Los investigadores que estudian la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450966","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un exoplaneta del tama\u00f1o de J\u00fapiter ha intrigado durante mucho tiempo a los astr\u00f3nomos debido a sus temperaturas abrasadoras, vientos fuertes y lluvia lateral hecha de vidrio. Ahora, datos del Telescopio Espacial James Webb revelaron otra caracter\u00edstica intrigante del planeta conocido como HD 189733b: huele a huevos podridos. Los investigadores que estudian la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T02:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar\",\"datePublished\":\"2024-07-09T02:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/\"},\"wordCount\":1133,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/\",\"name\":\"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-09T02:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar - Noticias","og_description":"(CNN) &#8212; Un exoplaneta del tama\u00f1o de J\u00fapiter ha intrigado durante mucho tiempo a los astr\u00f3nomos debido a sus temperaturas abrasadoras, vientos fuertes y lluvia lateral hecha de vidrio. Ahora, datos del Telescopio Espacial James Webb revelaron otra caracter\u00edstica intrigante del planeta conocido como HD 189733b: huele a huevos podridos. Los investigadores que estudian la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-09T02:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/"},"author":{"name":"","@id":""},"headline":"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar","datePublished":"2024-07-09T02:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/"},"wordCount":1133,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/","name":"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-09T02:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\u00e9cula no encontrada antes fuera de nuestro sistema solar","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/08\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-09T02:03:48Z","datePublished":"2024-07-09T02:03:48Z","dateModified":"2024-07-09T02:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un exoplaneta cercano apesta a huevos podridos, lo que revela una mol\\u00e9cula no encontrada antes fuera de nuestro sistema solar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/08\\\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/08\\\/exoplaneta-que-huele-a-huevos-podridos-telescopio-webb-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-09T02:03:48Z\",\"datePublished\":\"2024-07-09T02:03:48Z\",\"dateModified\":\"2024-07-09T02:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1449746,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/05\/24\/cientificos-descubren-planeta-teoricamente-habitable-tierra-gliese-12b-trax\/","url_meta":{"origin":1450966,"position":0},"title":"Los cient\u00edficos descubrieron un planeta te\u00f3ricamente habitable del tama\u00f1o de la Tierra","author":"","date":"mayo 24, 2024","format":false,"excerpt":"(CNN) --Dos equipos de cient\u00edficos descubrieron un planeta te\u00f3ricamente habitable, m\u00e1s peque\u00f1o que la Tierra pero m\u00e1s grande que Venus, que orbita una peque\u00f1a estrella a unos 40 a\u00f1os luz de distancia.El exoplaneta, llamado Gliese 12b, orbita una fr\u00eda estrella enana roja situada en la constelaci\u00f3n de Piscis y tiene\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451242,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/18\/extrano-planeta-orbita-invertida-juiter-gemelo-trax\/","url_meta":{"origin":1450966,"position":1},"title":"Un extra\u00f1o planeta con una \u00f3rbita invertida en forma de pepino se est\u00e1 convirtiendo en otro tipo de mundo","author":"","date":"julio 18, 2024","format":false,"excerpt":"(CNN) -- Astr\u00f3nomos han detectado un exoplaneta con una \u00f3rbita muy oblonga que experimenta cambios bruscos de temperatura, y que podr\u00eda estar convirti\u00e9ndose en otro tipo de mundo.El exoplaneta, denominado TIC 241249530 b, orbita alrededor de una estrella situada a unos 1.100 a\u00f1os-luz de la Tierra. La estrella forma parte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461304,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/04\/17\/cientificos-vida-en-un-planeta-alienigena-reux\/","url_meta":{"origin":1450966,"position":2},"title":"Los cient\u00edficos encuentran la evidencia m\u00e1s s\u00f3lida hasta el momento de vida en un planeta alien\u00edgena","author":"","date":"abril 17, 2025","format":false,"excerpt":"En un descubrimiento potencialmente hist\u00f3rico, cient\u00edficos que utilizan el telescopio espacial James Webb han obtenido lo que llaman las se\u00f1ales m\u00e1s fuertes hasta ahora de posible vida m\u00e1s all\u00e1 de nuestro sistema solar, detectando en la atm\u00f3sfera de un planeta alien\u00edgena las huellas qu\u00edmicas de gases que en la Tierra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450419,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/06\/16\/telescopio-webb-colision-asteroides-gigantes-trax\/","url_meta":{"origin":1450966,"position":3},"title":"Observaciones del telescopio Webb insin\u00faan una colisi\u00f3n de asteroides gigantes en un sistema planetario cercano","author":"","date":"junio 16, 2024","format":false,"excerpt":"(CNN) -- Es probable que en los \u00faltimos a\u00f1os se haya producido una colisi\u00f3n entre asteroides gigantes en un sistema estelar vecino llamado Beta Pictoris. Dos observatorios espaciales diferentes ayudan a contar la historia.El sistema Beta Pictoris, ubicado a 63 a\u00f1os luz de la Tierra, intrig\u00f3 durante mucho tiempo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469371,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/12\/17\/cometa-interestelar-3iatlas-aproximacion-tierra-orix\/","url_meta":{"origin":1450966,"position":4},"title":"El cometa interestelar 3I\/ATLAS har\u00e1 su aproximaci\u00f3n m\u00e1s cercana a la Tierra: as\u00ed capt\u00f3 la atenci\u00f3n del mundo","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"El cometa 3I\/ATLAS ha captado la atenci\u00f3n del mundo este a\u00f1o debido a que se sabe muy poco de su origen: proviene del espacio profundo y es tan solo el tercer objeto interestelar jam\u00e1s observado despu\u00e9s del 1I\/\u02bbOumuamua en 2017 y el 2I\/Borisov en 2019.Se infiere que es un objeto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473728,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/05\/02\/cometa-interestelar-sistema-solar-trax\/","url_meta":{"origin":1450966,"position":5},"title":"\u00bfDe d\u00f3nde ven\u00eda el cometa 3I\/ATLAS? Estudios revelan que se form\u00f3 en un sistema muy distinto al nuestro","author":"","date":"mayo 2, 2026","format":false,"excerpt":"Astr\u00f3nomos que utilizan observaciones con radiotelescopios para analizar en detalle un cometa interestelar han obtenido nuevos indicios sobre cu\u00e1ndo y d\u00f3nde se form\u00f3 este objeto celeste.El cometa, llamado 3I\/ATLAS, capt\u00f3 la atenci\u00f3n mundial cuando los investigadores lo detectaron por primera vez atravesando nuestro sistema solar en julio. Es apenas el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1450966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1450966"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1450966\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1450966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1450966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1450966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}