{"id":1451022,"date":"2024-07-10T18:03:52","date_gmt":"2024-07-11T01:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/"},"modified":"2024-07-10T18:03:52","modified_gmt":"2024-07-11T01:03:52","slug":"canciller-venezuela-maduro-desventaja-elecciones-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/","title":{"rendered":"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El canciller de Venezuela, Yv\u00e1n Gil, dijo este mi\u00e9rcoles que el presidente Nicol\u00e1s Maduro parte en \u201cclara desventaja\u201d rumbo a las elecciones del 28 de julio, debido a las sanciones internacionales.<\/p>\n<p>\u201cSon unas elecciones que vamos en clara distorsi\u00f3n, desventaja, que tiene el candidato a la reelecci\u00f3n (el presidente Nicol\u00e1s Maduro). Este Gobierno ha sido sometido a una pol\u00edtica de sanciones, una pol\u00edtica de agresiones (\u2026) 936 sanciones que han ido al coraz\u00f3n del ejercicio del Gobierno\u201d, dijo Gil.<\/p>\n<p>El d\u00eda despu\u00e9s de las elecciones en Venezuela: el an\u00e1lisis de Andr\u00e9s Oppenheimer<\/p>\n<p>El canciller venezolano dijo tambi\u00e9n que \u201ca pesar de las sanciones\u201d no se suspender\u00e1 la elecci\u00f3n presidencial prevista para el 28 de julio.<\/p>\n<p>Gil inform\u00f3 que ya hay confirmados m\u00e1s de 625 veedores electorales que observar\u00e1n el desarrollo de la elecci\u00f3n. Sin embargo, no habr\u00eda ninguno de la Uni\u00f3n Europea, ya que el Consejo Nacional Electoral venezolano revoc\u00f3 en mayo la invitaci\u00f3n a los observadores del bloque, tras criticar la ratificaci\u00f3n de la mayor\u00eda de las sanciones contra el pa\u00eds.<\/p>\n<p>En una reuni\u00f3n con el cuerpo diplom\u00e1tico acreditado en Venezuela, Gil defini\u00f3 al sistema electoral venezolano como uno de los sistemas electorales \u201cde mayor perfecci\u00f3n que existen\u201d.<\/p>\n<p>Sin embargo, la oposici\u00f3n ha se\u00f1alado y denunciado varias irregularidades.<\/p>\n<p>Estas son algunas de las propuestas de Nicol\u00e1s Maduro como candidato a las elecciones presidenciales de Venezuela<\/p>\n<p>La opositora Mar\u00eda Corina Machado, cuya candidatura fue inhabilitada en enero por el Tribunal Supremo Electoral venezolano, dijo en una entrevista en Oppenheimer Presenta en mayo que \u201ceste es un terreno totalmente inclinado, aqu\u00ed no son elecciones limpias, libres, tenemos unas condiciones absolutamente adversas y un Consejo Nacional Electoral totalmente sumiso y sometido al r\u00e9gimen\u201d.<\/p>\n<p>El principal candidato de la oposici\u00f3n, Edmundo Gonz\u00e1lez Urrutia, se manifest\u00f3 en el mismo sentido, al afirmar que \u201cestas elecciones no se celebran con las garant\u00edas que debe tener una elecci\u00f3n democr\u00e1tica\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El canciller de Venezuela, Yv\u00e1n Gil, dijo este mi\u00e9rcoles que el presidente Nicol\u00e1s Maduro parte en \u201cclara desventaja\u201d rumbo a las elecciones del 28 de julio, debido a las sanciones internacionales. \u201cSon unas elecciones que vamos en clara distorsi\u00f3n, desventaja, que tiene el candidato a la reelecci\u00f3n (el presidente Nicol\u00e1s Maduro). Este [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1451022","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El canciller de Venezuela, Yv\u00e1n Gil, dijo este mi\u00e9rcoles que el presidente Nicol\u00e1s Maduro parte en \u201cclara desventaja\u201d rumbo a las elecciones del 28 de julio, debido a las sanciones internacionales. \u201cSon unas elecciones que vamos en clara distorsi\u00f3n, desventaja, que tiene el candidato a la reelecci\u00f3n (el presidente Nicol\u00e1s Maduro). Este [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T01:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales\",\"datePublished\":\"2024-07-11T01:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/\",\"name\":\"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-11T01:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El canciller de Venezuela, Yv\u00e1n Gil, dijo este mi\u00e9rcoles que el presidente Nicol\u00e1s Maduro parte en \u201cclara desventaja\u201d rumbo a las elecciones del 28 de julio, debido a las sanciones internacionales. \u201cSon unas elecciones que vamos en clara distorsi\u00f3n, desventaja, que tiene el candidato a la reelecci\u00f3n (el presidente Nicol\u00e1s Maduro). Este [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-11T01:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/"},"author":{"name":"","@id":""},"headline":"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales","datePublished":"2024-07-11T01:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/","name":"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-11T01:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Canciller de Venezuela dice que Maduro va con \u201cdesventaja\u201d a las elecciones presidenciales","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/07\/10\/canciller-venezuela-maduro-desventaja-elecciones-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-11T01:03:52Z","datePublished":"2024-07-11T01:03:52Z","dateModified":"2024-07-11T01:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Canciller de Venezuela dice que Maduro va con \\u201cdesventaja\\u201d a las elecciones presidenciales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/10\\\/canciller-venezuela-maduro-desventaja-elecciones-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/07\\\/10\\\/canciller-venezuela-maduro-desventaja-elecciones-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-11T01:03:52Z\",\"datePublished\":\"2024-07-11T01:03:52Z\",\"dateModified\":\"2024-07-11T01:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452406,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","url_meta":{"origin":1451022,"position":0},"title":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Gobierno de Estados Unidos mantiene sanciones sectoriales e individuales sobre Venezuela y contin\u00faa evaluando su pol\u00edtica hacia el pa\u00eds sudamericano, al que incaut\u00f3 un avi\u00f3n utilizado por el presidente Nicol\u00e1s Maduro, seg\u00fan anunci\u00f3\u00a0este lunes el Departamento de Estado estadounidense.El secretario de Justicia de Estados Unidos, Merrick Garland,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451501,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/07\/30\/sanciones-eeuu-venezuela-elecciones-orix\/","url_meta":{"origin":1451022,"position":1},"title":"\u00bfQu\u00e9 podr\u00eda pasar con las sanciones de EE.UU. a Venezuela tras las elecciones?","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La situaci\u00f3n en Venezuela tras las elecciones de este domingo se vuelve cada vez m\u00e1s compleja, mientras siguen sin difundirse datos oficiales adicionales de los resultados y tanto el oficialismo como la oposici\u00f3n se adjudican el triunfo. \u00bfC\u00f3mo puede afectar esto al pa\u00eds en cuanto a sanciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444679,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/01\/30\/estados-unidos-reactiva-sanciones-al-sector-de-petroleo-y-gas-de-venezuela-en-reaccion-a-la-inhabilitacion-de-la-candidatura-de-maria-corina-machado\/","url_meta":{"origin":1451022,"position":2},"title":"Estados Unidos reactiva sanciones al sector de petr\u00f3leo y gas de Venezuela en reacci\u00f3n a la inhabilitaci\u00f3n de la candidatura de Mar\u00eda Corina Machado","author":"","date":"enero 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Estados Unidos anunci\u00f3 este martes que reactivar\u00e1 las sanciones al sector de petr\u00f3leo y gas de Venezuela, en respuesta a la decisi\u00f3n del Tribunal Supremo de Justicia venezolano (TSJ) de inhabilitar la candidatura de la opositora Mar\u00eda Corina Machado.Tribunal Supremo de Venezuela inhabilita la candidatura presidencial de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444726,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/01\/31\/estados-unidos-reactiva-sanciones-al-sector-de-petroleo-y-gas-de-venezuela-en-reaccion-a-la-inhabilitacion-de-la-candidatura-de-maria-corina-machado-2\/","url_meta":{"origin":1451022,"position":3},"title":"Estados Unidos reactiva sanciones al sector de petr\u00f3leo y gas de Venezuela en reacci\u00f3n a la inhabilitaci\u00f3n de la candidatura de Mar\u00eda Corina Machado","author":"","date":"enero 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Estados Unidos anunci\u00f3 este martes que reactivar\u00e1 las sanciones al sector de petr\u00f3leo y gas de Venezuela, en respuesta a la decisi\u00f3n del Tribunal Supremo de Justicia venezolano (TSJ) de inhabilitar la candidatura de la opositora Mar\u00eda Corina Machado.Tribunal Supremo de Venezuela inhabilita la candidatura presidencial de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456117,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/11\/27\/ee-uu-sancionara-funcionarios-afines-maduro-venezuela-trax\/","url_meta":{"origin":1451022,"position":4},"title":"EE.UU. sancionar\u00e1 a m\u00e1s de 20 funcionarios afines a Maduro para presionar al presidente de Venezuela a aceptar los resultados electorales","author":"","date":"noviembre 27, 2024","format":false,"excerpt":"(CNN) -- Estados Unidos anunciar\u00e1 el mi\u00e9rcoles nuevas sanciones individuales a m\u00e1s de 20 funcionarios alineados con el presidente autoritario de Venezuela, Nicol\u00e1s Maduro, para presionarlo a aceptar los resultados de las elecciones presidenciales de julio en Venezuela, dijeron funcionarios de alto rango de la administraci\u00f3n en una sesi\u00f3n informativa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468651,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/11\/24\/maduro-sanciones-eeuu-venezuela-cartel-soles-orix\/","url_meta":{"origin":1451022,"position":5},"title":"Tras designaci\u00f3n del Cartel de los Soles, Maduro podr\u00eda recibir m\u00e1s sanciones \u00bfCu\u00e1les ya se aplicaron sobre \u00e9l y su Gobierno?","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"El Gobierno de Estados Unidos mantiene una serie de sanciones sectoriales e individuales sobre Venezuela, pero estas podr\u00edan ampliarse con m\u00e1s medidas contra los activos y la infraestructura del presidente Nicol\u00e1s Maduro, luego de la designaci\u00f3n del \u201cCartel de los Soles\u201d como organizaci\u00f3n terrorista extranjera.Las sanciones son medidas del Departamento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1451022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1451022"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1451022\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1451022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1451022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1451022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}