{"id":1456435,"date":"2024-12-10T12:03:41","date_gmt":"2024-12-10T20:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/"},"modified":"2024-12-10T12:03:41","modified_gmt":"2024-12-10T20:03:41","slug":"trump-registros-kash-patel-filtraciones-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/","title":{"rendered":"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones"},"content":{"rendered":"<p>El Departamento de Justicia obtuvo en secreto registros telef\u00f3nicos de dos miembros del Congreso y 43 empleados, incluido <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/11\/30\/trump-quiere-reemplazar-director-fbi-kash-patel-trax\">Kash Patel, la selecci\u00f3n del presidente electo Donald Trump para dirigir el FBI<\/a>, durante amplias investigaciones de filtraciones en el primer mandato de Trump, seg\u00fan un <a href=\"https:\/\/oig.justice.gov\/sites\/default\/files\/reports\/25-010.pdf\">informe de supervisi\u00f3n publicado este martes<\/a>.<\/p>\n<p>El nuevo informe del inspector general del Departamento de Justicia plantea inquietudes sobre c\u00f3mo el departamento intent\u00f3 eliminar las fuentes de los periodistas de una lista extensa y bipartidista de empleados federales que ten\u00edan acceso a informaci\u00f3n clasificada debido a su trabajo.<\/p>\n<p>En el informe no se nombra a Patel ni a los dos miembros del Congreso, pero dos fuentes familiarizadas con el asunto le dijeron a CNN que Patel fue el blanco de los ataques junto con los representantes dem\u00f3cratas <a href=\"https:\/\/www.cnn.com\/2024\/11\/17\/politics\/video\/adam-schiff-donald-trump-enemy-from-within-response-sotu-digvid\">Adam Schiff<\/a> y Eric Swalwell. Patel era miembro del personal del Comit\u00e9 de Inteligencia de la C\u00e1mara de Representantes, liderado por el Partido Republicano y Schiff fue elegido senador y asumi\u00f3 el cargo este lunes.<\/p>\n<p>Los fiscales tambi\u00e9n buscaron registros que inclu\u00edan correos electr\u00f3nicos de periodistas de CNN, The Washington Post y The New York Times, seg\u00fan el informe.<\/p>\n<p>El informe encontr\u00f3 que los investigadores del Departamento de Justicia realizaron una b\u00fasqueda amplia en funci\u00f3n de qui\u00e9n pudo haber tenido acceso a la informaci\u00f3n confidencial que se filtr\u00f3.<\/p>\n<p>Solicitar registros bas\u00e1ndose \u00fanicamente en \u201cla proximidad temporal entre el acceso a la informaci\u00f3n clasificada y la posterior publicaci\u00f3n de la informaci\u00f3n\u2026 corre el riesgo de enfriar la capacidad del Congreso de supervisar el poder ejecutivo\u201d, escribi\u00f3 el inspector general.<\/p>\n<p>Esto se debe a que tal medida \u201cexpone a los funcionarios del Congreso a que sus registros sean revisados \u200b\u200bpor el Departamento \u00fanicamente por llevar a cabo los deberes de supervisi\u00f3n autorizados constitucionalmente del Congreso y crea, como m\u00ednimo, la apariencia de una interferencia inapropiada del poder ejecutivo en la actividad de supervisi\u00f3n leg\u00edtima del poder legislativo\u201d, agreg\u00f3 el inspector general.<\/p>\n<p>El inspector general no recomend\u00f3 presentar cargos contra nadie en su revisi\u00f3n y no encontr\u00f3 ninguna indicaci\u00f3n de que los fiscales de carrera asignados a la investigaci\u00f3n de la filtraci\u00f3n estuvieran motivados por la pol\u00edtica.<\/p>\n<p>Patel, reunido con senadores este martes para abordar su pr\u00f3xima confirmaci\u00f3n como director del FBI, no hizo comentarios sobre el informe.<\/p>\n<p>Entre los problemas que se\u00f1al\u00f3 el inspector general est\u00e1 que no existen protecciones para los fiscales que quieren solicitar registros de comunicaciones de los miembros del Congreso o de su personal, y que si bien existen algunas protecciones para los periodistas, no se cumplen adecuadamente.<\/p>\n<p>Por ejemplo, los fiscales no tuvieron que informar a los l\u00edderes del Departamento de Justicia que los registros que buscaban eran los de miembros del Congreso, y Bill Barr, quien era el secretario de Justicia en ese momento, dijo que \u201cno ten\u00eda conocimiento de que se buscaran los registros de ning\u00fan congresista en un caso de filtraci\u00f3n\u201d. Barr se neg\u00f3 a ser entrevistado como parte de la revisi\u00f3n del asunto por parte del inspector general.<\/p>\n<p>El informe tambi\u00e9n se\u00f1ala que el Departamento de Justicia obtuvo \u00f3rdenes de confidencialidad en 40 de los casos del Congreso, lo que significa que los miembros y su personal no sab\u00edan que se hab\u00edan confiscado sus registros de comunicaciones. Al solicitar esas \u00f3rdenes, los fiscales no estaban obligados a especificar de qu\u00e9 registros estaban tratando de obtener informaci\u00f3n.<\/p>\n<p>Si bien los periodistas tienen m\u00e1s protecciones descritas en las reglas del Departamento de Justicia, el informe detalla violaciones de ese protocolo en los esfuerzos del departamento por obtener secretamente comunicaciones de ocho periodistas en organizaciones de noticias.<\/p>\n<p>Dentro de CNN, la administraci\u00f3n Trump busc\u00f3 y obtuvo en secreto los registros telef\u00f3nicos y de correo electr\u00f3nico de 2017 de la corresponsal del Pent\u00e1gono, <a href=\"https:\/\/www.cnn.com\/2021\/06\/09\/politics\/trump-pursuit-cnn-reporter-records-secret-court-battle\/index.html\">Barbara Starr<\/a>. El Departamento de Justicia de Biden inform\u00f3 m\u00e1s tarde a Starr que los fiscales hab\u00edan obtenido sus registros correspondientes a dos meses entre el 1 de junio de 2017 y el 30 de julio de 2017. No est\u00e1 claro qu\u00e9 buscaba la administraci\u00f3n Trump en los registros de Starr.<\/p>\n<p>El inspector general descubri\u00f3 que los fiscales no hab\u00edan seguido algunas de las directrices del departamento que les ordenaban agotar todas las dem\u00e1s opciones de investigaci\u00f3n antes de solicitar citaciones judiciales para obtener los registros de los periodistas. Entre esas fallas est\u00e1 que nunca se convoc\u00f3 un comit\u00e9 interno que se supone debe revisar las solicitudes de citaci\u00f3n judicial para obtener los registros de los periodistas, dice el informe.<\/p>\n<p>En una investigaci\u00f3n de filtraci\u00f3n, los fiscales no obtuvieron la certificaci\u00f3n requerida del director de Inteligencia Nacional, dijo el inspector general. En otra, obtuvieron la certificaci\u00f3n requerida, pero no est\u00e1 claro si alguna vez se le proporcion\u00f3 a Barr, entonces secretario de Justicia.<\/p>\n<p>Los fiscales tampoco lograron obtener la aprobaci\u00f3n de Barr, que era un paso necesario en el proceso para obtener \u00f3rdenes de confidencialidad que imped\u00edan que los periodistas se enteraran de que sus registros hab\u00edan sido confiscados.<\/p>\n<p>Despu\u00e9s de que se revelara p\u00fablicamente el intento de obtener los registros, el Departamento de Justicia codific\u00f3 una norma que proh\u00edbe a los empleados del departamento buscar en secreto los registros de los periodistas, salvo en circunstancias limitadas. Seg\u00fan las normas anteriores del Departamento de Justicia, los investigadores pod\u00edan obtener en secreto los registros de los periodistas mediante una orden judicial sin el conocimiento de los periodistas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Justicia obtuvo en secreto registros telef\u00f3nicos de dos miembros del Congreso y 43 empleados, incluido Kash Patel, la selecci\u00f3n del presidente electo Donald Trump para dirigir el FBI, durante amplias investigaciones de filtraciones en el primer mandato de Trump, seg\u00fan un informe de supervisi\u00f3n publicado este martes. El nuevo informe del inspector [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456435","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Departamento de Justicia obtuvo en secreto registros telef\u00f3nicos de dos miembros del Congreso y 43 empleados, incluido Kash Patel, la selecci\u00f3n del presidente electo Donald Trump para dirigir el FBI, durante amplias investigaciones de filtraciones en el primer mandato de Trump, seg\u00fan un informe de supervisi\u00f3n publicado este martes. El nuevo informe del inspector [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T20:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones\",\"datePublished\":\"2024-12-10T20:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/\"},\"wordCount\":976,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/\",\"name\":\"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-10T20:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones - Noticias","og_description":"El Departamento de Justicia obtuvo en secreto registros telef\u00f3nicos de dos miembros del Congreso y 43 empleados, incluido Kash Patel, la selecci\u00f3n del presidente electo Donald Trump para dirigir el FBI, durante amplias investigaciones de filtraciones en el primer mandato de Trump, seg\u00fan un informe de supervisi\u00f3n publicado este martes. El nuevo informe del inspector [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-10T20:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/"},"author":{"name":"","@id":""},"headline":"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones","datePublished":"2024-12-10T20:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/"},"wordCount":976,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/","name":"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-10T20:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/10\/trump-registros-kash-patel-filtraciones-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-10T20:03:41Z","datePublished":"2024-12-10T20:03:41Z","dateModified":"2024-12-10T20:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Departamento de Justicia de Trump obtuvo en secreto registros de Kash Patel, legisladores y medios por filtraciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/10\\\/trump-registros-kash-patel-filtraciones-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/10\\\/trump-registros-kash-patel-filtraciones-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-10T20:03:41Z\",\"datePublished\":\"2024-12-10T20:03:41Z\",\"dateModified\":\"2024-12-10T20:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461936,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/05\/03\/trump-periodismo-investigacion-trax\/","url_meta":{"origin":1456435,"position":0},"title":"Trump intenta frenar el periodismo de investigaci\u00f3n que le pide rendir cuentas","author":"","date":"mayo 3, 2025","format":false,"excerpt":"Gran parte de lo que el p\u00fablico sabe sobre el ca\u00f3tico Gobierno del presidente Donald Trump procede de s\u00f3lidas investigaciones period\u00edsticas, incluidas filtraciones de fuentes an\u00f3nimas del gobierno.Pero Trump y sus ayudantes est\u00e1n tratando activamente de impedir esta informaci\u00f3n e intimidar a los medios de comunicaci\u00f3n, creando un sombr\u00edo tel\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459138,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/02\/24\/dan-bongino-subdirector-fbi-trump-trax\/","url_meta":{"origin":1456435,"position":1},"title":"El presentador de podcast y exagente del Servicio Secreto Dan Bongino ser\u00e1 subdirector del FBI, seg\u00fan Trump","author":"","date":"febrero 24, 2025","format":false,"excerpt":"Dan Bongino, un exagente del Servicio Secreto convertido en podcaster de derecha, fue nombrado pr\u00f3ximo subdirector del FBI, seg\u00fan anunci\u00f3 este domingo el presidente Donald Trump, la \u00faltima personalidad medi\u00e1tica fuera del establishment que el mandatario ha elegido para ocupar un importante puesto de poder supervisando grandes ramas de complejas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465757,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/08\/22\/fbi-registra-casa-john-bolton-trax\/","url_meta":{"origin":1456435,"position":2},"title":"El FBI registra la casa de John Bolton como parte de una investigaci\u00f3n de seguridad nacional","author":"","date":"agosto 22, 2025","format":false,"excerpt":"El FBI llev\u00f3 a cabo un registro autorizado por un tribunal en el domicilio de John Bolton como parte de una investigaci\u00f3n de seguridad nacional para determinar si revel\u00f3 informaci\u00f3n clasificada en su libro de 2020, seg\u00fan dos personas familiarizadas con el asunto.CNN observ\u00f3 a personal del FBI en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466414,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/13\/crecientes-preocupaciones-liderazgo-patel-fbi-trax\/","url_meta":{"origin":1456435,"position":3},"title":"&#171;Es inaceptable&#187;: Crecientes preocupaciones sobre el liderazgo de Patel en el FBI","author":"","date":"septiembre 13, 2025","format":false,"excerpt":"Al acercarse al micr\u00f3fono en una conferencia de prensa este viernes por la ma\u00f1ana en Utah, el director del FBI, Kash Patel, no perdi\u00f3 tiempo en explicar lo que llev\u00f3 a la captura del sospechoso del asesinato del activista conservador Charlie Kirk.\u201cEsto es lo que pasa cuando dejas que los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473330,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/20\/kash-patel-demanda-difamacion-atlantic-trax\/","url_meta":{"origin":1456435,"position":4},"title":"El director del FBI, Kash Patel, presenta una demanda por difamaci\u00f3n de US$ 250 millones contra la revista The Atlantic","author":"","date":"abril 20, 2026","format":false,"excerpt":"El director del FBI, Kash Patel, demand\u00f3 a la revista The Atlantic y a la periodista Sarah Fitzpatrick por un art\u00edculo que alegaba que Patel \u201cha alarmado a colegas con episodios de consumo excesivo de alcohol y ausencias inexplicables\u201d.La demanda por difamaci\u00f3n, presentada la ma\u00f1ana de este lunes ante un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460284,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/03\/22\/pentagono-investigacion-filtraciones-pruebas-poligrafo-trax\/","url_meta":{"origin":1456435,"position":5},"title":"El Pent\u00e1gono anuncia una investigaci\u00f3n sobre filtraciones que incluir\u00e1 pruebas de pol\u00edgrafo","author":"","date":"marzo 22, 2025","format":false,"excerpt":"El Departamento de Defensa est\u00e1 investigando \u201crecientes divulgaciones no autorizadas de informaci\u00f3n de seguridad nacional\u201d y planea usar pol\u00edgrafos, conocidos com\u00fanmente como \u201cdetectores de mentiras\u201d como parte de la investigaci\u00f3n, seg\u00fan un memorando publicado en el sitio web del departamento el viernes.\u201cEl uso de pol\u00edgrafos en la ejecuci\u00f3n de esta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1456435"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456435\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1456435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1456435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1456435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}