{"id":1456473,"date":"2024-12-11T09:03:46","date_gmt":"2024-12-11T17:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/"},"modified":"2024-12-11T09:03:46","modified_gmt":"2024-12-11T17:03:46","slug":"sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/","title":{"rendered":"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU."},"content":{"rendered":"<p>Ante la designaci\u00f3n que hizo el presidente electo, Donald Trump, de nombrar nuevo embajador de Estados Unidos en M\u00e9xico a Ronald Johnson, la presidenta de este pa\u00eds, Claudia Sheinbaum, dijo durante su rueda de prensa matutina que \u201ccon este embajador o con otros siempre defender\u00e1 la soberan\u00eda, y la condici\u00f3n de igualdad\u201d.<\/p>\n<p>La mandataria a\u00f1adi\u00f3 que \u201cse va a colaborar y cooperar en todo lo que se requiera, y subray\u00f3 que siempre ser\u00e1 en inter\u00e9s del pueblo de M\u00e9xico y de la naci\u00f3n\u201d.<\/p>\n<p>Trump design\u00f3 a Johnson en el cargo el martes y lo anunci\u00f3 con un mensaje en su red Truth Social. \u201cRon trabajar\u00e1 de cerca con nuestro gran nominado para la Secretar\u00eda de Estado, Marco Rubio, para promover la seguridad y prosperidad de nuestra naci\u00f3n\u201d, dijo Trump.<\/p>\n<p>\u201cJuntos, pondremos fin al crimen de migrantes, detendremos el tr\u00e1fico ilegal de fentanilo y otras peligrosas drogas a nuestro pa\u00eds y haremos que Estados Unidos est\u00e9 seguro de nuevo\u201d, agreg\u00f3.<\/p>\n<p>Johnson tiene una carrera de m\u00e1s de 40 a\u00f1os en el Gobierno de Estados Unidos, seg\u00fan el Departamento de Estado, primero como militar y posteriormente en la Agencia Central de Inteligencia de EE.UU. (CIA, por sus siglas en ingl\u00e9s). Antes de encabezar la embajada de El Salvador entre 2019 y 2021, Johnson no hab\u00eda ocupado otro cargo diplom\u00e1tico.<\/p>\n<p>Su designaci\u00f3n, como la de todos los embajadores de EE.UU., debe ser aprobada por el Senado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante la designaci\u00f3n que hizo el presidente electo, Donald Trump, de nombrar nuevo embajador de Estados Unidos en M\u00e9xico a Ronald Johnson, la presidenta de este pa\u00eds, Claudia Sheinbaum, dijo durante su rueda de prensa matutina que \u201ccon este embajador o con otros siempre defender\u00e1 la soberan\u00eda, y la condici\u00f3n de igualdad\u201d. La mandataria a\u00f1adi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456473","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ante la designaci\u00f3n que hizo el presidente electo, Donald Trump, de nombrar nuevo embajador de Estados Unidos en M\u00e9xico a Ronald Johnson, la presidenta de este pa\u00eds, Claudia Sheinbaum, dijo durante su rueda de prensa matutina que \u201ccon este embajador o con otros siempre defender\u00e1 la soberan\u00eda, y la condici\u00f3n de igualdad\u201d. La mandataria a\u00f1adi\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-11T17:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU.\",\"datePublished\":\"2024-12-11T17:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/\"},\"wordCount\":286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/\",\"name\":\"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-11T17:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU. - Noticias","og_description":"Ante la designaci\u00f3n que hizo el presidente electo, Donald Trump, de nombrar nuevo embajador de Estados Unidos en M\u00e9xico a Ronald Johnson, la presidenta de este pa\u00eds, Claudia Sheinbaum, dijo durante su rueda de prensa matutina que \u201ccon este embajador o con otros siempre defender\u00e1 la soberan\u00eda, y la condici\u00f3n de igualdad\u201d. La mandataria a\u00f1adi\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-11T17:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/"},"author":{"name":"","@id":""},"headline":"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU.","datePublished":"2024-12-11T17:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/"},"wordCount":286,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/","name":"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-11T17:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Sheinbaum: Defenderemos nuestra soberan\u00eda y la condici\u00f3n de igualdad ante el nuevo embajador de EE.UU.","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/11\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-11T17:03:46Z","datePublished":"2024-12-11T17:03:46Z","dateModified":"2024-12-11T17:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Sheinbaum: Defenderemos nuestra soberan\\u00eda y la condici\\u00f3n de igualdad ante el nuevo embajador de EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/11\\\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/11\\\/sheinbaum-ronald-johnson-nuevo-embajador-eeuu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-11T17:03:46Z\",\"datePublished\":\"2024-12-11T17:03:46Z\",\"dateModified\":\"2024-12-11T17:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467844,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/10\/29\/sheinbaum-desacuerdo-operativos-ee-uu-aguas-internacionales-cercanas-mexico-orix\/","url_meta":{"origin":1456473,"position":0},"title":"Sheinbaum dice que no est\u00e1 de acuerdo con los operativos de EE.UU. en aguas internacionales cercanas a M\u00e9xico","author":"","date":"octubre 29, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este mi\u00e9rcoles que no est\u00e1 de acuerdo con los ataques del Gobierno de Estados Unidos a embarcaciones que presuntamente transportan drogas en el Caribe y el Pac\u00edfico, por lo que pidi\u00f3 a Washington cambiar su protocolo de combate al crimen organizado en aguas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456517,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/12\/5-cosas-12-de-diciembre-biden-inmigrantes-orix\/","url_meta":{"origin":1456473,"position":1},"title":"Las 5 cosas que debes saber este 12 de diciembre: Inmigrantes, captura, embajador, FBI y Copa del Mundo","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Biden enfrenta a una creciente presi\u00f3n para proteger a los inmigrantes. Qui\u00e9n es el elegido de Trump para ser embajador de EE.UU. en M\u00e9xico. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha las 5\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456449,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/10\/ron-johnson-embajador-mexico-trump-trax\/","url_meta":{"origin":1456473,"position":2},"title":"Trump anuncia que propondr\u00e1 a Ron Johnson, exembajador de EE.UU. en El Salvador, como embajador en M\u00e9xico","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"El presidente electo de Estados Unidos, Donald Trump, anunci\u00f3 este martes que propondr\u00e1 a Ron Johnson como embajador en M\u00e9xico.\u201cRon trabajar\u00e1 de cerca con nuestro gran nominado para la Secretar\u00eda de Estado, Marco Rubio, para promover la seguridad y prosperidad de nuestra naci\u00f3n\u201d, escribi\u00f3 Trump en su red Truth Social.\u201cJuntos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457703,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/01\/21\/mexico-defendera-soberania-sheinbaum-decretos-trump-orix\/","url_meta":{"origin":1456473,"position":3},"title":"M\u00e9xico defender\u00e1 su soberan\u00eda, dice Sheinbaum tras decretos de Trump sobre inmigraci\u00f3n","author":"","date":"enero 21, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo que su pa\u00eds defender\u00e1 su soberan\u00eda y apoyar\u00e1 a los mexicanos en Estados Unidos despu\u00e9s de que el presidente Donald Trump firmara decretos y acciones ejecutivas que podr\u00edan afectar a millones de inmigrantes mexicanos que viven all\u00ed.Claudia Sheinbaum dijo durante una conferencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459938,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/03\/14\/sheinbaum-intervencion-militar-orix\/","url_meta":{"origin":1456473,"position":4},"title":"Sheinbaum afirma que la idea de una intervenci\u00f3n militar en M\u00e9xico &#171;no est\u00e1 en ning\u00fan lado&#187;","author":"","date":"marzo 14, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, manifest\u00f3 este viernes de manera firme que la idea de una intervenci\u00f3n militar estadounidense en M\u00e9xico \u201cno est\u00e1 en la mesa, ni en la silla, ni sobre el piso, ni sobre ning\u00fan lado\u201dLa mandataria respondi\u00f3 as\u00ed al designado embajador de Estados Unidos en M\u00e9xico,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470818,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/02\/03\/peru-nuevo-embajador-eeuu-china-orix\/","url_meta":{"origin":1456473,"position":5},"title":"China desplaz\u00f3 a EE.UU. como primer socio comercial de Per\u00fa. El nuevo embajador de Washington busca revertir esa tendencia","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Bernie Navarro, un empresario estrechamente ligado a Per\u00fa, es el nuevo embajador de Estados Unidos en el pa\u00eds sudamericano y este martes present\u00f3 sus credenciales al presidente Jos\u00e9 Jer\u00ed en el Palacio de Gobierno, seg\u00fan inform\u00f3 el propio diplom\u00e1tico en X.Navarro est\u00e1 casado con una peruana y a\u00f1os atr\u00e1s celebr\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1456473"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456473\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1456473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1456473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1456473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}