{"id":1456512,"date":"2024-12-12T04:03:50","date_gmt":"2024-12-12T12:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/"},"modified":"2024-12-12T04:03:50","modified_gmt":"2024-12-12T12:03:50","slug":"analisis-brian-thompson-jordan-neely-politica-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/","title":{"rendered":"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense"},"content":{"rendered":"<p>Dos tragedias neoyorquinas que conmocionan a Estados Unidos muestran c\u00f3mo la pol\u00edtica est\u00e1 fracasando a la hora de abordar algunos de los problemas econ\u00f3micos y sociales m\u00e1s fundamentales y reflejan el estado de \u00e1nimo de la naci\u00f3n ante la segunda presidencia de Donald Trump.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/04\/matan-a-tiros-al-ceo-de-unitedhealthcare-en-el-centro-de-manhattan-trax\">El asesinato del CEO de UnitedHealthcare<\/a>, Brian Thompson, captado en im\u00e1genes de vigilancia, se convirti\u00f3 en un momento compartido de horror nacional. Pero pronto se vio superado por un debate m\u00e1s amplio sobre la complicidad de los grandes ejecutivos en los elevados costos de la sanidad estadounidense y las injusticias percibidas en el sector. Los \u201ctrolls\u201d de internet celebraron su asesinato, y algunas personas empatizaron con los supuestos objetivos de<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/10\/estados-unidos\/quien-es-luigi-mangione-sospechoso-homicidio-ceo-unitedhealthcare-trax\"> Luigi Mangione<\/a>, el joven de 26 a\u00f1os acusado en el caso, en lugar de expresar su consternaci\u00f3n por un marido y padre de dos hijos asesinado a tiros.<\/p>\n<p>En otro caso muy renombrado, un jurado de Manhattan absolvi\u00f3 este lunes a Daniel Penny de homicidio por negligencia criminal en la muerte de Jordan Neely, un artista callejero que luchaba contra la falta de hogar, las enfermedades mentales y las drogas, en un metro de Nueva York el a\u00f1o pasado. El jurado dio la raz\u00f3n a Penny, que tambi\u00e9n tiene 26 a\u00f1os, en que sujet\u00f3 a Neely porque intentaba asegurarse de que la gente del metro no resultara herida, o algo peor, por lo que, seg\u00fan los testigos, era el comportamiento err\u00e1tico de Neely. El caso de la \u201cllave de estrangulamiento\u201d tambi\u00e9n est\u00e1 politizado: Penny fue ensalzado como un h\u00e9roe buen samaritano en los medios conservadores, donde los comentaristas acusan a los fiscales liberales de perseguir a Trump pero ignorar la seguridad p\u00fablica. Las protestas tras el veredicto retrataron a Neely como v\u00edctima de la injusticia racial y del azote de los sin techo.<\/p>\n<p>La furia que se filtra en las redes sociales no es necesariamente una instant\u00e1nea fiel de todos los estadounidenses. Pero las conversaciones sobre estos casos se producen en un momento cultural poco frecuente y compartido por una naci\u00f3n tensa tras un amargo a\u00f1o electoral y en v\u00edsperas de una nueva presidencia.<\/p>\n<p>En cierto modo, el contexto de cada caso pone de relieve cuestiones sociales y econ\u00f3micas que los dirigentes nacionales, estatales y municipales no est\u00e1n abordando, como los exorbitantes costos de la atenci\u00f3n sanitaria y la falta de vivienda. Los casos captaron la atenci\u00f3n de la opini\u00f3n p\u00fablica tras unas elecciones en las que millones de estadounidenses mostraron su enfado con las instituciones pol\u00edticas y las denominadas \u00e9lites, que no est\u00e1n abordando sus preocupaciones m\u00e1s profundas ni sus amenazas m\u00e1s graves.<\/p>\n<p>Pero a pesar de toda la preocupaci\u00f3n suscitada tras las muertes de Thompson y Neely, ser\u00eda precipitado pensar que algo va a cambiar pronto.<\/p>\n<p>\u00bfTiene el Gabinete entrante de Trump, formado por multimillonarios y millonarios, alguna idea de que para muchos estadounidenses -incluso los que tienen un buen seguro m\u00e9dico- el miedo a un accidente o a un nuevo diagn\u00f3stico se ve agravado por el temor a c\u00f3mo podr\u00e1n pagar el tratamiento?<\/p>\n<p>En campa\u00f1a, los dem\u00f3cratas a menudo mencionan el descenso de los delitos violentos. Pero, \u00bfcomprenden realmente los l\u00edderes del partido en Washington la sensaci\u00f3n palpable entre muchos estadounidenses de que las ciudades se est\u00e1n volviendo m\u00e1s peligrosas en medio de la omnipresencia de los sin techo y la drogadicci\u00f3n? \u00bfY tiene Trump alg\u00fan plan real para abordar estos problemas, m\u00e1s all\u00e1 de su deseo de hacer demagogia con ellos como ejemplos de pol\u00edticas dem\u00f3cratas \u201cwoke\u201d (asociadas con estar en contra de las injusticias sociales)?<\/p>\n<p>La idea de que la muerte de Thompson pueda ser bien recibida, incluso en el pantano de las redes sociales, es aborrecible. Y la idea de que pueda haber alguna justificaci\u00f3n para la violencia en una sociedad democr\u00e1tica plantea interrogantes sobre la viabilidad y la resistencia de esa sociedad.<\/p>\n<p>\u201cEsto es horrible\u201d, dijo este martes la secretaria de Prensa de la Casa Blanca, Karine Jean-Pierre. \u201cLa violencia para combatir cualquier tipo de codicia corporativa es inaceptable\u201d.<\/p>\n<p>El abogado de Mangione dijo que su cliente se declarar\u00e1 inocente de los cargos en Pensilvania relacionados con una identificaci\u00f3n falsa y un arma y probablemente har\u00e1 lo mismo con el cargo de asesinato en Nueva York.<\/p>\n<p>Pero si el sospechoso ten\u00eda un m\u00f3vil pol\u00edtico -cuesti\u00f3n que la polic\u00eda sigue investigando- puede que lo haya conseguido.<\/p>\n<p>Pocas horas despu\u00e9s del asesinato, las redes sociales como TikTok y X se llenaron de mensajes de personas que dec\u00edan que United y otras aseguradoras les hab\u00edan denegado la cobertura o que hab\u00edan sufrido la miseria de pasar horas al tel\u00e9fono intentando autorizar procedimientos o entender facturas sorpresa.<\/p>\n<p>La celebraci\u00f3n del asesinato de Thompson es chocante, pero habla de frustraciones m\u00e1s profundas, en una naci\u00f3n donde una encuesta de KFF de 2022 revel\u00f3 que<a href=\"https:\/\/www.kff.org\/health-costs\/press-release\/people-with-medical-debt-are-much-more-likely-to-experience-other-forms-of-financial-stress\/#:~:text=KFF's%202022%20Health%20Care%20Debt,or%20owed%20to%20family%20members.\"> el 41% de los estadounidenses tiene alg\u00fan tipo de deuda sanitaria<\/a>. Incluso para las personas con seguro m\u00e9dico, las elevadas primas, los caros copagos y las resoluciones y denegaciones de atenci\u00f3n, sobre lo que a menudo parece ser una base arbitraria, pueden ser devastadoras para quienes se enfrentan a los momentos m\u00e1s estresantes de sus vidas. Los malentendidos o la confusi\u00f3n sobre lo que se ha cubierto a menudo pueden hacer que un paciente caiga en la pr\u00f3spera industria de las empresas de cobro de cr\u00e9ditos.<\/p>\n<p>No todos los costos crecientes pueden achacarse a un af\u00e1n de lucro. Los nuevos tratamientos revolucionarios suelen ser caros. A veces, los proveedores imponen precios m\u00e1s altos de lo que las aseguradoras consideran razonable. Pero en un momento de tensi\u00f3n pol\u00edtica como el actual, existe una evidente yuxtaposici\u00f3n <a href=\"https:\/\/www.unitedhealthgroup.com\/newsroom\/2024\/2024-10-15-uhg-reports-third-quarter-results.html\">entre las multimillonarias ganancias de UnitedHealthcare<\/a> y sus competidores y la agon\u00eda de alguien que necesita pagar por una atenci\u00f3n que le salva la vida.<\/p>\n<p>Cuando Mangione fue puesto bajo custodia y compareci\u00f3 ante el tribunal por primera vez esta semana, la empat\u00eda hacia \u00e9l en internet pareci\u00f3 crecer. Miembros de la comunidad y agentes de Polic\u00eda de Altoona, Pensilvania, donde fue detenido, recibieron amenazas de muerte. Y el McDonald\u2019s donde fue visto recibi\u00f3 una avalancha de cr\u00edticas negativas en internet. En Baltimore, cerca de la ciudad natal de Mangione, apareci\u00f3 en la I-83 un cartel en el que se le\u00eda \u201cNegar, defender, deponer\u201d y \u201cAtenci\u00f3n sanitaria para todos\u201d, inform\u00f3 el sitio de noticias <a href=\"https:\/\/www.thebaltimorebanner.com\/\">Baltimore Banner<\/a>. El eslogan coincide con las palabras garabateadas en la munici\u00f3n recuperada por los detectives cerca del lugar del tiroteo de Thompson, seg\u00fan inform\u00f3 la Polic\u00eda de Nueva York la semana pasada, y se hace eco del lenguaje utilizado por los cr\u00edticos del sector de los seguros m\u00e9dicos.<\/p>\n<p>Las circunstancias del asesinato de Thompson y la reacci\u00f3n contra el seguro han supuesto un reto para los pol\u00edticos. El gobernador dem\u00f3crata de Maryland, Wes Moore, dijo este  mi\u00e9rcoles que, cuando ten\u00eda tres a\u00f1os, hab\u00eda visto morir a su padre porque no pod\u00eda recibir el tratamiento que necesitaba. He vivido en mis propias carnes el \u201ccolapso del sistema sanitario\u201d, y es algo que todav\u00eda me afecta\u201d, afirm\u00f3. \u201cTambi\u00e9n s\u00e9 que la forma de resolver las cosas no es matando a gente a sangre fr\u00eda\u201d, dijo Moore en Baltimore. Pidi\u00f3 justicia para Thompson y su familia, y a\u00f1adi\u00f3: \u201cHay dos adolescentes ahora mismo en Minnesota que est\u00e1n creciendo como yo lo hice: sin padre\u201d.<\/p>\n<p>El gobernador de Pensilvania, Josh Shapiro, posible candidato presidencial dem\u00f3crata en 2028, conden\u00f3 a quienes celebran a Mangione. \u201cNo es un h\u00e9roe\u201d, dijo Shapiro. \u201cEn Estados Unidos, no matamos a gente a sangre fr\u00eda para resolver diferencias pol\u00edticas o expresar un punto de vista\u201d. Y a\u00f1adi\u00f3: \u201cEn una sociedad civil, todos estamos menos seguros cuando los ide\u00f3logos se dedican a la justicia por mano propia\u201d.<\/p>\n<p>Pero Mangione puede convertirse en una causa c\u00e9lebre a medida que su caso avance hacia el juicio, poniendo potencialmente de relieve los agravios que muchos estadounidenses tienen con sus proveedores de seguros. En ese sentido, el asesinato de Thompson puso de manifiesto una de las cuestiones pol\u00edticas m\u00e1s importantes que los gobernadores, los legisladores estatales y federales y los presidentes no han sabido resolver y que, sin duda, est\u00e1 contribuyendo a la angustia que sienten por las instituciones de gobierno del pa\u00eds.<\/p>\n<p>Penny, el veterano de la Infanter\u00eda de Marina absuelto en el caso Neely, concedi\u00f3 su primera entrevista a Fox News. En un clip de adelanto emitido este martes, dijo que no quer\u00eda \u201catenci\u00f3n ni elogios, y sigo sin quererlos\u201d. Y dijo que se habr\u00eda sentido culpable si alguien hubiera resultado herido tras las amenazas que los testigos declararon que Neely hizo en el tren. \u201cAceptar\u00eda un mill\u00f3n de comparecencias ante los tribunales y que la gente me insultara y me odiara solo para evitar que una de esas personas resultara herida o muerta\u201d, dijo Penny.<\/p>\n<p>Para muchos conservadores, el caso fue una verg\u00fcenza. \u201cGracias a Dios se hizo justicia en este caso. En primer lugar, fue un esc\u00e1ndalo que se procesara a Penny\u201d, escribi\u00f3 el vicepresidente electo J.D. Vance en X este lunes.<\/p>\n<p>La idea de que un ciudadano act\u00fae en defensa de otros -y luego la percepci\u00f3n de que est\u00e1 siendo perseguido por lo que los cr\u00edticos consideran una extralimitaci\u00f3n de los fiscales liberales- es un manjar para los medios de comunicaci\u00f3n de derecha. El presentador de Fox News, Sean Hannity, por ejemplo, dijo en su mon\u00f3logo de este martes por la noche que para \u201ctanta gente de izquierda\u201d, el caso \u201cno tiene que ver con la verdad, ni con la justicia, ni siquiera con la vida. Para ellos es un juego pol\u00edtico\u201d.<\/p>\n<p>Ir\u00f3nicamente, muchos escritores de publicaciones de derecha est\u00e1n vitoreando el mismo sistema de jurado de Nueva York que argumentaron que era irremediablemente parcial cuando Trump fue condenado en un caso de dinero subrepticio en Manhattan a principios de este a\u00f1o. (Trump se declar\u00f3 inocente en el caso en el que su sentencia qued\u00f3 en suspenso tras las elecciones de noviembre).<\/p>\n<p>Pero tambi\u00e9n hubo fuertes condenas al fiscal del distrito de Manhattan, Alvin Bragg, un dem\u00f3crata que llev\u00f3 el caso que hizo que Trump se convirtiera en el primer expresidente de la historia en ser condenado penalmente y cuya oficina tambi\u00e9n proces\u00f3 el caso Penny.<\/p>\n<p>En su entrevista con la presentadora de Fox News, Jeanine Pirro, Penny critic\u00f3 a los funcionarios de Nueva York, de quienes dijo que estaban pol\u00edticamente motivados y comprometidos con pol\u00edticas que \u201cclaramente no han funcionado.\u201d Se quej\u00f3 de pol\u00edticas \u201cque la gente, la poblaci\u00f3n en general, no apoya, pero sus egos son demasiado grandes para admitir que est\u00e1n equivocados.\u201d<\/p>\n<p>Pero fuera del tribunal este lunes, el padre de Neely y un abogado de la familia dijeron que el veredicto del jurado reflejaba mal el sistema de justicia penal. \u201cEcho de menos a mi hijo. Mi hijo no ten\u00eda que pasar por esto. Yo tampoco ten\u00eda que pasar por esto\u201d, dijo Andre Zachary. \u201cDuele, de verdad, de verdad que duele. \u00bfQu\u00e9 vamos a hacer? \u00bfQu\u00e9 nos va a pasar ahora? Ya estoy harto. El sistema est\u00e1 ama\u00f1ado\u201d.<\/p>\n<p>Los detractores del veredicto se preguntaron si habr\u00eda ocurrido lo mismo si las tornas hubieran cambiado y Penny fuera negra y Neely blanca. Este no es ni mucho menos el primer caso en el que se cuestiona si se hizo justicia por motivos de raza. Y aunque el caso penal contra Penny ha terminado, se enfrenta a una demanda civil del padre de Neely alegando que caus\u00f3 la muerte de Neely.<\/p>\n<p>La decisi\u00f3n del jurado significa que Penny se considera vindicado a los ojos de la ley, pero la cobertura medi\u00e1tica en torno al caso puso de relieve otro ejemplo de c\u00f3mo la percepci\u00f3n de una tragedia puede verse influida por las opiniones pol\u00edticas o la agenda de los medios de comunicaci\u00f3n.<\/p>\n<p>Una cuesti\u00f3n que se plantea ahora es si los cr\u00edticos conservadores que arremetieron contra la acusaci\u00f3n reflexionar\u00e1n sobre cuestiones como la salud mental, la falta de vivienda y las condiciones que pueden conducir al consumo de drogas y a la desarticulaci\u00f3n social, que no justifican la violencia y las amenazas pero pueden ser factores coadyuvantes. Esas tambi\u00e9n deber\u00edan ser preocupaciones para los alcaldes y gobernadores dem\u00f3cratas despu\u00e9s de una elecci\u00f3n en la que Trump obtuvo ganancias incluso en estados azules en medio de una percepci\u00f3n de que el partido en la Casa Blanca estaba fuera de contacto con los problemas que enfrenta la mayor\u00eda de los estadounidenses.<\/p>\n<p>Mientras tanto, la \u00fanica respuesta a la reacci\u00f3n en contra de los gigantes de la salud tras el asesinato de Thompson parece ser que <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/12\/economia\/ejecutivos-miedo-tras-asesinato-ceo-unitedhealthcare-trax\">los CEO entran en p\u00e1nico<\/a> por su propia seguridad en lugar de considerar los agravios que muchos estadounidenses tienen sobre las compa\u00f1\u00edas de seguros.<\/p>\n<p>En cinco semanas y media, corresponder\u00e1 a Trump y a su administraci\u00f3n abordar los problemas m\u00e1s espinosos a los que se enfrentan los estadounidenses despu\u00e9s de que el presidente electo citara en sus m\u00edtines la delincuencia en las ciudades y el elevado costo de la sanidad.<\/p>\n<p>Es justo preguntarse si un nuevo presidente con solo un \u201cconcepto\u201d de plan para sustituir el Obamacare y que a menudo ha utilizado la ret\u00f3rica racial para demonizar a las ciudades tiene verdadero inter\u00e9s en los resultados.<\/p>\n<p>Pero no es culpa solo de Trump. Dos episodios distintos en Nueva York crearon r\u00e9plicas pol\u00edticas que muestran cu\u00e1n fundamentalmente el sistema pol\u00edtico estadounidense est\u00e1 fallando en arreglar algunos de los problemas m\u00e1s profundos de la sociedad. Y lo que puede desencadenarse como resultado<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos tragedias neoyorquinas que conmocionan a Estados Unidos muestran c\u00f3mo la pol\u00edtica est\u00e1 fracasando a la hora de abordar algunos de los problemas econ\u00f3micos y sociales m\u00e1s fundamentales y reflejan el estado de \u00e1nimo de la naci\u00f3n ante la segunda presidencia de Donald Trump. El asesinato del CEO de UnitedHealthcare, Brian Thompson, captado en im\u00e1genes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456512","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense - Noticias\" \/>\n<meta property=\"og:description\" content=\"Dos tragedias neoyorquinas que conmocionan a Estados Unidos muestran c\u00f3mo la pol\u00edtica est\u00e1 fracasando a la hora de abordar algunos de los problemas econ\u00f3micos y sociales m\u00e1s fundamentales y reflejan el estado de \u00e1nimo de la naci\u00f3n ante la segunda presidencia de Donald Trump. El asesinato del CEO de UnitedHealthcare, Brian Thompson, captado en im\u00e1genes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-12T12:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense\",\"datePublished\":\"2024-12-12T12:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/\"},\"wordCount\":2424,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/\",\"name\":\"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-12T12:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense - Noticias","og_description":"Dos tragedias neoyorquinas que conmocionan a Estados Unidos muestran c\u00f3mo la pol\u00edtica est\u00e1 fracasando a la hora de abordar algunos de los problemas econ\u00f3micos y sociales m\u00e1s fundamentales y reflejan el estado de \u00e1nimo de la naci\u00f3n ante la segunda presidencia de Donald Trump. El asesinato del CEO de UnitedHealthcare, Brian Thompson, captado en im\u00e1genes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-12T12:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense","datePublished":"2024-12-12T12:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/"},"wordCount":2424,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/","name":"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-12T12:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\u00edtica en un tenso momento estadounidense","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/12\/analisis-brian-thompson-jordan-neely-politica-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-12T12:03:50Z","datePublished":"2024-12-12T12:03:50Z","dateModified":"2024-12-12T12:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Dos tragedias de Nueva York pusieron de manifiesto el fracaso de la pol\\u00edtica en un tenso momento estadounidense\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/12\\\/analisis-brian-thompson-jordan-neely-politica-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/12\\\/analisis-brian-thompson-jordan-neely-politica-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-12T12:03:50Z\",\"datePublished\":\"2024-12-12T12:03:50Z\",\"dateModified\":\"2024-12-12T12:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466355,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/11\/analisis-muerte-violenta-kirk-tragedia-nacional-trax\/","url_meta":{"origin":1456512,"position":0},"title":"La muerte violenta de Kirk es una tragedia nacional en unos Estados Unidos polarizados","author":"","date":"septiembre 11, 2025","format":false,"excerpt":"La muerte violenta de Charlie Kirk es una tragedia para todos los estadounidenses, incluso para aquellos que desde\u00f1aban al carism\u00e1tico portavoz de los j\u00f3venes conservadores MAGA. Esto se debe a que la bala que mat\u00f3 al padre de dos hijos de 31 a\u00f1os en el campus universitario de Utah el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452508,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/09\/07\/estadounidense-asesinada-ribera-occidental-familia-trax\/","url_meta":{"origin":1456512,"position":1},"title":"La familia de la estadounidense asesinada en la Ribera Occidental culpa a Israel de su muerte y exige una investigaci\u00f3n independiente","author":"","date":"septiembre 7, 2024","format":false,"excerpt":"(CNN) -- La familia de una estadounidense muerta por disparos mientras protestaba en la Ribera Occidental ocupada ha culpado a Israel de su muerte y ha pedido una investigaci\u00f3n independiente, afirmando en un comunicado que una investigaci\u00f3n dirigida por Israel ser\u00eda inadecuada.Dos testigos presenciales dijeron a CNN que Aysenur Eygi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466404,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/12\/trump-kirk-temperatura-gobernador-cox-trax\/","url_meta":{"origin":1456512,"position":2},"title":"Trump ha subido la temperatura tras el asesinato de Kirk. El gobernador Spencer Cox intenta bajarla","author":"","date":"septiembre 12, 2025","format":false,"excerpt":"Durante las aproximadamente 40 horas transcurridas entre el asesinato de Charlie Kirk y el anuncio de este viernes de la detenci\u00f3n de un sospechoso, la derecha fren\u00f3 las acusaciones.Algunos republicanos, comentaristas e influencers de derecha hablaron de \u201cguerra\u201d y de la radicalizaci\u00f3n de su bando como respuesta. El presidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468502,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/11\/19\/trump-khashoggi-defiende-principe-heredero-saudi-trax\/","url_meta":{"origin":1456512,"position":3},"title":"Trump afirma que Khashoggi, el periodista asesinado, era &#171;extremadamente controvertido&#187; y defiende al pr\u00edncipe heredero saud\u00ed","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"El presidente Donald Trump rechaz\u00f3 airadamente el martes una pregunta sobre el asesinato de Jamal Khashoggi en 2018, al alegar que el periodista disidente saudita era \u201cextremadamente controvertido\u201d e insistir en que el tema solo se mencionaba durante su reuni\u00f3n con el pr\u00edncipe heredero saudita Mohammed bin Salman para avergonzar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468027,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/11\/04\/eeuu-condena-asesinato-manzo-violencia-michoacan-orix\/","url_meta":{"origin":1456512,"position":4},"title":"EE.UU. condena el asesinato del alcalde de Uruapan, que desat\u00f3 una ola de protestas en Michoac\u00e1n","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"La Casa Blanca conden\u00f3 este martes \u201ctoda forma de violencia pol\u00edtica\u201d tras el asesinato del alcalde de Uruapan, Carlos Manzo, un hecho que ha desatado protestas e indignaci\u00f3n en Michoac\u00e1n, uno de los estados m\u00e1s golpeados por la inseguridad en M\u00e9xico.Karoline Leavitt, secretaria de Prensa de la Casa Blanca, dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466639,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/20\/analisis-charlie-kirk-mensaje-directo-van-jones-trax\/","url_meta":{"origin":1456512,"position":5},"title":"Charlie Kirk me envi\u00f3 un mensaje directo antes de que lo asesinaran. Esto es lo que dijo","author":"","date":"septiembre 20, 2025","format":false,"excerpt":"El d\u00eda antes de que lo asesinaran horriblemente, Charlie Kirk me envi\u00f3 un mensaje directo en X.\u00c9l y yo hab\u00edamos estado discutiendo p\u00fablicamente sobre el apu\u00f1alamiento de una refugiada ucraniana y su relaci\u00f3n con la raza.Kirk dijo que el horrible asesinato de una mujer blanca a manos de un hombre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1456512"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456512\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1456512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1456512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1456512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}