{"id":1456579,"date":"2024-12-13T16:03:43","date_gmt":"2024-12-14T00:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/"},"modified":"2024-12-13T16:03:43","modified_gmt":"2024-12-14T00:03:43","slug":"musk-sec-multa-compra-twitter-cargos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/","title":{"rendered":"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos"},"content":{"rendered":"<p>Elon Musk aparentemente tiene una \u00faltima batalla que librar con el presidente saliente de la Comisi\u00f3n de Bolsa y Valores, Gary Gensler.<\/p>\n<p>Musk revel\u00f3 en su plataforma de redes sociales X que la agencia est\u00e1 exigiendo que acepte una multa de una cantidad no revelada para resolver los cargos por su compra inicial de acciones, en 2022, de lo que entonces se llamaba Twitter.<\/p>\n<p>Musk public\u00f3 una carta enviada por su abogado Alex Spiro a Gensler en la que dec\u00eda que la agencia exig\u00eda que Musk aceptara en 48 horas pagar una multa relacionada con la falta de divulgaci\u00f3n de sus compras iniciales de acciones de Twitter o, en caso contrario, \u201cenfrentar cargos por numerosos delitos.\u201d<\/p>\n<p>\u201cOh Gary, \u00bfc\u00f3mo pudiste hacerme esto?\u201d, dijo burlonamente en la publicaci\u00f3n.<\/p>\n<p>La Comisi\u00f3n de Bolsa y Valores dijo que no hcen comentarios sobre investigaciones en curso, como parte de su pol\u00edtica.<\/p>\n<p>La carta afirmaba que el personal de la Comisi\u00f3n de Bolsa y Valores indic\u00f3 \u201cque esta demanda era el resultado de una directiva de sus superiores y que los cargos se presentar\u00edan de manera inminente a menos que el Sr. Musk acceda\u201d. La carta dice que Musk se niega a aceptar la demanda.<\/p>\n<p>Musk y la Comisi\u00f3n de Bolsa y Valores han estado enfrent\u00e1ndose durante varios a\u00f1os, incluso durante el primer mandato de Donald Trump. Sin embargo, los enfrentamientos se han intensificado en los \u00faltimos a\u00f1os, ya que Musk ha desafiado los derechos de la agencia para limitar sus comunicaciones con los inversores, y Gensler se ha convertido en uno de los cr\u00edticos m\u00e1s vocales de las criptomonedas, de las que Musk es un importante inversor y defensor.<\/p>\n<p>La carta que Musk public\u00f3 tambi\u00e9n dec\u00eda que Spiro fue citado para dar testimonio, lo cual se neg\u00f3 a hacer. A\u00f1ad\u00eda que la agencia reabri\u00f3 una investigaci\u00f3n sobre otra de las empresas de Musk, Neuralink.<\/p>\n<p>\u201cEsta serie de eventos deja claro que la comisi\u00f3n no busca la verdad, sino que est\u00e1 involucrada en una campa\u00f1a con motivaciones indebidas contra el Sr. Musk y las personas y empresas asociadas a \u00e9l\u201d, escribi\u00f3 Spiro en la carta. \u201cExigimos saber qui\u00e9n dirigi\u00f3 estas acciones, si fue usted o la Casa Blanca. Estas t\u00e1cticas y esquemas indebidos no nos intimidar\u00e1n\u201d.<\/p>\n<p>En 2018, la Comisi\u00f3n de Bolsa y Valores lleg\u00f3 a un acuerdo con Musk y Tesla despu\u00e9s de encontrar que Musk hab\u00eda enga\u00f1ado a los inversores cuando tuite\u00f3 que ten\u00eda \u201cfinanciamiento asegurado\u201d para hacer que Tesla fuera privada. Bajo ese acuerdo, Tesla y Musk pagaron multas de US$ 20 millones cada uno, y Musk acord\u00f3 que sus tuits sobre eventos en la empresa fueran aprobados por otros en Tesla. Tambi\u00e9n renunci\u00f3 al t\u00edtulo de presidente de Tesla, aunque retuvo el de CEO. Musk dijo m\u00e1s tarde que acept\u00f3 el acuerdo porque no hacerlo habr\u00eda cortado fuentes vitales de financiamiento de los bancos que Tesla, entonces con problemas de liquidez, necesitaba para sobrevivir.<\/p>\n<p>En abril de 2022, Musk revel\u00f3 que compr\u00f3 el 9% de las acciones de Twitter antes de su <a href=\"https:\/\/cnnespanol.cnn.com\/2022\/10\/28\/elon-musk-completa-adquisicion-twitter-trax\">compra de toda la empresa m\u00e1s tarde ese a\u00f1o.<\/a> La Comisi\u00f3n de Bolsa y Valores le envi\u00f3 una carta queriendo saber por qu\u00e9 no hab\u00eda divulgado esas compras dentro de los 10 d\u00edas de cruzar el umbral del 5% de acciones pose\u00eddas, como lo exige la ley de valores. Musk finalmente adquiri\u00f3 todas las acciones de Twitter en una compra de US$ 44.000 millones, y poco despu\u00e9s la renombr\u00f3 X.<\/p>\n<p>Musk y Gensler tambi\u00e9n han chocado sobre la regulaci\u00f3n de las criptomonedas, de las cuales Musk es un defensor vocal, mientras que Gensler las ha descrito como valores que deber\u00edan estar bajo la autoridad de la Comisi\u00f3n de Bolsa y Valores. Gensler ha calificado a las criptomonedas como \u201cllenas de fraudes, estafas y abusos en ciertas aplicaciones\u201d.<\/p>\n<p>Sin embargo, Musk, uno de los principales partidarios del presidente electo Donald Trump, no tendr\u00e1 que preocuparse por tratar con una Comisi\u00f3n de Bolsa y Valores liderada por Gensler por mucho m\u00e1s tiempo. Trump eligi\u00f3 a <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/04\/estados-unidos\/trump-nombra-atkins-sec-slater-antimonopolio-trax\">Paul Atkins<\/a>, quien ha sido copresidente del grupo de defensa de criptomonedas Digital Chamber\u2019s Token Alliance desde 2017, para liderar la agencia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elon Musk aparentemente tiene una \u00faltima batalla que librar con el presidente saliente de la Comisi\u00f3n de Bolsa y Valores, Gary Gensler. Musk revel\u00f3 en su plataforma de redes sociales X que la agencia est\u00e1 exigiendo que acepte una multa de una cantidad no revelada para resolver los cargos por su compra inicial de acciones, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456579","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Elon Musk aparentemente tiene una \u00faltima batalla que librar con el presidente saliente de la Comisi\u00f3n de Bolsa y Valores, Gary Gensler. Musk revel\u00f3 en su plataforma de redes sociales X que la agencia est\u00e1 exigiendo que acepte una multa de una cantidad no revelada para resolver los cargos por su compra inicial de acciones, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-14T00:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos\",\"datePublished\":\"2024-12-14T00:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/\"},\"wordCount\":765,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/\",\"name\":\"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-14T00:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos - Noticias","og_description":"Elon Musk aparentemente tiene una \u00faltima batalla que librar con el presidente saliente de la Comisi\u00f3n de Bolsa y Valores, Gary Gensler. Musk revel\u00f3 en su plataforma de redes sociales X que la agencia est\u00e1 exigiendo que acepte una multa de una cantidad no revelada para resolver los cargos por su compra inicial de acciones, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-14T00:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/"},"author":{"name":"","@id":""},"headline":"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos","datePublished":"2024-12-14T00:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/"},"wordCount":765,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/","name":"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-14T00:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Elon Musk dice que la Comisi\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\u00e1 cargos","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/13\/musk-sec-multa-compra-twitter-cargos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-14T00:03:43Z","datePublished":"2024-12-14T00:03:43Z","dateModified":"2024-12-14T00:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Elon Musk dice que la Comisi\\u00f3n de Bolsa y Valores le ordena pagar una multa por la compra de Twitter o enfrentar\\u00e1 cargos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/13\\\/musk-sec-multa-compra-twitter-cargos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/13\\\/musk-sec-multa-compra-twitter-cargos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-14T00:03:43Z\",\"datePublished\":\"2024-12-14T00:03:43Z\",\"dateModified\":\"2024-12-14T00:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457515,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/01\/14\/sec-demanda-elon-musk-participacion-twitter-trax\/","url_meta":{"origin":1456579,"position":0},"title":"La SEC demanda a Elon Musk por supuestamente no revelar adecuadamente su participaci\u00f3n en Twitter","author":"","date":"enero 14, 2025","format":false,"excerpt":"La Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s) de Estados Unidos demand\u00f3 este martes a Elon Musk por no revelar adecuadamente su propiedad de X, entonces conocida como Twitter, lo que le permiti\u00f3 comprar acciones de la plataforma a \u201cprecios artificialmente bajos\u201d.The-CNN-Wire\u2122 & \u00a9 2025 Cable\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472768,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/01\/spacex-planes-salir-bolsa-trax\/","url_meta":{"origin":1456579,"position":1},"title":"SpaceX presenta, seg\u00fan reportes, planes para cotizar en bolsa con una oferta que podr\u00eda ser hist\u00f3rica","author":"","date":"abril 1, 2026","format":false,"excerpt":"SpaceX, la empresa de cohetes de Elon Musk que se fusion\u00f3 a comienzos de este a\u00f1o con la compa\u00f1\u00eda de inteligencia artificial xAI, present\u00f3 de forma confidencial planes para una oferta p\u00fablica inicial este mi\u00e9rcoles, en lo que podr\u00eda ser una de las m\u00e1s grandes de la historia, seg\u00fan m\u00faltiples\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469157,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/12\/10\/musk-planeando-salida-bolsa-spacex-trax\/","url_meta":{"origin":1456579,"position":2},"title":"Elon Musk estar\u00eda planeando una enorme salida a bolsa para SpaceX. Esto es lo que significa","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"Elon Musk, el hombre m\u00e1s rico del mundo, pronto podr\u00eda ser mucho m\u00e1s rico. Bloomberg informa que est\u00e1 planeando una de las ofertas p\u00fablicas iniciales m\u00e1s grandes de la historia para SpaceX.La empresa espacial de Musk planea recaudar US$ 30.000 millones el pr\u00f3ximo a\u00f1o, inform\u00f3 Bloomberg, y una Oferta P\u00fablica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457090,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/30\/multa-tiktok-venezuela-orix\/","url_meta":{"origin":1456579,"position":3},"title":"Multan a TikTok en Venezuela con US$ 10 millones y la acusan de permitir la difusi\u00f3n de retos virales","author":"","date":"diciembre 30, 2024","format":false,"excerpt":"En una audiencia transmitida este lunes por el canal Estatal VTV, la presidenta de la Sala Constitucional del Tribunal Supremo de Justicia de Venezuela, Tania D\u2019Amelio, inform\u00f3 de la imposici\u00f3n de una multa equivalente a US$ 10 millones a la plataforma de videos TikTok, tras acusarla de falta de control\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465409,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/08\/12\/elon-musk-amenaza-demandar-apple-app-store-trax\/","url_meta":{"origin":1456579,"position":4},"title":"Elon Musk amenaza con demandar a Apple por la clasificaci\u00f3n de su aplicaci\u00f3n de inteligencia artificial en la App Store","author":"","date":"agosto 12, 2025","format":false,"excerpt":"Elon Musk afirm\u00f3 que su startup de inteligencia artificial xAI demandar\u00e1 a Apple por supuestamente favorecer a competidores de IA en su App Store, lo que calific\u00f3 como una violaci\u00f3n de las regulaciones antimonopolio.En una serie de publicaciones en X el lunes, la plataforma de redes sociales de su propiedad,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449870,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/05\/30\/apuesta-elon-musk-politica-trump-trax\/","url_meta":{"origin":1456579,"position":5},"title":"\u00bfLe apuesta Elon Musk a la pol\u00edtica? El camino podr\u00eda ser Trump","author":"","date":"mayo 30, 2024","format":false,"excerpt":"(CNN) -- Elon Musk ha tratado de acumular un capital pol\u00edtico acorde con su extravagante riqueza. En el \u00faltimo a\u00f1o, Musk ha opinado p\u00fablicamente sobre conflictos mundiales, se ha reunido con numerosos l\u00edderes mundiales y senadores estadounidenses para hablar de inteligencia artificial y de sus tecnolog\u00edas espaciales y de sat\u00e9lites.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1456579"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456579\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1456579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1456579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1456579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}