{"id":1456599,"date":"2024-12-14T11:03:44","date_gmt":"2024-12-14T19:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/"},"modified":"2024-12-14T11:03:44","modified_gmt":"2024-12-14T19:03:44","slug":"kennedy-trump-abogado-vacuna-polio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/","title":{"rendered":"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio"},"content":{"rendered":"<p>El presidente electo Donald Trump elogi\u00f3 la vacuna contra la poliomielitis o polio como \u201calgo muy grande\u201d, pero un abogado ligado al elegido de Trump para liderar la principal agencia de salud del pa\u00eds solicit\u00f3 a la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) que <a href=\"https:\/\/icandecide.org\/wp-content\/uploads\/2023\/05\/Petition-IPOL-2022-08-23.pdf\">revoque la aprobaci\u00f3n de la vacuna <\/a>utilizada en Estados Unidos.<\/p>\n<p>El abogado, Aaron Siri, <a href=\"https:\/\/icandecide.org\/wp-content\/uploads\/2023\/05\/Petition-IPOL-2022-08-23.pdf\">present\u00f3 la solicitud en 2022<\/a> en nombre de la Red de Acci\u00f3n de Consentimiento Informado, o ICAN, una organizaci\u00f3n sin fines de lucro que cuestiona la seguridad de las vacunas y los mandatos de vacunaci\u00f3n. Siri ha trabajado estrechamente con Robert F. Kennedy Jr. \u2014un esc\u00e9ptico de las vacunas y el elegido de Trump para liderar el Departamento de Salud y Servicios Humanos de EE.UU.\u2014 eligiendo a funcionarios para la administraci\u00f3n entrante. Tambi\u00e9n fue el abogado personal de Kennedy durante su propia campa\u00f1a presidencial.<\/p>\n<p>\u201cLa Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) contin\u00faa revisando la solicitud\u201d, dijo un portavoz de la agencia en un correo electr\u00f3nico a CNN el viernes. \u201cNo podemos predecir cu\u00e1ndo se completar\u00e1n las revisiones. La FDA tomar\u00e1 en cuenta las preocupaciones expuestas en la solicitud hasta que se tome una decisi\u00f3n final. La FDA responder\u00e1 directamente al solicitante, y esa respuesta se publicar\u00e1 en el expediente. Hasta entonces, no podemos comentar m\u00e1s\u201d.<\/p>\n<p>Si Kennedy es confirmado como secretario del Departamento de Salud y Servicios Humanos, supervisar\u00e1 a la FDA y podr\u00eda incluso intervenir en el proceso de revisi\u00f3n de solicitudes. En una entrevista reciente, Kennedy declar\u00f3 a NBC News que no iba a quitarle las vacunas a nadie, pero dijo: \u201cLa gente debe poder elegir, y esa elecci\u00f3n debe basarse en informaci\u00f3n correcta\u201d.<\/p>\n<p>Trump dijo a la revista Time en una entrevista que se realiz\u00f3 a finales de noviembre y que fue publicada esta semana, que se llevar\u00e1n a cabo m\u00e1s investigaciones y que considerar\u00eda deshacerse de algunas vacunas para ni\u00f1os, si cree que son \u201cpeligrosas\u201d o \u201cque no son beneficiosas\u201d.<\/p>\n<p>Sin embargo, Trump tambi\u00e9n ha elogiado la vacunaci\u00f3n contra la polio.<\/p>\n<p>\u201cLa vacuna contra la polio es algo muy grande. Si alguien me dijera que me deshiciera de la vacuna contra la polio, tendr\u00eda que trabajar muy duro para convencerme\u201d, afirm\u00f3 Trump a NBC en \u201cMeet the Press\u201d en una entrevista transmitida este domingo.<\/p>\n<p>La solicitud y la afiliaci\u00f3n de Kennedy con el abogado que present\u00f3 la solicitud <a href=\"https:\/\/www.nytimes.com\/2024\/12\/13\/health\/aaron-siri-rfk-jr-vaccines.html\">fueron reportadas <\/a>por primera vez por The New York Times.<\/p>\n<p>CNN se comunic\u00f3 con el equipo de transici\u00f3n de Trump y con ICAN para obtener comentarios, pero no obtuvo respuesta.<\/p>\n<p>El l\u00edder de la minor\u00eda del Senado, Mitch McConnell, sobreviviente del polio, emiti\u00f3 una advertencia sobre el tema el viernes que aparentemente estaba destinada a Kennedy.<\/p>\n<p>\u201cLa vacuna contra la polio ha salvado millones de vidas y ha ayudado a erradicar una terrible enfermedad\u201d, dijo en un comunicado. \u201cLos intentos por socavar la confianza p\u00fablica en los tratamientos probados no solo son desinformados; son peligrosos. Cualquiera que busque el consentimiento del Senado para servir en la administraci\u00f3n entrante har\u00eda bien en mantenerse lejos incluso de la idea de tales intentos\u201d.<\/p>\n<p>La vacunaci\u00f3n contra la polio se considera uno de los mayores logros de la salud p\u00fablica mundial. Antes era una enfermedad que paralizaba y mataba a miles de personas, pero la aparici\u00f3n de la vacuna en la d\u00e9cada de 1950 redujo enormemente la incidencia en todo el mundo, llevando el objetivo de <a href=\"https:\/\/polioeradication.org\/about-polio\/history-of-polio\/\">erradicaci\u00f3n de la enfermedad<\/a> al borde de convertirse en realidad.<\/p>\n<p>En la d\u00e9cada de 1950, antes de que una vacuna estuviera disponible, la polio mataba o paralizaba a m\u00e1s de medio mill\u00f3n de personas a nivel mundial cada a\u00f1o, <a href=\"https:\/\/www.who.int\/news-room\/spotlight\/history-of-vaccination\/history-of-polio-vaccination\">seg\u00fan la Organizaci\u00f3n Mundial de la Salud.<\/a><\/p>\n<p>La petici\u00f3n de Siri solicita a la FDA que retire o suspenda la aprobaci\u00f3n de la vacuna inactiva contra la polio hasta que \u201cse realice un ensayo doble ciego, adecuadamente controlado y con el poder estad\u00edstico necesario, de suficiente duraci\u00f3n para evaluar la seguridad de este producto\u201d.<\/p>\n<p>Siri present\u00f3 la petici\u00f3n el mismo a\u00f1o en que los funcionarios de salud de Nueva York intensificaron las campa\u00f1as de vacunaci\u00f3n contra la polio despu\u00e9s de que un joven adulto no vacunado quedara paralizado por la infecci\u00f3n y el virus apareciera en las aguas residuales locales. Ese caso fue el primero en EE.UU. en casi una d\u00e9cada.<\/p>\n<p>La petici\u00f3n se centra en lo que parece un hecho alarmante: que no hubo un ensayo cl\u00ednico controlado con placebo para demostrar la seguridad de la vacuna. Los expertos, sin embargo, dicen que esa idea distorsiona la realidad al hacer parecer que los riesgos de la vacunaci\u00f3n contra la polio podr\u00edan superar los beneficios, lo cual no es cierto.<\/p>\n<p>De hecho, los ensayos controlados con placebo no se consideran \u00e9ticos para la mayor\u00eda de las vacunas porque una porci\u00f3n de las personas que participan en ellos no recibir\u00eda la vacuna, dej\u00e1ndola desprotegida. La polio no circula de forma masiva, y no ser\u00eda \u00e9tico infectar deliberadamente a una persona sana con el virus. No hay cura para la polio, y alguien que est\u00e9 desprotegido podr\u00eda quedar paralizado por el resto de su vida.<\/p>\n<p>\u201cEst\u00e1s sustituyendo un riesgo te\u00f3rico por un riesgo real\u201d, dijo el Dr. Paul Offit, experto en vacunas del Hospital Infantil de Filadelfia, a The New York Times. \u201cLos riesgos reales son las enfermedades\u201d.<\/p>\n<p>Los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC) se\u00f1alan que no se han documentado eventos adversos graves relacionados con el uso de la vacuna inactivada contra la poliomielitis. Rara vez, las personas pueden<a href=\"https:\/\/www.cdc.gov\/vaccines\/vpd\/polio\/hcp\/contraindications-precautions.html\"> tener reacciones<\/a> a la vacuna si son al\u00e9rgicas a ciertos tipos de antibi\u00f3ticos, como estreptomicina, colistina B o neomicina.<\/p>\n<p>La petici\u00f3n de Siri se centra en la vacuna inactivada contra la poliomielitis, que se ha utilizado en Estados Unidos durante m\u00e1s de dos d\u00e9cadas.<\/p>\n<p>EE.UU. dej\u00f3 de usar la vacuna oral \u2014que utiliza una versi\u00f3n viva pero debilitada del virus\u2014 porque alrededor de una vez cada 3 millones de veces que se administra, el virus debilitado puede causar par\u00e1lisis en el receptor de la vacuna. Sin embargo, la vacuna oral todav\u00eda se usa en algunos otros pa\u00edses.<\/p>\n<p>La vacuna inactivada contra la poliomielitis que se utiliza en Estados Unidos se administra por inyecci\u00f3n y no conlleva ese riesgo, lo que la hace a\u00fan m\u00e1s segura para las personas que la reciben. Pero la vacuna inyectada no crea una llamada inmunidad mucosal, lo que significa que no impide que el virus pueda infectar a las personas si ingresa al cuerpo.<\/p>\n<p>En cambio, la vacuna inyectada protege a las personas contra ese peor escenario: ayuda al sistema inmunol\u00f3gico a reconocer el virus y combatirlo antes de que llegue al sistema nervioso.<\/p>\n<p>Sin embargo, no detiene la transmisi\u00f3n del virus, porque las personas que la reciben a\u00fan pueden infectarse y eliminar el virus en sus heces.<\/p>\n<p>Con todo, en Estados Unidos esto no ha sido problema porque \u2014gracias a la vacunaci\u00f3n\u2014 el poliovirus no suele circular.<\/p>\n<p>El poliovirus se propaga de persona a persona a trav\u00e9s de la ruta fecal-oral. Las personas se infectan entre s\u00ed cuando se contagian el virus en las manos despu\u00e9s de usar el ba\u00f1o y luego se dan la mano o tocan superficies.<\/p>\n<p>El virus debilitado de la vacuna oral tambi\u00e9n se puede eliminar en las heces, y eso puede convertirse en un problema en poblaciones que no est\u00e1n adecuadamente vacunadas. Si esta transmisi\u00f3n ocurre en una poblaci\u00f3n que no est\u00e1 bien vacunada, hay una posibilidad de que pueda mutar de nuevo a una forma que cause par\u00e1lisis.<\/p>\n<p>La mayor\u00eda de los casos de poliomielitis en el mundo ahora son causados por virus derivados de la vacuna. En 2023, el n\u00famero de casos de poliomielitis causados por cepas derivadas de la vacuna fue de 524, una disminuci\u00f3n respecto a 881 en 2022.<\/p>\n<p><em>Manu Raju y Morgan Rimmer de CNN contribuyeron a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente electo Donald Trump elogi\u00f3 la vacuna contra la poliomielitis o polio como \u201calgo muy grande\u201d, pero un abogado ligado al elegido de Trump para liderar la principal agencia de salud del pa\u00eds solicit\u00f3 a la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) que revoque la aprobaci\u00f3n de la vacuna utilizada en Estados [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456599","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente electo Donald Trump elogi\u00f3 la vacuna contra la poliomielitis o polio como \u201calgo muy grande\u201d, pero un abogado ligado al elegido de Trump para liderar la principal agencia de salud del pa\u00eds solicit\u00f3 a la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) que revoque la aprobaci\u00f3n de la vacuna utilizada en Estados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-14T19:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio\",\"datePublished\":\"2024-12-14T19:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/\"},\"wordCount\":1440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/\",\"name\":\"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-14T19:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio - Noticias","og_description":"El presidente electo Donald Trump elogi\u00f3 la vacuna contra la poliomielitis o polio como \u201calgo muy grande\u201d, pero un abogado ligado al elegido de Trump para liderar la principal agencia de salud del pa\u00eds solicit\u00f3 a la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) que revoque la aprobaci\u00f3n de la vacuna utilizada en Estados [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-14T19:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/"},"author":{"name":"","@id":""},"headline":"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio","datePublished":"2024-12-14T19:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/"},"wordCount":1440,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/","name":"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-14T19:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\u00f3n de la vacuna contra la polio","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/14\/kennedy-trump-abogado-vacuna-polio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-14T19:03:44Z","datePublished":"2024-12-14T19:03:44Z","dateModified":"2024-12-14T19:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Abogado del elegido de Trump para el Departamento de Salud pide a la FDA que revoque aprobaci\\u00f3n de la vacuna contra la polio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/14\\\/kennedy-trump-abogado-vacuna-polio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/14\\\/kennedy-trump-abogado-vacuna-polio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-14T19:03:44Z\",\"datePublished\":\"2024-12-14T19:03:44Z\",\"dateModified\":\"2024-12-14T19:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471090,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/02\/10\/fda-solicitud-moderna-vacuna-antigripal-arnm-trax\/","url_meta":{"origin":1456599,"position":0},"title":"La FDA se niega a revisar la solicitud de Moderna para vacuna antigripal de ARNm, dice la empresa","author":"","date":"febrero 10, 2026","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) se neg\u00f3 a aceptar una solicitud de Moderna para revisar su primera vacuna antigripal estacional de ARNm, inform\u00f3 la empresa el martes, en otro rev\u00e9s para la tecnolog\u00eda que ha sido objeto de cr\u00edticas por parte de algunos funcionarios de salud\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462852,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/05\/27\/recomendacion-vacuna-covid-19-ninos-embarazadas-trax\/","url_meta":{"origin":1456599,"position":1},"title":"RFK Jr. afirma que la vacuna contra el covid-19 ya no se recomendar\u00e1 para ni\u00f1os sanos y mujeres embarazadas","author":"","date":"mayo 27, 2025","format":false,"excerpt":"El secretario del Departamento de Salud y Servicios Humanos de EE.UU., Robert F. Kennedy Jr., anunci\u00f3 el martes que la vacuna contra el covid-19 ya no figurar\u00e1 entre las vacunas recomendadas para mujeres embarazadas y ni\u00f1os sanos en el calendario de vacunaci\u00f3n de los Centros para el Control y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462967,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/05\/29\/cambios-politica-vacuna-contra-covid-19-ee-uu-pueden-afectarte-trax\/","url_meta":{"origin":1456599,"position":2},"title":"\u00bfC\u00f3mo pueden afectarte los cambios en la pol\u00edtica de la vacuna contra el covid-19 en EE.UU.?","author":"","date":"mayo 29, 2025","format":false,"excerpt":"El Departamento de Salud y Servicios Humanos de EE.UU., bajo la direcci\u00f3n del secretario Robert F. Kennedy Jr., ha realizado recientemente cambios significativos en la forma en que se aprueban las vacunas contra el covid-19 y los grupos para los cuales se recomiendan.Durante los \u00faltimos a\u00f1os, el Gobierno federal ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469208,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/12\/12\/fda-advertencia-vacuna-covid-19-trax\/","url_meta":{"origin":1456599,"position":3},"title":"La FDA pretende poner su advertencia m\u00e1s seria a las vacunas contra el covid-19, seg\u00fan fuentes","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) planea colocar una advertencia de \u201crecuadro negro\u201d en las vacunas contra el covid-19, seg\u00fan dos personas familiarizadas con los planes de la agencia.Un recuadro de advertencia, que aparece en la parte superior de la informaci\u00f3n de prescripci\u00f3n de los medicamentos, es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461831,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/05\/01\/hhs-pruebas-placebo-todas-vacunas-nuevas-dudas-aprobacion-vacunas-covid-trax\/","url_meta":{"origin":1456599,"position":4},"title":"El HHS exigir\u00e1 pruebas con placebo para &#171;todas las vacunas nuevas&#187;, planteando dudas sobre la aprobaci\u00f3n de vacunas covid-19","author":"","date":"mayo 1, 2025","format":false,"excerpt":"El Departamento de Salud y Servicios Humanos de Estados Unidos (HHS, por sus siglas en ingl\u00e9s) anunci\u00f3 que exigir\u00e1 que todas las vacunas nuevas se prueben en ensayos controlados con placebo antes de autorizar su uso, lo que plantea preguntas urgentes sobre el sistema utilizado para autorizar las vacunas contra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456038,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/11\/23\/trump-puestos-clave-en-salud-publica-trax\/","url_meta":{"origin":1456599,"position":5},"title":"Trump designa puestos clave en salud p\u00fablica","author":"","date":"noviembre 23, 2024","format":false,"excerpt":"(CNN) -- El presidente electo, Donald Trump, anunci\u00f3 este viernes sus candidatos para los puestos de salud p\u00fablica m\u00e1s importantes de su pr\u00f3xima administraci\u00f3n.Trump nombr\u00f3 a la Dra. Janette Nesheiwat como directora general de Sanidad de EE.UU., al Dr. Marty Makary como comisionado de la Administraci\u00f3n de Alimentos y Medicamentos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1456599"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456599\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1456599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1456599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1456599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}