{"id":1456602,"date":"2024-12-14T14:03:56","date_gmt":"2024-12-14T22:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/"},"modified":"2024-12-14T14:03:56","modified_gmt":"2024-12-14T22:03:56","slug":"advertencia-tornado-san-francisco-historia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/","title":{"rendered":"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco"},"content":{"rendered":"<p>Por primera vez en la historia registrada, el centro de San Francisco recibi\u00f3 una advertencia de tornado este s\u00e1bado mientras tormentas severas azotaban la ciudad, justo una semana despu\u00e9s de que una<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/05\/noticias-terremoto-california-tsunami-trax\/\"> advertencia de tsunami<\/a> causara p\u00e1nico en la regi\u00f3n.<\/p>\n<p>El <a href=\"https:\/\/x.com\/SF_emergency\">Departamento de Gesti\u00f3n de Emergencias de San Francisco <\/a>(SFDEM) confirm\u00f3 que la amenaza de tornado termin\u00f3 alrededor de las 6:14 a.m., hora PST, (9:14 a.m. ET) despu\u00e9s de que la tormenta se moviera al noreste desde el centro.<\/p>\n<p>\u201cBusquen refugio ahora en un s\u00f3tano o en una habitaci\u00f3n interior en el piso de m\u00e1s bajo de un edificio resistente. Si est\u00e1n al aire libre, en una casa m\u00f3vil o en un veh\u00edculo, mu\u00e9vanse al refugio m\u00e1s cercano y prot\u00e9janse de los escombros\u201d, inst\u00f3 el SFDEM a los residentes en una publicaci\u00f3n en X.<\/p>\n<p>El Servicio Meteorol\u00f3gico Nacional (NWS) tambi\u00e9n emiti\u00f3 un aviso de inundaci\u00f3n y una advertencia de vientos fuertes, con vientos sostenidos de hasta 65 km\/h para varias \u00e1reas a lo largo de la costa. El Aeropuerto de San Francisco report\u00f3 una r\u00e1faga de viento de 72 nudos (134 km\/h) en el momento en que la tormenta pas\u00f3. Un <a href=\"https:\/\/www.facebook.com\/john.lira.505\/videos\/605914475201282\/\">video<\/a> compartido en Facebook muestra vientos extremos sacudiendo palmeras en el centro de San Francisco.<\/p>\n<p>M\u00e1s de 10.000 personas estaban <a href=\"https:\/\/poweroutage.us\/area\/county\/2939\">sin electricidad <\/a>en San Francisco hasta la ma\u00f1ana de este s\u00e1bado.<\/p>\n<p>California promedia nueve tornados al a\u00f1o. No se hab\u00edan registrado previamente advertencias de tornado para el centro de San Francisco, confirm\u00f3 el NWS.<\/p>\n<p>Una semana antes, se emiti\u00f3 una advertencia de tsunami para el \u00e1rea de la bah\u00eda de San Francisco que afect\u00f3 a casi 5 millones de personas a lo largo de la costa del norte de California y Oregon despu\u00e9s de que un sismo de magnitud 7,0 golpeara la costa del estado el 5 de diciembre. Un terremoto tan fuerte es relativamente raro, con solo alrededor de 15 reportados en todo el mundo cada a\u00f1o.<\/p>\n<p>Las comunidades costeras evitaron un desastre potencial y la advertencia fue cancelada por el Centro Nacional de Advertencia de Tsunamis despu\u00e9s de que algunos residentes huyeran de sus hogares. La mayor\u00eda de los sismos significativos fuera de la costa provocan tales advertencias, ya que los expertos tienen poco tiempo para determinar el riesgo inmediato, y el resultado de un tsunami podr\u00eda ser desastroso.<\/p>\n<p>El epicentro del terremoto fue en el oc\u00e9ano Pac\u00edfico al sur de Eureka, California, dijo el Servicio Geol\u00f3gico de EE.UU. Eureka es la ciudad costera m\u00e1s grande entre San Francisco y Portland, Oregon, y est\u00e1 a unas 300 millas (480 kil\u00f3metros) al noroeste de Sacramento.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por primera vez en la historia registrada, el centro de San Francisco recibi\u00f3 una advertencia de tornado este s\u00e1bado mientras tormentas severas azotaban la ciudad, justo una semana despu\u00e9s de que una advertencia de tsunami causara p\u00e1nico en la regi\u00f3n. El Departamento de Gesti\u00f3n de Emergencias de San Francisco (SFDEM) confirm\u00f3 que la amenaza de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456602","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Emiten la primera avertencia de tornado de la historia para el centro de San Francisco - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco - Noticias\" \/>\n<meta property=\"og:description\" content=\"Por primera vez en la historia registrada, el centro de San Francisco recibi\u00f3 una advertencia de tornado este s\u00e1bado mientras tormentas severas azotaban la ciudad, justo una semana despu\u00e9s de que una advertencia de tsunami causara p\u00e1nico en la regi\u00f3n. El Departamento de Gesti\u00f3n de Emergencias de San Francisco (SFDEM) confirm\u00f3 que la amenaza de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-14T22:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco\",\"datePublished\":\"2024-12-14T22:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/\",\"name\":\"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-14T22:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco - Noticias","og_description":"Por primera vez en la historia registrada, el centro de San Francisco recibi\u00f3 una advertencia de tornado este s\u00e1bado mientras tormentas severas azotaban la ciudad, justo una semana despu\u00e9s de que una advertencia de tsunami causara p\u00e1nico en la regi\u00f3n. El Departamento de Gesti\u00f3n de Emergencias de San Francisco (SFDEM) confirm\u00f3 que la amenaza de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-14T22:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/"},"author":{"name":"","@id":""},"headline":"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco","datePublished":"2024-12-14T22:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/","name":"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-14T22:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/14\/advertencia-tornado-san-francisco-historia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-14T22:03:56Z","datePublished":"2024-12-14T22:03:56Z","dateModified":"2024-12-14T22:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Emiten la primera avertencia de tornado de la historia para el centro de San Francisco\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/14\\\/advertencia-tornado-san-francisco-historia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/14\\\/advertencia-tornado-san-francisco-historia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-14T22:03:56Z\",\"datePublished\":\"2024-12-14T22:03:56Z\",\"dateModified\":\"2024-12-14T22:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448641,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/","url_meta":{"origin":1456602,"position":0},"title":"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas","author":"","date":"abril 28, 2024","format":false,"excerpt":"(CNN) -- Al menos cuatro personas murieron, entre ellas un beb\u00e9, despu\u00e9s de un tornado que azot\u00f3 Oklahoma durante la noche, mientras fuertes tormentas amenazan con m\u00e1s tornados, fuertes lluvias y granizo desde Missouri hasta Texas este domingo.Seg\u00fan el Servicio Meteorol\u00f3gico Nacional de EE.UU., se reportaron simult\u00e1neamente m\u00faltiples tornados grandes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472119,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/03\/12\/tormentas-severas-avanzan-este-tornado-mortal-trax\/","url_meta":{"origin":1456602,"position":1},"title":"Tormentas severas avanzan hacia el este de EE.UU. tras tornado mortal","author":"","date":"marzo 12, 2026","format":false,"excerpt":"Una l\u00ednea de turbonadas con fuertes lluvias y frecuentes rel\u00e1mpagos avanza por el sureste la madrugada del jueves.Como consecuencia, se mantienen los avisos por tornado en Alabama y Georgia, donde podr\u00edan formarse r\u00e1pidamente a lo largo de la l\u00ednea fronteriza mutua. Los vientos destructivos en l\u00ednea recta siguen siendo la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448626,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/04\/27\/brote-tornados-oklahoma-causa-llamados-mientras-amenaza-fuertes-tormentas-continua-desde-missouri-hasta-texas-trax\/","url_meta":{"origin":1456602,"position":2},"title":"Brote de tornados en Oklahoma causa llamados a resguardarse mientras la amenaza de fuertes tormentas contin\u00faa desde Missouri hasta Texas","author":"","date":"abril 27, 2024","format":false,"excerpt":"(CNN) -- La amenaza de fuertes tormentas que generan tornados contin\u00faa este domingo desde Missouri hasta Texas, donde es posible que se produzcan m\u00e1s tornados, lluvias intensas y granizo grande, mientras las comunidades en Nebraska e Iowa eval\u00faan la destrucci\u00f3n que las tormentas ya han dejado.Un brote de tornados en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447038,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/03\/16\/tormentas-tornados-indiana-ohio-trax\/","url_meta":{"origin":1456602,"position":3},"title":"Tormentas devastadoras y fuertes tornados dejan varios muertos, decenas de heridos y viviendas destruidas en Indiana y Ohio","author":"","date":"marzo 16, 2024","format":false,"excerpt":"(CNN) --\u00a0Tormentas devastadoras y fuertes tornados azotaron Indiana y Ohio la noche de este jueves, dejando al menos tres personas muertas, seg\u00fan las autoridades. El mal tiempo tambi\u00e9n destruy\u00f3 zonas de varias ciudades y llev\u00f3 a que se activaran los esfuerzos de b\u00fasqueda y rescate, detallaron funcionarios.\"La mejor manera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467162,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/10\/06\/primer-tornado-ef5-decada-estados-unidos-trax\/","url_meta":{"origin":1456602,"position":4},"title":"Expertos confirman el primer tornado EF5 en m\u00e1s de una d\u00e9cada en Estados Unidos","author":"","date":"octubre 6, 2025","format":false,"excerpt":"Un raro y monstruoso tornado EF5 que azot\u00f3 Estados Unidos hace m\u00e1s de tres meses fue confirmado como el primero de su tipo en m\u00e1s de una d\u00e9cada, anunciaron expertos este lunes.Un tornado que rugi\u00f3 a trav\u00e9s de una parte del este de Dakota del Norte en junio y mat\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449764,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/05\/25\/nueva-alerta-tornado-kansas-trax\/","url_meta":{"origin":1456602,"position":5},"title":"Nueva alerta de tornado emitida para algunas zonas de Kansas","author":"","date":"mayo 25, 2024","format":false,"excerpt":"(CNN) -- Se emiti\u00f3 una nueva alerta de tornado para partes de Kansas hasta la 1 a. m. CDT. Este reloj incluye ciudades como Salina y Emporia, Kansas.Las tormentas superc\u00e9lulas est\u00e1n comenzando a desencadenarse y podr\u00edan generar un par de tornados, granizo esparcido del tama\u00f1o de pelotas de b\u00e9isbol y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1456602"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456602\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1456602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1456602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1456602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}