{"id":1456632,"date":"2024-12-15T16:03:46","date_gmt":"2024-12-16T00:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/"},"modified":"2024-12-15T16:03:46","modified_gmt":"2024-12-16T00:03:46","slug":"netanyahu-trump-llamada-siria-altos-del-golan-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/","title":{"rendered":"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &#171;victoria&#187; en una llamada telef\u00f3nica &#171;muy c\u00e1lida&#187;"},"content":{"rendered":"<p>El primer ministro de Israel, Benjamin Netanyahu, dijo este domingo que tuvo una llamada telef\u00f3nica \u201cmuy c\u00e1lida\u201d con el presidente electo de Estados Unidos, Donald Trump, durante la cual hablaron sobre la necesidad de la victoria de Israel en su guerra contra Hamas en Gaza y su postura sobre Siria.<\/p>\n<p>En un mensaje grabado en video, el l\u00edder israel\u00ed dijo que trat\u00f3 una serie de temas con Trump durante la llamada el s\u00e1bado por la noche, incluido el compromiso de Israel de impedir que Hezbollah, con sede en el L\u00edbano, se rearme y el conflicto de Israel con Hamas, que ha matado a casi 45.000 palestinos en el asediado enclave de Gaza.<\/p>\n<p>Los l\u00edderes tambi\u00e9n hablaron de la necesidad de traer a casa a los rehenes que quedan en Gaza, dijo Netanyahu.<\/p>\n<p>\u201cAnoche volv\u00ed a hablar de todo esto con mi amigo, el presidente electo de Estados Unidos, Donald Trump\u201d, dijo Netanyahu.<\/p>\n<p>\u201cFue una conversaci\u00f3n muy amistosa, muy c\u00e1lida y muy importante. Hablamos de la necesidad de completar la victoria de Israel, y tambi\u00e9n hablamos largo y tendido sobre los esfuerzos que estamos haciendo para liberar a nuestros rehenes\u201d.<\/p>\n<p>Se cree que Hamas y otros grupos siguen reteniendo a 100 rehenes en Gaza, entre ellos siete estadounidenses. Todos menos cuatro de los rehenes fueron capturados durante el ataque de Hamas contra Israel el 7 de octubre de 2023.<\/p>\n<p>Netanyahu afirm\u00f3 que Israel sigue \u201ctrabajando incansablemente para traer a casa a nuestros rehenes, tanto a los vivos como a los muertos. Y a\u00f1ado, cuanto menos hablemos de ello, mejor, y as\u00ed, con la ayuda de Dios, lo conseguiremos\u201d.<\/p>\n<p>CNN se puso en contacto con el equipo de transici\u00f3n de Trump para obtener comentarios.<\/p>\n<p>En cuanto a Siria, donde una coalici\u00f3n rebelde derroc\u00f3 al r\u00e9gimen del presidente Bashar al-Assad el pasado fin de semana tras un avance rel\u00e1mpago por el pa\u00eds, Netanyahu dijo que Israel no ten\u00eda \u201cning\u00fan inter\u00e9s en un conflicto\u201d con el pa\u00eds, sino que ajustar\u00eda su pol\u00edtica en funci\u00f3n de la \u201crealidad emergente sobre el terreno\u201d.<\/p>\n<p>Sus comentarios m\u00e1s recientes se producen despu\u00e9s de que, tras la ca\u00edda de Assad, las fuerzas israel\u00edes tomaran el control de una antigua <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/14\/mundo\/israel-siria-golan-monte-hermon-trax\">zona de amortiguamiento<\/a> que hab\u00eda separado durante d\u00e9cadas a las fuerzas israel\u00edes y sirias, una medida que los rebeldes que ahora mandan en Siria y algunos vecinos del pa\u00eds han criticado.<\/p>\n<p>Funcionarios israel\u00edes dijeron que la medida era temporal y Netanyahu insisti\u00f3 en que Israel \u201cno tiene intenci\u00f3n\u201d de intervenir en los asuntos internos de Siria.<\/p>\n<p>Sin embargo, en su declaraci\u00f3n de este domingo, el l\u00edder israel\u00ed se\u00f1al\u00f3 que Siria hab\u00eda \u201cpermitido a Ir\u00e1n armar a Hezbollah a trav\u00e9s de su territorio\u201d y dijo que Israel estaba comprometido a impedir que el grupo militante se rearmara.<\/p>\n<p>\u201cEsta es una prueba permanente para Israel, debemos afrontarla y lo haremos. A Hezbollah e Ir\u00e1n les digo en t\u00e9rminos inequ\u00edvocos: para evitar que nos perjudiquen, seguiremos actuando contra ustedes tanto como sea necesario, en todos los \u00e1mbitos y en cualquier momento\u201d, afirm\u00f3.<\/p>\n<p>Israel lleg\u00f3 a un acuerdo de alto el fuego con Hezbollah en noviembre, tras un conflicto de 13 meses librado en gran parte a lo largo de la frontera de Israel con L\u00edbano, en el que Israel mat\u00f3 a varios altos mandos de Hezbollah. Los continuos ataques pusieron en peligro el acuerdo.<\/p>\n<p>El control israel\u00ed de la zona de contenci\u00f3n se ha sumado a las tensiones con Siria por su presencia durante d\u00e9cadas en los Altos del Gol\u00e1n, una meseta estrat\u00e9gica en el suroeste de Siria que Israel ocupa desde una guerra en 1967. Siria intent\u00f3 retomar el territorio en un ataque por sorpresa en 1973, pero fracas\u00f3, e Israel se lo anexion\u00f3 en 1981.<\/p>\n<p>Desde la ca\u00edda de Assad la semana pasada, el ej\u00e9rcito israel\u00ed tambi\u00e9n tom\u00f3 el control del monte Herm\u00f3n, colindante con los Altos del Gol\u00e1n y situado en la zona de amortiguamiento que antes separaba a las tropas de ambos bandos.<\/p>\n<p>A pesar de la insistencia de Israel en que el movimiento es temporal, varios Estados \u00e1rabes han acusado a Israel de explotar la inestabilidad en Siria para ejecutar una apropiaci\u00f3n de tierras, mientras que la coalici\u00f3n rebelde ahora a cargo de Siria lo ha acusado de \u201ccruzar las l\u00edneas de compromiso\u201d.<\/p>\n<p>Para aumentar esas tensiones, el Gobierno de Israel aprob\u00f3 este domingo un plan de Netanyahu para ampliar los asentamientos en los Altos del Gol\u00e1n ocupados, seg\u00fan un comunicado de la oficina del primer ministro.<\/p>\n<p>\u201cA la luz de la guerra y del nuevo frente contra Siria, y por el deseo de duplicar la poblaci\u00f3n de los Altos del Gol\u00e1n, el primer ministro Benjamin Netanyahu someti\u00f3 hoy a la aprobaci\u00f3n del gobierno la primera enmienda al plan para fomentar el crecimiento demogr\u00e1fico en los Altos del Gol\u00e1n y los Altos de Katzrin\u201d, se\u00f1al\u00f3 el comunicado. Katzrin es un asentamiento israel\u00ed en el Gol\u00e1n.<\/p>\n<p>El plan \u201cayudar\u00e1 al Consejo Regional del Gol\u00e1n a absorber a los nuevos residentes que lleguen\u201d, indic\u00f3 el comunicado.<\/p>\n<p>\u201cFortalecer los Altos del Gol\u00e1n es fortalecer el Estado de Israel, y es especialmente importante en estos momentos. Seguiremos aferr\u00e1ndonos a \u00e9l, haci\u00e9ndolo florecer y asent\u00e1ndolo\u201d, dijo Netanyahu, seg\u00fan el comunicado.<\/p>\n<p>La ocupaci\u00f3n es ilegal seg\u00fan el derecho internacional, pero Estados Unidos reconoci\u00f3 la reclamaci\u00f3n de Israel sobre el Gol\u00e1n durante el Gobierno de Trump en 2019. Israel no considera su presencia en el Gol\u00e1n como asentamientos.<\/p>\n<p>Arabia Saudita, Emiratos \u00c1rabes Unidos y Qatar condenaron el plan de expansi\u00f3n del asentamiento del Gol\u00e1n. Qatar dijo que consideraba el plan de expansi\u00f3n una \u201cviolaci\u00f3n flagrante del derecho internacional\u201d y una nueva agresi\u00f3n a los territorios sirios; Arabia Saudita dijo que la medida descarrilar\u00eda las posibilidades de Siria de restablecer la seguridad y la estabilidad.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer ministro de Israel, Benjamin Netanyahu, dijo este domingo que tuvo una llamada telef\u00f3nica \u201cmuy c\u00e1lida\u201d con el presidente electo de Estados Unidos, Donald Trump, durante la cual hablaron sobre la necesidad de la victoria de Israel en su guerra contra Hamas en Gaza y su postura sobre Siria. En un mensaje grabado en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456632","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &quot;victoria&quot; en una llamada telef\u00f3nica &quot;muy c\u00e1lida&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &quot;victoria&quot; en una llamada telef\u00f3nica &quot;muy c\u00e1lida&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El primer ministro de Israel, Benjamin Netanyahu, dijo este domingo que tuvo una llamada telef\u00f3nica \u201cmuy c\u00e1lida\u201d con el presidente electo de Estados Unidos, Donald Trump, durante la cual hablaron sobre la necesidad de la victoria de Israel en su guerra contra Hamas en Gaza y su postura sobre Siria. En un mensaje grabado en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T00:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &#171;victoria&#187; en una llamada telef\u00f3nica &#171;muy c\u00e1lida&#187;\",\"datePublished\":\"2024-12-16T00:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/\"},\"wordCount\":1057,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/\",\"name\":\"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la \\\"victoria\\\" en una llamada telef\u00f3nica \\\"muy c\u00e1lida\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-16T00:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &#171;victoria&#187; en una llamada telef\u00f3nica &#171;muy c\u00e1lida&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la \"victoria\" en una llamada telef\u00f3nica \"muy c\u00e1lida\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la \"victoria\" en una llamada telef\u00f3nica \"muy c\u00e1lida\" - Noticias","og_description":"El primer ministro de Israel, Benjamin Netanyahu, dijo este domingo que tuvo una llamada telef\u00f3nica \u201cmuy c\u00e1lida\u201d con el presidente electo de Estados Unidos, Donald Trump, durante la cual hablaron sobre la necesidad de la victoria de Israel en su guerra contra Hamas en Gaza y su postura sobre Siria. En un mensaje grabado en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-16T00:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/"},"author":{"name":"","@id":""},"headline":"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &#171;victoria&#187; en una llamada telef\u00f3nica &#171;muy c\u00e1lida&#187;","datePublished":"2024-12-16T00:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/"},"wordCount":1057,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/","name":"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la \"victoria\" en una llamada telef\u00f3nica \"muy c\u00e1lida\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-16T00:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &#171;victoria&#187; en una llamada telef\u00f3nica &#171;muy c\u00e1lida&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &#171;victoria&#187; en una llamada telef\u00f3nica &#171;muy c\u00e1lida&#187;","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-16T00:03:46Z","datePublished":"2024-12-16T00:03:46Z","dateModified":"2024-12-16T00:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Netanyahu dice que habl\\u00f3 con Trump sobre la necesidad de la &#171;victoria&#187; en una llamada telef\\u00f3nica &#171;muy c\\u00e1lida&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/15\\\/netanyahu-trump-llamada-siria-altos-del-golan-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/15\\\/netanyahu-trump-llamada-siria-altos-del-golan-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-16T00:03:46Z\",\"datePublished\":\"2024-12-16T00:03:46Z\",\"dateModified\":\"2024-12-16T00:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463450,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/06\/11\/trump-netanyahu-fin-guerra-gaza-amenazas-iran-trax\/","url_meta":{"origin":1456632,"position":0},"title":"Trump le dice a Netanyahu que ponga fin a la guerra de Gaza y detenga las amenazas contra Ir\u00e1n, seg\u00fan una fuente","author":"","date":"junio 11, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, le dijo al primer ministro de Israel, Benjamin Netanyahu, que pusiera fin a la guerra en Gaza y dejara de hablar sobre un ataque a Ir\u00e1n, seg\u00fan una fuente familiarizada con la conversaci\u00f3n.Los dos l\u00edderes hablaron por tel\u00e9fono el lunes. M\u00e1s tarde, Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467107,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/10\/04\/trump-victoria-hamas-acorrala-netanyahu-trax\/","url_meta":{"origin":1456632,"position":1},"title":"Trump cant\u00f3 victoria tras la respuesta de Hamas al plan de alto el fuego, lo que acorrala a Netanyahu","author":"","date":"octubre 4, 2025","format":false,"excerpt":"Cuando lleg\u00f3 la noticia a la Casa Blanca el viernes por la tarde de que Hamas, despu\u00e9s de casi cinco d\u00edas, hab\u00eda respondido a la propuesta de 20 puntos del presidente Donald Trump para poner fin a la guerra en Gaza, los funcionarios fueron tan r\u00e1pidos en acoger la declaraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460867,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/04\/05\/trump-reunion-netanyahu-casa-blanca-lunes-trax\/","url_meta":{"origin":1456632,"position":2},"title":"Trump se reunir\u00e1 con Netanyahu en la Casa Blanca el lunes, dice un funcionario","author":"","date":"abril 5, 2025","format":false,"excerpt":"Se espera que el presidente de Estados Unidos, Donald Trump, reciba al primer ministro de Israel, Benjamin Netanyahu, en la Casa Blanca el lunes, seg\u00fan dijo un funcionario de la Casa Blanca a CNN.La visita, reportada por primera vez por Axios, se produce mientras Estados Unidos impone aranceles del 17%\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466947,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/29\/netanyahu-disculpa-qatar-casa-blanca-trax\/","url_meta":{"origin":1456632,"position":3},"title":"Mientras estaba en la Casa Blanca, Netanyahu se disculp\u00f3 con Qatar por el ataque en Doha, dijeron fuentes a CNN","author":"","date":"septiembre 29, 2025","format":false,"excerpt":"El primer ministro de Israel, Benjamin Netanyahu, se disculp\u00f3 con Qatar por el ataque en Doha desde la Casa Blanca, donde se reuni\u00f3 este lunes con el presidente de EE.UU., Donald Trump, seg\u00fan una fuente israel\u00ed.Por otra parte, una persona cercana tambi\u00e9n confirm\u00f3 que Netanyahu se disculp\u00f3 con el primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466958,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/29\/trump-netanyahu-cese-fuego-gaza-acuerdo-trax\/","url_meta":{"origin":1456632,"position":4},"title":"Trump dice que un cese del fuego en Gaza est\u00e1 m\u00e1s cerca que nunca, pero la realidad es m\u00e1s complicada","author":"","date":"septiembre 29, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump sali\u00f3 de las conversaciones con el primer ministro de Israel Benjamin Netanyahu, el lunes, afirmando que el fin de la guerra en Gaza estaba m\u00e1s cerca que nunca despu\u00e9s de que Netanyahu aceptara un plan de 20 puntos que establece los par\u00e1metros de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467302,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/10\/11\/trump-acorralo-netanyahu-salvado-trax\/","url_meta":{"origin":1456632,"position":5},"title":"Trump acorral\u00f3 a Netanyahu, pero tambi\u00e9n podr\u00eda haberlo salvado","author":"","date":"octubre 11, 2025","format":false,"excerpt":"En la Plaza de los Rehenes de Tel Aviv, Donald Trump reina con autoridad. Pancartas que proclaman \u201cAmamos a Trump\u201d ofrecen un efusivo agradecimiento al presidente de Estados Unidos. Para las familias de los rehenes israel\u00edes secuestrados por Hamas en Gaza, y las multitudes que apoyaron su lucha durante dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1456632"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456632\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1456632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1456632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1456632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}