{"id":1456899,"date":"2024-12-23T15:03:38","date_gmt":"2024-12-23T23:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/"},"modified":"2024-12-23T15:03:38","modified_gmt":"2024-12-23T23:03:38","slug":"historia-canal-panama-por-que-trump-amenaza-control-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","title":{"rendered":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?"},"content":{"rendered":"<p>El presidente electo de Estados Unidos, Donald Trump, sugiri\u00f3 el fin de semana que EE.UU. deber\u00eda retomar el <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/22\/estados-unidos\/trump-podria-exigir-canal-panama-estados-unidos-orix\">Canal de Panam\u00e1<\/a>, una idea que fue inmediatamente rechazada por el Gobierno de Panam\u00e1, que ha controlado el paso durante d\u00e9cadas.<\/p>\n<p>En mensajes en redes sociales y comentarios a sus simpatizantes, Trump acus\u00f3 a Panam\u00e1 de cobrar a EE.UU. \u201ctarifas exorbitantes\u201d por utilizar el canal e insinu\u00f3 la creciente influencia china sobre la crucial v\u00eda navegable.<\/p>\n<p>\u201cLas tarifas que cobra Panam\u00e1 son rid\u00edculas, especialmente conociendo la extraordinaria generosidad que ha otorgado EE.UU. a Panam\u00e1\u201d, escribi\u00f3 Trump en Truth Social el s\u00e1bado.<\/p>\n<p>El canal, construido por Estados Unidos, fue inaugurado en 1914 y controlado por ese pa\u00eds hasta que un acuerdo de 1977 dispuso su eventual traspaso a Panam\u00e1. El canal fue operado conjuntamente por ambos pa\u00edses hasta que el Gobierno paname\u00f1o se qued\u00f3 con el control total a partir de 1999.<\/p>\n<p>En un <a href=\"https:\/\/www.cnn.com\/2024\/12\/22\/politics\/trump-turning-point-rally-key-lines\/index.html\">discurso ante una multitud<\/a> de j\u00f3venes conservadores en Phoenix el domingo, Trump dijo que, si no se sigue el esp\u00edritu de ese acuerdo, \u201centonces exigiremos que el Canal de Panam\u00e1 sea devuelto a Estados Unidos. As\u00ed que, a los funcionarios de Panam\u00e1, por favor, que se gu\u00eden en consecuencia\u201d.<\/p>\n<p>No est\u00e1 claro hasta qu\u00e9 punto Trump se est\u00e1 tomando en serio su amenaza de reclamar el control sobre el canal, aunque la del fin de semana <a href=\"https:\/\/www.rev.com\/transcripts\/tucker-on-x-debate-night-interview-with-donald-trump-transcript\">no ha sido la primera vez<\/a> que ha dicho que Estados Unidos est\u00e1 recibiendo un trato injusto. El presidente electo no ha aclarado c\u00f3mo obligar\u00eda a un pa\u00eds soberano y amigo a ceder su propio territorio.<\/p>\n<p>Y el Gobierno de Panam\u00e1 no quiere tener nada que ver con la sugerencia de Trump.<\/p>\n<p>\u201cComo presidente, quiero expresar de manera precisa que cada metro cuadrado del Canal de Panam\u00e1 y su zona adyacente es de Panam\u00e1, y lo seguir\u00e1 siendo\u201d, dijo el presidente del pa\u00eds, Jos\u00e9 Ra\u00fal Mulino, en un comunicado el domingo.<\/p>\n<p>\u201cLa soberan\u00eda y la independencia de nuestro pa\u00eds no son negociables\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Antes de la finalizaci\u00f3n del canal, los barcos que viajaban entre las costas este y oeste de Am\u00e9rica ten\u00edan que rodear el Cabo de Hornos, en el extremo sur de Sudam\u00e9rica, lo que a\u00f1ad\u00eda miles de kil\u00f3metros y varios meses a sus viajes.<\/p>\n<p>La creaci\u00f3n de un paso que acortara ese viaje hab\u00eda sido un objetivo dif\u00edcil de alcanzar para varios imperios que ten\u00edan colonias en el continente americano.<\/p>\n<p>A principios del siglo XX, el presidente estadounidense Theodore Roosevelt hizo de la construcci\u00f3n de un paso una prioridad. El territorio estaba entonces controlado por la Rep\u00fablica de Colombia, pero una revuelta apoyada por EE.UU. condujo a la separaci\u00f3n de Panam\u00e1 y Colombia, y a la formaci\u00f3n de la Rep\u00fablica de Panam\u00e1 en 1903. Estados Unidos y la reci\u00e9n formada rep\u00fablica firmaron ese a\u00f1o un tratado que otorgaba a Estados Unidos el control sobre una franja de 16 kil\u00f3metros de terreno para construir el canal a cambio de un reembolso econ\u00f3mico.<\/p>\n<p>El canal se termin\u00f3 en 1914, consolidando el estatus de Estados Unidos como superpotencia tecnol\u00f3gica y de ingenier\u00eda, pero tuvo un enorme coste humano. <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC8314810\/#:~:text=Records%20indicate%20that%20during%20the,died%20of%20injury%20and%20disease.\">Se calcula que unas 5.600 personas murieron<\/a> durante la construcci\u00f3n del canal.<\/p>\n<p>La utilidad del canal qued\u00f3 demostrada durante la Segunda Guerra Mundial, cuando se utiliz\u00f3 como v\u00eda de paso fundamental para el esfuerzo b\u00e9lico de los Aliados entre los oc\u00e9anos Atl\u00e1ntico y Pac\u00edfico. Pero la relaci\u00f3n entre Estados Unidos y Panam\u00e1 se fue desintegrando poco a poco por desacuerdos sobre el control del canal, el trato a los trabajadores paname\u00f1os, y cuestiones sobre si las banderas estadounidense y paname\u00f1a deb\u00edan ondear conjuntamente en la zona del canal.<\/p>\n<p>Estas tensiones alcanzaron su punto \u00e1lgido el 9 de enero de 1964, cuando los disturbios antiestadounidenses provocaron varias muertes en la zona del canal y la breve ruptura de las relaciones diplom\u00e1ticas entre ambos pa\u00edses.<\/p>\n<p>A\u00f1os de negociaciones para llegar a un acuerdo m\u00e1s equitativo desembocaron en dos tratados durante el Gobierno del presidente Jimmy Carter. Los acuerdos declaraban el canal neutral y abierto a todos los buques y preve\u00edan el control conjunto de EE.UU. y Panam\u00e1 del territorio hasta finales de 1999, fecha en la que se otorgar\u00eda a Panam\u00e1 el control total.<\/p>\n<p>\u201cDebido a que hemos controlado una franja de 16 kil\u00f3metros de ancho en el coraz\u00f3n de su pa\u00eds y a que consideran injustas las condiciones originales del acuerdo, el pueblo paname\u00f1o no est\u00e1 satisfecho con el tratado\u201d, declar\u00f3 Carter a los estadounidenses tras la firma de los tratados. \u201cFue redactado aqu\u00ed, en nuestro pa\u00eds, y no fue firmado por ning\u00fan paname\u00f1o\u201d.<\/p>\n<p>El entonces presidente a\u00f1adi\u00f3: \u201cPor supuesto, esto no da a Estados Unidos ning\u00fan derecho a intervenir en los asuntos internos de Panam\u00e1, ni nuestra acci\u00f3n militar ir\u00eda nunca dirigida contra la integridad territorial o la independencia pol\u00edtica de Panam\u00e1\u201d.<\/p>\n<p>No todo el mundo apoyaba el plan de Carter. En un discurso de 1976, el entonces candidato presidencial Ronald Reagan dijo que \u201cel pueblo de Estados Unidos\u201d es \u201cel leg\u00edtimo propietario de la zona del canal\u201d.<\/p>\n<p>Las tensiones en torno al canal volvieron a deteriorarse a finales de la d\u00e9cada de 1980, bajo el Gobierno de Manuel Noriega, destituido tras la invasi\u00f3n estadounidense de Panam\u00e1 en el marco de la \u201cguerra contra las drogas\u201d.<\/p>\n<p>Poco despu\u00e9s de que los paname\u00f1os retuvieran el control total del canal en 2000, el volumen de transporte mar\u00edtimo super\u00f3 r\u00e1pidamente la capacidad de la v\u00eda navegable. En 2007 se inici\u00f3 un enorme proyecto de ampliaci\u00f3n que se complet\u00f3 casi una d\u00e9cada despu\u00e9s.<\/p>\n<p>Pero la zona que rodea el canal ha sufrido <a href=\"https:\/\/cnnespanol.cnn.com\/2023\/06\/13\/sequia-precedentes-canal-panama-el-nino-trax\">graves sequ\u00edas<\/a>, lo que ha reducido los niveles de agua y ha dificultado su correcto funcionamiento. Las autoridades del canal establecieron restricciones al tr\u00e1fico e impusieron tarifas m\u00e1s elevadas para atravesarlo.<\/p>\n<p>Esas tarifas parecen formar parte del problema de Trump con el canal. El presidente electo las calific\u00f3 el domingo de \u201crid\u00edculas\u201d y \u201cmuy injustas, sobre todo conociendo la extraordinaria generosidad que ha otorgado a Panam\u00e1, digo, muy tontamente, Estados Unidos\u201d.<\/p>\n<p>La otra afirmaci\u00f3n de Trump, la de que China busca ejercer m\u00e1s control sobre Panam\u00e1 y la zona del canal, no carece de fundamento. En 2017, <a href=\"https:\/\/www.cnn.com\/2017\/06\/13\/asia\/panama-china-taiwan\/index.html\">Panam\u00e1 firm\u00f3<\/a> un comunicado conjunto que subrayaba que no mantendr\u00eda ning\u00fan v\u00ednculo oficial con Taiw\u00e1n, la democracia aut\u00f3noma que el gobernante Partido Comunista de China reclama como territorio propio. Desde entonces, la influencia de China en los alrededores del canal <a href=\"https:\/\/www.csis.org\/analysis\/key-decision-point-coming-panama-canal\">ha crecido<\/a>.<\/p>\n<p>En respuesta a las declaraciones de Trump durante el fin de semana, el presidente de Panam\u00e1 dijo: \u201cLas tarifas no son un capricho\u201d. Tambi\u00e9n descart\u00f3 la idea de que China ejerza un control abierto sobre el canal.<\/p>\n<p>\u201cEl canal no tiene ning\u00fan control, ni directo ni indirecto, ni de China, ni de la Comunidad Europea, ni de Estados Unidos ni de ninguna otra potencia\u201d, dijo Mulino en su declaraci\u00f3n.<\/p>\n<p>Las declaraciones de Trump son el m\u00e1s reciente ejemplo del presidente electo expresando su deseo de obtener, o amenazando con tomar o invadir, territorio perteneciente a una potencia extranjera amiga.<\/p>\n<p>Desde su elecci\u00f3n en noviembre, Trump se ha burlado del primer ministro de Canad\u00e1, Justin Trudeau, <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/18\/estados-unidos\/trump-va-a-por-canada-pero-sigue-resto-analisis-trax\">sugiriendo que su pa\u00eds<\/a> deber\u00eda convertirse en el 51\u00ba estado de Estados Unidos.<\/p>\n<p>Durante su primer mandato, Trump plante\u00f3 repetidamente la idea de que Estados Unidos comprar\u00eda Groenlandia a Dinamarca. El Gobierno de la isla dijo que \u201c<a href=\"https:\/\/www.cnn.com\/2019\/08\/15\/politics\/trump-buy-greenland-wall-street-journal\/index.html\">no est\u00e1 en venta<\/a>\u201d.<\/p>\n<p>Pero Trump no parece disuadido. Durante el fin de semana, el presidente electo <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-transition-government-shutdown-12-22-24#cm50exb2h00003b6mlz3xtolo\">resucit\u00f3 la idea<\/a> al anunciar su elecci\u00f3n como embajador en Dinamarca.<\/p>\n<p>\u201cPor motivos de seguridad nacional y libertad en todo el mundo, Estados Unidos de Am\u00e9rica considera que la propiedad y el control de Groenlandia es una necesidad absoluta\u201d, dijo Trump al anunciar su elecci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente electo de Estados Unidos, Donald Trump, sugiri\u00f3 el fin de semana que EE.UU. deber\u00eda retomar el Canal de Panam\u00e1, una idea que fue inmediatamente rechazada por el Gobierno de Panam\u00e1, que ha controlado el paso durante d\u00e9cadas. En mensajes en redes sociales y comentarios a sus simpatizantes, Trump acus\u00f3 a Panam\u00e1 de cobrar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456899","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente electo de Estados Unidos, Donald Trump, sugiri\u00f3 el fin de semana que EE.UU. deber\u00eda retomar el Canal de Panam\u00e1, una idea que fue inmediatamente rechazada por el Gobierno de Panam\u00e1, que ha controlado el paso durante d\u00e9cadas. En mensajes en redes sociales y comentarios a sus simpatizantes, Trump acus\u00f3 a Panam\u00e1 de cobrar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-23T23:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?\",\"datePublished\":\"2024-12-23T23:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/\"},\"wordCount\":1400,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/\",\"name\":\"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-23T23:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control? - Noticias","og_description":"El presidente electo de Estados Unidos, Donald Trump, sugiri\u00f3 el fin de semana que EE.UU. deber\u00eda retomar el Canal de Panam\u00e1, una idea que fue inmediatamente rechazada por el Gobierno de Panam\u00e1, que ha controlado el paso durante d\u00e9cadas. En mensajes en redes sociales y comentarios a sus simpatizantes, Trump acus\u00f3 a Panam\u00e1 de cobrar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-23T23:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?","datePublished":"2024-12-23T23:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/"},"wordCount":1400,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","name":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-23T23:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?","url":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-23T23:03:38Z","datePublished":"2024-12-23T23:03:38Z","dateModified":"2024-12-23T23:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfCu\\u00e1l es la historia del Canal de Panam\\u00e1 y por qu\\u00e9 Trump amenaza con retomar su control?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/23\\\/historia-canal-panama-por-que-trump-amenaza-control-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2024\\\/12\\\/23\\\/historia-canal-panama-por-que-trump-amenaza-control-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-23T23:03:38Z\",\"datePublished\":\"2024-12-23T23:03:38Z\",\"dateModified\":\"2024-12-23T23:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461673,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/04\/26\/trump-barcos-militares-deberian-pagar-canales-panama-suez-trax\/","url_meta":{"origin":1456899,"position":0},"title":"Trump dice que los barcos militares de EE.UU. no deber\u00edan pagar por usar los canales de Panam\u00e1 y Suez","author":"","date":"abril 26, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, dijo este s\u00e1bado que cree que los barcos estadounidenses no deber\u00edan tener que pagar para usar el canal de Panam\u00e1 ni el canal de Suez, en Egipto.\u201c\u00a1Los barcos estadounidenses, tanto militares como comerciales, deber\u00edan poder viajar, sin cargo, a trav\u00e9s de los canales de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457013,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/27\/trump-panama-groenlandia-tactica-negociacion-trax\/","url_meta":{"origin":1456899,"position":1},"title":"Los llamados de Trump para la expansi\u00f3n de EE.UU. en Panam\u00e1 y Groenlandia son parte de una t\u00e1ctica de negociaci\u00f3n","author":"","date":"diciembre 27, 2024","format":false,"excerpt":"La fijaci\u00f3n del presidente electo Donald Trump esta semana por querer tomar control del canal de Panam\u00e1 y su resurgimiento del deseo de comprar Groenlandia son parte de un esfuerzo mayor para intentar forzar a los l\u00edderes extranjeros a la mesa de negociaciones de maneras que Trump cree que son\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457344,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/01\/08\/historia-canal-panama-trump-trax\/","url_meta":{"origin":1456899,"position":2},"title":"\u00bfCu\u00e1l es la historia del canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?","author":"","date":"enero 8, 2025","format":false,"excerpt":"El presidente electo de Estados Unidos, Donald Trump, ha sugerido que EE.UU. deber\u00eda retomar el canal de Panam\u00e1, una idea firmemente rechazada por el Gobierno de Panam\u00e1, que ha controlado el paso durante d\u00e9cadas.En mensajes publicados en diciembre, Trump acus\u00f3 a Panam\u00e1 de cobrar a EE.UU. \u201ctarifas exorbitantes\u201d por utilizar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456932,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/24\/presidentes-panama-declaracion-canal-amenaza-trump-trax\/","url_meta":{"origin":1456899,"position":3},"title":"Cuatro presidentes de Panam\u00e1 firman declaraci\u00f3n para reafirmar soberan\u00eda sobre el canal de Panam\u00e1 tras amenaza de Trump","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"Tres expresidentes de Panam\u00e1 firmaron el lunes una declaraci\u00f3n conjunta con el actual mandatario, Jos\u00e9 Ra\u00fal Mulino, en la que reafirman el control de su pa\u00eds sobre el canal de Panam\u00e1, luego de que el presidente electo de Estados Unidos, Donald Trump, amenazara con retomar la v\u00eda acu\u00e1tica para EE.UU.\u201cComo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456957,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/25\/trump-nombra-embajador-panama-control-canal-trax\/","url_meta":{"origin":1456899,"position":4},"title":"Trump nombra al embajador de EE.UU. en Panam\u00e1 en medio de pol\u00e9mica por el control del Canal","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"El presidente electo Donald Trump eligi\u00f3 a Kevin Marino Cabrera para ocupar el cargo de embajador de Estados Unidos en la Rep\u00fablica de Panam\u00e1 en medio de su esfuerzo por tomar el control del Canal de Panam\u00e1 en la naci\u00f3n centroamericana, a la que ha acusado de explotar al Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457065,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/29\/entrevista-mulino-presidente-panama-oppenheimer-orix\/","url_meta":{"origin":1456899,"position":5},"title":"&#171;El canal es de los paname\u00f1os y seguir\u00e1 siendo de los paname\u00f1os. No hay otra forma de verlo&#187;, dice Jos\u00e9 Ra\u00fal Mulino a CNN","author":"","date":"diciembre 29, 2024","format":false,"excerpt":"A ra\u00edz de las declaraciones de Donald Trump sobre sus intenciones de quedarse con el control del canal de Panam\u00e1, el presidente Jos\u00e9 Ra\u00fal Mulino respondi\u00f3 a los dichos del presidente electo de EE. UU. en una conversaci\u00f3n con Andr\u00e9s Oppenheimer.El mandatario paname\u00f1o dijo que las palabras de Trump reflejan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1456899"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1456899\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1456899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1456899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1456899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}